{"id":25438,"date":"2022-12-09T14:52:05","date_gmt":"2022-12-09T13:52:05","guid":{"rendered":"https:\/\/ayto-ciempozuelos.org\/?post_type=tribe_events&#038;p=25438"},"modified":"2022-12-09T14:52:05","modified_gmt":"2022-12-09T13:52:05","slug":"taller-descubrir-los-clasicos-con-fernando-vicente","status":"publish","type":"tribe_events","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/","title":{"rendered":"Taller: Descubrir los cl\u00e1sicos con Fernando Vicente"},"content":{"rendered":"<div id=\"textoEntradilla\" class=\"texto\"><img decoding=\"async\" class=\"size-medium wp-image-25231 alignright\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/11\/cartel-AVENTURAS-ILUSTRADAS-212x300.png\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/11\/cartel-AVENTURAS-ILUSTRADAS-200x283.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/11\/cartel-AVENTURAS-ILUSTRADAS-212x300.png 212w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/11\/cartel-AVENTURAS-ILUSTRADAS-400x566.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/11\/cartel-AVENTURAS-ILUSTRADAS-600x849.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/11\/cartel-AVENTURAS-ILUSTRADAS-724x1024.png 724w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/11\/cartel-AVENTURAS-ILUSTRADAS-768x1086.png 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/11\/cartel-AVENTURAS-ILUSTRADAS-800x1132.png 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/11\/cartel-AVENTURAS-ILUSTRADAS-1200x1697.png 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/11\/cartel-AVENTURAS-ILUSTRADAS.png 1414w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/>En el marco de la exposici\u00f3n &#8216;Aventuras ilustradas&#8217; que se expone en la Sala de Exposiciones de la Biblioteca Municipal Almudena Grandes del 1 al 21 de diciembre, se ha organizado un taller familiar, el viernes 16 de diciembre a las 18:00 h., titulado &#8216;Descubrir los cl\u00e1sicos con Fernando Vicente&#8217;.<\/div>\n<div><\/div>\n<div class=\"texto\">Partiendo de la predisposici\u00f3n natural de los ni\u00f1os hacia las im\u00e1genes, este taller les introducir\u00e1 a trav\u00e9s de las m\u00e1gicas ilustraciones del artista, en algunos de los m\u00e1s famosos cl\u00e1sicos de la literatura infantil y juvenil. Una actividad en la que los ni\u00f1os aprender\u00e1n a mirar con intensidad, a leer im\u00e1genes y a crear y recrear gracias a ellas algunas de las m\u00e1s fascinantes historias de aventuras de todos los tiempos. Concebida para proporcionar a grandes y peque\u00f1os un espacio para observar, imaginar y fomentar el disfrute de lo art\u00edstico.<\/div>\n<div id=\"textoCuerpo\" class=\"texto\">\n<p>Y para que el juego contin\u00fae el taller finalizar\u00e1 con la creaci\u00f3n por parte de cada participante de un cubo m\u00e1gico con ilustraciones ocultas de Fernando Vicente que les permitir\u00e1 continuar imaginando cl\u00e1sicos en sus casas y les servir\u00e1 de gu\u00eda en su visita a la exposici\u00f3n.<\/p>\n<ul>\n<li>Por: RZ100arte<\/li>\n<li>Actividad destinada a ni\u00f1as y ni\u00f1os de 5 a 10 a\u00f1os acompa\u00f1ados de un adulto.<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la exposici\u00f3n &#8216;Aventuras ilustradas&#8217; que se expone en la Sala de Exposiciones de la Biblioteca Municipal Almudena Grandes del 1 al 21 de diciembre, se ha organizado un taller familiar, el viernes 16 de diciembre a las 18:00 h., titulado &#8216;Descubrir los cl\u00e1sicos con Fernando Vicente&#8217;. Partiendo de la predisposici\u00f3n natural [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":25232,"template":"","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[2671,2719,1708,2672,2720,2680],"tribe_events_cat":[90],"class_list":["post-25438","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-aventuras-ilustradas","tag-descubrir-los-clasicos-con-fernando-vicente","tag-exposicion","tag-fernando-vicente","tag-ilustraciones","tag-taller-familiar","tribe_events_cat-talleres","cat_talleres"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En el marco de la exposici\u00f3n &#039;Aventuras ilustradas&#039; que se expone en la Sala de Exposiciones de la Biblioteca Municipal Almudena Grandes del 1 al 21 de diciembre, se ha organizado un taller familiar, el viernes 16 de diciembre a las 18:00 h., titulado &#039;Descubrir los cl\u00e1sicos con Fernando Vicente&#039;. Partiendo de la predisposici\u00f3n natural\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Comunicacion1 Ayto. Ciempozuelos\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Taller: Descubrir los cl\u00e1sicos con Fernando Vicente - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"En el marco de la exposici\u00f3n &#039;Aventuras ilustradas&#039; que se expone en la Sala de Exposiciones de la Biblioteca Municipal Almudena Grandes del 1 al 21 de diciembre, se ha organizado un taller familiar, el viernes 16 de diciembre a las 18:00 h., titulado &#039;Descubrir los cl\u00e1sicos con Fernando Vicente&#039;. Partiendo de la predisposici\u00f3n natural\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-12-09T13:52:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-12-09T13:52:05+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Taller: Descubrir los cl\u00e1sicos con Fernando Vicente - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En el marco de la exposici\u00f3n &#039;Aventuras ilustradas&#039; que se expone en la Sala de Exposiciones de la Biblioteca Municipal Almudena Grandes del 1 al 21 de diciembre, se ha organizado un taller familiar, el viernes 16 de diciembre a las 18:00 h., titulado &#039;Descubrir los cl\u00e1sicos con Fernando Vicente&#039;. Partiendo de la predisposici\u00f3n natural\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/taller-descubrir-los-clasicos-con-fernando-vicente\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/eventos\\\/#listItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/eventos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposicion\\\/#listItem\",\"name\":\"exposici\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposicion\\\/#listItem\",\"position\":3,\"name\":\"exposici\\u00f3n\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposicion\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/taller-descubrir-los-clasicos-con-fernando-vicente\\\/#listItem\",\"name\":\"Taller: Descubrir los cl\\u00e1sicos con Fernando Vicente\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/taller-descubrir-los-clasicos-con-fernando-vicente\\\/#listItem\",\"position\":4,\"name\":\"Taller: Descubrir los cl\\u00e1sicos con Fernando Vicente\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposicion\\\/#listItem\",\"name\":\"exposici\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/comunicacion1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/comunicacion1\\\/\",\"name\":\"Comunicacion1 Ayto. Ciempozuelos\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/taller-descubrir-los-clasicos-con-fernando-vicente\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60afb79958439e9dbf77c5215ce03fdff0878893472237ab5f48091ac0b68591?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Comunicacion1 Ayto. Ciempozuelos\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/taller-descubrir-los-clasicos-con-fernando-vicente\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/taller-descubrir-los-clasicos-con-fernando-vicente\\\/\",\"name\":\"Taller: Descubrir los cl\\u00e1sicos con Fernando Vicente - Ayuntamiento de Ciempozuelos\",\"description\":\"En el marco de la exposici\\u00f3n 'Aventuras ilustradas' que se expone en la Sala de Exposiciones de la Biblioteca Municipal Almudena Grandes del 1 al 21 de diciembre, se ha organizado un taller familiar, el viernes 16 de diciembre a las 18:00 h., titulado 'Descubrir los cl\\u00e1sicos con Fernando Vicente'. Partiendo de la predisposici\\u00f3n natural\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/taller-descubrir-los-clasicos-con-fernando-vicente\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/comunicacion1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/comunicacion1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/aventuras-ilustradas.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/taller-descubrir-los-clasicos-con-fernando-vicente\\\/#mainImage\",\"width\":1012,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/taller-descubrir-los-clasicos-con-fernando-vicente\\\/#mainImage\"},\"datePublished\":\"2022-12-09T14:52:05+01:00\",\"dateModified\":\"2022-12-09T14:52:05+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Taller: Descubrir los cl\u00e1sicos con Fernando Vicente - Ayuntamiento de Ciempozuelos","description":"En el marco de la exposici\u00f3n 'Aventuras ilustradas' que se expone en la Sala de Exposiciones de la Biblioteca Municipal Almudena Grandes del 1 al 21 de diciembre, se ha organizado un taller familiar, el viernes 16 de diciembre a las 18:00 h., titulado 'Descubrir los cl\u00e1sicos con Fernando Vicente'. Partiendo de la predisposici\u00f3n natural","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/#listItem","position":2,"name":"Eventos","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposicion\/#listItem","name":"exposici\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposicion\/#listItem","position":3,"name":"exposici\u00f3n","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposicion\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/#listItem","name":"Taller: Descubrir los cl\u00e1sicos con Fernando Vicente"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/#listItem","position":4,"name":"Taller: Descubrir los cl\u00e1sicos con Fernando Vicente","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposicion\/#listItem","name":"exposici\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/comunicacion1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/comunicacion1\/","name":"Comunicacion1 Ayto. Ciempozuelos","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/60afb79958439e9dbf77c5215ce03fdff0878893472237ab5f48091ac0b68591?s=96&d=mm&r=g","width":96,"height":96,"caption":"Comunicacion1 Ayto. Ciempozuelos"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/","name":"Taller: Descubrir los cl\u00e1sicos con Fernando Vicente - Ayuntamiento de Ciempozuelos","description":"En el marco de la exposici\u00f3n 'Aventuras ilustradas' que se expone en la Sala de Exposiciones de la Biblioteca Municipal Almudena Grandes del 1 al 21 de diciembre, se ha organizado un taller familiar, el viernes 16 de diciembre a las 18:00 h., titulado 'Descubrir los cl\u00e1sicos con Fernando Vicente'. Partiendo de la predisposici\u00f3n natural","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/comunicacion1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/comunicacion1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/11\/aventuras-ilustradas.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/#mainImage","width":1012,"height":640},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/#mainImage"},"datePublished":"2022-12-09T14:52:05+01:00","dateModified":"2022-12-09T14:52:05+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Taller: Descubrir los cl\u00e1sicos con Fernando Vicente - Ayuntamiento de Ciempozuelos","og:description":"En el marco de la exposici\u00f3n 'Aventuras ilustradas' que se expone en la Sala de Exposiciones de la Biblioteca Municipal Almudena Grandes del 1 al 21 de diciembre, se ha organizado un taller familiar, el viernes 16 de diciembre a las 18:00 h., titulado 'Descubrir los cl\u00e1sicos con Fernando Vicente'. Partiendo de la predisposici\u00f3n natural","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/","article:published_time":"2022-12-09T13:52:05+00:00","article:modified_time":"2022-12-09T13:52:05+00:00","twitter:card":"summary","twitter:title":"Taller: Descubrir los cl\u00e1sicos con Fernando Vicente - Ayuntamiento de Ciempozuelos","twitter:description":"En el marco de la exposici\u00f3n 'Aventuras ilustradas' que se expone en la Sala de Exposiciones de la Biblioteca Municipal Almudena Grandes del 1 al 21 de diciembre, se ha organizado un taller familiar, el viernes 16 de diciembre a las 18:00 h., titulado 'Descubrir los cl\u00e1sicos con Fernando Vicente'. Partiendo de la predisposici\u00f3n natural"},"aioseo_meta_data":{"post_id":"25438","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"#aioseo-web-page-63f919744699a","slug":"web-page","graphName":"WebPage","label":"P\u00e1gina web","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-12-09 13:52:09","updated":"2025-06-05 00:27:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/\" title=\"Eventos\">Eventos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposicion\/\" title=\"exposici\u00f3n\">exposici\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTaller: Descubrir los cl\u00e1sicos con Fernando Vicente\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Eventos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/"},{"label":"exposici\u00f3n","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposicion\/"},{"label":"Taller: Descubrir los cl\u00e1sicos con Fernando Vicente","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/taller-descubrir-los-clasicos-con-fernando-vicente\/"}],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tribe_events\/25438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tribe_events\/25438\/revisions"}],"predecessor-version":[{"id":25439,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tribe_events\/25438\/revisions\/25439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/25232"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=25438"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=25438"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=25438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}