{"id":25420,"date":"2022-12-05T10:58:06","date_gmt":"2022-12-05T09:58:06","guid":{"rendered":"https:\/\/ayto-ciempozuelos.org\/?post_type=tribe_events&#038;p=25420"},"modified":"2022-12-09T21:41:58","modified_gmt":"2022-12-09T20:41:58","slug":"navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial","status":"publish","type":"tribe_events","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/","title":{"rendered":"Navidad 2022: Inauguraci\u00f3n del alumbrado navide\u00f1o y gran nevada artificial"},"content":{"rendered":"<p><img decoding=\"async\" class=\"size-medium wp-image-25421 alignright\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/12\/5.-Cartel-inauguracion-de-alumbrado-214x300.png\" alt=\"\" width=\"214\" height=\"300\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/12\/5.-Cartel-inauguracion-de-alumbrado-200x280.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/12\/5.-Cartel-inauguracion-de-alumbrado-214x300.png 214w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/12\/5.-Cartel-inauguracion-de-alumbrado-400x560.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/12\/5.-Cartel-inauguracion-de-alumbrado-600x840.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/12\/5.-Cartel-inauguracion-de-alumbrado-731x1024.png 731w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/12\/5.-Cartel-inauguracion-de-alumbrado-768x1076.png 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/12\/5.-Cartel-inauguracion-de-alumbrado-800x1120.png 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/12\/5.-Cartel-inauguracion-de-alumbrado-1200x1681.png 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2022\/12\/5.-Cartel-inauguracion-de-alumbrado.png 1428w\" sizes=\"(max-width: 214px) 100vw, 214px\" \/>Ciempozuelos inaugura la Navidad de 2022\/2023 con el encendido del alumbrado navide\u00f1o y una gran nevada artificial el pr\u00f3ximo 15 de diciembre a las 19:00 horas en la Plaza de la Constituci\u00f3n.<\/p>\n<ul>\n<li>Saluda de la alcaldesa Raquel Jimeno.<\/li>\n<li>Organiza: concejal\u00eda de Festejos.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ciempozuelos inaugura la Navidad de 2022\/2023 con el encendido del alumbrado navide\u00f1o y una gran nevada artificial el pr\u00f3ximo 15 de diciembre a las 19:00 horas en la Plaza de la Constituci\u00f3n. Saluda de la alcaldesa Raquel Jimeno. Organiza: concejal\u00eda de Festejos.<\/p>\n","protected":false},"author":4,"featured_media":5051,"template":"","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[2226,2225,2618,2715],"tribe_events_cat":[94],"class_list":["post-25420","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-alumbrado","tag-inauguracion","tag-navidad-2022","tag-nevada-artificial","tribe_events_cat-navidad","cat_navidad"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ciempozuelos inaugura la Navidad de 2022\/2023 con el encendido del alumbrado navide\u00f1o y una gran nevada artificial el pr\u00f3ximo 15 de diciembre a las 19:00 horas en la Plaza de la Constituci\u00f3n. Saluda de la alcaldesa Raquel Jimeno. Organiza: concejal\u00eda de Festejos.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Comunicacion1 Ayto. Ciempozuelos\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Navidad 2022: Inauguraci\u00f3n del alumbrado navide\u00f1o y gran nevada artificial - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Ciempozuelos inaugura la Navidad de 2022\/2023 con el encendido del alumbrado navide\u00f1o y una gran nevada artificial el pr\u00f3ximo 15 de diciembre a las 19:00 horas en la Plaza de la Constituci\u00f3n. Saluda de la alcaldesa Raquel Jimeno. Organiza: concejal\u00eda de Festejos.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-12-05T09:58:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-12-09T20:41:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Navidad 2022: Inauguraci\u00f3n del alumbrado navide\u00f1o y gran nevada artificial - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ciempozuelos inaugura la Navidad de 2022\/2023 con el encendido del alumbrado navide\u00f1o y una gran nevada artificial el pr\u00f3ximo 15 de diciembre a las 19:00 horas en la Plaza de la Constituci\u00f3n. Saluda de la alcaldesa Raquel Jimeno. Organiza: concejal\u00eda de Festejos.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/eventos\\\/#listItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/eventos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/inauguracion\\\/#listItem\",\"name\":\"inauguraci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/inauguracion\\\/#listItem\",\"position\":3,\"name\":\"inauguraci\\u00f3n\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/inauguracion\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\\\/#listItem\",\"name\":\"Navidad 2022: Inauguraci\\u00f3n del alumbrado navide\\u00f1o y gran nevada artificial\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/eventos\\\/#listItem\",\"name\":\"Eventos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\\\/#listItem\",\"position\":4,\"name\":\"Navidad 2022: Inauguraci\\u00f3n del alumbrado navide\\u00f1o y gran nevada artificial\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/inauguracion\\\/#listItem\",\"name\":\"inauguraci\\u00f3n\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/comunicacion1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/comunicacion1\\\/\",\"name\":\"Comunicacion1 Ayto. Ciempozuelos\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60afb79958439e9dbf77c5215ce03fdff0878893472237ab5f48091ac0b68591?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Comunicacion1 Ayto. Ciempozuelos\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\\\/\",\"name\":\"Navidad 2022: Inauguraci\\u00f3n del alumbrado navide\\u00f1o y gran nevada artificial - Ayuntamiento de Ciempozuelos\",\"description\":\"Ciempozuelos inaugura la Navidad de 2022\\\/2023 con el encendido del alumbrado navide\\u00f1o y una gran nevada artificial el pr\\u00f3ximo 15 de diciembre a las 19:00 horas en la Plaza de la Constituci\\u00f3n. Saluda de la alcaldesa Raquel Jimeno. Organiza: concejal\\u00eda de Festejos.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/comunicacion1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/comunicacion1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/1.-Comercio-Local.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\\\/#mainImage\",\"width\":1600,\"height\":1200,\"caption\":\"Plaza de la Constituci\\u00f3n. Navidad 2020-2021\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/evento\\\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\\\/#mainImage\"},\"datePublished\":\"2022-12-05T10:58:06+01:00\",\"dateModified\":\"2022-12-09T21:41:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Navidad 2022: Inauguraci\u00f3n del alumbrado navide\u00f1o y gran nevada artificial - Ayuntamiento de Ciempozuelos","description":"Ciempozuelos inaugura la Navidad de 2022\/2023 con el encendido del alumbrado navide\u00f1o y una gran nevada artificial el pr\u00f3ximo 15 de diciembre a las 19:00 horas en la Plaza de la Constituci\u00f3n. Saluda de la alcaldesa Raquel Jimeno. Organiza: concejal\u00eda de Festejos.","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/#listItem","position":2,"name":"Eventos","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/inauguracion\/#listItem","name":"inauguraci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/inauguracion\/#listItem","position":3,"name":"inauguraci\u00f3n","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/inauguracion\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/#listItem","name":"Navidad 2022: Inauguraci\u00f3n del alumbrado navide\u00f1o y gran nevada artificial"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/#listItem","name":"Eventos"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/#listItem","position":4,"name":"Navidad 2022: Inauguraci\u00f3n del alumbrado navide\u00f1o y gran nevada artificial","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/inauguracion\/#listItem","name":"inauguraci\u00f3n"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/comunicacion1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/comunicacion1\/","name":"Comunicacion1 Ayto. Ciempozuelos","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/60afb79958439e9dbf77c5215ce03fdff0878893472237ab5f48091ac0b68591?s=96&d=mm&r=g","width":96,"height":96,"caption":"Comunicacion1 Ayto. Ciempozuelos"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/","name":"Navidad 2022: Inauguraci\u00f3n del alumbrado navide\u00f1o y gran nevada artificial - Ayuntamiento de Ciempozuelos","description":"Ciempozuelos inaugura la Navidad de 2022\/2023 con el encendido del alumbrado navide\u00f1o y una gran nevada artificial el pr\u00f3ximo 15 de diciembre a las 19:00 horas en la Plaza de la Constituci\u00f3n. Saluda de la alcaldesa Raquel Jimeno. Organiza: concejal\u00eda de Festejos.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/comunicacion1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/comunicacion1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/01\/1.-Comercio-Local.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/#mainImage","width":1600,"height":1200,"caption":"Plaza de la Constituci\u00f3n. Navidad 2020-2021"},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/#mainImage"},"datePublished":"2022-12-05T10:58:06+01:00","dateModified":"2022-12-09T21:41:58+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Navidad 2022: Inauguraci\u00f3n del alumbrado navide\u00f1o y gran nevada artificial - Ayuntamiento de Ciempozuelos","og:description":"Ciempozuelos inaugura la Navidad de 2022\/2023 con el encendido del alumbrado navide\u00f1o y una gran nevada artificial el pr\u00f3ximo 15 de diciembre a las 19:00 horas en la Plaza de la Constituci\u00f3n. Saluda de la alcaldesa Raquel Jimeno. Organiza: concejal\u00eda de Festejos.","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/","article:published_time":"2022-12-05T09:58:06+00:00","article:modified_time":"2022-12-09T20:41:58+00:00","twitter:card":"summary","twitter:title":"Navidad 2022: Inauguraci\u00f3n del alumbrado navide\u00f1o y gran nevada artificial - Ayuntamiento de Ciempozuelos","twitter:description":"Ciempozuelos inaugura la Navidad de 2022\/2023 con el encendido del alumbrado navide\u00f1o y una gran nevada artificial el pr\u00f3ximo 15 de diciembre a las 19:00 horas en la Plaza de la Constituci\u00f3n. Saluda de la alcaldesa Raquel Jimeno. Organiza: concejal\u00eda de Festejos."},"aioseo_meta_data":{"post_id":"25420","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"#aioseo-web-page-63f87844427f5","slug":"web-page","graphName":"WebPage","label":"P\u00e1gina web","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-12-05 09:58:08","updated":"2025-06-05 00:27:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/\" title=\"Eventos\">Eventos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/inauguracion\/\" title=\"inauguraci\u00f3n\">inauguraci\u00f3n<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNavidad 2022: Inauguraci\u00f3n del alumbrado navide\u00f1o y gran nevada artificial\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Eventos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/eventos\/"},{"label":"inauguraci\u00f3n","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/inauguracion\/"},{"label":"Navidad 2022: Inauguraci\u00f3n del alumbrado navide\u00f1o y gran nevada artificial","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/evento\/navidad-2022-inauguracion-del-alumbrado-navideno-y-gran-nevada-artificial\/"}],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tribe_events\/25420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tribe_events\/25420\/revisions"}],"predecessor-version":[{"id":25422,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tribe_events\/25420\/revisions\/25422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/5051"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=25420"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=25420"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=25420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}