{"id":43118,"date":"2026-04-17T14:32:48","date_gmt":"2026-04-17T12:32:48","guid":{"rendered":"https:\/\/ayto-ciempozuelos.org\/?p=43118"},"modified":"2026-04-17T14:32:48","modified_gmt":"2026-04-17T12:32:48","slug":"el-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/04\/17\/el-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos\/","title":{"rendered":"El Ayuntamiento de Ciempozuelos ayudar\u00e1 a las familias a pagar las extraescolares de las ni\u00f1as y los ni\u00f1os"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div ><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1195\" height=\"288\" alt=\"Ciempozuelos Informa\" title=\"Ciempozuelos Informa\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa.jpg\" class=\"img-responsive wp-image-16209\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-200x48.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-400x96.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-600x145.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-800x193.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa.jpg 1195w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 1195px\" \/><\/span><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column k_hide\" id=\"k_principalultimasnoticias\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-end fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:#e8e8e8;border-width: 2px 2px 2px 2px;border-color:#f44336;border-style:solid;padding: 10px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\" id=\"k_principalultimasnoticias1\"><p><img decoding=\"async\" class=\"k_imgultimasnoticias wp-image-16863 alignleft\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png\" alt=\"\" width=\"173\" height=\"50\" data-wp-editing=\"1\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-200x58.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-300x87.png 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-400x115.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-600x173.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png 693w\" sizes=\"(max-width: 173px) 100vw, 173px\" \/><div class=\"lcp_catlist\" id=\"lcp_instance_0\"><\/div><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 10px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0 !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style>\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_3 2_3 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-2\"><p style=\"text-align: center;\"><img decoding=\"async\" width=\"1440\" height=\"1080\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/04\/484052105_1056629156499009_8397524646934044410_n.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/04\/484052105_1056629156499009_8397524646934044410_n-200x150.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/04\/484052105_1056629156499009_8397524646934044410_n-300x225.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/04\/484052105_1056629156499009_8397524646934044410_n-400x300.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/04\/484052105_1056629156499009_8397524646934044410_n-600x450.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/04\/484052105_1056629156499009_8397524646934044410_n-768x576.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/04\/484052105_1056629156499009_8397524646934044410_n-800x600.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/04\/484052105_1056629156499009_8397524646934044410_n-1024x768.jpg 1024w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/04\/484052105_1056629156499009_8397524646934044410_n-1200x900.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/04\/484052105_1056629156499009_8397524646934044410_n.jpg 1440w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/p>\n<\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-1{margin-top:0px!important;margin-bottom:30px!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-three ktitle_post\" style=\"margin-top:0px;margin-bottom:30px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-\" style=\"border-color:#e2e2e2;\"><\/div><\/div><h3 class=\"title-heading-left\" style=\"font-family:&quot;PT Sans&quot;;font-weight:700;margin:0;color:#000859;\">El Ayuntamiento de Ciempozuelos ayudar\u00e1 a las familias a pagar las extraescolares de las ni\u00f1as y los ni\u00f1os<\/h3><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-\" style=\"border-color:#e2e2e2;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-3\"><div style=\"font-size: 13px; font-style: italic;\">17 de abril de 2026<\/div>\n<\/div><div class=\"fusion-text fusion-text-4\"><p>150.000 euros. Es la cantidad que el Ayuntamiento va a destinar de los Presupuestos 2026 para las familias de Ciempozuelos. Concretamente, <strong>se va a otorgar una ayuda a todas aquellas con menores de entre 6 y 15 a\u00f1os que realicen una actividad extraescolar en el municipio.<\/strong> <em>\u201cLas actividades extraescolares son un complemento muy importante para la educaci\u00f3n de nuestros ni\u00f1os y de nuestras ni\u00f1as pero a la vez todas las familias sabemos que suponen un importante esfuerzo econ\u00f3mico cada mes<\/em>\u201d, dice la alcaldesa, Raquel Jimeno.<\/p>\n<p>Con la voluntad de hacer m\u00e1s liviana esta carga, <strong>el consistorio subvencionar\u00e1 a las familias con hasta un m\u00e1ximo de 60 euros por ni\u00f1o o ni\u00f1a que durante los meses escolares de 2026 del curso 2025\/2026 haya realizado o est\u00e9 realizando alguna actividad formativa no lectiva en Ciempozuelos<em>. <\/em><\/strong>Una cantidad que pretende sufragar los costes de matricula, inscripci\u00f3n o cuota.<em> \u201c<strong>La extraescolar que realicen los ni\u00f1os o ni\u00f1as puede ser municipal o en un centro privado y, tambi\u00e9n, de cualquier naturaleza: deportiva, art\u00edstica, cultural, musical, de idiomas\u2026El \u00fanico requisito es que las hagan en nuestra localidad\u201d<\/strong><\/em>, explica Rosa Revuelta, responsable de la concejal\u00eda de Educaci\u00f3n y Ense\u00f1anzas No Regladas que es el \u00e1rea que gestionar\u00e1 estas ayudas.<\/p>\n<p><strong>Solicitar la ayuda<\/strong><\/p>\n<p>En los pr\u00f3ximos d\u00edas, el Ayuntamiento de Ciempozuelos anunciar\u00e1 a trav\u00e9s de sus canales de comunicaci\u00f3n habituales qu\u00e9 tienen que hacer las familias para solicitar la ayuda, pero desde la concejal\u00eda de Educaci\u00f3n ya adelantan que el procedimiento ser\u00e1 <em>\u201cel habitual. Es decir, hacer la solicitud al Ayuntamiento entregando documentaci\u00f3n que acredite que se est\u00e1 realizando la extraescolar, como es la factura y el justificante de pago\u201d.<\/em><\/p>\n<p><strong><em>\u201cEl apoyo a las familias y a la educaci\u00f3n de los ni\u00f1os y ni\u00f1as de Ciempozuelos es una prioridad para este equipo de Gobierno, y desde el Ayuntamiento seguiremos apoy\u00e1ndolo de manera directa, como en este caso, o indirecta\u201d<\/em>, concluye la alcaldesa.<\/strong><\/p>\n<\/div><div class=\"fusion-text fusion-text-5\"><p><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/ciempozuelos-informa\/\"><em><span style=\"font-size: 14px;\" data-fusion-font=\"true\">&gt;&gt; Regresar a Hemeroteca &#8211; Ciempozuelos Informa<\/span><\/em><\/a><\/p>\n<\/div><div class=\"share-box fusion-sharing-box\" style=\"background-color:#e8e8e8;\" data-title=\"El Ayuntamiento de Ciempozuelos ayudar\u00e1 a las familias a pagar las extraescolares de las ni\u00f1as y los ni\u00f1os\" data-description=\"Your Content Goes Here \r\n \r\n\r\n150.000 euros. Es la cantidad que el Ayuntamiento va a destinar de los Presupuestos 2026 para las familias de Ciempozuelos. Concretamente, se va a otorgar una ayuda a todas aquellas con menores de entre 6 y 15\" data-link=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/04\/17\/el-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos\/\"><h4 class=\"tagline\" style=\"color:#000859;\"> \u00a1Comparte esta noticia en tus redes sociales!<\/h4><div class=\"fusion-social-networks\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-facebook fusion-icon-facebook\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2026%2F04%2F17%2Fel-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos%2F&amp;t=El%20Ayuntamiento%20de%20Ciempozuelos%20ayudar%C3%A1%20a%20las%20familias%20a%20pagar%20las%20extraescolares%20de%20las%20ni%C3%B1as%20y%20los%20ni%C3%B1os\" target=\"_blank\" style=\"color:#3b5998;\" title=\"Facebook\" aria-label=\"Facebook\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Facebook\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-twitter fusion-icon-twitter\" href=\"https:\/\/twitter.com\/share?text=El%20Ayuntamiento%20de%20Ciempozuelos%20ayudar%C3%A1%20a%20las%20familias%20a%20pagar%20las%20extraescolares%20de%20las%20ni%C3%B1as%20y%20los%20ni%C3%B1os&amp;url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2026%2F04%2F17%2Fel-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos%2F\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#55acee;\" title=\"Twitter\" aria-label=\"Twitter\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Twitter\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin fusion-icon-linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2026%2F04%2F17%2Fel-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos%2F&amp;title=El%20Ayuntamiento%20de%20Ciempozuelos%20ayudar%C3%A1%20a%20las%20familias%20a%20pagar%20las%20extraescolares%20de%20las%20ni%C3%B1as%20y%20los%20ni%C3%B1os&amp;summary=Your%20Content%20Goes%20Here%20%0D%0A%20%20%0D%0A%0D%0A150.000%20euros.%20Es%20la%20cantidad%20que%20el%20Ayuntamiento%20va%20a%20destinar%20de%20los%20Presupuestos%202026%20para%20las%20familias%20de%20Ciempozuelos.%20Concretamente%2C%20se%20va%20a%20otorgar%20una%20ayuda%20a%20todas%20aquellas%20con%20menores%20de%20entre%206%20y%2015\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#0077b5;\" title=\"LinkedIn\" aria-label=\"LinkedIn\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"LinkedIn\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-whatsapp fusion-icon-whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2026%2F04%2F17%2Fel-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos%2F\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#77e878;\" title=\"WhatsApp\" aria-label=\"WhatsApp\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"WhatsApp\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-tumblr fusion-icon-tumblr\" href=\"http:\/\/www.tumblr.com\/share\/link?url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2026%2F04%2F17%2Fel-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos%2F&amp;name=El%20Ayuntamiento%20de%20Ciempozuelos%20ayudar%C3%A1%20a%20las%20familias%20a%20pagar%20las%20extraescolares%20de%20las%20ni%C3%B1as%20y%20los%20ni%C3%B1os&amp;description=Your%20Content%20Goes%20Here%20%0D%0A%20%20%0D%0A%0D%0A150.000%20euros.%20Es%20la%20cantidad%20que%20el%20Ayuntamiento%20va%20a%20destinar%20de%20los%20Presupuestos%202026%20para%20las%20familias%20de%20Ciempozuelos.%20Concretamente%2C%20se%20va%20a%20otorgar%20una%20ayuda%20a%20todas%20aquellas%20con%20menores%20de%20entre%206%20y%2015\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#35465c;\" title=\"Tumblr\" aria-label=\"Tumblr\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Tumblr\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail fusion-icon-mail\" href=\"mailto:?subject=El%20Ayuntamiento%20de%20Ciempozuelos%20ayudar%C3%A1%20a%20las%20familias%20a%20pagar%20las%20extraescolares%20de%20las%20ni%C3%B1as%20y%20los%20ni%C3%B1os&amp;body=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2026%2F04%2F17%2Fel-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos%2F\" target=\"_self\" style=\"color:#000000;\" title=\"Correo electr\u00f3nico\" aria-label=\"Correo electr\u00f3nico\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Correo electr\u00f3nico\"><\/a><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-2{width:66.666666666667% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-2 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 2.88%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 2.88%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_3 1_3 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-6\"><p><span style=\"color: #000859;\"><strong>\u00daLTIMAS NOTICIAS &#8211; CIEMPOZUELOS INFORMA<\/strong><\/span><\/p>\n<\/div><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-no fusion-blog-no-images fusion-blog-layout-left\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:8.5px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -8.5px !important; margin-right:-8.5px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-no fusion-blog-layout-grid fusion-blog-layout-grid-1 isotope\" data-pages=\"238\" data-grid-col-space=\"17\" style=\"margin: -8.5px -8.5px 0;min-height:500px;\"><article id=\"blog-1-post-43605\" class=\"fusion-post-grid post-43605 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-a4 tag-alcaldesa tag-ciempozuelos tag-guardia-civil tag-incendio tag-mercadona tag-policia tag-poligono tag-raquel-jimeno tag-seguridad tag-sendilla\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/07\/guardia-civil-detiene-al-presunto-autor-del-incendio-del-pasado-mes-de-junio-en-el-poligono-industrial-la-sendilla\/\">Guardia Civil detiene al presunto autor del incendio del pasado mes de junio en el pol\u00edgono industrial La Sendilla<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/\" title=\"Entradas de Comunicaci\u00f3n Ciempozuelos\" rel=\"author\">Comunicaci\u00f3n Ciempozuelos<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-07T13:28:36+02:00<\/span><span>julio 7th, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/07\/guardia-civil-detiene-al-presunto-autor-del-incendio-del-pasado-mes-de-junio-en-el-poligono-industrial-la-sendilla\/\" aria-label=\"More on Guardia Civil detiene al presunto autor del incendio del pasado mes de junio en el pol\u00edgono industrial La Sendilla\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-43588\" class=\"fusion-post-grid post-43588 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-cimepozuelos tag-empleo-ruben-iglesias-garcia tag-empresa tag-formacion-sin-categoria tag-vecinos tag-verano\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/06\/nuevas-incorporaciones-en-los-programas-de-empleo-formacion-2026\/\">Nuevas incorporaciones en los Programas de Empleo-Formaci\u00f3n 2026<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/sara-lazaro\/\" title=\"Entradas de Sara L\u00e1zaro\" rel=\"author\">Sara L\u00e1zaro<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-06T13:46:58+02:00<\/span><span>julio 6th, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/06\/nuevas-incorporaciones-en-los-programas-de-empleo-formacion-2026\/\" aria-label=\"More on Nuevas incorporaciones en los Programas de Empleo-Formaci\u00f3n 2026\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-43565\" class=\"fusion-post-grid post-43565 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-alcaldesa tag-cimepozuelos tag-concejal tag-deportes-jorge-alonso-diaz tag-empresa tag-gimnasio tag-justicia tag-morgado tag-piscina tag-raquel-jimeno tag-vecinos tag-verano\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\">El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/\" title=\"Entradas de Comunicaci\u00f3n Ciempozuelos\" rel=\"author\">Comunicaci\u00f3n Ciempozuelos<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-02T14:26:33+02:00<\/span><span>julio 2nd, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" aria-label=\"More on El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-7 k_hide\" id=\"k_principalultimasnoticias\"><p><img decoding=\"async\" class=\"k_imgultimasnoticias wp-image-16863 alignleft\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png\" alt=\"\" width=\"173\" height=\"50\" data-wp-editing=\"1\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-200x58.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-300x87.png 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-400x115.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-600x173.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png 693w\" sizes=\"(max-width: 173px) 100vw, 173px\" \/><div class=\"lcp_catlist\" id=\"lcp_instance_0\"><\/div><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-3{width:33.333333333333% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-3 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 5.76%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 5.76%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;margin-top : 25px;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-2{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<p>150.000 euros. Es la cantidad que el Ayuntamiento va a destinar de los Presupuestos 2026 para las familias de Ciempozuelos. Concretamente, se va a otorgar una ayuda a todas aquellas con menores de entre 6 y 15 a\u00f1os que realicen una actividad extraescolar en el municipio. \u201cLas actividades extraescolares son un complemento muy importante para la educaci\u00f3n de nuestros ni\u00f1os y de nuestras ni\u00f1as pero a la vez todas las familias sabemos que suponen un importante esfuerzo econ\u00f3mico cada mes\u201d, dice la alcaldesa, Raquel Jimeno.<\/p>\n","protected":false},"author":32,"featured_media":43119,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1436],"tags":[2281,1451,1442,1706,1744,1105,4317,2496,2207,1805,1446,4318,1445],"class_list":["post-43118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciempozuelosinforma","tag-alcaldesa","tag-ayudas","tag-ciempozuelos","tag-colegio","tag-colegios","tag-educacion-jorge-alonso-diaz","tag-extraescolares","tag-familias","tag-futbol","tag-ingles","tag-ninas","tag-nino","tag-ninos"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Comunicaci\u00f3n Ciempozuelos\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-02T12:26:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-02T12:26:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#blogposting\",\"name\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\",\"headline\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/piscina-de-verano.jpeg\",\"width\":1152,\"height\":2048},\"datePublished\":\"2026-07-02T14:26:32+02:00\",\"dateModified\":\"2026-07-02T14:26:33+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\"},\"articleSection\":\"Ciempozuelos Informa, alcaldesa, cimepozuelos, concejal, Deportes, empresa, gimnasio, justicia, morgado, piscina, Raquel Jimeno, vecinos, verano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"name\":\"Ciempozuelos Informa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"position\":2,\"name\":\"Ciempozuelos Informa\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/04\\\/17\\\/el-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos\\\/#listItem\",\"name\":\"El Ayuntamiento de Ciempozuelos ayudar\\u00e1 a las familias a pagar las extraescolares de las ni\\u00f1as y los ni\\u00f1os\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/04\\\/17\\\/el-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos\\\/#listItem\",\"position\":3,\"name\":\"El Ayuntamiento de Ciempozuelos ayudar\\u00e1 a las familias a pagar las extraescolares de las ni\\u00f1as y los ni\\u00f1os\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"name\":\"Ciempozuelos Informa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/\",\"name\":\"Comunicaci\\u00f3n Ciempozuelos\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9b31ac435c51f3c129db96365b19c4f642ee8a126c018d7b9a12fcee80bc5f1?s=96&d=https%3A%2F%2Fayto-ciempozuelos.org%2Fwp-content%2Fplugins%2Fwp-jobsearch%2Fimages%2Fno-image.jpg&r=g\",\"width\":96,\"height\":96,\"caption\":\"Comunicaci\\u00f3n Ciempozuelos\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/\",\"name\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\",\"description\":\"La piscina municipal de verano de Ciempozuelos abrir\\u00e1 ma\\u00f1ana al p\\u00fablico. Lo hace tras el secuestro de la concesi\\u00f3n de la instalaci\\u00f3n a la empresa Neo la que, por contrato, deber\\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/piscina-de-verano.jpeg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#mainImage\",\"width\":1152,\"height\":2048},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#mainImage\"},\"datePublished\":\"2026-07-02T14:26:32+02:00\",\"dateModified\":\"2026-07-02T14:26:33+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#blogposting","name":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","headline":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/07\/piscina-de-verano.jpeg","width":1152,"height":2048},"datePublished":"2026-07-02T14:26:32+02:00","dateModified":"2026-07-02T14:26:33+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage"},"articleSection":"Ciempozuelos Informa, alcaldesa, cimepozuelos, concejal, Deportes, empresa, gimnasio, justicia, morgado, piscina, Raquel Jimeno, vecinos, verano"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","name":"Ciempozuelos Informa"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","position":2,"name":"Ciempozuelos Informa","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/04\/17\/el-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos\/#listItem","name":"El Ayuntamiento de Ciempozuelos ayudar\u00e1 a las familias a pagar las extraescolares de las ni\u00f1as y los ni\u00f1os"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/04\/17\/el-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos\/#listItem","position":3,"name":"El Ayuntamiento de Ciempozuelos ayudar\u00e1 a las familias a pagar las extraescolares de las ni\u00f1as y los ni\u00f1os","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","name":"Ciempozuelos Informa"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/","name":"Comunicaci\u00f3n Ciempozuelos","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b9b31ac435c51f3c129db96365b19c4f642ee8a126c018d7b9a12fcee80bc5f1?s=96&d=https%3A%2F%2Fayto-ciempozuelos.org%2Fwp-content%2Fplugins%2Fwp-jobsearch%2Fimages%2Fno-image.jpg&r=g","width":96,"height":96,"caption":"Comunicaci\u00f3n Ciempozuelos"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","name":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/07\/piscina-de-verano.jpeg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#mainImage","width":1152,"height":2048},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#mainImage"},"datePublished":"2026-07-02T14:26:32+02:00","dateModified":"2026-07-02T14:26:33+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","og:description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","article:published_time":"2026-07-02T12:26:32+00:00","article:modified_time":"2026-07-02T12:26:33+00:00","twitter:card":"summary","twitter:title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","twitter:description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo."},"aioseo_meta_data":{"post_id":"43118","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-04-17 12:22:23","updated":"2026-04-17 12:57:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/\" title=\"Ciempozuelos Informa\">Ciempozuelos Informa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl Ayuntamiento de Ciempozuelos ayudar\u00e1 a las familias a pagar las extraescolares de las ni\u00f1as y los ni\u00f1os\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Ciempozuelos Informa","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/"},{"label":"El Ayuntamiento de Ciempozuelos ayudar\u00e1 a las familias a pagar las extraescolares de las ni\u00f1as y los ni\u00f1os","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/04\/17\/el-ayuntamiento-de-ciempozuelos-ayudara-a-las-familias-a-pagar-las-extraescolares-de-las-ninas-y-los-ninos\/"}],"modified_by":"Comunicaci\u00f3n Ciempozuelos","publishpress_future_action":{"enabled":false,"date":"2026-07-22 14:06:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/43118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=43118"}],"version-history":[{"count":1,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/43118\/revisions"}],"predecessor-version":[{"id":43120,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/43118\/revisions\/43120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/43119"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=43118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=43118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=43118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}