{"id":35342,"date":"2024-06-19T10:04:59","date_gmt":"2024-06-19T08:04:59","guid":{"rendered":"https:\/\/ayto-ciempozuelos.org\/?p=35342"},"modified":"2024-07-15T09:07:12","modified_gmt":"2024-07-15T07:07:12","slug":"abierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2024\/06\/19\/abierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024\/","title":{"rendered":"Abierto el plazo de solicitud para la autorizaci\u00f3n de puestos, bares y atracciones de feria en las fiestas patronales &#8220;Virgen del Consuelo 2024&#8221;"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div ><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1195\" height=\"288\" alt=\"Ciempozuelos Informa\" title=\"Ciempozuelos Informa\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa.jpg\" class=\"img-responsive wp-image-16209\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-200x48.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-400x96.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-600x145.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-800x193.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa.jpg 1195w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 1195px\" \/><\/span><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column k_hide\" id=\"k_principalultimasnoticias\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-end fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:#e8e8e8;border-width: 2px 2px 2px 2px;border-color:#f44336;border-style:solid;padding: 10px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\" id=\"k_principalultimasnoticias1\"><p><img decoding=\"async\" class=\"k_imgultimasnoticias wp-image-16863 alignleft\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png\" alt=\"\" width=\"173\" height=\"50\" data-wp-editing=\"1\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-200x58.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-300x87.png 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-400x115.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-600x173.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png 693w\" sizes=\"(max-width: 173px) 100vw, 173px\" \/><div class=\"lcp_catlist\" id=\"lcp_instance_0\"><\/div><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 10px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0 !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style>\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_3 2_3 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-2\"><p style=\"text-align: center;\"><img decoding=\"async\" width=\"2016\" height=\"1512\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2024\/06\/IMG-9502.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2024\/06\/IMG-9502-200x150.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2024\/06\/IMG-9502-300x225.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2024\/06\/IMG-9502-400x300.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2024\/06\/IMG-9502-600x450.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2024\/06\/IMG-9502-768x576.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2024\/06\/IMG-9502-800x600.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2024\/06\/IMG-9502-1024x768.jpg 1024w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2024\/06\/IMG-9502-1200x900.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2024\/06\/IMG-9502-1536x1152.jpg 1536w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2024\/06\/IMG-9502.jpg 2016w\" sizes=\"(max-width: 2016px) 100vw, 2016px\" \/><\/p>\n<\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-1{margin-top:0px!important;margin-bottom:30px!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-three ktitle_post\" style=\"margin-top:0px;margin-bottom:30px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-\" style=\"border-color:#e2e2e2;\"><\/div><\/div><h3 class=\"title-heading-left\" style=\"font-family:&quot;PT Sans&quot;;font-weight:700;margin:0;color:#000859;\">Abierto el plazo de solicitud para la autorizaci\u00f3n de puestos, bares y atracciones de feria en las fiestas patronales &#8220;Virgen del Consuelo 2024&#8221;<\/h3><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-\" style=\"border-color:#e2e2e2;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-3\"><div style=\"font-size: 13px; font-style: italic;\">19 de junio de 2024<\/div>\n<\/div><div class=\"fusion-text fusion-text-4\"><p>El plazo para presentar solicitudes es del 19 de junio \u2013 5 de julio de 2024 (ambos inclusive)<\/p>\n<p><div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/ayto-ciempozuelos.org\/index.php\/download\/bases-para-el-montaje-de-puestos-y-atracciones-de-feria-en-las-fiestas-patronales-2024\/'>Bases para el montaje de puestos y atracciones de feria en las fiestas patronales 2024<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 350.92 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/ayto-ciempozuelos.org\/index.php\/download\/bases-para-el-montaje-de-puestos-y-atracciones-de-feria-en-las-fiestas-patronales-2024\/?wpdmdl=35341&refresh=6a5796faedeef1784125178\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div>\n<div class='w3eden'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icono\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/ayto-ciempozuelos.org\/index.php\/download\/instancia-solicitud-puesto-de-feria-fiestas-patronales-2024\/'>Instancia solicitud puesto de feria fiestas patronales 2024<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1 archivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 215.77 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/ayto-ciempozuelos.org\/index.php\/download\/instancia-solicitud-puesto-de-feria-fiestas-patronales-2024\/?wpdmdl=35340&refresh=6a5796fb30ade1784125179\">Descargar<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><\/p>\n<\/div><div class=\"fusion-text fusion-text-5\"><p><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/ciempozuelos-informa\/\"><em><span style=\"font-size: 14px;\" data-fusion-font=\"true\">&gt;&gt; Regresar a Hemeroteca &#8211; Ciempozuelos Informa<\/span><\/em><\/a><\/p>\n<\/div><div class=\"share-box fusion-sharing-box\" style=\"background-color:#e8e8e8;\" data-title=\"Abierto el plazo de solicitud para la autorizaci\u00f3n de puestos, bares y atracciones de feria en las fiestas patronales &#8220;Virgen del Consuelo 2024&#8221;\" data-description=\"Your Content Goes Here \r\n \r\n\r\nEl plazo para presentar solicitudes es del 19 de junio \u2013 5 de julio de 2024 (ambos inclusive)\r\n\r\n \r\n\r\n \r\n\r\n&gt;&gt; Regresar a Hemeroteca - Ciempozuelos Informa  \r\n\r\n\u00daLTIMAS NOTICIAS\" data-link=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2024\/06\/19\/abierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024\/\"><h4 class=\"tagline\" style=\"color:#000859;\"> \u00a1Comparte esta noticia en tus redes sociales!<\/h4><div class=\"fusion-social-networks\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-facebook fusion-icon-facebook\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2024%2F06%2F19%2Fabierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024%2F&amp;t=Abierto%20el%20plazo%20de%20solicitud%20para%20la%20autorizaci%C3%B3n%20de%20puestos%2C%20bares%20y%20atracciones%20de%20feria%20en%20las%20fiestas%20patronales%20%26%238220%3BVirgen%20del%20Consuelo%202024%26%238221%3B\" target=\"_blank\" style=\"color:#3b5998;\" title=\"Facebook\" aria-label=\"Facebook\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Facebook\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-twitter fusion-icon-twitter\" href=\"https:\/\/twitter.com\/share?text=Abierto%20el%20plazo%20de%20solicitud%20para%20la%20autorizaci%C3%B3n%20de%20puestos%2C%20bares%20y%20atracciones%20de%20feria%20en%20las%20fiestas%20patronales%20%E2%80%9CVirgen%20del%20Consuelo%202024%E2%80%9D&amp;url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2024%2F06%2F19%2Fabierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024%2F\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#55acee;\" title=\"Twitter\" aria-label=\"Twitter\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Twitter\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin fusion-icon-linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2024%2F06%2F19%2Fabierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024%2F&amp;title=Abierto%20el%20plazo%20de%20solicitud%20para%20la%20autorizaci%C3%B3n%20de%20puestos%2C%20bares%20y%20atracciones%20de%20feria%20en%20las%20fiestas%20patronales%20%26%238220%3BVirgen%20del%20Consuelo%202024%26%238221%3B&amp;summary=Your%20Content%20Goes%20Here%20%0D%0A%20%20%0D%0A%0D%0AEl%20plazo%20para%20presentar%20solicitudes%20es%20del%2019%20de%20junio%20%E2%80%93%205%20de%20julio%20de%202024%20%28ambos%20inclusive%29%0D%0A%0D%0A%20%0D%0A%0D%0A%20%20%0D%0A%0D%0A%26gt%3B%26gt%3B%20Regresar%20a%20Hemeroteca%20-%20Ciempozuelos%20Informa%20%20%20%0D%0A%0D%0A%C3%9ALTIMAS%20NOTICIAS\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#0077b5;\" title=\"LinkedIn\" aria-label=\"LinkedIn\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"LinkedIn\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-whatsapp fusion-icon-whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2024%2F06%2F19%2Fabierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024%2F\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#77e878;\" title=\"WhatsApp\" aria-label=\"WhatsApp\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"WhatsApp\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-tumblr fusion-icon-tumblr\" href=\"http:\/\/www.tumblr.com\/share\/link?url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2024%2F06%2F19%2Fabierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024%2F&amp;name=Abierto%20el%20plazo%20de%20solicitud%20para%20la%20autorizaci%C3%B3n%20de%20puestos%2C%20bares%20y%20atracciones%20de%20feria%20en%20las%20fiestas%20patronales%20%26%238220%3BVirgen%20del%20Consuelo%202024%26%238221%3B&amp;description=Your%20Content%20Goes%20Here%20%0D%0A%20%20%0D%0A%0D%0AEl%20plazo%20para%20presentar%20solicitudes%20es%20del%2019%20de%20junio%20%E2%80%93%205%20de%20julio%20de%202024%20%28ambos%20inclusive%29%0D%0A%0D%0A%20%0D%0A%0D%0A%20%20%0D%0A%0D%0A%26gt%3B%26gt%3B%20Regresar%20a%20Hemeroteca%20-%20Ciempozuelos%20Informa%20%20%20%0D%0A%0D%0A%C3%9ALTIMAS%20NOTICIAS\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#35465c;\" title=\"Tumblr\" aria-label=\"Tumblr\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Tumblr\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail fusion-icon-mail\" href=\"mailto:?subject=Abierto%20el%20plazo%20de%20solicitud%20para%20la%20autorizaci%C3%B3n%20de%20puestos%2C%20bares%20y%20atracciones%20de%20feria%20en%20las%20fiestas%20patronales%20%26%238220%3BVirgen%20del%20Consuelo%202024%26%238221%3B&amp;body=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2024%2F06%2F19%2Fabierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024%2F\" target=\"_self\" style=\"color:#000000;\" title=\"Correo electr\u00f3nico\" aria-label=\"Correo electr\u00f3nico\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Correo electr\u00f3nico\"><\/a><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-2{width:66.666666666667% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-2 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 2.88%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 2.88%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_3 1_3 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-6\"><p><span style=\"color: #000859;\"><strong>\u00daLTIMAS NOTICIAS &#8211; CIEMPOZUELOS INFORMA<\/strong><\/span><\/p>\n<\/div><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-no fusion-blog-no-images fusion-blog-layout-left\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:8.5px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -8.5px !important; margin-right:-8.5px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-no fusion-blog-layout-grid fusion-blog-layout-grid-1 isotope\" data-pages=\"238\" data-grid-col-space=\"17\" style=\"margin: -8.5px -8.5px 0;min-height:500px;\"><article id=\"blog-1-post-43605\" class=\"fusion-post-grid post-43605 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-a4 tag-alcaldesa tag-ciempozuelos tag-guardia-civil tag-incendio tag-mercadona tag-policia tag-poligono tag-raquel-jimeno tag-seguridad tag-sendilla\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/07\/guardia-civil-detiene-al-presunto-autor-del-incendio-del-pasado-mes-de-junio-en-el-poligono-industrial-la-sendilla\/\">Guardia Civil detiene al presunto autor del incendio del pasado mes de junio en el pol\u00edgono industrial La Sendilla<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/\" title=\"Entradas de Comunicaci\u00f3n Ciempozuelos\" rel=\"author\">Comunicaci\u00f3n Ciempozuelos<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-07T13:28:36+02:00<\/span><span>julio 7th, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/07\/guardia-civil-detiene-al-presunto-autor-del-incendio-del-pasado-mes-de-junio-en-el-poligono-industrial-la-sendilla\/\" aria-label=\"More on Guardia Civil detiene al presunto autor del incendio del pasado mes de junio en el pol\u00edgono industrial La Sendilla\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-43588\" class=\"fusion-post-grid post-43588 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-cimepozuelos tag-empleo-ruben-iglesias-garcia tag-empresa tag-formacion-sin-categoria tag-vecinos tag-verano\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/06\/nuevas-incorporaciones-en-los-programas-de-empleo-formacion-2026\/\">Nuevas incorporaciones en los Programas de Empleo-Formaci\u00f3n 2026<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/sara-lazaro\/\" title=\"Entradas de Sara L\u00e1zaro\" rel=\"author\">Sara L\u00e1zaro<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-06T13:46:58+02:00<\/span><span>julio 6th, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/06\/nuevas-incorporaciones-en-los-programas-de-empleo-formacion-2026\/\" aria-label=\"More on Nuevas incorporaciones en los Programas de Empleo-Formaci\u00f3n 2026\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-43565\" class=\"fusion-post-grid post-43565 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-alcaldesa tag-cimepozuelos tag-concejal tag-deportes-jorge-alonso-diaz tag-empresa tag-gimnasio tag-justicia tag-morgado tag-piscina tag-raquel-jimeno tag-vecinos tag-verano\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\">El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/\" title=\"Entradas de Comunicaci\u00f3n Ciempozuelos\" rel=\"author\">Comunicaci\u00f3n Ciempozuelos<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-02T14:26:33+02:00<\/span><span>julio 2nd, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" aria-label=\"More on El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-7 k_hide\" id=\"k_principalultimasnoticias\"><p><img decoding=\"async\" class=\"k_imgultimasnoticias wp-image-16863 alignleft\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png\" alt=\"\" width=\"173\" height=\"50\" data-wp-editing=\"1\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-200x58.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-300x87.png 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-400x115.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-600x173.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png 693w\" sizes=\"(max-width: 173px) 100vw, 173px\" \/><div class=\"lcp_catlist\" id=\"lcp_instance_0\"><\/div><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-3{width:33.333333333333% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-3 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 5.76%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 5.76%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;margin-top : 25px;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-2{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":28,"featured_media":35343,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1436,1677],"tags":[],"class_list":["post-35342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciempozuelosinforma","category-festejos"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Comunicaci\u00f3n Ciempozuelos\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-02T12:26:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-02T12:26:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#blogposting\",\"name\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\",\"headline\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/piscina-de-verano.jpeg\",\"width\":1152,\"height\":2048},\"datePublished\":\"2026-07-02T14:26:32+02:00\",\"dateModified\":\"2026-07-02T14:26:33+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\"},\"articleSection\":\"Ciempozuelos Informa, alcaldesa, cimepozuelos, concejal, Deportes, empresa, gimnasio, justicia, morgado, piscina, Raquel Jimeno, vecinos, verano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"name\":\"Ciempozuelos Informa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"position\":2,\"name\":\"Ciempozuelos Informa\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2024\\\/06\\\/19\\\/abierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024\\\/#listItem\",\"name\":\"Abierto el plazo de solicitud para la autorizaci\\u00f3n de puestos, bares y atracciones de feria en las fiestas patronales &#8220;Virgen del Consuelo 2024&#8221;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2024\\\/06\\\/19\\\/abierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024\\\/#listItem\",\"position\":3,\"name\":\"Abierto el plazo de solicitud para la autorizaci\\u00f3n de puestos, bares y atracciones de feria en las fiestas patronales &#8220;Virgen del Consuelo 2024&#8221;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"name\":\"Ciempozuelos Informa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/\",\"name\":\"Comunicaci\\u00f3n Ciempozuelos\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9b31ac435c51f3c129db96365b19c4f642ee8a126c018d7b9a12fcee80bc5f1?s=96&d=https%3A%2F%2Fayto-ciempozuelos.org%2Fwp-content%2Fplugins%2Fwp-jobsearch%2Fimages%2Fno-image.jpg&r=g\",\"width\":96,\"height\":96,\"caption\":\"Comunicaci\\u00f3n Ciempozuelos\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/\",\"name\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\",\"description\":\"La piscina municipal de verano de Ciempozuelos abrir\\u00e1 ma\\u00f1ana al p\\u00fablico. Lo hace tras el secuestro de la concesi\\u00f3n de la instalaci\\u00f3n a la empresa Neo la que, por contrato, deber\\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/piscina-de-verano.jpeg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#mainImage\",\"width\":1152,\"height\":2048},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#mainImage\"},\"datePublished\":\"2026-07-02T14:26:32+02:00\",\"dateModified\":\"2026-07-02T14:26:33+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#blogposting","name":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","headline":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/07\/piscina-de-verano.jpeg","width":1152,"height":2048},"datePublished":"2026-07-02T14:26:32+02:00","dateModified":"2026-07-02T14:26:33+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage"},"articleSection":"Ciempozuelos Informa, alcaldesa, cimepozuelos, concejal, Deportes, empresa, gimnasio, justicia, morgado, piscina, Raquel Jimeno, vecinos, verano"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","name":"Ciempozuelos Informa"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","position":2,"name":"Ciempozuelos Informa","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2024\/06\/19\/abierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024\/#listItem","name":"Abierto el plazo de solicitud para la autorizaci\u00f3n de puestos, bares y atracciones de feria en las fiestas patronales &#8220;Virgen del Consuelo 2024&#8221;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2024\/06\/19\/abierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024\/#listItem","position":3,"name":"Abierto el plazo de solicitud para la autorizaci\u00f3n de puestos, bares y atracciones de feria en las fiestas patronales &#8220;Virgen del Consuelo 2024&#8221;","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","name":"Ciempozuelos Informa"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/","name":"Comunicaci\u00f3n Ciempozuelos","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b9b31ac435c51f3c129db96365b19c4f642ee8a126c018d7b9a12fcee80bc5f1?s=96&d=https%3A%2F%2Fayto-ciempozuelos.org%2Fwp-content%2Fplugins%2Fwp-jobsearch%2Fimages%2Fno-image.jpg&r=g","width":96,"height":96,"caption":"Comunicaci\u00f3n Ciempozuelos"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","name":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/07\/piscina-de-verano.jpeg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#mainImage","width":1152,"height":2048},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#mainImage"},"datePublished":"2026-07-02T14:26:32+02:00","dateModified":"2026-07-02T14:26:33+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","og:description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","article:published_time":"2026-07-02T12:26:32+00:00","article:modified_time":"2026-07-02T12:26:33+00:00","twitter:card":"summary","twitter:title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","twitter:description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo."},"aioseo_meta_data":{"post_id":"35342","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2024-06-19 08:04:42","updated":"2025-06-04 23:48:00","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/\" title=\"Ciempozuelos Informa\">Ciempozuelos Informa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAbierto el plazo de solicitud para la autorizaci\u00f3n de puestos, bares y atracciones de feria en las fiestas patronales \u201cVirgen del Consuelo 2024\u201d\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Ciempozuelos Informa","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/"},{"label":"Abierto el plazo de solicitud para la autorizaci\u00f3n de puestos, bares y atracciones de feria en las fiestas patronales &#8220;Virgen del Consuelo 2024&#8221;","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2024\/06\/19\/abierto-el-plazo-de-solicitud-para-la-autorizacion-de-puestos-bares-y-atracciones-de-feria-en-las-fiestas-patronales-virgen-del-consuelo-2024\/"}],"modified_by":"Comunicacion1 Ayto. Ciempozuelos","publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:19:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/35342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=35342"}],"version-history":[{"count":3,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/35342\/revisions"}],"predecessor-version":[{"id":35405,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/35342\/revisions\/35405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/35343"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=35342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=35342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=35342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}