{"id":33290,"date":"2023-12-14T14:55:16","date_gmt":"2023-12-14T13:55:16","guid":{"rendered":"https:\/\/ayto-ciempozuelos.org\/?p=33290"},"modified":"2023-12-14T15:14:10","modified_gmt":"2023-12-14T14:14:10","slug":"la-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2023\/12\/14\/la-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion\/","title":{"rendered":"La Fuente de Ventura Rodr\u00edguez recupera su esplendor tras un gran trabajo de restauraci\u00f3n"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div ><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1195\" height=\"288\" alt=\"Ciempozuelos Informa\" title=\"Ciempozuelos Informa\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa.jpg\" class=\"img-responsive wp-image-16209\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-200x48.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-400x96.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-600x145.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-800x193.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa.jpg 1195w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 1195px\" \/><\/span><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column k_hide\" id=\"k_principalultimasnoticias\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-end fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:#e8e8e8;border-width: 2px 2px 2px 2px;border-color:#f44336;border-style:solid;padding: 10px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\" id=\"k_principalultimasnoticias1\"><p><img decoding=\"async\" class=\"k_imgultimasnoticias wp-image-16863 alignleft\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png\" alt=\"\" width=\"173\" height=\"50\" data-wp-editing=\"1\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-200x58.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-300x87.png 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-400x115.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-600x173.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png 693w\" sizes=\"(max-width: 173px) 100vw, 173px\" \/><div class=\"lcp_catlist\" id=\"lcp_instance_0\"><\/div><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 10px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0 !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style>\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_3 2_3 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-2\"><p style=\"text-align: center;\"><img decoding=\"async\" width=\"2400\" height=\"1600\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-200x133.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-300x200.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-400x267.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-600x400.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-768x512.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-800x533.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-1024x683.jpg 1024w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-1200x800.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3.jpg 2400w\" sizes=\"(max-width: 2400px) 100vw, 2400px\" \/><\/p>\n<\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-1{margin-top:0px!important;margin-bottom:30px!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-three ktitle_post\" style=\"margin-top:0px;margin-bottom:30px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-\" style=\"border-color:#e2e2e2;\"><\/div><\/div><h3 class=\"title-heading-left\" style=\"font-family:&quot;PT Sans&quot;;font-weight:700;margin:0;color:#000859;\">La Fuente de Ventura Rodr\u00edguez recupera su esplendor tras un gran trabajo de restauraci\u00f3n<\/h3><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-\" style=\"border-color:#e2e2e2;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-3\"><div style=\"font-size: 13px; font-style: italic;\">14 de diciembre de 2023<\/div>\n<\/div><div class=\"fusion-text fusion-text-4\"><p>La alcaldesa, Raquel Jimeno, acompa\u00f1ada por Pedro Pablo Caballero, arquitecto del \u00c1rea de protecci\u00f3n del patrimonio hist\u00f3rico en la Direcci\u00f3n General de Patrimonio Cultural de la Comunidad de Madrid, y Oscar Caselles, arquitecto encargado del proyecto, ha reabierto esta ma\u00f1ana la Fuente de Ventura Rodr\u00edguez tras una restauraci\u00f3n que comenz\u00f3 el pasado mes de octubre. Las actuaciones, que han ascendido a algo m\u00e1s de 48.000\u20ac, han contemplado la limpieza profunda de la piedra, adem\u00e1s de su reconstrucci\u00f3n en algunas zonas, se ha impermeabilizado el vaso y se ha restaurado todo el sistema hidr\u00e1ulico y el sistema el\u00e9ctrico.<\/p>\n<p>Esta emblem\u00e1tica fuente ornamental, construida entre 1897 y 1898 gracias al proyecto de Luis Mar\u00eda Argenti y Herrera y la escultura de Jaime Lluc, fue hasta la d\u00e9cada de 1970 el principal suministro de agua de l@s vecin@s de Ciempozuelos y se encontraba muy deteriorada. \u201cRecuperar el esplendor de la fuente de Ventura Rodr\u00edguez es rescatar una parte de la historia de nuestro municipio. Muchas de nuestras vecinas y vecinos recuerdan c\u00f3mo ven\u00edan a recoger agua a esta fuente y, desde hace tiempo, ven\u00edan pidiendo su restauraci\u00f3n. Estamos muy satisfechos del trabajo que se ha realizado y del resultado\u201d, ha destacado la alcaldesa.<\/p>\n<p>Las obras de restauraci\u00f3n se han llevado a cabo con cargo al Plan de Jardines y Fuentes Hist\u00f3ricas de la Comunidad de Madrid, a trav\u00e9s de la Direcci\u00f3n General de Patrimonio Cultural, Consejer\u00eda de Cultura, Turismo y Deporte de la Comunidad de Madrid, gestionadas desde la concejal\u00eda de Urbanismo, Edificios p\u00fablicos y Monumentos.<\/p>\n<\/div><div class=\"fusion-image-carousel fusion-image-carousel-fixed lightbox-enabled fusion-carousel-border\"><div class=\"fusion-carousel\" data-autoplay=\"no\" data-columns=\"3\" data-itemmargin=\"13\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-imagesize=\"fixed\"><div class=\"fusion-carousel-positioner\"><ul class=\"fusion-carousel-holder\"><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Fuente Ventura9\" aria-label=\"Fuente Ventura9\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura9.jpg\" target=\"_self\"><img decoding=\"async\" width=\"393\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura9.jpg\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura9-200x150.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura9-400x300.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura9-600x450.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura9-800x600.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura9-1200x900.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura9.jpg 1613w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Fuente Ventura8\" aria-label=\"Fuente Ventura8\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura8.jpg\" target=\"_self\"><img decoding=\"async\" width=\"393\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura8.jpg\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura8-200x150.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura8-400x300.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura8-600x450.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura8-800x600.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura8-1200x900.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura8.jpg 1613w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Fuente Ventura7\" aria-label=\"Fuente Ventura7\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura7.jpg\" target=\"_self\"><img decoding=\"async\" width=\"393\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura7.jpg\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura7-200x150.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura7-400x300.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura7-600x450.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura7-800x600.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura7-1200x900.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura7.jpg 1613w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Fuente Ventura6\" aria-label=\"Fuente Ventura6\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura6.jpg\" target=\"_self\"><img decoding=\"async\" width=\"221\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura6.jpg\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura6-200x267.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura6-400x533.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura6-600x800.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura6-800x1066.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura6-1200x1600.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura6.jpg 1210w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Fuente Ventura5\" aria-label=\"Fuente Ventura5\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura5.jpg\" target=\"_self\"><img decoding=\"async\" width=\"442\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura5.jpg\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura5-200x133.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura5-400x267.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura5-600x400.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura5-800x534.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura5-1200x800.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura5.jpg 2066w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Fuente Ventura4\" aria-label=\"Fuente Ventura4\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura4.jpg\" target=\"_self\"><img decoding=\"async\" width=\"197\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura4.jpg\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura4-200x300.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura4-400x600.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura4-600x900.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura4-800x1200.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura4-1200x1800.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura4.jpg 1600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Fuente Ventura3\" aria-label=\"Fuente Ventura3\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3.jpg\" target=\"_self\"><img decoding=\"async\" width=\"443\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3.jpg\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-200x133.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-400x267.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-600x400.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-800x533.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3-1200x800.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura3.jpg 2400w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Fuente Ventura2\" aria-label=\"Fuente Ventura2\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura2.jpg\" target=\"_self\"><img decoding=\"async\" width=\"443\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura2.jpg\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura2-200x133.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura2-400x267.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura2-600x400.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura2-800x533.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura2-1200x800.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura2.jpg 2400w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Fuente Ventura\" aria-label=\"Fuente Ventura\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura.jpg\" target=\"_self\"><img decoding=\"async\" width=\"443\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura.jpg\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura-200x133.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura-400x267.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura-600x400.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura-800x533.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura-1200x800.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/12\/Fuente-Ventura.jpg 2400w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><\/ul><div class=\"fusion-carousel-nav\"><span class=\"fusion-nav-prev\"><\/span><span class=\"fusion-nav-next\"><\/span><\/div><\/div><\/div><\/div><div class=\"fusion-text fusion-text-5\"><p><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/ciempozuelos-informa\/\"><em><span style=\"font-size: 14px;\" data-fusion-font=\"true\">&gt;&gt; Regresar a Hemeroteca &#8211; Ciempozuelos Informa<\/span><\/em><\/a><\/p>\n<\/div><div class=\"share-box fusion-sharing-box\" style=\"background-color:#e8e8e8;\" data-title=\"La Fuente de Ventura Rodr\u00edguez recupera su esplendor tras un gran trabajo de restauraci\u00f3n\" data-description=\"Your Content Goes Here \r\n \r\n\r\nLa alcaldesa, Raquel Jimeno, acompa\u00f1ada por Pedro Pablo Caballero, arquitecto del \u00c1rea de protecci\u00f3n del patrimonio hist\u00f3rico en la Direcci\u00f3n General de Patrimonio Cultural de la Comunidad de Madrid, y Oscar Caselles, arquitecto encargado del proyecto, ha\" data-link=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2023\/12\/14\/la-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion\/\"><h4 class=\"tagline\" style=\"color:#000859;\"> \u00a1Comparte esta noticia en tus redes sociales!<\/h4><div class=\"fusion-social-networks\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-facebook fusion-icon-facebook\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F12%2F14%2Fla-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion%2F&amp;t=La%20Fuente%20de%20Ventura%20Rodr%C3%ADguez%20recupera%20su%20esplendor%20tras%20un%20gran%20trabajo%20de%20restauraci%C3%B3n\" target=\"_blank\" style=\"color:#3b5998;\" title=\"Facebook\" aria-label=\"Facebook\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Facebook\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-twitter fusion-icon-twitter\" href=\"https:\/\/twitter.com\/share?text=La%20Fuente%20de%20Ventura%20Rodr%C3%ADguez%20recupera%20su%20esplendor%20tras%20un%20gran%20trabajo%20de%20restauraci%C3%B3n&amp;url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F12%2F14%2Fla-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion%2F\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#55acee;\" title=\"Twitter\" aria-label=\"Twitter\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Twitter\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin fusion-icon-linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F12%2F14%2Fla-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion%2F&amp;title=La%20Fuente%20de%20Ventura%20Rodr%C3%ADguez%20recupera%20su%20esplendor%20tras%20un%20gran%20trabajo%20de%20restauraci%C3%B3n&amp;summary=Your%20Content%20Goes%20Here%20%0D%0A%20%20%0D%0A%0D%0ALa%20alcaldesa%2C%20Raquel%20Jimeno%2C%20acompa%C3%B1ada%20por%20Pedro%20Pablo%20Caballero%2C%20arquitecto%20del%20%C3%81rea%20de%20protecci%C3%B3n%20del%20patrimonio%20hist%C3%B3rico%20en%20la%20Direcci%C3%B3n%20General%20de%20Patrimonio%20Cultural%20de%20la%20Comunidad%20de%20Madrid%2C%20y%20Oscar%20Caselles%2C%20arquitecto%20encargado%20del%20proyecto%2C%20ha\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#0077b5;\" title=\"LinkedIn\" aria-label=\"LinkedIn\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"LinkedIn\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-whatsapp fusion-icon-whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F12%2F14%2Fla-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion%2F\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#77e878;\" title=\"WhatsApp\" aria-label=\"WhatsApp\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"WhatsApp\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-tumblr fusion-icon-tumblr\" href=\"http:\/\/www.tumblr.com\/share\/link?url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F12%2F14%2Fla-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion%2F&amp;name=La%20Fuente%20de%20Ventura%20Rodr%C3%ADguez%20recupera%20su%20esplendor%20tras%20un%20gran%20trabajo%20de%20restauraci%C3%B3n&amp;description=Your%20Content%20Goes%20Here%20%0D%0A%20%20%0D%0A%0D%0ALa%20alcaldesa%2C%20Raquel%20Jimeno%2C%20acompa%C3%B1ada%20por%20Pedro%20Pablo%20Caballero%2C%20arquitecto%20del%20%C3%81rea%20de%20protecci%C3%B3n%20del%20patrimonio%20hist%C3%B3rico%20en%20la%20Direcci%C3%B3n%20General%20de%20Patrimonio%20Cultural%20de%20la%20Comunidad%20de%20Madrid%2C%20y%20Oscar%20Caselles%2C%20arquitecto%20encargado%20del%20proyecto%2C%20ha\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#35465c;\" title=\"Tumblr\" aria-label=\"Tumblr\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Tumblr\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail fusion-icon-mail\" href=\"mailto:?subject=La%20Fuente%20de%20Ventura%20Rodr%C3%ADguez%20recupera%20su%20esplendor%20tras%20un%20gran%20trabajo%20de%20restauraci%C3%B3n&amp;body=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F12%2F14%2Fla-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion%2F\" target=\"_self\" style=\"color:#000000;\" title=\"Correo electr\u00f3nico\" aria-label=\"Correo electr\u00f3nico\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Correo electr\u00f3nico\"><\/a><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-2{width:66.666666666667% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-2 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 2.88%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 2.88%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_3 1_3 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-6\"><p><span style=\"color: #000859;\"><strong>\u00daLTIMAS NOTICIAS &#8211; CIEMPOZUELOS INFORMA<\/strong><\/span><\/p>\n<\/div><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-no fusion-blog-no-images fusion-blog-layout-left\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:8.5px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -8.5px !important; margin-right:-8.5px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-no fusion-blog-layout-grid fusion-blog-layout-grid-1 isotope\" data-pages=\"238\" data-grid-col-space=\"17\" style=\"margin: -8.5px -8.5px 0;min-height:500px;\"><article id=\"blog-1-post-43605\" class=\"fusion-post-grid post-43605 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-a4 tag-alcaldesa tag-ciempozuelos tag-guardia-civil tag-incendio tag-mercadona tag-policia tag-poligono tag-raquel-jimeno tag-seguridad tag-sendilla\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/07\/guardia-civil-detiene-al-presunto-autor-del-incendio-del-pasado-mes-de-junio-en-el-poligono-industrial-la-sendilla\/\">Guardia Civil detiene al presunto autor del incendio del pasado mes de junio en el pol\u00edgono industrial La Sendilla<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/\" title=\"Entradas de Comunicaci\u00f3n Ciempozuelos\" rel=\"author\">Comunicaci\u00f3n Ciempozuelos<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-07T13:28:36+02:00<\/span><span>julio 7th, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/07\/guardia-civil-detiene-al-presunto-autor-del-incendio-del-pasado-mes-de-junio-en-el-poligono-industrial-la-sendilla\/\" aria-label=\"More on Guardia Civil detiene al presunto autor del incendio del pasado mes de junio en el pol\u00edgono industrial La Sendilla\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-43588\" class=\"fusion-post-grid post-43588 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-cimepozuelos tag-empleo-ruben-iglesias-garcia tag-empresa tag-formacion-sin-categoria tag-vecinos tag-verano\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/06\/nuevas-incorporaciones-en-los-programas-de-empleo-formacion-2026\/\">Nuevas incorporaciones en los Programas de Empleo-Formaci\u00f3n 2026<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/sara-lazaro\/\" title=\"Entradas de Sara L\u00e1zaro\" rel=\"author\">Sara L\u00e1zaro<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-06T13:46:58+02:00<\/span><span>julio 6th, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/06\/nuevas-incorporaciones-en-los-programas-de-empleo-formacion-2026\/\" aria-label=\"More on Nuevas incorporaciones en los Programas de Empleo-Formaci\u00f3n 2026\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-43565\" class=\"fusion-post-grid post-43565 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-alcaldesa tag-cimepozuelos tag-concejal tag-deportes-jorge-alonso-diaz tag-empresa tag-gimnasio tag-justicia tag-morgado tag-piscina tag-raquel-jimeno tag-vecinos tag-verano\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\">El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/\" title=\"Entradas de Comunicaci\u00f3n Ciempozuelos\" rel=\"author\">Comunicaci\u00f3n Ciempozuelos<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-02T14:26:33+02:00<\/span><span>julio 2nd, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" aria-label=\"More on El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-7 k_hide\" id=\"k_principalultimasnoticias\"><p><img decoding=\"async\" class=\"k_imgultimasnoticias wp-image-16863 alignleft\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png\" alt=\"\" width=\"173\" height=\"50\" data-wp-editing=\"1\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-200x58.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-300x87.png 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-400x115.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-600x173.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png 693w\" sizes=\"(max-width: 173px) 100vw, 173px\" \/><div class=\"lcp_catlist\" id=\"lcp_instance_0\"><\/div><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-3{width:33.333333333333% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-3 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 5.76%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 5.76%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;margin-top : 25px;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-2{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La alcaldesa, Raquel Jimeno, acompa\u00f1ada por Pedro Pablo Caballero, arquitecto del \u00c1rea de protecci\u00f3n del patrimonio hist\u00f3rico en la Direcci\u00f3n General de Patrimonio Cultural de la Comunidad de Madrid, y Oscar Caselles, arquitecto encargado del proyecto, ha reabierto esta ma\u00f1ana la Fuente de Ventura Rodr\u00edguez tras una restauraci\u00f3n que comenz\u00f3 el pasado mes de octubre. Las actuaciones, que han ascendido a algo m\u00e1s de 48.000\u20ac, han contemplado la limpieza profunda de la piedra, adem\u00e1s de su reconstrucci\u00f3n en algunas zonas, se ha impermeabilizado el vaso y se ha restaurado todo el sistema hidr\u00e1ulico y el sistema el\u00e9ctrico.<\/p>\n","protected":false},"author":4,"featured_media":33297,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1436,1493],"tags":[3584,1722,3583],"class_list":["post-33290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciempozuelosinforma","category-urbanismo","tag-fuente","tag-restauracion","tag-ventura-rodriguez"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Comunicaci\u00f3n Ciempozuelos\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-02T12:26:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-02T12:26:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#blogposting\",\"name\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\",\"headline\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/piscina-de-verano.jpeg\",\"width\":1152,\"height\":2048},\"datePublished\":\"2026-07-02T14:26:32+02:00\",\"dateModified\":\"2026-07-02T14:26:33+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\"},\"articleSection\":\"Ciempozuelos Informa, alcaldesa, cimepozuelos, concejal, Deportes, empresa, gimnasio, justicia, morgado, piscina, Raquel Jimeno, vecinos, verano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"name\":\"Ciempozuelos Informa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"position\":2,\"name\":\"Ciempozuelos Informa\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2023\\\/12\\\/14\\\/la-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion\\\/#listItem\",\"name\":\"La Fuente de Ventura Rodr\\u00edguez recupera su esplendor tras un gran trabajo de restauraci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2023\\\/12\\\/14\\\/la-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion\\\/#listItem\",\"position\":3,\"name\":\"La Fuente de Ventura Rodr\\u00edguez recupera su esplendor tras un gran trabajo de restauraci\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"name\":\"Ciempozuelos Informa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/\",\"name\":\"Comunicaci\\u00f3n Ciempozuelos\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9b31ac435c51f3c129db96365b19c4f642ee8a126c018d7b9a12fcee80bc5f1?s=96&d=https%3A%2F%2Fayto-ciempozuelos.org%2Fwp-content%2Fplugins%2Fwp-jobsearch%2Fimages%2Fno-image.jpg&r=g\",\"width\":96,\"height\":96,\"caption\":\"Comunicaci\\u00f3n Ciempozuelos\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/\",\"name\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\",\"description\":\"La piscina municipal de verano de Ciempozuelos abrir\\u00e1 ma\\u00f1ana al p\\u00fablico. Lo hace tras el secuestro de la concesi\\u00f3n de la instalaci\\u00f3n a la empresa Neo la que, por contrato, deber\\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/piscina-de-verano.jpeg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#mainImage\",\"width\":1152,\"height\":2048},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#mainImage\"},\"datePublished\":\"2026-07-02T14:26:32+02:00\",\"dateModified\":\"2026-07-02T14:26:33+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#blogposting","name":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","headline":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/07\/piscina-de-verano.jpeg","width":1152,"height":2048},"datePublished":"2026-07-02T14:26:32+02:00","dateModified":"2026-07-02T14:26:33+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage"},"articleSection":"Ciempozuelos Informa, alcaldesa, cimepozuelos, concejal, Deportes, empresa, gimnasio, justicia, morgado, piscina, Raquel Jimeno, vecinos, verano"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","name":"Ciempozuelos Informa"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","position":2,"name":"Ciempozuelos Informa","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2023\/12\/14\/la-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion\/#listItem","name":"La Fuente de Ventura Rodr\u00edguez recupera su esplendor tras un gran trabajo de restauraci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2023\/12\/14\/la-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion\/#listItem","position":3,"name":"La Fuente de Ventura Rodr\u00edguez recupera su esplendor tras un gran trabajo de restauraci\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","name":"Ciempozuelos Informa"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/","name":"Comunicaci\u00f3n Ciempozuelos","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b9b31ac435c51f3c129db96365b19c4f642ee8a126c018d7b9a12fcee80bc5f1?s=96&d=https%3A%2F%2Fayto-ciempozuelos.org%2Fwp-content%2Fplugins%2Fwp-jobsearch%2Fimages%2Fno-image.jpg&r=g","width":96,"height":96,"caption":"Comunicaci\u00f3n Ciempozuelos"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","name":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/07\/piscina-de-verano.jpeg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#mainImage","width":1152,"height":2048},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#mainImage"},"datePublished":"2026-07-02T14:26:32+02:00","dateModified":"2026-07-02T14:26:33+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","og:description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","article:published_time":"2026-07-02T12:26:32+00:00","article:modified_time":"2026-07-02T12:26:33+00:00","twitter:card":"summary","twitter:title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","twitter:description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo."},"aioseo_meta_data":{"post_id":"33290","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2023-12-14 13:34:51","updated":"2025-06-04 23:37:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/\" title=\"Ciempozuelos Informa\">Ciempozuelos Informa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Fuente de Ventura Rodr\u00edguez recupera su esplendor tras un gran trabajo de restauraci\u00f3n\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Ciempozuelos Informa","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/"},{"label":"La Fuente de Ventura Rodr\u00edguez recupera su esplendor tras un gran trabajo de restauraci\u00f3n","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2023\/12\/14\/la-fuente-de-ventura-rodriguez-recupera-su-esplendor-tras-un-gran-trabajo-de-restauracion\/"}],"modified_by":"Comunicacion1 Ayto. Ciempozuelos","publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:07:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/33290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=33290"}],"version-history":[{"count":2,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/33290\/revisions"}],"predecessor-version":[{"id":33301,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/33290\/revisions\/33301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/33297"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=33290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=33290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=33290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}