{"id":32215,"date":"2023-10-09T14:48:34","date_gmt":"2023-10-09T12:48:34","guid":{"rendered":"https:\/\/ayto-ciempozuelos.org\/?p=32215"},"modified":"2023-10-24T10:17:03","modified_gmt":"2023-10-24T08:17:03","slug":"la-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2023\/10\/09\/la-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula\/","title":{"rendered":"La Biblioteca Municipal Almudena Grandes invita a l@s vecin@s a pasar unas tardes de oto\u00f1o de pel\u00edcula"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div ><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1195\" height=\"288\" alt=\"Ciempozuelos Informa\" title=\"Ciempozuelos Informa\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa.jpg\" class=\"img-responsive wp-image-16209\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-200x48.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-400x96.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-600x145.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa-800x193.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/cabecera_informa.jpg 1195w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 1195px\" \/><\/span><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;order : 0;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column k_hide\" id=\"k_principalultimasnoticias\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-end fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:#e8e8e8;border-width: 2px 2px 2px 2px;border-color:#f44336;border-style:solid;padding: 10px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-1\" id=\"k_principalultimasnoticias1\"><p><img decoding=\"async\" class=\"k_imgultimasnoticias wp-image-16863 alignleft\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png\" alt=\"\" width=\"173\" height=\"50\" data-wp-editing=\"1\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-200x58.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-300x87.png 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-400x115.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-600x173.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png 693w\" sizes=\"(max-width: 173px) 100vw, 173px\" \/><div class=\"lcp_catlist\" id=\"lcp_instance_0\"><\/div><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-1{width:100% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-1 > .fusion-column-wrapper {padding-top : 10px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0 !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-1{width:100% !important;order : 0;}.fusion-builder-column-1 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style>\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_3 2_3 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-2\"><p style=\"text-align: center;\"><img decoding=\"async\" width=\"1800\" height=\"1013\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/jurassic-world-dominion-universal-pictures.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/jurassic-world-dominion-universal-pictures-200x113.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/jurassic-world-dominion-universal-pictures-300x169.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/jurassic-world-dominion-universal-pictures-400x225.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/jurassic-world-dominion-universal-pictures-600x338.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/jurassic-world-dominion-universal-pictures-768x432.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/jurassic-world-dominion-universal-pictures-800x450.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/jurassic-world-dominion-universal-pictures-1024x576.jpg 1024w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/jurassic-world-dominion-universal-pictures-1200x675.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/jurassic-world-dominion-universal-pictures.jpg 1800w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/><\/p>\n<\/div><style type=\"text\/css\">@media only screen and (max-width:1024px) {.fusion-title.fusion-title-1{margin-top:0px!important;margin-bottom:30px!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-three ktitle_post\" style=\"margin-top:0px;margin-bottom:30px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep-\" style=\"border-color:#e2e2e2;\"><\/div><\/div><h3 class=\"title-heading-left\" style=\"font-family:&quot;PT Sans&quot;;font-weight:700;margin:0;color:#000859;\">La Biblioteca Municipal Almudena Grandes invita a l@s vecin@s a pasar unas tardes de oto\u00f1o de pel\u00edcula<\/h3><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep-\" style=\"border-color:#e2e2e2;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-3\"><div style=\"font-size: 13px; font-style: italic;\">9 de octubre de 2023<\/div>\n<\/div><div class=\"fusion-text fusion-text-4\"><p>El Sal\u00f3n de Actos de la Biblioteca Municipal Almudena Grandes acoger\u00e1, entre los meses de octubre y enero, seis ciclos de cine tem\u00e1ticos que pretenden atraer al p\u00fablico de todas las edades. La acci\u00f3n y lo fant\u00e1stico son el nexo de uni\u00f3n de la mayor\u00eda de pel\u00edculas elegidas, aunque tambi\u00e9n hay lugar para el terror extremo, con un ciclo dedicado a Halloween, sin olvidar al p\u00fablico infantil y familiar.<\/p>\n<p>El Ciclo Jurassic Word abrir\u00e1 la programaci\u00f3n con la trilog\u00eda de Chris Pratt y Bryce Dallas Howard (18, 19 y 20 de octubre), a este le seguir\u00e1 el Ciclo de Halloween (del 25 al 31 de octubre) que proyectar\u00e1 t\u00edtulos familiares como \u2018Scooby Doo. Truco o trato\u2019 o \u2018La familia Adams 2\u2019 con otros recomendados para p\u00fablico adulto, como \u2018La noche de Halloween\u2019 o \u2018It\u2019, entre otras. Dos ciclos de cine acoger\u00e1n el universo de J. K. Rolling justo antes de Navidad, fechas que se celebrar\u00e1n con un ciclo de tem\u00e1tica familiar. Finalmente, el \u00faltimo ciclo estar\u00e1 destinado a J.R.R. Tolkien y su trilog\u00eda de \u2018El se\u00f1or de los Anillos\u2019 (29 de diciembre y 2 y 3 de enero), para que todos los fans puedan volver a disfrutar de este cl\u00e1sico.<\/p>\n<p>En palabras de Javier Morgado, concejal de Artes y difusi\u00f3n de la cultura, \u201ccon estos ciclos de cine pretendemos acercar a los vecinos y vecinas t\u00edtulos ya cl\u00e1sicos, cuyos seguidores est\u00e1n encantados de volver a ver, con otros m\u00e1s recientes y de gran calidad. No podemos olvidar que en compa\u00f1\u00eda el cine se disfruta mejor, ya que tras la sesi\u00f3n a todos nos gusta valorar y comentar los mejores momentos\u201d.<\/p>\n<p>Cada ciclo de cine ir\u00e1 acompa\u00f1ado de una exposici\u00f3n bibliogr\u00e1fica en la que se incluir\u00e1 una selecci\u00f3n de libros y DVDs relacionados con cada tem\u00e1tica para que los usuarios de la Biblioteca Municipal Almudena Grandes puedan llev\u00e1rselos en pr\u00e9stamo.<\/p>\n<\/div><div class=\"fusion-image-carousel fusion-image-carousel-fixed lightbox-enabled fusion-carousel-border\"><div class=\"fusion-carousel\" data-autoplay=\"no\" data-columns=\"3\" data-itemmargin=\"13\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-imagesize=\"fixed\"><div class=\"fusion-carousel-positioner\"><ul class=\"fusion-carousel-holder\"><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Ciclos de cine\" aria-label=\"Ciclos de cine\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclos-de-cine.png\" target=\"_self\"><img decoding=\"async\" width=\"209\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclos-de-cine.png\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclos-de-cine-200x283.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclos-de-cine-400x566.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclos-de-cine-600x849.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclos-de-cine-800x1132.png 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclos-de-cine-1200x1697.png 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclos-de-cine.png 1414w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Ciclo de cine jurassic word\" aria-label=\"Ciclo de cine jurassic word\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-jurassic-word-1.png\" target=\"_self\"><img decoding=\"async\" width=\"209\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-jurassic-word-1.png\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-jurassic-word-1-200x283.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-jurassic-word-1-400x566.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-jurassic-word-1-600x849.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-jurassic-word-1-800x1132.png 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-jurassic-word-1-1200x1697.png 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-jurassic-word-1.png 1414w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"ciclos de cine halloween\" aria-label=\"ciclos de cine halloween\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/ciclos-de-cine-1.png\" target=\"_self\"><img decoding=\"async\" width=\"209\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/ciclos-de-cine-1.png\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/ciclos-de-cine-1-200x283.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/ciclos-de-cine-1-400x566.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/ciclos-de-cine-1-600x849.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/ciclos-de-cine-1-800x1132.png 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/ciclos-de-cine-1-1200x1697.png 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/ciclos-de-cine-1.png 1414w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Ciclo de cine harry potter\" aria-label=\"Ciclo de cine harry potter\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-harry-potter.png\" target=\"_self\"><img decoding=\"async\" width=\"209\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-harry-potter.png\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-harry-potter-200x283.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-harry-potter-400x566.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-harry-potter-600x849.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-harry-potter-800x1132.png 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-harry-potter-1200x1697.png 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-harry-potter.png 1414w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Ciclo de cine Animales Fant\u00e1sticos\" aria-label=\"Ciclo de cine Animales Fant\u00e1sticos\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Animales-Fantasticos.png\" target=\"_self\"><img decoding=\"async\" width=\"209\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Animales-Fantasticos.png\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Animales-Fantasticos-200x283.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Animales-Fantasticos-400x566.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Animales-Fantasticos-600x849.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Animales-Fantasticos-800x1132.png 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Animales-Fantasticos-1200x1697.png 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Animales-Fantasticos.png 1414w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Ciclo de cine Navidad\" aria-label=\"Ciclo de cine Navidad\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Navidad.png\" target=\"_self\"><img decoding=\"async\" width=\"209\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Navidad.png\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Navidad-200x283.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Navidad-400x566.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Navidad-600x849.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Navidad-800x1132.png 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Navidad-1200x1697.png 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-Navidad.png 1414w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><li class=\"fusion-carousel-item\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Ciclo de cine JKK Tolkien\" aria-label=\"Ciclo de cine JKK Tolkien\" href=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-JKK-Tolkien.png\" target=\"_self\"><img decoding=\"async\" width=\"209\" height=\"295\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-JKK-Tolkien.png\" class=\"attachment-portfolio-two size-portfolio-two\" alt=\"\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-JKK-Tolkien-200x283.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-JKK-Tolkien-400x566.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-JKK-Tolkien-600x849.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-JKK-Tolkien-800x1132.png 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-JKK-Tolkien-1200x1697.png 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2023\/10\/Ciclo-de-cine-JKK-Tolkien.png 1414w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 824px) 381px, (min-width: 732px) 572px, (min-width: 640px) 732px, \" \/><\/a><\/div><\/div><\/li><\/ul><div class=\"fusion-carousel-nav\"><span class=\"fusion-nav-prev\"><\/span><span class=\"fusion-nav-next\"><\/span><\/div><\/div><\/div><\/div><style type='text\/css'>.reading-box-container-1 .element-bottomshadow:before,.reading-box-container-1 .element-bottomshadow:after{opacity:0.7;}<\/style><div class=\"fusion-reading-box-container reading-box-container-1\" style=\"margin-top:30px;margin-bottom:30px;\"><div class=\"reading-box\" style=\"background-color:#ededed;border-width:1px;border-color:#e2e2e2;border-left-width:3px;border-left-color:var(--primary_color);border-style:solid;\"><div class=\"reading-box-additional\">\n<h3>Programaci\u00f3n:<\/h3>\n<p><strong>JURASSIC WORLD<\/strong><\/p>\n<ul>\n<li>18 OCT | <span class=\"OYPEnA text-decoration-none text-strikethrough-none\">17:00H.<\/span>: Jurassic World.<\/li>\n<li>19 OCT | <span class=\"OYPEnA text-decoration-none text-strikethrough-none\">17:00H.<\/span>: Jurassic World. El reino ca\u00eddo.<\/li>\n<li>20 OCT | <span class=\"OYPEnA text-decoration-none text-strikethrough-none\">17:00H.<\/span>: Jurassic World. Dominion.<\/li>\n<\/ul>\n<p><strong>HALLOWEEN<\/strong><\/p>\n<ul>\n<li>25 OCT | 17:00h.: Scoob!<\/li>\n<li>26 OCT | 17:00h.: La familia Adams 2.<\/li>\n<li>27 OCT | 18:00h.: La noche de Halloween.<\/li>\n<li>28 OCT | 16:00h.: Halloween kills+Halloween: el final.<\/li>\n<li>30 OCT | 18:00h.: IT.<\/li>\n<li>31 OCT | 18:00h.: IT 2.<\/li>\n<\/ul>\n<p><strong>HARRY POTTER<\/strong><\/p>\n<ul>\n<li>2 NOV | 17:00h.:\u00a0Harry Potter y la piedra filosofal.<\/li>\n<li>3 NOV | 17:00h.:Harry Potter y la c\u00e1mara secreta.<\/li>\n<li>9 NOV | 17:00h.: Harry Potter y el prisionero de Azkaban.<\/li>\n<li>10 NOV | 17:00h.: Harry Potter y el c\u00e1liz de fuego.<\/li>\n<li>16 NOV | 17:00h.: Harry Potter y la orden del F\u00e9nix.<\/li>\n<li>23 NOV | 17:00h.: Harry Potter y el misterio del pr\u00edncipe.<\/li>\n<li>24 NOV | 17:00h.: Harry Potter y las reliquias de la muerte &#8211; Parte 1.<\/li>\n<li>30 NOV | 17:00h.: Harry Potter y las reliquias de la muerte &#8211; Parte 2.<\/li>\n<\/ul>\n<p><strong>ANIMALES FANT\u00c1STICOS<\/strong><\/p>\n<ul>\n<li>1 DIC | 17:00h.: Animales fant\u00e1sticos y d\u00f3nde encontrarlos.<\/li>\n<li>7 DIC | 17:00h.: Animales fant\u00e1sticos: Los cr\u00edmenes de Grindelwald.<\/li>\n<li>14 DIC | 17:00h.: Animales fant\u00e1sticos: Los secretos de Dumbledore.<\/li>\n<\/ul>\n<p><strong>NAVIDAD<\/strong><\/p>\n<ul>\n<li>21 DIC | 17:00h.: La patrulla canina. La pel\u00edcula.<\/li>\n<li>22 DIC | 17:00h.: Charlie y la f\u00e1brica de chocolate.<\/li>\n<li>28 DIC | 17:00h.: El Grinch.<\/li>\n<\/ul>\n<p><strong>J.R.R. TOLKIEN<\/strong><\/p>\n<ul>\n<li>9 DIC | 17:00h.: El se\u00f1or de los anillos: La comunidad del anillo.<\/li>\n<li>2 ENE | 17:00h.: El se\u00f1or de los anillos: Las dos torres.<\/li>\n<li>3 ENE | 17:00h.: El se\u00f1or de los anillos. El retorno del rey.<\/li>\n<\/ul>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-5\"><p><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/ciempozuelos-informa\/\"><em><span style=\"font-size: 14px;\" data-fusion-font=\"true\">&gt;&gt; Regresar a Hemeroteca &#8211; Ciempozuelos Informa<\/span><\/em><\/a><\/p>\n<\/div><div class=\"share-box fusion-sharing-box\" style=\"background-color:#e8e8e8;\" data-title=\"La Biblioteca Municipal Almudena Grandes invita a l@s vecin@s a pasar unas tardes de oto\u00f1o de pel\u00edcula\" data-description=\"Your Content Goes Here \r\n \r\n\r\nEl Sal\u00f3n de Actos de la Biblioteca Municipal Almudena Grandes acoger\u00e1, entre los meses de octubre y enero, seis ciclos de cine tem\u00e1ticos que pretenden atraer al p\u00fablico de todas las edades. La acci\u00f3n y lo fant\u00e1stico\" data-link=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2023\/10\/09\/la-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula\/\"><h4 class=\"tagline\" style=\"color:#000859;\"> \u00a1Comparte esta noticia en tus redes sociales!<\/h4><div class=\"fusion-social-networks\"><a class=\"fusion-social-network-icon fusion-tooltip fusion-facebook fusion-icon-facebook\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F10%2F09%2Fla-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula%2F&amp;t=La%20Biblioteca%20Municipal%20Almudena%20Grandes%20invita%20a%20l%40s%20vecin%40s%20a%20pasar%20unas%20tardes%20de%20oto%C3%B1o%20de%20pel%C3%ADcula\" target=\"_blank\" style=\"color:#3b5998;\" title=\"Facebook\" aria-label=\"Facebook\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Facebook\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-twitter fusion-icon-twitter\" href=\"https:\/\/twitter.com\/share?text=La%20Biblioteca%20Municipal%20Almudena%20Grandes%20invita%20a%20l%40s%20vecin%40s%20a%20pasar%20unas%20tardes%20de%20oto%C3%B1o%20de%20pel%C3%ADcula&amp;url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F10%2F09%2Fla-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula%2F\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#55acee;\" title=\"Twitter\" aria-label=\"Twitter\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Twitter\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-linkedin fusion-icon-linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F10%2F09%2Fla-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula%2F&amp;title=La%20Biblioteca%20Municipal%20Almudena%20Grandes%20invita%20a%20l%40s%20vecin%40s%20a%20pasar%20unas%20tardes%20de%20oto%C3%B1o%20de%20pel%C3%ADcula&amp;summary=Your%20Content%20Goes%20Here%20%0D%0A%20%20%0D%0A%0D%0AEl%20Sal%C3%B3n%20de%20Actos%20de%20la%20Biblioteca%20Municipal%20Almudena%20Grandes%20acoger%C3%A1%2C%20entre%20los%20meses%20de%20octubre%20y%20enero%2C%20seis%20ciclos%20de%20cine%20tem%C3%A1ticos%20que%20pretenden%20atraer%20al%20p%C3%BAblico%20de%20todas%20las%20edades.%20La%20acci%C3%B3n%20y%20lo%20fant%C3%A1stico\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#0077b5;\" title=\"LinkedIn\" aria-label=\"LinkedIn\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"LinkedIn\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-whatsapp fusion-icon-whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F10%2F09%2Fla-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula%2F\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#77e878;\" title=\"WhatsApp\" aria-label=\"WhatsApp\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"WhatsApp\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-tumblr fusion-icon-tumblr\" href=\"http:\/\/www.tumblr.com\/share\/link?url=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F10%2F09%2Fla-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula%2F&amp;name=La%20Biblioteca%20Municipal%20Almudena%20Grandes%20invita%20a%20l%40s%20vecin%40s%20a%20pasar%20unas%20tardes%20de%20oto%C3%B1o%20de%20pel%C3%ADcula&amp;description=Your%20Content%20Goes%20Here%20%0D%0A%20%20%0D%0A%0D%0AEl%20Sal%C3%B3n%20de%20Actos%20de%20la%20Biblioteca%20Municipal%20Almudena%20Grandes%20acoger%C3%A1%2C%20entre%20los%20meses%20de%20octubre%20y%20enero%2C%20seis%20ciclos%20de%20cine%20tem%C3%A1ticos%20que%20pretenden%20atraer%20al%20p%C3%BAblico%20de%20todas%20las%20edades.%20La%20acci%C3%B3n%20y%20lo%20fant%C3%A1stico\" target=\"_blank\" rel=\"noopener noreferrer\" style=\"color:#35465c;\" title=\"Tumblr\" aria-label=\"Tumblr\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Tumblr\"><\/a><a class=\"fusion-social-network-icon fusion-tooltip fusion-mail fusion-icon-mail\" href=\"mailto:?subject=La%20Biblioteca%20Municipal%20Almudena%20Grandes%20invita%20a%20l%40s%20vecin%40s%20a%20pasar%20unas%20tardes%20de%20oto%C3%B1o%20de%20pel%C3%ADcula&amp;body=https%3A%2F%2Fayto-ciempozuelos.org%2Findex.php%2F2023%2F10%2F09%2Fla-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula%2F\" target=\"_self\" style=\"color:#000000;\" title=\"Correo electr\u00f3nico\" aria-label=\"Correo electr\u00f3nico\" data-placement=\"top\" data-toggle=\"tooltip\" data-title=\"Correo electr\u00f3nico\"><\/a><\/div><\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-2{width:66.666666666667% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-2 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 2.88%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 2.88%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-2{width:100% !important;order : 0;}.fusion-builder-column-2 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_3 1_3 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><div class=\"fusion-text fusion-text-6\"><p><span style=\"color: #000859;\"><strong>\u00daLTIMAS NOTICIAS &#8211; CIEMPOZUELOS INFORMA<\/strong><\/span><\/p>\n<\/div><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-no fusion-blog-no-images fusion-blog-layout-left\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:8.5px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -8.5px !important; margin-right:-8.5px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-no fusion-blog-layout-grid fusion-blog-layout-grid-1 isotope\" data-pages=\"238\" data-grid-col-space=\"17\" style=\"margin: -8.5px -8.5px 0;min-height:500px;\"><article id=\"blog-1-post-43605\" class=\"fusion-post-grid post-43605 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-a4 tag-alcaldesa tag-ciempozuelos tag-guardia-civil tag-incendio tag-mercadona tag-policia tag-poligono tag-raquel-jimeno tag-seguridad tag-sendilla\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/07\/guardia-civil-detiene-al-presunto-autor-del-incendio-del-pasado-mes-de-junio-en-el-poligono-industrial-la-sendilla\/\">Guardia Civil detiene al presunto autor del incendio del pasado mes de junio en el pol\u00edgono industrial La Sendilla<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/\" title=\"Entradas de Comunicaci\u00f3n Ciempozuelos\" rel=\"author\">Comunicaci\u00f3n Ciempozuelos<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-07T13:28:36+02:00<\/span><span>julio 7th, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/07\/guardia-civil-detiene-al-presunto-autor-del-incendio-del-pasado-mes-de-junio-en-el-poligono-industrial-la-sendilla\/\" aria-label=\"More on Guardia Civil detiene al presunto autor del incendio del pasado mes de junio en el pol\u00edgono industrial La Sendilla\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-43588\" class=\"fusion-post-grid post-43588 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-cimepozuelos tag-empleo-ruben-iglesias-garcia tag-empresa tag-formacion-sin-categoria tag-vecinos tag-verano\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/06\/nuevas-incorporaciones-en-los-programas-de-empleo-formacion-2026\/\">Nuevas incorporaciones en los Programas de Empleo-Formaci\u00f3n 2026<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/sara-lazaro\/\" title=\"Entradas de Sara L\u00e1zaro\" rel=\"author\">Sara L\u00e1zaro<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-06T13:46:58+02:00<\/span><span>julio 6th, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/06\/nuevas-incorporaciones-en-los-programas-de-empleo-formacion-2026\/\" aria-label=\"More on Nuevas incorporaciones en los Programas de Empleo-Formaci\u00f3n 2026\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-43565\" class=\"fusion-post-grid post-43565 post type-post status-publish format-standard has-post-thumbnail hentry category-ciempozuelosinforma tag-alcaldesa tag-cimepozuelos tag-concejal tag-deportes-jorge-alonso-diaz tag-empresa tag-gimnasio tag-justicia tag-morgado tag-piscina tag-raquel-jimeno tag-vecinos tag-verano\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(232,232,232,1);border:1px solid #ebeaea;border-bottom-width:3px;\"><div class=\"fusion-post-content-wrapper\" style=\"padding:10px 10px 10px 10PX;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\">El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria<\/a><\/h2><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/\" title=\"Entradas de Comunicaci\u00f3n Ciempozuelos\" rel=\"author\">Comunicaci\u00f3n Ciempozuelos<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-02T14:26:33+02:00<\/span><span>julio 2nd, 2026<\/span><span class=\"fusion-inline-sep\">|<\/span><\/p><div class=\"fusion-content-sep sep-none\" style=\"border-color:#e0dede;\"><\/div><\/div><div class=\"fusion-meta-info\"><div class=\"fusion-alignleft\"><a class=\"fusion-read-more\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" aria-label=\"More on El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria\">Leer M\u00e1s<\/a><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-7 k_hide\" id=\"k_principalultimasnoticias\"><p><img decoding=\"async\" class=\"k_imgultimasnoticias wp-image-16863 alignleft\" src=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png\" alt=\"\" width=\"173\" height=\"50\" data-wp-editing=\"1\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-200x58.png 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-300x87.png 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-400x115.png 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo-600x173.png 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2020\/09\/ayuntamiento-informa_rojo.png 693w\" sizes=\"(max-width: 173px) 100vw, 173px\" \/><div class=\"lcp_catlist\" id=\"lcp_instance_0\"><\/div><\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-3{width:33.333333333333% !important;margin-top : 0px;margin-bottom : 20px;}.fusion-builder-column-3 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 5.76%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 5.76%;}@media only screen and (max-width:1024px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-3{width:100% !important;order : 0;margin-top : 25px;}.fusion-builder-column-3 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-2{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Sal\u00f3n de Actos de la Biblioteca Municipal Almudena Grandes acoger\u00e1, entre los meses de octubre y enero, seis ciclos de cine tem\u00e1ticos que pretenden atraer al p\u00fablico de todas las edades. La acci\u00f3n y lo fant\u00e1stico son el nexo de uni\u00f3n de la mayor\u00eda de pel\u00edculas elegidas, aunque tambi\u00e9n hay lugar para el terror extremo, con un ciclo dedicado a Halloween, sin olvidar al p\u00fablico infantil y familiar.<\/p>\n<p>El Ciclo Jurassic Word abrir\u00e1 la programaci\u00f3n con la trilog\u00eda de Chris Pratt y Bryce Dallas Howard (18, 19 y 20 de octubre)&#8230;<\/p>\n","protected":false},"author":4,"featured_media":32225,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1436,1676],"tags":[1075,3556,1078,3551],"class_list":["post-32215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciempozuelosinforma","category-cultura","tag-biblioteca","tag-ciclo","tag-cine","tag-otono"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Comunicaci\u00f3n Ciempozuelos\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-02T12:26:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-02T12:26:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#blogposting\",\"name\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\",\"headline\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/piscina-de-verano.jpeg\",\"width\":1152,\"height\":2048},\"datePublished\":\"2026-07-02T14:26:32+02:00\",\"dateModified\":\"2026-07-02T14:26:33+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\"},\"articleSection\":\"Ciempozuelos Informa, alcaldesa, cimepozuelos, concejal, Deportes, empresa, gimnasio, justicia, morgado, piscina, Raquel Jimeno, vecinos, verano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"name\":\"Ciempozuelos Informa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"position\":2,\"name\":\"Ciempozuelos Informa\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2023\\\/10\\\/09\\\/la-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula\\\/#listItem\",\"name\":\"La Biblioteca Municipal Almudena Grandes invita a l@s vecin@s a pasar unas tardes de oto\\u00f1o de pel\\u00edcula\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2023\\\/10\\\/09\\\/la-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula\\\/#listItem\",\"position\":3,\"name\":\"La Biblioteca Municipal Almudena Grandes invita a l@s vecin@s a pasar unas tardes de oto\\u00f1o de pel\\u00edcula\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/category\\\/ciempozuelosinforma\\\/#listItem\",\"name\":\"Ciempozuelos Informa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/\",\"name\":\"Comunicaci\\u00f3n Ciempozuelos\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9b31ac435c51f3c129db96365b19c4f642ee8a126c018d7b9a12fcee80bc5f1?s=96&d=https%3A%2F%2Fayto-ciempozuelos.org%2Fwp-content%2Fplugins%2Fwp-jobsearch%2Fimages%2Fno-image.jpg&r=g\",\"width\":96,\"height\":96,\"caption\":\"Comunicaci\\u00f3n Ciempozuelos\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/\",\"name\":\"El Ayuntamiento de Ciempozuelos abre ma\\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos\",\"description\":\"La piscina municipal de verano de Ciempozuelos abrir\\u00e1 ma\\u00f1ana al p\\u00fablico. Lo hace tras el secuestro de la concesi\\u00f3n de la instalaci\\u00f3n a la empresa Neo la que, por contrato, deber\\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\\u00f3n legal de la misma para que el Consistorio se hiciera cargo.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/silvia-campillo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/piscina-de-verano.jpeg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#mainImage\",\"width\":1152,\"height\":2048},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2026\\\/07\\\/02\\\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\\\/#mainImage\"},\"datePublished\":\"2026-07-02T14:26:32+02:00\",\"dateModified\":\"2026-07-02T14:26:33+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#blogposting","name":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","headline":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/07\/piscina-de-verano.jpeg","width":1152,"height":2048},"datePublished":"2026-07-02T14:26:32+02:00","dateModified":"2026-07-02T14:26:33+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage"},"articleSection":"Ciempozuelos Informa, alcaldesa, cimepozuelos, concejal, Deportes, empresa, gimnasio, justicia, morgado, piscina, Raquel Jimeno, vecinos, verano"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","name":"Ciempozuelos Informa"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","position":2,"name":"Ciempozuelos Informa","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2023\/10\/09\/la-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula\/#listItem","name":"La Biblioteca Municipal Almudena Grandes invita a l@s vecin@s a pasar unas tardes de oto\u00f1o de pel\u00edcula"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2023\/10\/09\/la-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula\/#listItem","position":3,"name":"La Biblioteca Municipal Almudena Grandes invita a l@s vecin@s a pasar unas tardes de oto\u00f1o de pel\u00edcula","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/#listItem","name":"Ciempozuelos Informa"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/","name":"Comunicaci\u00f3n Ciempozuelos","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b9b31ac435c51f3c129db96365b19c4f642ee8a126c018d7b9a12fcee80bc5f1?s=96&d=https%3A%2F%2Fayto-ciempozuelos.org%2Fwp-content%2Fplugins%2Fwp-jobsearch%2Fimages%2Fno-image.jpg&r=g","width":96,"height":96,"caption":"Comunicaci\u00f3n Ciempozuelos"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","name":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/silvia-campillo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2026\/07\/piscina-de-verano.jpeg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#mainImage","width":1152,"height":2048},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/#mainImage"},"datePublished":"2026-07-02T14:26:32+02:00","dateModified":"2026-07-02T14:26:33+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","og:description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo.","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2026\/07\/02\/el-ayuntamiento-de-ciempozuelos-abre-manana-la-piscina-de-verano-municipal-tras-el-secuestro-a-la-empresa-concesionaria\/","article:published_time":"2026-07-02T12:26:32+00:00","article:modified_time":"2026-07-02T12:26:33+00:00","twitter:card":"summary","twitter:title":"El Ayuntamiento de Ciempozuelos abre ma\u00f1ana la piscina de verano municipal tras el secuestro a la empresa concesionaria - Ayuntamiento de Ciempozuelos","twitter:description":"La piscina municipal de verano de Ciempozuelos abrir\u00e1 ma\u00f1ana al p\u00fablico. Lo hace tras el secuestro de la concesi\u00f3n de la instalaci\u00f3n a la empresa Neo la que, por contrato, deber\u00eda haberla abierto en el pasado 1 de junio tal y como recoge el contrato. Sin embargo, tras la negativa de esta, todos los grupos pol\u00edticos aprobaron, en el pleno extraordinario del 14 de junio, la intervenci\u00f3n legal de la misma para que el Consistorio se hiciera cargo."},"aioseo_meta_data":{"post_id":"32215","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2023-10-09 12:18:49","updated":"2025-06-04 23:31:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/\" title=\"Ciempozuelos Informa\">Ciempozuelos Informa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Biblioteca Municipal Almudena Grandes invita a l@s vecin@s a pasar unas tardes de oto\u00f1o de pel\u00edcula\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Ciempozuelos Informa","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/category\/ciempozuelosinforma\/"},{"label":"La Biblioteca Municipal Almudena Grandes invita a l@s vecin@s a pasar unas tardes de oto\u00f1o de pel\u00edcula","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2023\/10\/09\/la-biblioteca-municipal-almudena-grandes-invita-a-ls-vecins-a-pasar-unas-tardes-de-otono-de-pelicula\/"}],"modified_by":"Comunicacion1 Ayto. Ciempozuelos","publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:05:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/32215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=32215"}],"version-history":[{"count":5,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/32215\/revisions"}],"predecessor-version":[{"id":32464,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/32215\/revisions\/32464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/32225"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=32215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=32215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=32215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}