{"id":15545,"date":"2021-03-24T08:53:16","date_gmt":"2021-03-24T08:53:16","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/"},"modified":"2021-03-24T08:53:16","modified_gmt":"2021-03-24T08:53:16","slug":"anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/","title":{"rendered":"Anuncio aclaratorio referente al segundo ejercicio &#8211; Bolsa de T\u00e9cnico de unidad sancionadora"},"content":{"rendered":"<p>Adjunto se publica &#8216;Anuncio aclaratorio referente al segundo ejercicio &#8211; Bolsa de T\u00e9cnico de unidad sancionadora&#8217;<\/p>\n<p>\u00a0<\/p>\n<p>{jd_file file==3532}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adjunto se publica &#8216;Anuncio aclaratorio referente al segundo ejercicio &#8211; Bolsa de T\u00e9cnico de unidad sancionadora&#8217; \u00a0 {jd_file file==3532}<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1204],"class_list":["post-15545","post","type-post","status-publish","format-standard","hentry","tag-noticias"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Adjunto se publica &#039;Anuncio aclaratorio referente al segundo ejercicio - Bolsa de T\u00e9cnico de unidad sancionadora&#039; {jd_file file==3532}\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Anuncio aclaratorio referente al segundo ejercicio \u2013 Bolsa de T\u00e9cnico de unidad sancionadora - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Adjunto se publica &#039;Anuncio aclaratorio referente al segundo ejercicio - Bolsa de T\u00e9cnico de unidad sancionadora&#039; {jd_file file==3532}\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-03-24T08:53:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-03-24T08:53:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Anuncio aclaratorio referente al segundo ejercicio \u2013 Bolsa de T\u00e9cnico de unidad sancionadora - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Adjunto se publica &#039;Anuncio aclaratorio referente al segundo ejercicio - Bolsa de T\u00e9cnico de unidad sancionadora&#039; {jd_file file==3532}\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2021\\\/03\\\/24\\\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\\\/#blogposting\",\"name\":\"Anuncio aclaratorio referente al segundo ejercicio \\u2013 Bolsa de T\\u00e9cnico de unidad sancionadora - Ayuntamiento de Ciempozuelos\",\"headline\":\"Anuncio aclaratorio referente al segundo ejercicio &#8211; Bolsa de T\\u00e9cnico de unidad sancionadora\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2021-03-24T08:53:16+01:00\",\"dateModified\":\"2021-03-24T08:53:16+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2021\\\/03\\\/24\\\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2021\\\/03\\\/24\\\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\\\/#webpage\"},\"articleSection\":\"Noticias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2021\\\/03\\\/24\\\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2021\\\/03\\\/24\\\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\\\/#listItem\",\"name\":\"Anuncio aclaratorio referente al segundo ejercicio &#8211; Bolsa de T\\u00e9cnico de unidad sancionadora\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2021\\\/03\\\/24\\\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\\\/#listItem\",\"position\":3,\"name\":\"Anuncio aclaratorio referente al segundo ejercicio &#8211; Bolsa de T\\u00e9cnico de unidad sancionadora\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2021\\\/03\\\/24\\\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2021\\\/03\\\/24\\\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2021\\\/03\\\/24\\\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\\\/\",\"name\":\"Anuncio aclaratorio referente al segundo ejercicio \\u2013 Bolsa de T\\u00e9cnico de unidad sancionadora - Ayuntamiento de Ciempozuelos\",\"description\":\"Adjunto se publica 'Anuncio aclaratorio referente al segundo ejercicio - Bolsa de T\\u00e9cnico de unidad sancionadora' {jd_file file==3532}\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2021\\\/03\\\/24\\\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2021-03-24T08:53:16+01:00\",\"dateModified\":\"2021-03-24T08:53:16+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Anuncio aclaratorio referente al segundo ejercicio \u2013 Bolsa de T\u00e9cnico de unidad sancionadora - Ayuntamiento de Ciempozuelos","description":"Adjunto se publica 'Anuncio aclaratorio referente al segundo ejercicio - Bolsa de T\u00e9cnico de unidad sancionadora' {jd_file file==3532}","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/#blogposting","name":"Anuncio aclaratorio referente al segundo ejercicio \u2013 Bolsa de T\u00e9cnico de unidad sancionadora - Ayuntamiento de Ciempozuelos","headline":"Anuncio aclaratorio referente al segundo ejercicio &#8211; Bolsa de T\u00e9cnico de unidad sancionadora","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2021-03-24T08:53:16+01:00","dateModified":"2021-03-24T08:53:16+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/#webpage"},"articleSection":"Noticias"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/#listItem","name":"Anuncio aclaratorio referente al segundo ejercicio &#8211; Bolsa de T\u00e9cnico de unidad sancionadora"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/#listItem","position":3,"name":"Anuncio aclaratorio referente al segundo ejercicio &#8211; Bolsa de T\u00e9cnico de unidad sancionadora","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/","name":"Anuncio aclaratorio referente al segundo ejercicio \u2013 Bolsa de T\u00e9cnico de unidad sancionadora - Ayuntamiento de Ciempozuelos","description":"Adjunto se publica 'Anuncio aclaratorio referente al segundo ejercicio - Bolsa de T\u00e9cnico de unidad sancionadora' {jd_file file==3532}","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2021-03-24T08:53:16+01:00","dateModified":"2021-03-24T08:53:16+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Anuncio aclaratorio referente al segundo ejercicio \u2013 Bolsa de T\u00e9cnico de unidad sancionadora - Ayuntamiento de Ciempozuelos","og:description":"Adjunto se publica 'Anuncio aclaratorio referente al segundo ejercicio - Bolsa de T\u00e9cnico de unidad sancionadora' {jd_file file==3532}","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/","article:published_time":"2021-03-24T08:53:16+00:00","article:modified_time":"2021-03-24T08:53:16+00:00","twitter:card":"summary","twitter:title":"Anuncio aclaratorio referente al segundo ejercicio \u2013 Bolsa de T\u00e9cnico de unidad sancionadora - Ayuntamiento de Ciempozuelos","twitter:description":"Adjunto se publica 'Anuncio aclaratorio referente al segundo ejercicio - Bolsa de T\u00e9cnico de unidad sancionadora' {jd_file file==3532}"},"aioseo_meta_data":{"post_id":"15545","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 20:19:07","updated":"2025-06-04 22:44:08","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAnuncio aclaratorio referente al segundo ejercicio \u2013 Bolsa de T\u00e9cnico de unidad sancionadora\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Noticias","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/noticias\/"},{"label":"Anuncio aclaratorio referente al segundo ejercicio &#8211; Bolsa de T\u00e9cnico de unidad sancionadora","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2021\/03\/24\/anuncio-aclaratorio-referente-al-segundo-ejercicio-bolsa-de-tecnico-de-unidad-sancionadora\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:58:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/15545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=15545"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/15545\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=15545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=15545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=15545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}