{"id":14024,"date":"2016-05-19T13:08:57","date_gmt":"2016-05-19T13:08:57","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/"},"modified":"2016-05-19T13:08:57","modified_gmt":"2016-05-19T13:08:57","slug":"citas-con-el-teatro-este-fin-de-semana-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/","title":{"rendered":"Citas con el teatro este fin de semana"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">&#8216;<\/span><em style=\"font-size: 12.16px; line-height: 1.3em;\">La nave de los locos\u2019 y \u2018El principito que volaba en bicicleta\u2019<\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Enmarcadas en la programaci\u00f3n del XVI Certamen de Teatro \u2018Villa de Ciempozuelos\u2019 y la Muestra de Teatro Infanto- Juvenil, este fin de semana en Ciempozuelos podremos disfrutar de dos citas para p\u00fablico de todas las edades.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El s\u00e1bado 21 de mayo a las 20.00 horas la Sala Multifuncional acoge la comedia \u2018La nave de los locos\u2019 de la asociaci\u00f3n de teatro Aldaba Tres. Un espect\u00e1culo teatral de 75 minutos basado en textos de Dar\u00edo Fo, Alejandro Casona y Arcipreste de Hita.<\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> La obra est\u00e1 destinada a un p\u00fablico adulto\/joven.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La compa\u00f1\u00eda Cicloteatro presenta el domingo 22 de mayo a las 19.00 horas en la Sala Multifuncional \u2018El principito que volaba en bicicleta\u2019, un montaje teatral con el personaje de Saint- Exup\u00e8ry como protagonista. La obra est\u00e1 dirigida a p\u00fablico infantil a partir de 5 a\u00f1os. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><img decoding=\"async\" class=\" size-full wp-image-11266\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/05\/principito.jpg\" border=\"0\" width=\"100%\" style=\"font-size: 12.16px; line-height: 15.808px;\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/05\/principito-200x150.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/05\/principito-300x225.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/05\/principito-400x300.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/05\/principito.jpg 454w\" sizes=\"(max-width: 454px) 100vw, 454px\" \/><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8216;La nave de los locos\u2019 y \u2018El principito que volaba en bicicleta\u2019 Enmarcadas en la programaci\u00f3n del XVI Certamen de Teatro \u2018Villa de Ciempozuelos\u2019 y la Muestra de Teatro Infanto- Juvenil, este fin de semana en Ciempozuelos podremos disfrutar de dos citas para p\u00fablico de todas las edades. El s\u00e1bado 21 de mayo a las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[],"class_list":["post-14024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"&#039;La nave de los locos\u2019 y \u2018El principito que volaba en bicicleta\u2019 Enmarcadas en la programaci\u00f3n del XVI Certamen de Teatro \u2018Villa de Ciempozuelos\u2019 y la Muestra de Teatro Infanto- Juvenil, este fin de semana en Ciempozuelos podremos disfrutar de dos citas para p\u00fablico de todas las edades. El s\u00e1bado 21 de mayo a las\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Citas con el teatro este fin de semana - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"&#039;La nave de los locos\u2019 y \u2018El principito que volaba en bicicleta\u2019 Enmarcadas en la programaci\u00f3n del XVI Certamen de Teatro \u2018Villa de Ciempozuelos\u2019 y la Muestra de Teatro Infanto- Juvenil, este fin de semana en Ciempozuelos podremos disfrutar de dos citas para p\u00fablico de todas las edades. El s\u00e1bado 21 de mayo a las\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-05-19T13:08:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-05-19T13:08:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Citas con el teatro este fin de semana - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"&#039;La nave de los locos\u2019 y \u2018El principito que volaba en bicicleta\u2019 Enmarcadas en la programaci\u00f3n del XVI Certamen de Teatro \u2018Villa de Ciempozuelos\u2019 y la Muestra de Teatro Infanto- Juvenil, este fin de semana en Ciempozuelos podremos disfrutar de dos citas para p\u00fablico de todas las edades. El s\u00e1bado 21 de mayo a las\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/#blogposting\",\"name\":\"Citas con el teatro este fin de semana - Ayuntamiento de Ciempozuelos\",\"headline\":\"Citas con el teatro este fin de semana\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/principito.jpg\",\"width\":454,\"height\":340},\"datePublished\":\"2016-05-19T13:08:57+02:00\",\"dateModified\":\"2016-05-19T13:08:57+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/#webpage\"}},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/#listItem\",\"name\":\"Citas con el teatro este fin de semana\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/#listItem\",\"position\":2,\"name\":\"Citas con el teatro este fin de semana\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/\",\"name\":\"Citas con el teatro este fin de semana - Ayuntamiento de Ciempozuelos\",\"description\":\"'La nave de los locos\\u2019 y \\u2018El principito que volaba en bicicleta\\u2019 Enmarcadas en la programaci\\u00f3n del XVI Certamen de Teatro \\u2018Villa de Ciempozuelos\\u2019 y la Muestra de Teatro Infanto- Juvenil, este fin de semana en Ciempozuelos podremos disfrutar de dos citas para p\\u00fablico de todas las edades. El s\\u00e1bado 21 de mayo a las\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/principito.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/#mainImage\",\"width\":454,\"height\":340},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/19\\\/citas-con-el-teatro-este-fin-de-semana-3\\\/#mainImage\"},\"datePublished\":\"2016-05-19T13:08:57+02:00\",\"dateModified\":\"2016-05-19T13:08:57+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Citas con el teatro este fin de semana - Ayuntamiento de Ciempozuelos","description":"'La nave de los locos\u2019 y \u2018El principito que volaba en bicicleta\u2019 Enmarcadas en la programaci\u00f3n del XVI Certamen de Teatro \u2018Villa de Ciempozuelos\u2019 y la Muestra de Teatro Infanto- Juvenil, este fin de semana en Ciempozuelos podremos disfrutar de dos citas para p\u00fablico de todas las edades. El s\u00e1bado 21 de mayo a las","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/#blogposting","name":"Citas con el teatro este fin de semana - Ayuntamiento de Ciempozuelos","headline":"Citas con el teatro este fin de semana","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/05\/principito.jpg","width":454,"height":340},"datePublished":"2016-05-19T13:08:57+02:00","dateModified":"2016-05-19T13:08:57+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/#webpage"}},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/#listItem","name":"Citas con el teatro este fin de semana"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/#listItem","position":2,"name":"Citas con el teatro este fin de semana","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/","name":"Citas con el teatro este fin de semana - Ayuntamiento de Ciempozuelos","description":"'La nave de los locos\u2019 y \u2018El principito que volaba en bicicleta\u2019 Enmarcadas en la programaci\u00f3n del XVI Certamen de Teatro \u2018Villa de Ciempozuelos\u2019 y la Muestra de Teatro Infanto- Juvenil, este fin de semana en Ciempozuelos podremos disfrutar de dos citas para p\u00fablico de todas las edades. El s\u00e1bado 21 de mayo a las","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/05\/principito.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/#mainImage","width":454,"height":340},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/#mainImage"},"datePublished":"2016-05-19T13:08:57+02:00","dateModified":"2016-05-19T13:08:57+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Citas con el teatro este fin de semana - Ayuntamiento de Ciempozuelos","og:description":"'La nave de los locos\u2019 y \u2018El principito que volaba en bicicleta\u2019 Enmarcadas en la programaci\u00f3n del XVI Certamen de Teatro \u2018Villa de Ciempozuelos\u2019 y la Muestra de Teatro Infanto- Juvenil, este fin de semana en Ciempozuelos podremos disfrutar de dos citas para p\u00fablico de todas las edades. El s\u00e1bado 21 de mayo a las","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/","article:published_time":"2016-05-19T13:08:57+00:00","article:modified_time":"2016-05-19T13:08:57+00:00","twitter:card":"summary","twitter:title":"Citas con el teatro este fin de semana - Ayuntamiento de Ciempozuelos","twitter:description":"'La nave de los locos\u2019 y \u2018El principito que volaba en bicicleta\u2019 Enmarcadas en la programaci\u00f3n del XVI Certamen de Teatro \u2018Villa de Ciempozuelos\u2019 y la Muestra de Teatro Infanto- Juvenil, este fin de semana en Ciempozuelos podremos disfrutar de dos citas para p\u00fablico de todas las edades. El s\u00e1bado 21 de mayo a las"},"aioseo_meta_data":{"post_id":"14024","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 16:10:03","updated":"2025-06-04 18:35:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCitas con el teatro este fin de semana\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Citas con el teatro este fin de semana","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/19\/citas-con-el-teatro-este-fin-de-semana-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:07:36","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/14024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=14024"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/14024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/11266"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=14024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=14024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=14024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}