{"id":14003,"date":"2016-02-11T12:02:36","date_gmt":"2016-02-11T12:02:36","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/"},"modified":"2016-02-11T12:02:36","modified_gmt":"2016-02-11T12:02:36","slug":"ciempozuelos-se-viste-de-poesia-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/","title":{"rendered":"Ciempozuelos se viste de poes\u00eda"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><em>Este fin de semana se celebran talleres colectivos y acciones po\u00e9ticas<\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><em> <\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Enmarcada en la programaci\u00f3n del mes de febrero, la poes\u00eda se convierte en protagonista absoluta los d\u00edas 12, 13 y 14 de febrero en Ciempozuelos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Ma\u00f1ana arranca en la Casa de la Cultura un taller colectivo de poes\u00eda de 17.30 a 20.00 horas que tendr\u00e1 otra sesi\u00f3n el s\u00e1bado 13 en el mismo horario. Este taller se encargar\u00e1 de preparar la acci\u00f3n po\u00e9tica nocturna del s\u00e1bado 13 que dar\u00e1 comienzo una vez finalizada la segunda sesi\u00f3n del taller. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La poes\u00eda sale a la calle el s\u00e1bado 13 con la iniciativa de micro abierto po\u00e9tico en la que todos los que quieran podr\u00e1n subir al escenario que se colocar\u00e1 y recitar libros rom\u00e1nticos y poes\u00eda a la calle. La acci\u00f3n tendr\u00e1 lugar en la plaza de la Constituci\u00f3n a las 12.00 horas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">Por \u00faltimo, una recomendaci\u00f3n: el domingo 14 se sugiere a los vecinos y vecinas de Ciempozuelos que abran bien los ojos al despertar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana se celebran talleres colectivos y acciones po\u00e9ticas Enmarcada en la programaci\u00f3n del mes de febrero, la poes\u00eda se convierte en protagonista absoluta los d\u00edas 12, 13 y 14 de febrero en Ciempozuelos. Ma\u00f1ana arranca en la Casa de la Cultura un taller colectivo de poes\u00eda de 17.30 a 20.00 horas que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[],"class_list":["post-14003","post","type-post","status-publish","format-standard","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Este fin de semana se celebran talleres colectivos y acciones po\u00e9ticas Enmarcada en la programaci\u00f3n del mes de febrero, la poes\u00eda se convierte en protagonista absoluta los d\u00edas 12, 13 y 14 de febrero en Ciempozuelos. Ma\u00f1ana arranca en la Casa de la Cultura un taller colectivo de poes\u00eda de 17.30 a 20.00 horas que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ciempozuelos se viste de poes\u00eda - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Este fin de semana se celebran talleres colectivos y acciones po\u00e9ticas Enmarcada en la programaci\u00f3n del mes de febrero, la poes\u00eda se convierte en protagonista absoluta los d\u00edas 12, 13 y 14 de febrero en Ciempozuelos. Ma\u00f1ana arranca en la Casa de la Cultura un taller colectivo de poes\u00eda de 17.30 a 20.00 horas que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-11T12:02:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-11T12:02:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ciempozuelos se viste de poes\u00eda - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Este fin de semana se celebran talleres colectivos y acciones po\u00e9ticas Enmarcada en la programaci\u00f3n del mes de febrero, la poes\u00eda se convierte en protagonista absoluta los d\u00edas 12, 13 y 14 de febrero en Ciempozuelos. Ma\u00f1ana arranca en la Casa de la Cultura un taller colectivo de poes\u00eda de 17.30 a 20.00 horas que\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/11\\\/ciempozuelos-se-viste-de-poesia-3\\\/#blogposting\",\"name\":\"Ciempozuelos se viste de poes\\u00eda - Ayuntamiento de Ciempozuelos\",\"headline\":\"Ciempozuelos se viste de poes\\u00eda\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-02-11T12:02:36+01:00\",\"dateModified\":\"2016-02-11T12:02:36+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/11\\\/ciempozuelos-se-viste-de-poesia-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/11\\\/ciempozuelos-se-viste-de-poesia-3\\\/#webpage\"}},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/11\\\/ciempozuelos-se-viste-de-poesia-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/11\\\/ciempozuelos-se-viste-de-poesia-3\\\/#listItem\",\"name\":\"Ciempozuelos se viste de poes\\u00eda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/11\\\/ciempozuelos-se-viste-de-poesia-3\\\/#listItem\",\"position\":2,\"name\":\"Ciempozuelos se viste de poes\\u00eda\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/11\\\/ciempozuelos-se-viste-de-poesia-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/11\\\/ciempozuelos-se-viste-de-poesia-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/11\\\/ciempozuelos-se-viste-de-poesia-3\\\/\",\"name\":\"Ciempozuelos se viste de poes\\u00eda - Ayuntamiento de Ciempozuelos\",\"description\":\"Este fin de semana se celebran talleres colectivos y acciones po\\u00e9ticas Enmarcada en la programaci\\u00f3n del mes de febrero, la poes\\u00eda se convierte en protagonista absoluta los d\\u00edas 12, 13 y 14 de febrero en Ciempozuelos. Ma\\u00f1ana arranca en la Casa de la Cultura un taller colectivo de poes\\u00eda de 17.30 a 20.00 horas que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/11\\\/ciempozuelos-se-viste-de-poesia-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-02-11T12:02:36+01:00\",\"dateModified\":\"2016-02-11T12:02:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ciempozuelos se viste de poes\u00eda - Ayuntamiento de Ciempozuelos","description":"Este fin de semana se celebran talleres colectivos y acciones po\u00e9ticas Enmarcada en la programaci\u00f3n del mes de febrero, la poes\u00eda se convierte en protagonista absoluta los d\u00edas 12, 13 y 14 de febrero en Ciempozuelos. Ma\u00f1ana arranca en la Casa de la Cultura un taller colectivo de poes\u00eda de 17.30 a 20.00 horas que","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/#blogposting","name":"Ciempozuelos se viste de poes\u00eda - Ayuntamiento de Ciempozuelos","headline":"Ciempozuelos se viste de poes\u00eda","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-02-11T12:02:36+01:00","dateModified":"2016-02-11T12:02:36+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/#webpage"}},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/#listItem","name":"Ciempozuelos se viste de poes\u00eda"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/#listItem","position":2,"name":"Ciempozuelos se viste de poes\u00eda","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/","name":"Ciempozuelos se viste de poes\u00eda - Ayuntamiento de Ciempozuelos","description":"Este fin de semana se celebran talleres colectivos y acciones po\u00e9ticas Enmarcada en la programaci\u00f3n del mes de febrero, la poes\u00eda se convierte en protagonista absoluta los d\u00edas 12, 13 y 14 de febrero en Ciempozuelos. Ma\u00f1ana arranca en la Casa de la Cultura un taller colectivo de poes\u00eda de 17.30 a 20.00 horas que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-02-11T12:02:36+01:00","dateModified":"2016-02-11T12:02:36+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Ciempozuelos se viste de poes\u00eda - Ayuntamiento de Ciempozuelos","og:description":"Este fin de semana se celebran talleres colectivos y acciones po\u00e9ticas Enmarcada en la programaci\u00f3n del mes de febrero, la poes\u00eda se convierte en protagonista absoluta los d\u00edas 12, 13 y 14 de febrero en Ciempozuelos. Ma\u00f1ana arranca en la Casa de la Cultura un taller colectivo de poes\u00eda de 17.30 a 20.00 horas que","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/","article:published_time":"2016-02-11T12:02:36+00:00","article:modified_time":"2016-02-11T12:02:36+00:00","twitter:card":"summary","twitter:title":"Ciempozuelos se viste de poes\u00eda - Ayuntamiento de Ciempozuelos","twitter:description":"Este fin de semana se celebran talleres colectivos y acciones po\u00e9ticas Enmarcada en la programaci\u00f3n del mes de febrero, la poes\u00eda se convierte en protagonista absoluta los d\u00edas 12, 13 y 14 de febrero en Ciempozuelos. Ma\u00f1ana arranca en la Casa de la Cultura un taller colectivo de poes\u00eda de 17.30 a 20.00 horas que"},"aioseo_meta_data":{"post_id":"14003","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:32:57","updated":"2025-06-04 17:58:12","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCiempozuelos se viste de poes\u00eda\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Ciempozuelos se viste de poes\u00eda","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/11\/ciempozuelos-se-viste-de-poesia-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:46:36","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/14003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=14003"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/14003\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=14003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=14003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=14003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}