{"id":13995,"date":"2015-12-17T11:45:28","date_gmt":"2015-12-17T11:45:28","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/"},"modified":"2015-12-17T11:45:28","modified_gmt":"2015-12-17T11:45:28","slug":"navidad-musical-en-ciempozuelos-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/","title":{"rendered":"Navidad musical en Ciempozuelos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><em>Varios conciertos amenizar\u00e1n los d\u00edas previos a la fiesta de Navidad<\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La m\u00fasica ser\u00e1 la protagonista durante los pr\u00f3ximos d\u00edas con conciertos de distintos estilos musicales para disfrutar de eventos culturales para todos los gustos, organizados por la Mesa de Festejos dentro de<\/span><span style=\"font-size: 12.16px; line-height: 15.808px;\"> la programaci\u00f3n de Navidad.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El jueves 17 de diciembre, a las 18.00 horas, el Hogar del Jubilado acoge un concierto de voz y piano, interpretado por el pianista Juan Antonio R. Brisaboa y el cantante Antonio Garc\u00eda. <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">Al d\u00eda siguiente, el viernes 18 en el mismo escenario, en el Hogar del Jubilado, se podr\u00e1 disfrutar a las 18.00 horas con el concierto de copla de Ram\u00f3n Collado.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">El broche final del fin de semana correr\u00e1 a cargo de la Banda de M\u00fasica Municipal que ofrecer\u00e1 un concierto en la Sala Multifuncional el s\u00e1bado 19 a las 19.00 horas.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El martes 22 de diciembre se celebrar\u00e1n dos conciertos. A las 12.00 horas la Plaza de la Constituci\u00f3n acoger\u00e1 las voces de la Coral del Hogar del Jubilado y tambi\u00e9n tendr\u00e1 lugar <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">el Concierto de Navidad organizado por la Hermandad y Primitiva Cofrad\u00eda de Nuestro Padre Jes\u00fas Cautivo de Medinaceli junto con el Coro de \u2018Voces Para la Convivencia\u2019 y la coral del Centro C\u00edvico en el Convento Mater Dei (Clarisas) a las 20.00 horas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Adem\u00e1s de esta agenda musical, los m\u00e1s j\u00f3venes celebrar\u00e1n el fin del trimestre en la Fiesta de las Notas el d\u00eda 22 a las 18.00 horas en la Casa de la Cultura. Se desarrollar\u00e1n varios juegos y se repartir\u00e1 una merienda entre los j\u00f3venes (de 12 a 18 a\u00f1os) que acudan al centro.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Varios conciertos amenizar\u00e1n los d\u00edas previos a la fiesta de Navidad La m\u00fasica ser\u00e1 la protagonista durante los pr\u00f3ximos d\u00edas con conciertos de distintos estilos musicales para disfrutar de eventos culturales para todos los gustos, organizados por la Mesa de Festejos dentro de la programaci\u00f3n de Navidad. El jueves 17 de diciembre, a las 18.00 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[],"class_list":["post-13995","post","type-post","status-publish","format-standard","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Varios conciertos amenizar\u00e1n los d\u00edas previos a la fiesta de Navidad La m\u00fasica ser\u00e1 la protagonista durante los pr\u00f3ximos d\u00edas con conciertos de distintos estilos musicales para disfrutar de eventos culturales para todos los gustos, organizados por la Mesa de Festejos dentro de la programaci\u00f3n de Navidad. El jueves 17 de diciembre, a las 18.00\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Navidad musical en Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Varios conciertos amenizar\u00e1n los d\u00edas previos a la fiesta de Navidad La m\u00fasica ser\u00e1 la protagonista durante los pr\u00f3ximos d\u00edas con conciertos de distintos estilos musicales para disfrutar de eventos culturales para todos los gustos, organizados por la Mesa de Festejos dentro de la programaci\u00f3n de Navidad. El jueves 17 de diciembre, a las 18.00\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-12-17T11:45:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-12-17T11:45:28+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Navidad musical en Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Varios conciertos amenizar\u00e1n los d\u00edas previos a la fiesta de Navidad La m\u00fasica ser\u00e1 la protagonista durante los pr\u00f3ximos d\u00edas con conciertos de distintos estilos musicales para disfrutar de eventos culturales para todos los gustos, organizados por la Mesa de Festejos dentro de la programaci\u00f3n de Navidad. El jueves 17 de diciembre, a las 18.00\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/17\\\/navidad-musical-en-ciempozuelos-3\\\/#blogposting\",\"name\":\"Navidad musical en Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"Navidad musical en Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-12-17T11:45:28+01:00\",\"dateModified\":\"2015-12-17T11:45:28+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/17\\\/navidad-musical-en-ciempozuelos-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/17\\\/navidad-musical-en-ciempozuelos-3\\\/#webpage\"}},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/17\\\/navidad-musical-en-ciempozuelos-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/17\\\/navidad-musical-en-ciempozuelos-3\\\/#listItem\",\"name\":\"Navidad musical en Ciempozuelos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/17\\\/navidad-musical-en-ciempozuelos-3\\\/#listItem\",\"position\":2,\"name\":\"Navidad musical en Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/17\\\/navidad-musical-en-ciempozuelos-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/17\\\/navidad-musical-en-ciempozuelos-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/17\\\/navidad-musical-en-ciempozuelos-3\\\/\",\"name\":\"Navidad musical en Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"Varios conciertos amenizar\\u00e1n los d\\u00edas previos a la fiesta de Navidad La m\\u00fasica ser\\u00e1 la protagonista durante los pr\\u00f3ximos d\\u00edas con conciertos de distintos estilos musicales para disfrutar de eventos culturales para todos los gustos, organizados por la Mesa de Festejos dentro de la programaci\\u00f3n de Navidad. El jueves 17 de diciembre, a las 18.00\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/17\\\/navidad-musical-en-ciempozuelos-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-12-17T11:45:28+01:00\",\"dateModified\":\"2015-12-17T11:45:28+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Navidad musical en Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"Varios conciertos amenizar\u00e1n los d\u00edas previos a la fiesta de Navidad La m\u00fasica ser\u00e1 la protagonista durante los pr\u00f3ximos d\u00edas con conciertos de distintos estilos musicales para disfrutar de eventos culturales para todos los gustos, organizados por la Mesa de Festejos dentro de la programaci\u00f3n de Navidad. El jueves 17 de diciembre, a las 18.00","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/#blogposting","name":"Navidad musical en Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"Navidad musical en Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-12-17T11:45:28+01:00","dateModified":"2015-12-17T11:45:28+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/#webpage"}},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/#listItem","name":"Navidad musical en Ciempozuelos"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/#listItem","position":2,"name":"Navidad musical en Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/","name":"Navidad musical en Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"Varios conciertos amenizar\u00e1n los d\u00edas previos a la fiesta de Navidad La m\u00fasica ser\u00e1 la protagonista durante los pr\u00f3ximos d\u00edas con conciertos de distintos estilos musicales para disfrutar de eventos culturales para todos los gustos, organizados por la Mesa de Festejos dentro de la programaci\u00f3n de Navidad. El jueves 17 de diciembre, a las 18.00","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-12-17T11:45:28+01:00","dateModified":"2015-12-17T11:45:28+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Navidad musical en Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"Varios conciertos amenizar\u00e1n los d\u00edas previos a la fiesta de Navidad La m\u00fasica ser\u00e1 la protagonista durante los pr\u00f3ximos d\u00edas con conciertos de distintos estilos musicales para disfrutar de eventos culturales para todos los gustos, organizados por la Mesa de Festejos dentro de la programaci\u00f3n de Navidad. El jueves 17 de diciembre, a las 18.00","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/","article:published_time":"2015-12-17T11:45:28+00:00","article:modified_time":"2015-12-17T11:45:28+00:00","twitter:card":"summary","twitter:title":"Navidad musical en Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"Varios conciertos amenizar\u00e1n los d\u00edas previos a la fiesta de Navidad La m\u00fasica ser\u00e1 la protagonista durante los pr\u00f3ximos d\u00edas con conciertos de distintos estilos musicales para disfrutar de eventos culturales para todos los gustos, organizados por la Mesa de Festejos dentro de la programaci\u00f3n de Navidad. El jueves 17 de diciembre, a las 18.00"},"aioseo_meta_data":{"post_id":"13995","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:15:31","updated":"2025-06-04 17:42:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNavidad musical en Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Navidad musical en Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/17\/navidad-musical-en-ciempozuelos-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:48:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=13995"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13995\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=13995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=13995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=13995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}