{"id":13378,"date":"2016-04-08T09:17:41","date_gmt":"2016-04-08T09:17:41","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/"},"modified":"2016-04-08T09:17:41","modified_gmt":"2016-04-08T09:17:41","slug":"convocatoria-del-consejo-de-deportes-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/","title":{"rendered":"Convocatoria del Consejo de Deportes"},"content":{"rendered":"<p style=\"font-size: 12.16px; line-height: 15.808px;\">El Ayuntamiento de Ciempozuelos convoca el Consejo de Deportes el pr\u00f3ximo lunes, 11 de abril, a las 19.00 horas en el Sal\u00f3n de Plenos del Ayuntamiento.<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">El Orden del d\u00eda es el siguiente:<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">1. Normas de convivencia en instalaciones deportivas.<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">2. Ley del Deporte (tabaco y alcohol).<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">3. Certificado de delitos por naturaleza sexual.<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">4. Planificaci\u00f3n de Gesti\u00f3n Deportiva.<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">5. Espacio de utilizaci\u00f3n de clubes.<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">6. Ruegos y preguntas.<\/p>\n<p>Descargar archivo: {jd_file file==629}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Ciempozuelos convoca el Consejo de Deportes el pr\u00f3ximo lunes, 11 de abril, a las 19.00 horas en el Sal\u00f3n de Plenos del Ayuntamiento. El Orden del d\u00eda es el siguiente: 1. Normas de convivencia en instalaciones deportivas. 2. Ley del Deporte (tabaco y alcohol). 3. Certificado de delitos por naturaleza sexual. 4. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1252],"class_list":["post-13378","post","type-post","status-publish","format-standard","hentry","tag-consejo-municipal-de-deportes-deportes"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Ayuntamiento de Ciempozuelos convoca el Consejo de Deportes el pr\u00f3ximo lunes, 11 de abril, a las 19.00 horas en el Sal\u00f3n de Plenos del Ayuntamiento. El Orden del d\u00eda es el siguiente: 1. Normas de convivencia en instalaciones deportivas. 2. Ley del Deporte (tabaco y alcohol). 3. Certificado de delitos por naturaleza sexual. 4.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Convocatoria del Consejo de Deportes - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El Ayuntamiento de Ciempozuelos convoca el Consejo de Deportes el pr\u00f3ximo lunes, 11 de abril, a las 19.00 horas en el Sal\u00f3n de Plenos del Ayuntamiento. El Orden del d\u00eda es el siguiente: 1. Normas de convivencia en instalaciones deportivas. 2. Ley del Deporte (tabaco y alcohol). 3. Certificado de delitos por naturaleza sexual. 4.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-04-08T09:17:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-04-08T09:17:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Convocatoria del Consejo de Deportes - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Ayuntamiento de Ciempozuelos convoca el Consejo de Deportes el pr\u00f3ximo lunes, 11 de abril, a las 19.00 horas en el Sal\u00f3n de Plenos del Ayuntamiento. El Orden del d\u00eda es el siguiente: 1. Normas de convivencia en instalaciones deportivas. 2. Ley del Deporte (tabaco y alcohol). 3. Certificado de delitos por naturaleza sexual. 4.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/08\\\/convocatoria-del-consejo-de-deportes-3\\\/#blogposting\",\"name\":\"Convocatoria del Consejo de Deportes - Ayuntamiento de Ciempozuelos\",\"headline\":\"Convocatoria del Consejo de Deportes\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-04-08T09:17:41+02:00\",\"dateModified\":\"2016-04-08T09:17:41+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/08\\\/convocatoria-del-consejo-de-deportes-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/08\\\/convocatoria-del-consejo-de-deportes-3\\\/#webpage\"},\"articleSection\":\"Consejo Municipal de deportes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/08\\\/convocatoria-del-consejo-de-deportes-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/consejo-municipal-de-deportes-deportes\\\/#listItem\",\"name\":\"Consejo Municipal de deportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/consejo-municipal-de-deportes-deportes\\\/#listItem\",\"position\":2,\"name\":\"Consejo Municipal de deportes\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/consejo-municipal-de-deportes-deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/08\\\/convocatoria-del-consejo-de-deportes-3\\\/#listItem\",\"name\":\"Convocatoria del Consejo de Deportes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/08\\\/convocatoria-del-consejo-de-deportes-3\\\/#listItem\",\"position\":3,\"name\":\"Convocatoria del Consejo de Deportes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/consejo-municipal-de-deportes-deportes\\\/#listItem\",\"name\":\"Consejo Municipal de deportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/08\\\/convocatoria-del-consejo-de-deportes-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/08\\\/convocatoria-del-consejo-de-deportes-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/08\\\/convocatoria-del-consejo-de-deportes-3\\\/\",\"name\":\"Convocatoria del Consejo de Deportes - Ayuntamiento de Ciempozuelos\",\"description\":\"El Ayuntamiento de Ciempozuelos convoca el Consejo de Deportes el pr\\u00f3ximo lunes, 11 de abril, a las 19.00 horas en el Sal\\u00f3n de Plenos del Ayuntamiento. El Orden del d\\u00eda es el siguiente: 1. Normas de convivencia en instalaciones deportivas. 2. Ley del Deporte (tabaco y alcohol). 3. Certificado de delitos por naturaleza sexual. 4.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/08\\\/convocatoria-del-consejo-de-deportes-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-04-08T09:17:41+02:00\",\"dateModified\":\"2016-04-08T09:17:41+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Convocatoria del Consejo de Deportes - Ayuntamiento de Ciempozuelos","description":"El Ayuntamiento de Ciempozuelos convoca el Consejo de Deportes el pr\u00f3ximo lunes, 11 de abril, a las 19.00 horas en el Sal\u00f3n de Plenos del Ayuntamiento. El Orden del d\u00eda es el siguiente: 1. Normas de convivencia en instalaciones deportivas. 2. Ley del Deporte (tabaco y alcohol). 3. Certificado de delitos por naturaleza sexual. 4.","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/#blogposting","name":"Convocatoria del Consejo de Deportes - Ayuntamiento de Ciempozuelos","headline":"Convocatoria del Consejo de Deportes","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-04-08T09:17:41+02:00","dateModified":"2016-04-08T09:17:41+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/#webpage"},"articleSection":"Consejo Municipal de deportes"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/consejo-municipal-de-deportes-deportes\/#listItem","name":"Consejo Municipal de deportes"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/consejo-municipal-de-deportes-deportes\/#listItem","position":2,"name":"Consejo Municipal de deportes","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/consejo-municipal-de-deportes-deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/#listItem","name":"Convocatoria del Consejo de Deportes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/#listItem","position":3,"name":"Convocatoria del Consejo de Deportes","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/consejo-municipal-de-deportes-deportes\/#listItem","name":"Consejo Municipal de deportes"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/","name":"Convocatoria del Consejo de Deportes - Ayuntamiento de Ciempozuelos","description":"El Ayuntamiento de Ciempozuelos convoca el Consejo de Deportes el pr\u00f3ximo lunes, 11 de abril, a las 19.00 horas en el Sal\u00f3n de Plenos del Ayuntamiento. El Orden del d\u00eda es el siguiente: 1. Normas de convivencia en instalaciones deportivas. 2. Ley del Deporte (tabaco y alcohol). 3. Certificado de delitos por naturaleza sexual. 4.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-04-08T09:17:41+02:00","dateModified":"2016-04-08T09:17:41+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Convocatoria del Consejo de Deportes - Ayuntamiento de Ciempozuelos","og:description":"El Ayuntamiento de Ciempozuelos convoca el Consejo de Deportes el pr\u00f3ximo lunes, 11 de abril, a las 19.00 horas en el Sal\u00f3n de Plenos del Ayuntamiento. El Orden del d\u00eda es el siguiente: 1. Normas de convivencia en instalaciones deportivas. 2. Ley del Deporte (tabaco y alcohol). 3. Certificado de delitos por naturaleza sexual. 4.","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/","article:published_time":"2016-04-08T09:17:41+00:00","article:modified_time":"2016-04-08T09:17:41+00:00","twitter:card":"summary","twitter:title":"Convocatoria del Consejo de Deportes - Ayuntamiento de Ciempozuelos","twitter:description":"El Ayuntamiento de Ciempozuelos convoca el Consejo de Deportes el pr\u00f3ximo lunes, 11 de abril, a las 19.00 horas en el Sal\u00f3n de Plenos del Ayuntamiento. El Orden del d\u00eda es el siguiente: 1. Normas de convivencia en instalaciones deportivas. 2. Ley del Deporte (tabaco y alcohol). 3. Certificado de delitos por naturaleza sexual. 4."},"aioseo_meta_data":{"post_id":"13378","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:55:03","updated":"2025-06-04 18:19:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/consejo-municipal-de-deportes-deportes\/\" title=\"Consejo Municipal de deportes\">Consejo Municipal de deportes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tConvocatoria del Consejo de Deportes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Consejo Municipal de deportes","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/consejo-municipal-de-deportes-deportes\/"},{"label":"Convocatoria del Consejo de Deportes","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/08\/convocatoria-del-consejo-de-deportes-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:08:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=13378"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13378\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=13378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=13378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=13378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}