{"id":13343,"date":"2016-01-20T10:00:05","date_gmt":"2016-01-20T10:00:05","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/"},"modified":"2016-01-20T10:00:05","modified_gmt":"2016-01-20T10:00:05","slug":"nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/","title":{"rendered":"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\"><span style=\"text-align: justify; font-size: 12.16px; line-height: 1.3em;\"><em>En este encuentro se informar\u00e1 sobre la ordenanza de terrazas y la ruta de la tapa, entre otros asuntos<\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El Ayuntamiento de Ciempozuelos informa sobre la pr\u00f3xima celebraci\u00f3n de una nueva reuni\u00f3n los hosteleros del municipio este viernes, 22 de enero, a las 11.00 horas en el sal\u00f3n de plenos de la Casa Consistorial. El objetivo es informar sobre las novedades y continuar avanzando en la colaboraci\u00f3n entre el sector y la Administraci\u00f3n local.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Entre los temas que se abordar\u00e1n destaca la presentaci\u00f3n de la ordenanza de terrazas y la informaci\u00f3n relativa a la ruta de la tapa con una empresa cervecera. Adem\u00e1s, se preparar\u00e1n nuevas iniciativas y actividades para dinamizar e impulsar el sector hostelero de Ciempozuelos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Desde el Ayuntamiento se anima a todos los interesados a sumarse a estos encuentros. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este encuentro se informar\u00e1 sobre la ordenanza de terrazas y la ruta de la tapa, entre otros asuntos El Ayuntamiento de Ciempozuelos informa sobre la pr\u00f3xima celebraci\u00f3n de una nueva reuni\u00f3n los hosteleros del municipio este viernes, 22 de enero, a las 11.00 horas en el sal\u00f3n de plenos de la Casa Consistorial. El [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1150],"class_list":["post-13343","post","type-post","status-publish","format-standard","hentry","tag-comercio-local"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En este encuentro se informar\u00e1 sobre la ordenanza de terrazas y la ruta de la tapa, entre otros asuntos El Ayuntamiento de Ciempozuelos informa sobre la pr\u00f3xima celebraci\u00f3n de una nueva reuni\u00f3n los hosteleros del municipio este viernes, 22 de enero, a las 11.00 horas en el sal\u00f3n de plenos de la Casa Consistorial. El\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"En este encuentro se informar\u00e1 sobre la ordenanza de terrazas y la ruta de la tapa, entre otros asuntos El Ayuntamiento de Ciempozuelos informa sobre la pr\u00f3xima celebraci\u00f3n de una nueva reuni\u00f3n los hosteleros del municipio este viernes, 22 de enero, a las 11.00 horas en el sal\u00f3n de plenos de la Casa Consistorial. El\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-20T10:00:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-20T10:00:05+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En este encuentro se informar\u00e1 sobre la ordenanza de terrazas y la ruta de la tapa, entre otros asuntos El Ayuntamiento de Ciempozuelos informa sobre la pr\u00f3xima celebraci\u00f3n de una nueva reuni\u00f3n los hosteleros del municipio este viernes, 22 de enero, a las 11.00 horas en el sal\u00f3n de plenos de la Casa Consistorial. El\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/20\\\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\\\/#blogposting\",\"name\":\"Nueva reuni\\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"Nueva reuni\\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-01-20T10:00:05+01:00\",\"dateModified\":\"2016-01-20T10:00:05+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/20\\\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/20\\\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\\\/#webpage\"},\"articleSection\":\"Comercio Local\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/20\\\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/comercio-local\\\/#listItem\",\"name\":\"Comercio Local\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/comercio-local\\\/#listItem\",\"position\":2,\"name\":\"Comercio Local\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/comercio-local\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/20\\\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\\\/#listItem\",\"name\":\"Nueva reuni\\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/20\\\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\\\/#listItem\",\"position\":3,\"name\":\"Nueva reuni\\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/comercio-local\\\/#listItem\",\"name\":\"Comercio Local\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/20\\\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/20\\\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/20\\\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\\\/\",\"name\":\"Nueva reuni\\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"En este encuentro se informar\\u00e1 sobre la ordenanza de terrazas y la ruta de la tapa, entre otros asuntos El Ayuntamiento de Ciempozuelos informa sobre la pr\\u00f3xima celebraci\\u00f3n de una nueva reuni\\u00f3n los hosteleros del municipio este viernes, 22 de enero, a las 11.00 horas en el sal\\u00f3n de plenos de la Casa Consistorial. El\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/20\\\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-01-20T10:00:05+01:00\",\"dateModified\":\"2016-01-20T10:00:05+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"En este encuentro se informar\u00e1 sobre la ordenanza de terrazas y la ruta de la tapa, entre otros asuntos El Ayuntamiento de Ciempozuelos informa sobre la pr\u00f3xima celebraci\u00f3n de una nueva reuni\u00f3n los hosteleros del municipio este viernes, 22 de enero, a las 11.00 horas en el sal\u00f3n de plenos de la Casa Consistorial. El","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/#blogposting","name":"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-01-20T10:00:05+01:00","dateModified":"2016-01-20T10:00:05+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/#webpage"},"articleSection":"Comercio Local"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/comercio-local\/#listItem","name":"Comercio Local"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/comercio-local\/#listItem","position":2,"name":"Comercio Local","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/comercio-local\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/#listItem","name":"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/#listItem","position":3,"name":"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/comercio-local\/#listItem","name":"Comercio Local"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/","name":"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"En este encuentro se informar\u00e1 sobre la ordenanza de terrazas y la ruta de la tapa, entre otros asuntos El Ayuntamiento de Ciempozuelos informa sobre la pr\u00f3xima celebraci\u00f3n de una nueva reuni\u00f3n los hosteleros del municipio este viernes, 22 de enero, a las 11.00 horas en el sal\u00f3n de plenos de la Casa Consistorial. El","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-01-20T10:00:05+01:00","dateModified":"2016-01-20T10:00:05+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"En este encuentro se informar\u00e1 sobre la ordenanza de terrazas y la ruta de la tapa, entre otros asuntos El Ayuntamiento de Ciempozuelos informa sobre la pr\u00f3xima celebraci\u00f3n de una nueva reuni\u00f3n los hosteleros del municipio este viernes, 22 de enero, a las 11.00 horas en el sal\u00f3n de plenos de la Casa Consistorial. El","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/","article:published_time":"2016-01-20T10:00:05+00:00","article:modified_time":"2016-01-20T10:00:05+00:00","twitter:card":"summary","twitter:title":"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"En este encuentro se informar\u00e1 sobre la ordenanza de terrazas y la ruta de la tapa, entre otros asuntos El Ayuntamiento de Ciempozuelos informa sobre la pr\u00f3xima celebraci\u00f3n de una nueva reuni\u00f3n los hosteleros del municipio este viernes, 22 de enero, a las 11.00 horas en el sal\u00f3n de plenos de la Casa Consistorial. El"},"aioseo_meta_data":{"post_id":"13343","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:24:04","updated":"2025-06-04 17:51:00","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/comercio-local\/\" title=\"Comercio Local\">Comercio Local<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Comercio Local","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/comercio-local\/"},{"label":"Nueva reuni\u00f3n del Ayuntamiento con los hosteleros de Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/20\/nueva-reunion-del-ayuntamiento-con-los-hosteleros-de-ciempozuelos-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:20:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=13343"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13343\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=13343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=13343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=13343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}