{"id":13334,"date":"2015-12-02T12:00:08","date_gmt":"2015-12-02T12:00:08","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/"},"modified":"2015-12-02T12:00:08","modified_gmt":"2015-12-02T12:00:08","slug":"fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/","title":{"rendered":"Fallo del Ciclo de Cortos infantiles de Ciempozuelos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><em>El p\u00fablico otorg\u00f3 el primer premio al corto \u2018Mi pap\u00e1 es director de cine\u2019<\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Tras el recuento de las votaciones, se ha dado a conocer el fallo del p\u00fablico del Ciclo de Cortos infantiles de CortoEspa\u00f1a en Ciempozuelos. El primer premio ha sido para al corto \u2018Mi pap\u00e1 es director de cine\u2019 del director Germ\u00e1n Roda, con la interpretaci\u00f3n de Alba Roda y Natalia Ruiz. El corto ha obtenido 199 votos en los dos d\u00edas de votaciones.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El segundo lugar, con 198 votos, ha sido para \u2018El vendedor de humo\u2019, un corto de animaci\u00f3n bajo la direcci\u00f3n de Jaime Maestro. \u2018Academia Especialistas\u2019 ha obtenido el tercer puesto con un total de 179 votos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">En esta primera edici\u00f3n del Ciclo de Cortos infantiles en Ciempozuelos de CortoEspa\u00f1a, que tuvo lugar el pasado mes de noviembre en la Sala Multifuncional de Ciempozuelos, han participado siete cortometrajes de tem\u00e1tica infantil. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><img decoding=\"async\" class=\" size-full wp-image-10685\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/ganador-corto-cortoespaa.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/ganador-corto-cortoespaa-200x141.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/ganador-corto-cortoespaa-300x212.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/ganador-corto-cortoespaa-400x283.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/ganador-corto-cortoespaa-600x424.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/ganador-corto-cortoespaa-768x543.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/ganador-corto-cortoespaa-800x565.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/ganador-corto-cortoespaa.jpg 842w\" sizes=\"(max-width: 842px) 100vw, 842px\" \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El p\u00fablico otorg\u00f3 el primer premio al corto \u2018Mi pap\u00e1 es director de cine\u2019 Tras el recuento de las votaciones, se ha dado a conocer el fallo del p\u00fablico del Ciclo de Cortos infantiles de CortoEspa\u00f1a en Ciempozuelos. El primer premio ha sido para al corto \u2018Mi pap\u00e1 es director de cine\u2019 del director Germ\u00e1n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1144],"class_list":["post-13334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-cultura-noelia-fernandez-concejalias"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El p\u00fablico otorg\u00f3 el primer premio al corto \u2018Mi pap\u00e1 es director de cine\u2019 Tras el recuento de las votaciones, se ha dado a conocer el fallo del p\u00fablico del Ciclo de Cortos infantiles de CortoEspa\u00f1a en Ciempozuelos. El primer premio ha sido para al corto \u2018Mi pap\u00e1 es director de cine\u2019 del director Germ\u00e1n\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fallo del Ciclo de Cortos infantiles de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El p\u00fablico otorg\u00f3 el primer premio al corto \u2018Mi pap\u00e1 es director de cine\u2019 Tras el recuento de las votaciones, se ha dado a conocer el fallo del p\u00fablico del Ciclo de Cortos infantiles de CortoEspa\u00f1a en Ciempozuelos. El primer premio ha sido para al corto \u2018Mi pap\u00e1 es director de cine\u2019 del director Germ\u00e1n\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-12-02T12:00:08+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-12-02T12:00:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fallo del Ciclo de Cortos infantiles de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El p\u00fablico otorg\u00f3 el primer premio al corto \u2018Mi pap\u00e1 es director de cine\u2019 Tras el recuento de las votaciones, se ha dado a conocer el fallo del p\u00fablico del Ciclo de Cortos infantiles de CortoEspa\u00f1a en Ciempozuelos. El primer premio ha sido para al corto \u2018Mi pap\u00e1 es director de cine\u2019 del director Germ\u00e1n\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/#blogposting\",\"name\":\"Fallo del Ciclo de Cortos infantiles de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"Fallo del Ciclo de Cortos infantiles de Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/ganador-corto-cortoespaa.jpg\",\"width\":842,\"height\":595},\"datePublished\":\"2015-12-02T12:00:08+01:00\",\"dateModified\":\"2015-12-02T12:00:08+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/#webpage\"},\"articleSection\":\"Cultura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/cultura-noelia-fernandez-concejalias\\\/#listItem\",\"name\":\"Cultura\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/cultura-noelia-fernandez-concejalias\\\/#listItem\",\"position\":2,\"name\":\"Cultura\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/cultura-noelia-fernandez-concejalias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/#listItem\",\"name\":\"Fallo del Ciclo de Cortos infantiles de Ciempozuelos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/#listItem\",\"position\":3,\"name\":\"Fallo del Ciclo de Cortos infantiles de Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/cultura-noelia-fernandez-concejalias\\\/#listItem\",\"name\":\"Cultura\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/\",\"name\":\"Fallo del Ciclo de Cortos infantiles de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"El p\\u00fablico otorg\\u00f3 el primer premio al corto \\u2018Mi pap\\u00e1 es director de cine\\u2019 Tras el recuento de las votaciones, se ha dado a conocer el fallo del p\\u00fablico del Ciclo de Cortos infantiles de CortoEspa\\u00f1a en Ciempozuelos. El primer premio ha sido para al corto \\u2018Mi pap\\u00e1 es director de cine\\u2019 del director Germ\\u00e1n\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/ganador-corto-cortoespaa.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/#mainImage\",\"width\":842,\"height\":595},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\\\/#mainImage\"},\"datePublished\":\"2015-12-02T12:00:08+01:00\",\"dateModified\":\"2015-12-02T12:00:08+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Fallo del Ciclo de Cortos infantiles de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"El p\u00fablico otorg\u00f3 el primer premio al corto \u2018Mi pap\u00e1 es director de cine\u2019 Tras el recuento de las votaciones, se ha dado a conocer el fallo del p\u00fablico del Ciclo de Cortos infantiles de CortoEspa\u00f1a en Ciempozuelos. El primer premio ha sido para al corto \u2018Mi pap\u00e1 es director de cine\u2019 del director Germ\u00e1n","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/#blogposting","name":"Fallo del Ciclo de Cortos infantiles de Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"Fallo del Ciclo de Cortos infantiles de Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/ganador-corto-cortoespaa.jpg","width":842,"height":595},"datePublished":"2015-12-02T12:00:08+01:00","dateModified":"2015-12-02T12:00:08+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/#webpage"},"articleSection":"Cultura"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/#listItem","name":"Cultura"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/#listItem","position":2,"name":"Cultura","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/#listItem","name":"Fallo del Ciclo de Cortos infantiles de Ciempozuelos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/#listItem","position":3,"name":"Fallo del Ciclo de Cortos infantiles de Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/#listItem","name":"Cultura"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/","name":"Fallo del Ciclo de Cortos infantiles de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"El p\u00fablico otorg\u00f3 el primer premio al corto \u2018Mi pap\u00e1 es director de cine\u2019 Tras el recuento de las votaciones, se ha dado a conocer el fallo del p\u00fablico del Ciclo de Cortos infantiles de CortoEspa\u00f1a en Ciempozuelos. El primer premio ha sido para al corto \u2018Mi pap\u00e1 es director de cine\u2019 del director Germ\u00e1n","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/ganador-corto-cortoespaa.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/#mainImage","width":842,"height":595},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/#mainImage"},"datePublished":"2015-12-02T12:00:08+01:00","dateModified":"2015-12-02T12:00:08+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Fallo del Ciclo de Cortos infantiles de Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"El p\u00fablico otorg\u00f3 el primer premio al corto \u2018Mi pap\u00e1 es director de cine\u2019 Tras el recuento de las votaciones, se ha dado a conocer el fallo del p\u00fablico del Ciclo de Cortos infantiles de CortoEspa\u00f1a en Ciempozuelos. El primer premio ha sido para al corto \u2018Mi pap\u00e1 es director de cine\u2019 del director Germ\u00e1n","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/","article:published_time":"2015-12-02T12:00:08+00:00","article:modified_time":"2015-12-02T12:00:08+00:00","twitter:card":"summary","twitter:title":"Fallo del Ciclo de Cortos infantiles de Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"El p\u00fablico otorg\u00f3 el primer premio al corto \u2018Mi pap\u00e1 es director de cine\u2019 Tras el recuento de las votaciones, se ha dado a conocer el fallo del p\u00fablico del Ciclo de Cortos infantiles de CortoEspa\u00f1a en Ciempozuelos. El primer premio ha sido para al corto \u2018Mi pap\u00e1 es director de cine\u2019 del director Germ\u00e1n"},"aioseo_meta_data":{"post_id":"13334","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:10:56","updated":"2025-06-04 17:38:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/\" title=\"Cultura\">Cultura<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFallo del Ciclo de Cortos infantiles de Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Cultura","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/"},{"label":"Fallo del Ciclo de Cortos infantiles de Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/fallo-del-ciclo-de-cortos-infantiles-de-ciempozuelos-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:07:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=13334"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10685"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=13334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=13334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=13334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}