{"id":13333,"date":"2015-12-02T09:39:58","date_gmt":"2015-12-02T09:39:58","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/"},"modified":"2015-12-02T09:39:58","modified_gmt":"2015-12-02T09:39:58","slug":"a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/","title":{"rendered":"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales?"},"content":{"rendered":"<div class=\"WordSection1\" style=\"font-size: 12.16px; line-height: 15.808px;\">\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Las instalaciones destinadas al f\u00fatbol en Ciempozuelos estaban distribuidas, hasta este a\u00f1o, en base a un sistema de reparto irregular entre los clubes de f\u00fatbol de la localidad.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Desde el inicio de la nueva legislatura se trabaja desde el \u00e1rea de Deportes por solucionar esa situaci\u00f3n y por permitir que todos los clubes de Ciempozuelos dispongan de un n\u00famero de espacios equitativo, tanto en las instalaciones del campo de la Ciudad Deportiva como en las de Pe\u00f1uelas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Desde agosto se han mantenido, por parte del concejal de deportes y de la alcaldesa, reuniones con representantes de clubes y partidos pol\u00edticos de la localidad donde se acord\u00f3 que, efectivamente, era necesario proceder a un reparto m\u00e1s justo y equitativo.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Entonces, desde la concejal\u00eda se trabaj\u00f3 en realizar el reparto de los espacios municipales atendiendo a la necesidad y al n\u00famero de clubes. En los gr\u00e1ficos anexos se aprecia la distribuci\u00f3n, tanto en Pe\u00f1uelas como en la Ciudad Deportiva.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Esta es una tarea de fondo que de momento no ha sido implementada en su totalidad por una cuesti\u00f3n de plazos. A esta redistribuci\u00f3n de espacios hay que sumar el trabajo contrarreloj para que estas instalaciones se encuentren en las condiciones adecuadas y, para ello, se realizar\u00e1n las obras de acondicionamiento oportunas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><strong>El bar\/kiosko de Pe\u00f1uelas<\/strong> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">Antes del inicio de la pretemporada se acord\u00f3 en una reuni\u00f3n entre representantes de los clubes, la alcaldesa y el concejal de deportes que los clubes alternar\u00edan su gesti\u00f3n: cada dos semanas una entidad asumir\u00eda la administraci\u00f3n. Este acuerdo permit\u00eda seguir ofreciendo este servicio hasta que el Ayuntamiento regulase su situaci\u00f3n.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Despu\u00e9s de dos meses, este acuerdo se ha roto. Coincide esta situaci\u00f3n con un informe del equipo t\u00e9cnico del \u00e1rea de urbanismo del Ayuntamiento que advierte sobre posible deficiencias en la instalaci\u00f3n del bar. El pasado s\u00e1bado se procedi\u00f3 a su cierre, aunque desde el Ayuntamiento de Ciempozuelos se trabaja para restablecer lo antes posible el servicio de bar en Pe\u00f1uelas, atendiendo a las necesidades t\u00e9cnicas y legales, as\u00ed como a su correcta ubicaci\u00f3n.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Tambi\u00e9n se procura desde el Ayuntamiento la mediaci\u00f3n entre los clubes para hacer efectivo ese reparto justo y, porque no puede ser de otra forma, fomentar el deporte en Ciempozuelos y sus valores de compa\u00f1erismo y respeto frente cualquier tipo de rivalidad.<\/span><\/p>\n<\/div>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\"><img decoding=\"async\" class=\" size-full wp-image-10670\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-scaled.jpg\" border=\"0\" width=\"100%\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-200x226.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-266x300.jpg 266w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-400x452.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-600x677.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-768x867.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-800x903.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-907x1024.jpg 907w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-1200x1355.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-1360x1536.jpg 1360w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-1814x2048.jpg 1814w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-scaled.jpg 2267w\" sizes=\"(max-width: 2267px) 100vw, 2267px\" \/><\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\"><img decoding=\"async\" class=\" size-full wp-image-10671\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-scaled.jpg\" border=\"0\" width=\"100%\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-200x222.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-270x300.jpg 270w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-400x445.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-600x667.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-768x854.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-800x890.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-920x1024.jpg 920w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-1200x1335.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-1381x1536.jpg 1381w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-1841x2048.jpg 1841w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_peuelas-scaled.jpg 2301w\" sizes=\"(max-width: 2301px) 100vw, 2301px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las instalaciones destinadas al f\u00fatbol en Ciempozuelos estaban distribuidas, hasta este a\u00f1o, en base a un sistema de reparto irregular entre los clubes de f\u00fatbol de la localidad. Desde el inicio de la nueva legislatura se trabaja desde el \u00e1rea de Deportes por solucionar esa situaci\u00f3n y por permitir que todos los clubes de Ciempozuelos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1240],"class_list":["post-13333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-instalaciones-deportes"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las instalaciones destinadas al f\u00fatbol en Ciempozuelos estaban distribuidas, hasta este a\u00f1o, en base a un sistema de reparto irregular entre los clubes de f\u00fatbol de la localidad. Desde el inicio de la nueva legislatura se trabaja desde el \u00e1rea de Deportes por solucionar esa situaci\u00f3n y por permitir que todos los clubes de Ciempozuelos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales? - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Las instalaciones destinadas al f\u00fatbol en Ciempozuelos estaban distribuidas, hasta este a\u00f1o, en base a un sistema de reparto irregular entre los clubes de f\u00fatbol de la localidad. Desde el inicio de la nueva legislatura se trabaja desde el \u00e1rea de Deportes por solucionar esa situaci\u00f3n y por permitir que todos los clubes de Ciempozuelos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-12-02T09:39:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-12-02T09:39:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales? - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las instalaciones destinadas al f\u00fatbol en Ciempozuelos estaban distribuidas, hasta este a\u00f1o, en base a un sistema de reparto irregular entre los clubes de f\u00fatbol de la localidad. Desde el inicio de la nueva legislatura se trabaja desde el \u00e1rea de Deportes por solucionar esa situaci\u00f3n y por permitir que todos los clubes de Ciempozuelos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/#blogposting\",\"name\":\"\\u00bfA qu\\u00e9 responde la reestructuraci\\u00f3n de espacios deportivos municipales? - Ayuntamiento de Ciempozuelos\",\"headline\":\"\\u00bfA qu\\u00e9 responde la reestructuraci\\u00f3n de espacios deportivos municipales?\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/reparto_ciudad_deportiva-scaled.jpg\",\"width\":2267,\"height\":2560},\"datePublished\":\"2015-12-02T09:39:58+01:00\",\"dateModified\":\"2015-12-02T09:39:58+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/#webpage\"},\"articleSection\":\"Instalaciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/#listItem\",\"name\":\"Instalaciones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/#listItem\",\"position\":2,\"name\":\"Instalaciones\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/#listItem\",\"name\":\"\\u00bfA qu\\u00e9 responde la reestructuraci\\u00f3n de espacios deportivos municipales?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/#listItem\",\"position\":3,\"name\":\"\\u00bfA qu\\u00e9 responde la reestructuraci\\u00f3n de espacios deportivos municipales?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/#listItem\",\"name\":\"Instalaciones\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/\",\"name\":\"\\u00bfA qu\\u00e9 responde la reestructuraci\\u00f3n de espacios deportivos municipales? - Ayuntamiento de Ciempozuelos\",\"description\":\"Las instalaciones destinadas al f\\u00fatbol en Ciempozuelos estaban distribuidas, hasta este a\\u00f1o, en base a un sistema de reparto irregular entre los clubes de f\\u00fatbol de la localidad. Desde el inicio de la nueva legislatura se trabaja desde el \\u00e1rea de Deportes por solucionar esa situaci\\u00f3n y por permitir que todos los clubes de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/reparto_ciudad_deportiva-scaled.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/#mainImage\",\"width\":2267,\"height\":2560},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/02\\\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\\\/#mainImage\"},\"datePublished\":\"2015-12-02T09:39:58+01:00\",\"dateModified\":\"2015-12-02T09:39:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales? - Ayuntamiento de Ciempozuelos","description":"Las instalaciones destinadas al f\u00fatbol en Ciempozuelos estaban distribuidas, hasta este a\u00f1o, en base a un sistema de reparto irregular entre los clubes de f\u00fatbol de la localidad. Desde el inicio de la nueva legislatura se trabaja desde el \u00e1rea de Deportes por solucionar esa situaci\u00f3n y por permitir que todos los clubes de Ciempozuelos","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/#blogposting","name":"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales? - Ayuntamiento de Ciempozuelos","headline":"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales?","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-scaled.jpg","width":2267,"height":2560},"datePublished":"2015-12-02T09:39:58+01:00","dateModified":"2015-12-02T09:39:58+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/#webpage"},"articleSection":"Instalaciones"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/#listItem","name":"Instalaciones"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/#listItem","position":2,"name":"Instalaciones","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/#listItem","name":"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/#listItem","position":3,"name":"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales?","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/#listItem","name":"Instalaciones"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/","name":"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales? - Ayuntamiento de Ciempozuelos","description":"Las instalaciones destinadas al f\u00fatbol en Ciempozuelos estaban distribuidas, hasta este a\u00f1o, en base a un sistema de reparto irregular entre los clubes de f\u00fatbol de la localidad. Desde el inicio de la nueva legislatura se trabaja desde el \u00e1rea de Deportes por solucionar esa situaci\u00f3n y por permitir que todos los clubes de Ciempozuelos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/12\/reparto_ciudad_deportiva-scaled.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/#mainImage","width":2267,"height":2560},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/#mainImage"},"datePublished":"2015-12-02T09:39:58+01:00","dateModified":"2015-12-02T09:39:58+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales? - Ayuntamiento de Ciempozuelos","og:description":"Las instalaciones destinadas al f\u00fatbol en Ciempozuelos estaban distribuidas, hasta este a\u00f1o, en base a un sistema de reparto irregular entre los clubes de f\u00fatbol de la localidad. Desde el inicio de la nueva legislatura se trabaja desde el \u00e1rea de Deportes por solucionar esa situaci\u00f3n y por permitir que todos los clubes de Ciempozuelos","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/","article:published_time":"2015-12-02T09:39:58+00:00","article:modified_time":"2015-12-02T09:39:58+00:00","twitter:card":"summary","twitter:title":"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales? - Ayuntamiento de Ciempozuelos","twitter:description":"Las instalaciones destinadas al f\u00fatbol en Ciempozuelos estaban distribuidas, hasta este a\u00f1o, en base a un sistema de reparto irregular entre los clubes de f\u00fatbol de la localidad. Desde el inicio de la nueva legislatura se trabaja desde el \u00e1rea de Deportes por solucionar esa situaci\u00f3n y por permitir que todos los clubes de Ciempozuelos"},"aioseo_meta_data":{"post_id":"13333","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:10:56","updated":"2025-06-04 17:37:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/\" title=\"Instalaciones\">Instalaciones<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Instalaciones","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/"},{"label":"\u00bfA qu\u00e9 responde la reestructuraci\u00f3n de espacios deportivos municipales?","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/02\/a-que-responde-la-reestructuracion-de-espacios-deportivos-municipales-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:55:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=13333"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10670"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=13333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=13333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=13333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}