{"id":13319,"date":"2015-11-03T13:09:03","date_gmt":"2015-11-03T13:09:03","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/"},"modified":"2015-11-03T13:09:03","modified_gmt":"2015-11-03T13:09:03","slug":"el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/","title":{"rendered":"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><em>Los alumnos que lo deseen podr\u00e1n realizar sus trabajos de fin de carrera<\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El Ayuntamiento de Ciempozuelos ha establecido, junto con la Universidad Polit\u00e9cnica de Madrid (UPM), un convenio de cooperaci\u00f3n educativa con el objeto de acercar la formaci\u00f3n universitaria a la realidad social y profesional. Estas pr\u00e1cticas permitir\u00e1n completar el proceso formativo del alumnado con una puesta en pr\u00e1ctica de los conocimientos te\u00f3ricos adquiridos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Con el fin de facilitar la posterior incorporaci\u00f3n al mundo laboral, los estudiantes de grado y posgrado que lo deseen podr\u00e1n concursar a las plazas ofertadas por el Ayuntamiento, en colaboraci\u00f3n con la Universidad. Estas actividades formativas se incluir\u00e1n en el expediente acad\u00e9mico del alumno como pr\u00e1cticas curriculares o extracurriculares.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">As\u00ed mismo, los estudiantes que deseen realizar su Trabajo Fin de Grado (TFG), Trabajo Fin de M\u00e1ster (TFM), Proyecto Fin de Carrera (PFC) o Tesis Doctoral (TD), tambi\u00e9n podr\u00e1n suscribirse a este acuerdo.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos que lo deseen podr\u00e1n realizar sus trabajos de fin de carrera El Ayuntamiento de Ciempozuelos ha establecido, junto con la Universidad Polit\u00e9cnica de Madrid (UPM), un convenio de cooperaci\u00f3n educativa con el objeto de acercar la formaci\u00f3n universitaria a la realidad social y profesional. Estas pr\u00e1cticas permitir\u00e1n completar el proceso formativo del alumnado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1154],"class_list":["post-13319","post","type-post","status-publish","format-standard","hentry","tag-empleo-ruben-iglesias-garcia-concejalias"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los alumnos que lo deseen podr\u00e1n realizar sus trabajos de fin de carrera El Ayuntamiento de Ciempozuelos ha establecido, junto con la Universidad Polit\u00e9cnica de Madrid (UPM), un convenio de cooperaci\u00f3n educativa con el objeto de acercar la formaci\u00f3n universitaria a la realidad social y profesional. Estas pr\u00e1cticas permitir\u00e1n completar el proceso formativo del alumnado\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Los alumnos que lo deseen podr\u00e1n realizar sus trabajos de fin de carrera El Ayuntamiento de Ciempozuelos ha establecido, junto con la Universidad Polit\u00e9cnica de Madrid (UPM), un convenio de cooperaci\u00f3n educativa con el objeto de acercar la formaci\u00f3n universitaria a la realidad social y profesional. Estas pr\u00e1cticas permitir\u00e1n completar el proceso formativo del alumnado\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-11-03T13:09:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-11-03T13:09:03+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los alumnos que lo deseen podr\u00e1n realizar sus trabajos de fin de carrera El Ayuntamiento de Ciempozuelos ha establecido, junto con la Universidad Polit\u00e9cnica de Madrid (UPM), un convenio de cooperaci\u00f3n educativa con el objeto de acercar la formaci\u00f3n universitaria a la realidad social y profesional. Estas pr\u00e1cticas permitir\u00e1n completar el proceso formativo del alumnado\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/03\\\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\\\/#blogposting\",\"name\":\"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\\u00f3n educativa con la Universidad Polit\\u00e9cnica - Ayuntamiento de Ciempozuelos\",\"headline\":\"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\\u00f3n educativa con la Universidad Polit\\u00e9cnica\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-11-03T13:09:03+01:00\",\"dateModified\":\"2015-11-03T13:09:03+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/03\\\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/03\\\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\\\/#webpage\"},\"articleSection\":\"Empleo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/03\\\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/empleo-ruben-iglesias-garcia-concejalias\\\/#listItem\",\"name\":\"Empleo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/empleo-ruben-iglesias-garcia-concejalias\\\/#listItem\",\"position\":2,\"name\":\"Empleo\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/empleo-ruben-iglesias-garcia-concejalias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/03\\\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\\\/#listItem\",\"name\":\"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\\u00f3n educativa con la Universidad Polit\\u00e9cnica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/03\\\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\\\/#listItem\",\"position\":3,\"name\":\"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\\u00f3n educativa con la Universidad Polit\\u00e9cnica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/empleo-ruben-iglesias-garcia-concejalias\\\/#listItem\",\"name\":\"Empleo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/03\\\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/03\\\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/03\\\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\\\/\",\"name\":\"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\\u00f3n educativa con la Universidad Polit\\u00e9cnica - Ayuntamiento de Ciempozuelos\",\"description\":\"Los alumnos que lo deseen podr\\u00e1n realizar sus trabajos de fin de carrera El Ayuntamiento de Ciempozuelos ha establecido, junto con la Universidad Polit\\u00e9cnica de Madrid (UPM), un convenio de cooperaci\\u00f3n educativa con el objeto de acercar la formaci\\u00f3n universitaria a la realidad social y profesional. Estas pr\\u00e1cticas permitir\\u00e1n completar el proceso formativo del alumnado\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/03\\\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-11-03T13:09:03+01:00\",\"dateModified\":\"2015-11-03T13:09:03+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica - Ayuntamiento de Ciempozuelos","description":"Los alumnos que lo deseen podr\u00e1n realizar sus trabajos de fin de carrera El Ayuntamiento de Ciempozuelos ha establecido, junto con la Universidad Polit\u00e9cnica de Madrid (UPM), un convenio de cooperaci\u00f3n educativa con el objeto de acercar la formaci\u00f3n universitaria a la realidad social y profesional. Estas pr\u00e1cticas permitir\u00e1n completar el proceso formativo del alumnado","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/#blogposting","name":"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica - Ayuntamiento de Ciempozuelos","headline":"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-11-03T13:09:03+01:00","dateModified":"2015-11-03T13:09:03+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/#webpage"},"articleSection":"Empleo"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia-concejalias\/#listItem","name":"Empleo"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia-concejalias\/#listItem","position":2,"name":"Empleo","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia-concejalias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/#listItem","name":"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/#listItem","position":3,"name":"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia-concejalias\/#listItem","name":"Empleo"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/","name":"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica - Ayuntamiento de Ciempozuelos","description":"Los alumnos que lo deseen podr\u00e1n realizar sus trabajos de fin de carrera El Ayuntamiento de Ciempozuelos ha establecido, junto con la Universidad Polit\u00e9cnica de Madrid (UPM), un convenio de cooperaci\u00f3n educativa con el objeto de acercar la formaci\u00f3n universitaria a la realidad social y profesional. Estas pr\u00e1cticas permitir\u00e1n completar el proceso formativo del alumnado","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-11-03T13:09:03+01:00","dateModified":"2015-11-03T13:09:03+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica - Ayuntamiento de Ciempozuelos","og:description":"Los alumnos que lo deseen podr\u00e1n realizar sus trabajos de fin de carrera El Ayuntamiento de Ciempozuelos ha establecido, junto con la Universidad Polit\u00e9cnica de Madrid (UPM), un convenio de cooperaci\u00f3n educativa con el objeto de acercar la formaci\u00f3n universitaria a la realidad social y profesional. Estas pr\u00e1cticas permitir\u00e1n completar el proceso formativo del alumnado","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/","article:published_time":"2015-11-03T13:09:03+00:00","article:modified_time":"2015-11-03T13:09:03+00:00","twitter:card":"summary","twitter:title":"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica - Ayuntamiento de Ciempozuelos","twitter:description":"Los alumnos que lo deseen podr\u00e1n realizar sus trabajos de fin de carrera El Ayuntamiento de Ciempozuelos ha establecido, junto con la Universidad Polit\u00e9cnica de Madrid (UPM), un convenio de cooperaci\u00f3n educativa con el objeto de acercar la formaci\u00f3n universitaria a la realidad social y profesional. Estas pr\u00e1cticas permitir\u00e1n completar el proceso formativo del alumnado"},"aioseo_meta_data":{"post_id":"13319","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:57:57","updated":"2025-06-04 17:25:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia-concejalias\/\" title=\"Empleo\">Empleo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Empleo","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia-concejalias\/"},{"label":"El Ayuntamiento de Ciempozuelos firma un convenio de cooperaci\u00f3n educativa con la Universidad Polit\u00e9cnica","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/03\/el-ayuntamiento-de-ciempozuelos-firma-un-convenio-de-cooperacion-educativa-con-la-universidad-politecnica-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:51:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=13319"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13319\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=13319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=13319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=13319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}