{"id":13314,"date":"2015-10-22T13:18:23","date_gmt":"2015-10-22T13:18:23","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/"},"modified":"2015-10-22T13:18:23","modified_gmt":"2015-10-22T13:18:23","slug":"nuestros-mayores-activan-su-memoria-muscular-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/","title":{"rendered":"Nuestros mayores activan su memoria muscular"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><em>La salida est\u00e1 enmarcada en el taller de \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019<\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Los mayores de Ciempozuelos pudieron disfrutar ayer de una salida en el primer trimestre del taller \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019, del programa de autonom\u00eda personal organizado por la Mancomunidad intermunicipal de Servicios Sociales \u2018Las Vegas\u2019.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Este programa forma parte del proyecto de memoria muscular y fomenta la autonom\u00eda de las personas mayores gracias a actividades de car\u00e1cter f\u00edsico y mental.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">Los participantes realizaron un paseo por los alrededores de cada municipio, recopilando informaci\u00f3n de la zona, su historia, su flora,\u2026etc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La salida est\u00e1 enmarcada en el taller de \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019 Los mayores de Ciempozuelos pudieron disfrutar ayer de una salida en el primer trimestre del taller \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019, del programa de autonom\u00eda personal organizado por la Mancomunidad intermunicipal de Servicios Sociales \u2018Las Vegas\u2019. Este programa forma parte del proyecto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1138],"class_list":["post-13314","post","type-post","status-publish","format-standard","hentry","tag-mayores"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La salida est\u00e1 enmarcada en el taller de \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019 Los mayores de Ciempozuelos pudieron disfrutar ayer de una salida en el primer trimestre del taller \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019, del programa de autonom\u00eda personal organizado por la Mancomunidad intermunicipal de Servicios Sociales \u2018Las Vegas\u2019. Este programa forma parte del proyecto\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Nuestros mayores activan su memoria muscular - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La salida est\u00e1 enmarcada en el taller de \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019 Los mayores de Ciempozuelos pudieron disfrutar ayer de una salida en el primer trimestre del taller \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019, del programa de autonom\u00eda personal organizado por la Mancomunidad intermunicipal de Servicios Sociales \u2018Las Vegas\u2019. Este programa forma parte del proyecto\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-10-22T13:18:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-10-22T13:18:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Nuestros mayores activan su memoria muscular - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La salida est\u00e1 enmarcada en el taller de \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019 Los mayores de Ciempozuelos pudieron disfrutar ayer de una salida en el primer trimestre del taller \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019, del programa de autonom\u00eda personal organizado por la Mancomunidad intermunicipal de Servicios Sociales \u2018Las Vegas\u2019. Este programa forma parte del proyecto\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/22\\\/nuestros-mayores-activan-su-memoria-muscular-2\\\/#blogposting\",\"name\":\"Nuestros mayores activan su memoria muscular - Ayuntamiento de Ciempozuelos\",\"headline\":\"Nuestros mayores activan su memoria muscular\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-10-22T13:18:23+02:00\",\"dateModified\":\"2015-10-22T13:18:23+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/22\\\/nuestros-mayores-activan-su-memoria-muscular-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/22\\\/nuestros-mayores-activan-su-memoria-muscular-2\\\/#webpage\"},\"articleSection\":\"Mayores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/22\\\/nuestros-mayores-activan-su-memoria-muscular-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/mayores\\\/#listItem\",\"name\":\"Mayores\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/mayores\\\/#listItem\",\"position\":2,\"name\":\"Mayores\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/mayores\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/22\\\/nuestros-mayores-activan-su-memoria-muscular-2\\\/#listItem\",\"name\":\"Nuestros mayores activan su memoria muscular\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/22\\\/nuestros-mayores-activan-su-memoria-muscular-2\\\/#listItem\",\"position\":3,\"name\":\"Nuestros mayores activan su memoria muscular\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/mayores\\\/#listItem\",\"name\":\"Mayores\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/22\\\/nuestros-mayores-activan-su-memoria-muscular-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/22\\\/nuestros-mayores-activan-su-memoria-muscular-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/22\\\/nuestros-mayores-activan-su-memoria-muscular-2\\\/\",\"name\":\"Nuestros mayores activan su memoria muscular - Ayuntamiento de Ciempozuelos\",\"description\":\"La salida est\\u00e1 enmarcada en el taller de \\u2018Actividad f\\u00edsica, psicomotricidad y memoria\\u2019 Los mayores de Ciempozuelos pudieron disfrutar ayer de una salida en el primer trimestre del taller \\u2018Actividad f\\u00edsica, psicomotricidad y memoria\\u2019, del programa de autonom\\u00eda personal organizado por la Mancomunidad intermunicipal de Servicios Sociales \\u2018Las Vegas\\u2019. Este programa forma parte del proyecto\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/22\\\/nuestros-mayores-activan-su-memoria-muscular-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-10-22T13:18:23+02:00\",\"dateModified\":\"2015-10-22T13:18:23+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Nuestros mayores activan su memoria muscular - Ayuntamiento de Ciempozuelos","description":"La salida est\u00e1 enmarcada en el taller de \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019 Los mayores de Ciempozuelos pudieron disfrutar ayer de una salida en el primer trimestre del taller \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019, del programa de autonom\u00eda personal organizado por la Mancomunidad intermunicipal de Servicios Sociales \u2018Las Vegas\u2019. Este programa forma parte del proyecto","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/#blogposting","name":"Nuestros mayores activan su memoria muscular - Ayuntamiento de Ciempozuelos","headline":"Nuestros mayores activan su memoria muscular","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-10-22T13:18:23+02:00","dateModified":"2015-10-22T13:18:23+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/#webpage"},"articleSection":"Mayores"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/mayores\/#listItem","name":"Mayores"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/mayores\/#listItem","position":2,"name":"Mayores","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/mayores\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/#listItem","name":"Nuestros mayores activan su memoria muscular"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/#listItem","position":3,"name":"Nuestros mayores activan su memoria muscular","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/mayores\/#listItem","name":"Mayores"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/","name":"Nuestros mayores activan su memoria muscular - Ayuntamiento de Ciempozuelos","description":"La salida est\u00e1 enmarcada en el taller de \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019 Los mayores de Ciempozuelos pudieron disfrutar ayer de una salida en el primer trimestre del taller \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019, del programa de autonom\u00eda personal organizado por la Mancomunidad intermunicipal de Servicios Sociales \u2018Las Vegas\u2019. Este programa forma parte del proyecto","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-10-22T13:18:23+02:00","dateModified":"2015-10-22T13:18:23+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Nuestros mayores activan su memoria muscular - Ayuntamiento de Ciempozuelos","og:description":"La salida est\u00e1 enmarcada en el taller de \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019 Los mayores de Ciempozuelos pudieron disfrutar ayer de una salida en el primer trimestre del taller \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019, del programa de autonom\u00eda personal organizado por la Mancomunidad intermunicipal de Servicios Sociales \u2018Las Vegas\u2019. Este programa forma parte del proyecto","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/","article:published_time":"2015-10-22T13:18:23+00:00","article:modified_time":"2015-10-22T13:18:23+00:00","twitter:card":"summary","twitter:title":"Nuestros mayores activan su memoria muscular - Ayuntamiento de Ciempozuelos","twitter:description":"La salida est\u00e1 enmarcada en el taller de \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019 Los mayores de Ciempozuelos pudieron disfrutar ayer de una salida en el primer trimestre del taller \u2018Actividad f\u00edsica, psicomotricidad y memoria\u2019, del programa de autonom\u00eda personal organizado por la Mancomunidad intermunicipal de Servicios Sociales \u2018Las Vegas\u2019. Este programa forma parte del proyecto"},"aioseo_meta_data":{"post_id":"13314","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:52:56","updated":"2025-06-04 17:18:48","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/mayores\/\" title=\"Mayores\">Mayores<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNuestros mayores activan su memoria muscular\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Mayores","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/mayores\/"},{"label":"Nuestros mayores activan su memoria muscular","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/22\/nuestros-mayores-activan-su-memoria-muscular-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 21:55:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=13314"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13314\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=13314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=13314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=13314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}