{"id":13308,"date":"2015-10-16T09:17:13","date_gmt":"2015-10-16T09:17:13","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/"},"modified":"2015-10-16T09:17:13","modified_gmt":"2015-10-16T09:17:13","slug":"jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/","title":{"rendered":"Jornada de puertas abiertas en las instalaciones de la piscina cubierta"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Los asistentes podr\u00e1n realizar actividades de forma gratuita en las instalaciones de la piscina cubierta.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Ma\u00f1ana, s\u00e1bado 17 de octubre, el Centro Deportivo de Ciempozuelos abrir\u00e1 sus puertas de 11.00 a 14.00 horas con el objetivo de acercar algunas de las actividades que se realizan as\u00ed como fomentar la pr\u00e1ctica deportiva.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Los monitores impartir\u00e1n clases de Bodycombat Ciclo, Masterclass y Zumba familiar. La jornada estar\u00e1 amenizada con una actuaci\u00f3n de flamenco.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><img decoding=\"async\" class=\" size-full wp-image-10463\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos.jpg\" border=\"0\" width=\"100%\" style=\"font-size: 12.16px; line-height: 15.808px;\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos-200x291.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos-206x300.jpg 206w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos-400x581.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos-600x872.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos-704x1024.jpg 704w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos-768x1116.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos-800x1163.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos-1057x1536.jpg 1057w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos-1200x1744.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos.jpg 1248w\" sizes=\"(max-width: 1248px) 100vw, 1248px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los asistentes podr\u00e1n realizar actividades de forma gratuita en las instalaciones de la piscina cubierta. Ma\u00f1ana, s\u00e1bado 17 de octubre, el Centro Deportivo de Ciempozuelos abrir\u00e1 sus puertas de 11.00 a 14.00 horas con el objetivo de acercar algunas de las actividades que se realizan as\u00ed como fomentar la pr\u00e1ctica deportiva. Los monitores impartir\u00e1n clases [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1240],"class_list":["post-13308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-instalaciones-deportes"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los asistentes podr\u00e1n realizar actividades de forma gratuita en las instalaciones de la piscina cubierta. Ma\u00f1ana, s\u00e1bado 17 de octubre, el Centro Deportivo de Ciempozuelos abrir\u00e1 sus puertas de 11.00 a 14.00 horas con el objetivo de acercar algunas de las actividades que se realizan as\u00ed como fomentar la pr\u00e1ctica deportiva. Los monitores impartir\u00e1n clases\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Jornada de puertas abiertas en las instalaciones de la piscina cubierta - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Los asistentes podr\u00e1n realizar actividades de forma gratuita en las instalaciones de la piscina cubierta. Ma\u00f1ana, s\u00e1bado 17 de octubre, el Centro Deportivo de Ciempozuelos abrir\u00e1 sus puertas de 11.00 a 14.00 horas con el objetivo de acercar algunas de las actividades que se realizan as\u00ed como fomentar la pr\u00e1ctica deportiva. Los monitores impartir\u00e1n clases\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-10-16T09:17:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-10-16T09:17:13+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Jornada de puertas abiertas en las instalaciones de la piscina cubierta - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los asistentes podr\u00e1n realizar actividades de forma gratuita en las instalaciones de la piscina cubierta. Ma\u00f1ana, s\u00e1bado 17 de octubre, el Centro Deportivo de Ciempozuelos abrir\u00e1 sus puertas de 11.00 a 14.00 horas con el objetivo de acercar algunas de las actividades que se realizan as\u00ed como fomentar la pr\u00e1ctica deportiva. Los monitores impartir\u00e1n clases\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/#blogposting\",\"name\":\"Jornada de puertas abiertas en las instalaciones de la piscina cubierta - Ayuntamiento de Ciempozuelos\",\"headline\":\"Jornada de puertas abiertas en las instalaciones de la piscina cubierta\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/ciempozuelos.jpg\",\"width\":1248,\"height\":1814},\"datePublished\":\"2015-10-16T09:17:13+02:00\",\"dateModified\":\"2015-10-16T09:17:13+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/#webpage\"},\"articleSection\":\"Instalaciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/#listItem\",\"name\":\"Instalaciones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/#listItem\",\"position\":2,\"name\":\"Instalaciones\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/#listItem\",\"name\":\"Jornada de puertas abiertas en las instalaciones de la piscina cubierta\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/#listItem\",\"position\":3,\"name\":\"Jornada de puertas abiertas en las instalaciones de la piscina cubierta\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/#listItem\",\"name\":\"Instalaciones\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/\",\"name\":\"Jornada de puertas abiertas en las instalaciones de la piscina cubierta - Ayuntamiento de Ciempozuelos\",\"description\":\"Los asistentes podr\\u00e1n realizar actividades de forma gratuita en las instalaciones de la piscina cubierta. Ma\\u00f1ana, s\\u00e1bado 17 de octubre, el Centro Deportivo de Ciempozuelos abrir\\u00e1 sus puertas de 11.00 a 14.00 horas con el objetivo de acercar algunas de las actividades que se realizan as\\u00ed como fomentar la pr\\u00e1ctica deportiva. Los monitores impartir\\u00e1n clases\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/ciempozuelos.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/#mainImage\",\"width\":1248,\"height\":1814},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/16\\\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\\\/#mainImage\"},\"datePublished\":\"2015-10-16T09:17:13+02:00\",\"dateModified\":\"2015-10-16T09:17:13+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Jornada de puertas abiertas en las instalaciones de la piscina cubierta - Ayuntamiento de Ciempozuelos","description":"Los asistentes podr\u00e1n realizar actividades de forma gratuita en las instalaciones de la piscina cubierta. Ma\u00f1ana, s\u00e1bado 17 de octubre, el Centro Deportivo de Ciempozuelos abrir\u00e1 sus puertas de 11.00 a 14.00 horas con el objetivo de acercar algunas de las actividades que se realizan as\u00ed como fomentar la pr\u00e1ctica deportiva. Los monitores impartir\u00e1n clases","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/#blogposting","name":"Jornada de puertas abiertas en las instalaciones de la piscina cubierta - Ayuntamiento de Ciempozuelos","headline":"Jornada de puertas abiertas en las instalaciones de la piscina cubierta","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos.jpg","width":1248,"height":1814},"datePublished":"2015-10-16T09:17:13+02:00","dateModified":"2015-10-16T09:17:13+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/#webpage"},"articleSection":"Instalaciones"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/#listItem","name":"Instalaciones"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/#listItem","position":2,"name":"Instalaciones","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/#listItem","name":"Jornada de puertas abiertas en las instalaciones de la piscina cubierta"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/#listItem","position":3,"name":"Jornada de puertas abiertas en las instalaciones de la piscina cubierta","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/#listItem","name":"Instalaciones"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/","name":"Jornada de puertas abiertas en las instalaciones de la piscina cubierta - Ayuntamiento de Ciempozuelos","description":"Los asistentes podr\u00e1n realizar actividades de forma gratuita en las instalaciones de la piscina cubierta. Ma\u00f1ana, s\u00e1bado 17 de octubre, el Centro Deportivo de Ciempozuelos abrir\u00e1 sus puertas de 11.00 a 14.00 horas con el objetivo de acercar algunas de las actividades que se realizan as\u00ed como fomentar la pr\u00e1ctica deportiva. Los monitores impartir\u00e1n clases","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/ciempozuelos.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/#mainImage","width":1248,"height":1814},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/#mainImage"},"datePublished":"2015-10-16T09:17:13+02:00","dateModified":"2015-10-16T09:17:13+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Jornada de puertas abiertas en las instalaciones de la piscina cubierta - Ayuntamiento de Ciempozuelos","og:description":"Los asistentes podr\u00e1n realizar actividades de forma gratuita en las instalaciones de la piscina cubierta. Ma\u00f1ana, s\u00e1bado 17 de octubre, el Centro Deportivo de Ciempozuelos abrir\u00e1 sus puertas de 11.00 a 14.00 horas con el objetivo de acercar algunas de las actividades que se realizan as\u00ed como fomentar la pr\u00e1ctica deportiva. Los monitores impartir\u00e1n clases","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/","article:published_time":"2015-10-16T09:17:13+00:00","article:modified_time":"2015-10-16T09:17:13+00:00","twitter:card":"summary","twitter:title":"Jornada de puertas abiertas en las instalaciones de la piscina cubierta - Ayuntamiento de Ciempozuelos","twitter:description":"Los asistentes podr\u00e1n realizar actividades de forma gratuita en las instalaciones de la piscina cubierta. Ma\u00f1ana, s\u00e1bado 17 de octubre, el Centro Deportivo de Ciempozuelos abrir\u00e1 sus puertas de 11.00 a 14.00 horas con el objetivo de acercar algunas de las actividades que se realizan as\u00ed como fomentar la pr\u00e1ctica deportiva. Los monitores impartir\u00e1n clases"},"aioseo_meta_data":{"post_id":"13308","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:50:56","updated":"2025-06-04 17:17:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/\" title=\"Instalaciones\">Instalaciones<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJornada de puertas abiertas en las instalaciones de la piscina cubierta\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Instalaciones","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/"},{"label":"Jornada de puertas abiertas en las instalaciones de la piscina cubierta","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/16\/jornada-de-puertas-abiertas-en-las-instalaciones-de-la-piscina-cubierta-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 21:06:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=13308"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13308\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10463"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=13308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=13308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=13308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}