{"id":13273,"date":"2015-07-31T10:01:55","date_gmt":"2015-07-31T10:01:55","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/"},"modified":"2015-07-31T10:01:55","modified_gmt":"2015-07-31T10:01:55","slug":"limpieza-de-la-piscina-cubierta-de-ciempozuelos-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/","title":{"rendered":"Limpieza de la piscina cubierta de Ciempozuelos"},"content":{"rendered":"<p style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal;\">El Ayuntamiento de Ciempozuelos informa que con motivo de la limpieza profunda que se realiza anualmente en los vasos de las instalaciones deportivas de la piscina cubierta de Ciempozuelos se proceder\u00e1 al cierre de los siguiente espacios en las fechas indicadas:<\/p>\n<p style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal;\">&#8211; Vaso polivalente y Spa peque\u00f1o del 10 al 16 de agosto de 2015.<\/p>\n<p style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal;\">&#8211; Spa grande del 17 al 23 de agosto de 2015.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Ciempozuelos informa que con motivo de la limpieza profunda que se realiza anualmente en los vasos de las instalaciones deportivas de la piscina cubierta de Ciempozuelos se proceder\u00e1 al cierre de los siguiente espacios en las fechas indicadas: &#8211; Vaso polivalente y Spa peque\u00f1o del 10 al 16 de agosto de 2015. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1240],"class_list":["post-13273","post","type-post","status-publish","format-standard","hentry","tag-instalaciones-deportes"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Ayuntamiento de Ciempozuelos informa que con motivo de la limpieza profunda que se realiza anualmente en los vasos de las instalaciones deportivas de la piscina cubierta de Ciempozuelos se proceder\u00e1 al cierre de los siguiente espacios en las fechas indicadas: - Vaso polivalente y Spa peque\u00f1o del 10 al 16 de agosto de 2015.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Limpieza de la piscina cubierta de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El Ayuntamiento de Ciempozuelos informa que con motivo de la limpieza profunda que se realiza anualmente en los vasos de las instalaciones deportivas de la piscina cubierta de Ciempozuelos se proceder\u00e1 al cierre de los siguiente espacios en las fechas indicadas: - Vaso polivalente y Spa peque\u00f1o del 10 al 16 de agosto de 2015.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-07-31T10:01:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-07-31T10:01:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Limpieza de la piscina cubierta de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Ayuntamiento de Ciempozuelos informa que con motivo de la limpieza profunda que se realiza anualmente en los vasos de las instalaciones deportivas de la piscina cubierta de Ciempozuelos se proceder\u00e1 al cierre de los siguiente espacios en las fechas indicadas: - Vaso polivalente y Spa peque\u00f1o del 10 al 16 de agosto de 2015.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/31\\\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\\\/#blogposting\",\"name\":\"Limpieza de la piscina cubierta de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"Limpieza de la piscina cubierta de Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-07-31T10:01:55+02:00\",\"dateModified\":\"2015-07-31T10:01:55+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/31\\\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/31\\\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\\\/#webpage\"},\"articleSection\":\"Instalaciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/31\\\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/#listItem\",\"name\":\"Instalaciones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/#listItem\",\"position\":2,\"name\":\"Instalaciones\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/31\\\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\\\/#listItem\",\"name\":\"Limpieza de la piscina cubierta de Ciempozuelos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/31\\\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\\\/#listItem\",\"position\":3,\"name\":\"Limpieza de la piscina cubierta de Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones-deportes\\\/#listItem\",\"name\":\"Instalaciones\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/31\\\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/31\\\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/31\\\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\\\/\",\"name\":\"Limpieza de la piscina cubierta de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"El Ayuntamiento de Ciempozuelos informa que con motivo de la limpieza profunda que se realiza anualmente en los vasos de las instalaciones deportivas de la piscina cubierta de Ciempozuelos se proceder\\u00e1 al cierre de los siguiente espacios en las fechas indicadas: - Vaso polivalente y Spa peque\\u00f1o del 10 al 16 de agosto de 2015.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/31\\\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-07-31T10:01:55+02:00\",\"dateModified\":\"2015-07-31T10:01:55+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Limpieza de la piscina cubierta de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"El Ayuntamiento de Ciempozuelos informa que con motivo de la limpieza profunda que se realiza anualmente en los vasos de las instalaciones deportivas de la piscina cubierta de Ciempozuelos se proceder\u00e1 al cierre de los siguiente espacios en las fechas indicadas: - Vaso polivalente y Spa peque\u00f1o del 10 al 16 de agosto de 2015.","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/#blogposting","name":"Limpieza de la piscina cubierta de Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"Limpieza de la piscina cubierta de Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-07-31T10:01:55+02:00","dateModified":"2015-07-31T10:01:55+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/#webpage"},"articleSection":"Instalaciones"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/#listItem","name":"Instalaciones"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/#listItem","position":2,"name":"Instalaciones","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/#listItem","name":"Limpieza de la piscina cubierta de Ciempozuelos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/#listItem","position":3,"name":"Limpieza de la piscina cubierta de Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/#listItem","name":"Instalaciones"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/","name":"Limpieza de la piscina cubierta de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"El Ayuntamiento de Ciempozuelos informa que con motivo de la limpieza profunda que se realiza anualmente en los vasos de las instalaciones deportivas de la piscina cubierta de Ciempozuelos se proceder\u00e1 al cierre de los siguiente espacios en las fechas indicadas: - Vaso polivalente y Spa peque\u00f1o del 10 al 16 de agosto de 2015.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-07-31T10:01:55+02:00","dateModified":"2015-07-31T10:01:55+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Limpieza de la piscina cubierta de Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"El Ayuntamiento de Ciempozuelos informa que con motivo de la limpieza profunda que se realiza anualmente en los vasos de las instalaciones deportivas de la piscina cubierta de Ciempozuelos se proceder\u00e1 al cierre de los siguiente espacios en las fechas indicadas: - Vaso polivalente y Spa peque\u00f1o del 10 al 16 de agosto de 2015.","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/","article:published_time":"2015-07-31T10:01:55+00:00","article:modified_time":"2015-07-31T10:01:55+00:00","twitter:card":"summary","twitter:title":"Limpieza de la piscina cubierta de Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"El Ayuntamiento de Ciempozuelos informa que con motivo de la limpieza profunda que se realiza anualmente en los vasos de las instalaciones deportivas de la piscina cubierta de Ciempozuelos se proceder\u00e1 al cierre de los siguiente espacios en las fechas indicadas: - Vaso polivalente y Spa peque\u00f1o del 10 al 16 de agosto de 2015."},"aioseo_meta_data":{"post_id":"13273","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:25:05","updated":"2025-06-04 16:53:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/\" title=\"Instalaciones\">Instalaciones<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLimpieza de la piscina cubierta de Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Instalaciones","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones-deportes\/"},{"label":"Limpieza de la piscina cubierta de Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/31\/limpieza-de-la-piscina-cubierta-de-ciempozuelos-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 22:14:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=13273"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13273\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=13273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=13273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=13273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}