{"id":13271,"date":"2015-07-28T10:55:24","date_gmt":"2015-07-28T10:55:24","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/"},"modified":"2015-07-28T10:55:24","modified_gmt":"2015-07-28T10:55:24","slug":"musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/","title":{"rendered":"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px; text-align: justify;\"><em>La asociaci\u00f3n cultural Madrilen Txalaparta, \u2018Los Goonies\u2019 y A la sombrita forman el pr\u00f3ximo cartel de los Veranos Culturales<\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px; text-align: justify;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Los Veranos Culturales 2015, organizados por el Ayuntamiento de Ciempozuelos, contin\u00faan acercando la cultura a todos desde sus distintos \u00e1mbitos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px; text-align: justify;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Este viernes 31 de julio a las 22.00 horas en la Plaza Mayor se podr\u00e1 disfrutar del sonido de la txalaparta, instrumento de percusi\u00f3n tradicional del Pa\u00eds Vasco, gracias a la asociaci\u00f3n cultural Madrilen Txalaparta. Un espect\u00e1culo donde se realizar\u00e1n toques con txalapartas de madera, piedra y metal, combinando los ritmos tradicionales con los m\u00e1s modernos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px; text-align: justify;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">El cine de verano arranca el s\u00e1bado 1 de agosto a las 22.00 horas con la proyecci\u00f3n de \u2018Los Goonies\u2019 en la Plaza de la Ermita del Consuelo. El film relata el viaje de un grupo de ni\u00f1os en busca de un tesoro perdido y es considerada una de las pel\u00edculas de culto de los a\u00f1os 80.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px; text-align: justify;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">La magia del teatro de sombras cierra este fin de semana con el espect\u00e1culo \u2018Cuentos de pocas luces\u2019 de la compa\u00f1\u00eda A la sombrita. Un paseo por los or\u00edgenes de los cuentos desde su creaci\u00f3n en las cavernas con el descubrimiento del fuego, haciendo una recreaci\u00f3n de cu\u00e1l pudo ser el primer cuento del mundo. Esta sesi\u00f3n se podr\u00e1 disfrutar el domingo 2 de agosto a las 22.30 horas en la Plaza de la Ermita del Consuelo.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px; text-align: justify;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\"><img decoding=\"async\" class=\" size-full wp-image-10190\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/madrilen-txalaparta.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/madrilen-txalaparta-200x134.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/madrilen-txalaparta-300x200.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/madrilen-txalaparta-400x267.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/madrilen-txalaparta.jpg 500w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px; text-align: justify;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Foto: Madrilen Txalaparta<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px; text-align: justify;\"><em style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px;\"><img decoding=\"async\" class=\" size-full wp-image-10191\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/alasombrita.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/alasombrita-200x150.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/alasombrita-300x225.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/alasombrita-400x300.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/alasombrita-600x450.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/alasombrita-768x576.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/alasombrita-800x600.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/alasombrita-1024x768.jpg 1024w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/alasombrita-1200x900.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/alasombrita-1536x1152.jpg 1536w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/alasombrita.jpg 1632w\" sizes=\"(max-width: 1632px) 100vw, 1632px\" \/><\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px; text-align: justify;\">Foto: A la Sombrita<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La asociaci\u00f3n cultural Madrilen Txalaparta, \u2018Los Goonies\u2019 y A la sombrita forman el pr\u00f3ximo cartel de los Veranos Culturales Los Veranos Culturales 2015, organizados por el Ayuntamiento de Ciempozuelos, contin\u00faan acercando la cultura a todos desde sus distintos \u00e1mbitos. Este viernes 31 de julio a las 22.00 horas en la Plaza Mayor se podr\u00e1 disfrutar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1144],"class_list":["post-13271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-cultura-noelia-fernandez-concejalias"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La asociaci\u00f3n cultural Madrilen Txalaparta, \u2018Los Goonies\u2019 y A la sombrita forman el pr\u00f3ximo cartel de los Veranos Culturales Los Veranos Culturales 2015, organizados por el Ayuntamiento de Ciempozuelos, contin\u00faan acercando la cultura a todos desde sus distintos \u00e1mbitos. Este viernes 31 de julio a las 22.00 horas en la Plaza Mayor se podr\u00e1 disfrutar\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La asociaci\u00f3n cultural Madrilen Txalaparta, \u2018Los Goonies\u2019 y A la sombrita forman el pr\u00f3ximo cartel de los Veranos Culturales Los Veranos Culturales 2015, organizados por el Ayuntamiento de Ciempozuelos, contin\u00faan acercando la cultura a todos desde sus distintos \u00e1mbitos. Este viernes 31 de julio a las 22.00 horas en la Plaza Mayor se podr\u00e1 disfrutar\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-07-28T10:55:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-07-28T10:55:24+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La asociaci\u00f3n cultural Madrilen Txalaparta, \u2018Los Goonies\u2019 y A la sombrita forman el pr\u00f3ximo cartel de los Veranos Culturales Los Veranos Culturales 2015, organizados por el Ayuntamiento de Ciempozuelos, contin\u00faan acercando la cultura a todos desde sus distintos \u00e1mbitos. Este viernes 31 de julio a las 22.00 horas en la Plaza Mayor se podr\u00e1 disfrutar\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/#blogposting\",\"name\":\"M\\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"M\\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/madrilen-txalaparta.jpg\",\"width\":500,\"height\":334},\"datePublished\":\"2015-07-28T10:55:24+02:00\",\"dateModified\":\"2015-07-28T10:55:24+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/#webpage\"},\"articleSection\":\"Cultura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/cultura-noelia-fernandez-concejalias\\\/#listItem\",\"name\":\"Cultura\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/cultura-noelia-fernandez-concejalias\\\/#listItem\",\"position\":2,\"name\":\"Cultura\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/cultura-noelia-fernandez-concejalias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/#listItem\",\"name\":\"M\\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/#listItem\",\"position\":3,\"name\":\"M\\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/cultura-noelia-fernandez-concejalias\\\/#listItem\",\"name\":\"Cultura\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/\",\"name\":\"M\\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"La asociaci\\u00f3n cultural Madrilen Txalaparta, \\u2018Los Goonies\\u2019 y A la sombrita forman el pr\\u00f3ximo cartel de los Veranos Culturales Los Veranos Culturales 2015, organizados por el Ayuntamiento de Ciempozuelos, contin\\u00faan acercando la cultura a todos desde sus distintos \\u00e1mbitos. Este viernes 31 de julio a las 22.00 horas en la Plaza Mayor se podr\\u00e1 disfrutar\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/madrilen-txalaparta.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/#mainImage\",\"width\":500,\"height\":334},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/07\\\/28\\\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\\\/#mainImage\"},\"datePublished\":\"2015-07-28T10:55:24+02:00\",\"dateModified\":\"2015-07-28T10:55:24+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"La asociaci\u00f3n cultural Madrilen Txalaparta, \u2018Los Goonies\u2019 y A la sombrita forman el pr\u00f3ximo cartel de los Veranos Culturales Los Veranos Culturales 2015, organizados por el Ayuntamiento de Ciempozuelos, contin\u00faan acercando la cultura a todos desde sus distintos \u00e1mbitos. Este viernes 31 de julio a las 22.00 horas en la Plaza Mayor se podr\u00e1 disfrutar","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/#blogposting","name":"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/madrilen-txalaparta.jpg","width":500,"height":334},"datePublished":"2015-07-28T10:55:24+02:00","dateModified":"2015-07-28T10:55:24+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/#webpage"},"articleSection":"Cultura"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/#listItem","name":"Cultura"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/#listItem","position":2,"name":"Cultura","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/#listItem","name":"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/#listItem","position":3,"name":"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/#listItem","name":"Cultura"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/","name":"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"La asociaci\u00f3n cultural Madrilen Txalaparta, \u2018Los Goonies\u2019 y A la sombrita forman el pr\u00f3ximo cartel de los Veranos Culturales Los Veranos Culturales 2015, organizados por el Ayuntamiento de Ciempozuelos, contin\u00faan acercando la cultura a todos desde sus distintos \u00e1mbitos. Este viernes 31 de julio a las 22.00 horas en la Plaza Mayor se podr\u00e1 disfrutar","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/07\/madrilen-txalaparta.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/#mainImage","width":500,"height":334},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/#mainImage"},"datePublished":"2015-07-28T10:55:24+02:00","dateModified":"2015-07-28T10:55:24+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"La asociaci\u00f3n cultural Madrilen Txalaparta, \u2018Los Goonies\u2019 y A la sombrita forman el pr\u00f3ximo cartel de los Veranos Culturales Los Veranos Culturales 2015, organizados por el Ayuntamiento de Ciempozuelos, contin\u00faan acercando la cultura a todos desde sus distintos \u00e1mbitos. Este viernes 31 de julio a las 22.00 horas en la Plaza Mayor se podr\u00e1 disfrutar","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/","article:published_time":"2015-07-28T10:55:24+00:00","article:modified_time":"2015-07-28T10:55:24+00:00","twitter:card":"summary","twitter:title":"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"La asociaci\u00f3n cultural Madrilen Txalaparta, \u2018Los Goonies\u2019 y A la sombrita forman el pr\u00f3ximo cartel de los Veranos Culturales Los Veranos Culturales 2015, organizados por el Ayuntamiento de Ciempozuelos, contin\u00faan acercando la cultura a todos desde sus distintos \u00e1mbitos. Este viernes 31 de julio a las 22.00 horas en la Plaza Mayor se podr\u00e1 disfrutar"},"aioseo_meta_data":{"post_id":"13271","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:24:10","updated":"2025-06-04 16:52:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/\" title=\"Cultura\">Cultura<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tM\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Cultura","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/cultura-noelia-fernandez-concejalias\/"},{"label":"M\u00fasica tradicional, cine y teatro de sombras este fin de semana en Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/07\/28\/musica-tradicional-cine-y-teatro-de-sombras-este-fin-de-semana-en-ciempozuelos-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:08:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=13271"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10190"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=13271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=13271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=13271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}