{"id":13254,"date":"2015-06-23T12:39:30","date_gmt":"2015-06-23T12:39:30","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/"},"modified":"2015-06-23T12:39:30","modified_gmt":"2015-06-23T12:39:30","slug":"azufre-en-la-via-publica-4","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/","title":{"rendered":"Azufre en la v\u00eda p\u00fablica"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: left;\"><em>La deposici\u00f3n de productos qu\u00edmicos en la v\u00eda p\u00fablica es una pr\u00e1ctica ileg\u00edtima<\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: left;\"><span style=\"text-align: justify; font-size: 12.1599998474121px; line-height: 1.3em;\">A lo largo del tiempo se ha popularizado la pr\u00e1ctica de esparcir polvos de azufre en la v\u00eda p\u00fablica en las proximidades de las viviendas al efecto de impedir que los animales dom\u00e9sticos, especialmente los perros, realicen sus micciones. Sin embargo, desde el Ayuntamiento de Ciempozuelos se informa:<\/span><span style=\"text-align: justify; font-size: 12.1599998474121px; line-height: 1.3em;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">El azufre es una sustancia peligrosa que puede afectar a la salud de los animales y personas cuando es inhalado, ingerido y\/o por contacto con la piel. Los efectos de la exposici\u00f3n pueden ocasionar ulceraci\u00f3n de la piel, conjuntivitis, inflamaci\u00f3n de la mucosa nasal, falta de respiraci\u00f3n, asma y traqueobronquitis. Adem\u00e1s, se trata de un s\u00f3lido altamente inflamable lo que puede originar mezclas explosivas en contacto con el aire o con materiales oxidables. Debe evitarse su contacto con el agua. Debe ser almacenado en fr\u00edo, con ventilaci\u00f3n adecuada, lejos de fuentes de ignici\u00f3n y de materiales oxidables.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Por otra parte, no existe evidencia cient\u00edfica del efecto de esta sustancia como repelente de los animales de compa\u00f1\u00eda y en concreto de los perros, para evitar que orinen en la fachada de los edificios.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Por todo ello se puede concluir: <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">1. <\/span><span style=\"text-indent: -18pt; font-size: 12.1599998474121px; line-height: 1.3em;\">La deposici\u00f3n de productos qu\u00edmicos en la v\u00eda p\u00fablica es una pr\u00e1ctica ileg\u00edtima que puede producir problemas sanitarios a terceros. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"text-indent: -18pt; font-size: 12.1599998474121px; line-height: 1.3em;\">2. <\/span><span style=\"text-indent: -18pt; font-size: 12.1599998474121px; line-height: 1.3em;\">No existe constancia cient\u00edfica de este efecto. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"text-indent: -18pt; font-size: 12.1599998474121px; line-height: 1.3em;\">3. <\/span><span style=\"text-indent: -18pt; font-size: 12.1599998474121px; line-height: 1.3em;\">Es preciso concienciar a los due\u00f1os de estas mascotas a que adopten unos h\u00e1bitos higi\u00e9nicos en la v\u00eda p\u00fablica, tal y como est\u00e1 recogido en la Ordenanza de Tenencia de Animales y de Convivencia Ciudadana.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"text-indent: -18pt; font-size: 12.1599998474121px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">El civismo en sociedad empieza por el respeto de todos con los que se comparte la v\u00eda p\u00fablica.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La deposici\u00f3n de productos qu\u00edmicos en la v\u00eda p\u00fablica es una pr\u00e1ctica ileg\u00edtima A lo largo del tiempo se ha popularizado la pr\u00e1ctica de esparcir polvos de azufre en la v\u00eda p\u00fablica en las proximidades de las viviendas al efecto de impedir que los animales dom\u00e9sticos, especialmente los perros, realicen sus micciones. Sin embargo, desde [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1161],"class_list":["post-13254","post","type-post","status-publish","format-standard","hentry","tag-sanidad-juan-pedro-garcia-concejalias"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La deposici\u00f3n de productos qu\u00edmicos en la v\u00eda p\u00fablica es una pr\u00e1ctica ileg\u00edtima A lo largo del tiempo se ha popularizado la pr\u00e1ctica de esparcir polvos de azufre en la v\u00eda p\u00fablica en las proximidades de las viviendas al efecto de impedir que los animales dom\u00e9sticos, especialmente los perros, realicen sus micciones. Sin embargo, desde\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Azufre en la v\u00eda p\u00fablica - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La deposici\u00f3n de productos qu\u00edmicos en la v\u00eda p\u00fablica es una pr\u00e1ctica ileg\u00edtima A lo largo del tiempo se ha popularizado la pr\u00e1ctica de esparcir polvos de azufre en la v\u00eda p\u00fablica en las proximidades de las viviendas al efecto de impedir que los animales dom\u00e9sticos, especialmente los perros, realicen sus micciones. Sin embargo, desde\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-06-23T12:39:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-06-23T12:39:30+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Azufre en la v\u00eda p\u00fablica - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La deposici\u00f3n de productos qu\u00edmicos en la v\u00eda p\u00fablica es una pr\u00e1ctica ileg\u00edtima A lo largo del tiempo se ha popularizado la pr\u00e1ctica de esparcir polvos de azufre en la v\u00eda p\u00fablica en las proximidades de las viviendas al efecto de impedir que los animales dom\u00e9sticos, especialmente los perros, realicen sus micciones. Sin embargo, desde\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/23\\\/azufre-en-la-via-publica-4\\\/#blogposting\",\"name\":\"Azufre en la v\\u00eda p\\u00fablica - Ayuntamiento de Ciempozuelos\",\"headline\":\"Azufre en la v\\u00eda p\\u00fablica\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-06-23T12:39:30+02:00\",\"dateModified\":\"2015-06-23T12:39:30+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/23\\\/azufre-en-la-via-publica-4\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/23\\\/azufre-en-la-via-publica-4\\\/#webpage\"},\"articleSection\":\"Salud\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/23\\\/azufre-en-la-via-publica-4\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/sanidad-juan-pedro-garcia-concejalias\\\/#listItem\",\"name\":\"Salud\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/sanidad-juan-pedro-garcia-concejalias\\\/#listItem\",\"position\":2,\"name\":\"Salud\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/sanidad-juan-pedro-garcia-concejalias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/23\\\/azufre-en-la-via-publica-4\\\/#listItem\",\"name\":\"Azufre en la v\\u00eda p\\u00fablica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/23\\\/azufre-en-la-via-publica-4\\\/#listItem\",\"position\":3,\"name\":\"Azufre en la v\\u00eda p\\u00fablica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/sanidad-juan-pedro-garcia-concejalias\\\/#listItem\",\"name\":\"Salud\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/23\\\/azufre-en-la-via-publica-4\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/23\\\/azufre-en-la-via-publica-4\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/23\\\/azufre-en-la-via-publica-4\\\/\",\"name\":\"Azufre en la v\\u00eda p\\u00fablica - Ayuntamiento de Ciempozuelos\",\"description\":\"La deposici\\u00f3n de productos qu\\u00edmicos en la v\\u00eda p\\u00fablica es una pr\\u00e1ctica ileg\\u00edtima A lo largo del tiempo se ha popularizado la pr\\u00e1ctica de esparcir polvos de azufre en la v\\u00eda p\\u00fablica en las proximidades de las viviendas al efecto de impedir que los animales dom\\u00e9sticos, especialmente los perros, realicen sus micciones. Sin embargo, desde\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/06\\\/23\\\/azufre-en-la-via-publica-4\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-06-23T12:39:30+02:00\",\"dateModified\":\"2015-06-23T12:39:30+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Azufre en la v\u00eda p\u00fablica - Ayuntamiento de Ciempozuelos","description":"La deposici\u00f3n de productos qu\u00edmicos en la v\u00eda p\u00fablica es una pr\u00e1ctica ileg\u00edtima A lo largo del tiempo se ha popularizado la pr\u00e1ctica de esparcir polvos de azufre en la v\u00eda p\u00fablica en las proximidades de las viviendas al efecto de impedir que los animales dom\u00e9sticos, especialmente los perros, realicen sus micciones. Sin embargo, desde","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/#blogposting","name":"Azufre en la v\u00eda p\u00fablica - Ayuntamiento de Ciempozuelos","headline":"Azufre en la v\u00eda p\u00fablica","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-06-23T12:39:30+02:00","dateModified":"2015-06-23T12:39:30+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/#webpage"},"articleSection":"Salud"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/sanidad-juan-pedro-garcia-concejalias\/#listItem","name":"Salud"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/sanidad-juan-pedro-garcia-concejalias\/#listItem","position":2,"name":"Salud","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/sanidad-juan-pedro-garcia-concejalias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/#listItem","name":"Azufre en la v\u00eda p\u00fablica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/#listItem","position":3,"name":"Azufre en la v\u00eda p\u00fablica","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/sanidad-juan-pedro-garcia-concejalias\/#listItem","name":"Salud"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/","name":"Azufre en la v\u00eda p\u00fablica - Ayuntamiento de Ciempozuelos","description":"La deposici\u00f3n de productos qu\u00edmicos en la v\u00eda p\u00fablica es una pr\u00e1ctica ileg\u00edtima A lo largo del tiempo se ha popularizado la pr\u00e1ctica de esparcir polvos de azufre en la v\u00eda p\u00fablica en las proximidades de las viviendas al efecto de impedir que los animales dom\u00e9sticos, especialmente los perros, realicen sus micciones. Sin embargo, desde","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-06-23T12:39:30+02:00","dateModified":"2015-06-23T12:39:30+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Azufre en la v\u00eda p\u00fablica - Ayuntamiento de Ciempozuelos","og:description":"La deposici\u00f3n de productos qu\u00edmicos en la v\u00eda p\u00fablica es una pr\u00e1ctica ileg\u00edtima A lo largo del tiempo se ha popularizado la pr\u00e1ctica de esparcir polvos de azufre en la v\u00eda p\u00fablica en las proximidades de las viviendas al efecto de impedir que los animales dom\u00e9sticos, especialmente los perros, realicen sus micciones. Sin embargo, desde","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/","article:published_time":"2015-06-23T12:39:30+00:00","article:modified_time":"2015-06-23T12:39:30+00:00","twitter:card":"summary","twitter:title":"Azufre en la v\u00eda p\u00fablica - Ayuntamiento de Ciempozuelos","twitter:description":"La deposici\u00f3n de productos qu\u00edmicos en la v\u00eda p\u00fablica es una pr\u00e1ctica ileg\u00edtima A lo largo del tiempo se ha popularizado la pr\u00e1ctica de esparcir polvos de azufre en la v\u00eda p\u00fablica en las proximidades de las viviendas al efecto de impedir que los animales dom\u00e9sticos, especialmente los perros, realicen sus micciones. Sin embargo, desde"},"aioseo_meta_data":{"post_id":"13254","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:05:04","updated":"2025-06-04 16:39:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/sanidad-juan-pedro-garcia-concejalias\/\" title=\"Salud\">Salud<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAzufre en la v\u00eda p\u00fablica\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Salud","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/sanidad-juan-pedro-garcia-concejalias\/"},{"label":"Azufre en la v\u00eda p\u00fablica","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/06\/23\/azufre-en-la-via-publica-4\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:51:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=13254"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/13254\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=13254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=13254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=13254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}