{"id":11245,"date":"2016-05-17T09:05:17","date_gmt":"2016-05-17T09:05:17","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/"},"modified":"2016-05-17T09:05:17","modified_gmt":"2016-05-17T09:05:17","slug":"dia-internacional-contra-la-homofobia-y-la-transfobia-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/","title":{"rendered":"D\u00eda Internacional contra la homofobia y la transfobia"},"content":{"rendered":"<p style=\"text-align: justify;\">Hoy, 17 de mayo, se celebra el D\u00eda  Internacional contra la homofobia y la transfobia que conmemora la  eliminaci\u00f3n de la homosexualidad de la lista de enfermedades mentales  por parte de la Asamblea General de la Organizaci\u00f3n Mundial de la Salud  (OMS), un hecho que tuvo lugar el 17 de mayo de 1990 y que supuso el  reconocimiento oficial por parte de las entidades m\u00e9dicas  internacionales de que los deseos y las pr\u00e1cticas sexuales tienen que  ver con el \u00e1mbito de la libertad individual y no pueden, en ning\u00fan caso,  considerarse desde el estigma de la patolog\u00eda o desde la medicalizaci\u00f3n  de las conductas que afectan a la libertad individual. Esto signific\u00f3  un importante hito en la lucha contra la discriminaci\u00f3n por orientaci\u00f3n  sexual y una batalla ganada por la igualdad.<\/p>\n<p style=\"text-align: justify;\">El  principal objetivo del D\u00eda Internacional contra la homofobia y la  transfobia es el de coordinar todo tipo de acciones que denuncien la  discriminaci\u00f3n de que son objeto las personas homosexuales, lesbianas,  bisexuales y transexuales, y para el ejercicio pleno de sus derechos en  todo el mundo en condiciones de libertad, igualdad y dignidad.<\/p>\n<p style=\"text-align: justify;\">El  Ayuntamiento de Ciempozuelos se suma a esa reivindicaci\u00f3n b\u00e1sica y,  recogiendo lo manifestado en diversas ocasiones por los grupos  municipales, manifiesta su rechazo expl\u00edcito de todas las situaciones de  discriminaci\u00f3n por la orientaci\u00f3n sexual y, en \u00faltimo t\u00e9rmino, en  ejercicio de su libertad: no s\u00f3lo frente al prejuicio sino tambi\u00e9n  frente a las pr\u00e1cticas y las normas legales que puedan suponer cualquier  merma de derechos. En este sentido nos unimos tambi\u00e9n a la condena de  aquellos pa\u00edses en los que la homosexualidad sigue siendo considerada  delito y hacemos un llamamiento al respeto escrupuloso de los derechos  humanos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy, 17 de mayo, se celebra el D\u00eda Internacional contra la homofobia y la transfobia que conmemora la eliminaci\u00f3n de la homosexualidad de la lista de enfermedades mentales por parte de la Asamblea General de la Organizaci\u00f3n Mundial de la Salud (OMS), un hecho que tuvo lugar el 17 de mayo de 1990 y que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1160],"class_list":["post-11245","post","type-post","status-publish","format-standard","hentry","tag-igualdad-juan-pedro-garcia"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hoy, 17 de mayo, se celebra el D\u00eda Internacional contra la homofobia y la transfobia que conmemora la eliminaci\u00f3n de la homosexualidad de la lista de enfermedades mentales por parte de la Asamblea General de la Organizaci\u00f3n Mundial de la Salud (OMS), un hecho que tuvo lugar el 17 de mayo de 1990 y que\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"D\u00eda Internacional contra la homofobia y la transfobia - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Hoy, 17 de mayo, se celebra el D\u00eda Internacional contra la homofobia y la transfobia que conmemora la eliminaci\u00f3n de la homosexualidad de la lista de enfermedades mentales por parte de la Asamblea General de la Organizaci\u00f3n Mundial de la Salud (OMS), un hecho que tuvo lugar el 17 de mayo de 1990 y que\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-05-17T09:05:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-05-17T09:05:17+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"D\u00eda Internacional contra la homofobia y la transfobia - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hoy, 17 de mayo, se celebra el D\u00eda Internacional contra la homofobia y la transfobia que conmemora la eliminaci\u00f3n de la homosexualidad de la lista de enfermedades mentales por parte de la Asamblea General de la Organizaci\u00f3n Mundial de la Salud (OMS), un hecho que tuvo lugar el 17 de mayo de 1990 y que\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/17\\\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\\\/#blogposting\",\"name\":\"D\\u00eda Internacional contra la homofobia y la transfobia - Ayuntamiento de Ciempozuelos\",\"headline\":\"D\\u00eda Internacional contra la homofobia y la transfobia\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-05-17T09:05:17+02:00\",\"dateModified\":\"2016-05-17T09:05:17+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/17\\\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/17\\\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\\\/#webpage\"},\"articleSection\":\"Igualdad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/17\\\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/igualdad-juan-pedro-garcia\\\/#listItem\",\"name\":\"Igualdad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/igualdad-juan-pedro-garcia\\\/#listItem\",\"position\":2,\"name\":\"Igualdad\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/igualdad-juan-pedro-garcia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/17\\\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\\\/#listItem\",\"name\":\"D\\u00eda Internacional contra la homofobia y la transfobia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/17\\\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\\\/#listItem\",\"position\":3,\"name\":\"D\\u00eda Internacional contra la homofobia y la transfobia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/igualdad-juan-pedro-garcia\\\/#listItem\",\"name\":\"Igualdad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/17\\\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/17\\\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/17\\\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\\\/\",\"name\":\"D\\u00eda Internacional contra la homofobia y la transfobia - Ayuntamiento de Ciempozuelos\",\"description\":\"Hoy, 17 de mayo, se celebra el D\\u00eda Internacional contra la homofobia y la transfobia que conmemora la eliminaci\\u00f3n de la homosexualidad de la lista de enfermedades mentales por parte de la Asamblea General de la Organizaci\\u00f3n Mundial de la Salud (OMS), un hecho que tuvo lugar el 17 de mayo de 1990 y que\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/05\\\/17\\\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-05-17T09:05:17+02:00\",\"dateModified\":\"2016-05-17T09:05:17+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"D\u00eda Internacional contra la homofobia y la transfobia - Ayuntamiento de Ciempozuelos","description":"Hoy, 17 de mayo, se celebra el D\u00eda Internacional contra la homofobia y la transfobia que conmemora la eliminaci\u00f3n de la homosexualidad de la lista de enfermedades mentales por parte de la Asamblea General de la Organizaci\u00f3n Mundial de la Salud (OMS), un hecho que tuvo lugar el 17 de mayo de 1990 y que","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/#blogposting","name":"D\u00eda Internacional contra la homofobia y la transfobia - Ayuntamiento de Ciempozuelos","headline":"D\u00eda Internacional contra la homofobia y la transfobia","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-05-17T09:05:17+02:00","dateModified":"2016-05-17T09:05:17+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/#webpage"},"articleSection":"Igualdad"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/igualdad-juan-pedro-garcia\/#listItem","name":"Igualdad"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/igualdad-juan-pedro-garcia\/#listItem","position":2,"name":"Igualdad","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/igualdad-juan-pedro-garcia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/#listItem","name":"D\u00eda Internacional contra la homofobia y la transfobia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/#listItem","position":3,"name":"D\u00eda Internacional contra la homofobia y la transfobia","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/igualdad-juan-pedro-garcia\/#listItem","name":"Igualdad"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/","name":"D\u00eda Internacional contra la homofobia y la transfobia - Ayuntamiento de Ciempozuelos","description":"Hoy, 17 de mayo, se celebra el D\u00eda Internacional contra la homofobia y la transfobia que conmemora la eliminaci\u00f3n de la homosexualidad de la lista de enfermedades mentales por parte de la Asamblea General de la Organizaci\u00f3n Mundial de la Salud (OMS), un hecho que tuvo lugar el 17 de mayo de 1990 y que","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-05-17T09:05:17+02:00","dateModified":"2016-05-17T09:05:17+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"D\u00eda Internacional contra la homofobia y la transfobia - Ayuntamiento de Ciempozuelos","og:description":"Hoy, 17 de mayo, se celebra el D\u00eda Internacional contra la homofobia y la transfobia que conmemora la eliminaci\u00f3n de la homosexualidad de la lista de enfermedades mentales por parte de la Asamblea General de la Organizaci\u00f3n Mundial de la Salud (OMS), un hecho que tuvo lugar el 17 de mayo de 1990 y que","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/","article:published_time":"2016-05-17T09:05:17+00:00","article:modified_time":"2016-05-17T09:05:17+00:00","twitter:card":"summary","twitter:title":"D\u00eda Internacional contra la homofobia y la transfobia - Ayuntamiento de Ciempozuelos","twitter:description":"Hoy, 17 de mayo, se celebra el D\u00eda Internacional contra la homofobia y la transfobia que conmemora la eliminaci\u00f3n de la homosexualidad de la lista de enfermedades mentales por parte de la Asamblea General de la Organizaci\u00f3n Mundial de la Salud (OMS), un hecho que tuvo lugar el 17 de mayo de 1990 y que"},"aioseo_meta_data":{"post_id":"11245","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 16:08:04","updated":"2025-06-04 18:33:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/igualdad-juan-pedro-garcia\/\" title=\"Igualdad\">Igualdad<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tD\u00eda Internacional contra la homofobia y la transfobia\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Igualdad","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/igualdad-juan-pedro-garcia\/"},{"label":"D\u00eda Internacional contra la homofobia y la transfobia","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/05\/17\/dia-internacional-contra-la-homofobia-y-la-transfobia-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:53:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=11245"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11245\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=11245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=11245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=11245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}