{"id":11170,"date":"2016-04-26T08:58:40","date_gmt":"2016-04-26T08:58:40","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/"},"modified":"2016-04-26T08:58:40","modified_gmt":"2016-04-26T08:58:40","slug":"musiqueando-2016-en-ciempozuelos","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/","title":{"rendered":"Musiqueando 2016 en Ciempozuelos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><em>M\u00e1s de 100 alumnos de nuestro municipio participan el 28 de abril en esta jornada de sensibilizaci\u00f3n musical<\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><em> <\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Ciempozuelos se une a la convocatoria nacional de Musiqueando 2016 #nosimportalam\u00fasica, una jornada de sensibilizaci\u00f3n musical que traslada la m\u00fasica de las aulas a la calle de forma simult\u00e1nea en distintos puntos del pa\u00eds. <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">La Plaza de la Constituci\u00f3n acoge esta acci\u00f3n este jueves 28 de abril en la que participar\u00e1n m\u00e1s de un centenar de alumnos del CEIP Andr\u00e9s Segovia, CEIP Eloy Saavedra, CEIP Virgen del Consuelo y del IES Francisco Umbral.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">A las 12.00 horas est\u00e1 programada la llegada a la Plaza de la Constituci\u00f3n y la distribuci\u00f3n de escolares de la siguiente manera: IES Francisco Umbral (blanco), CEIP Virgen del Consuelo (morado), CEIP Eloy Saavedra (rojo) y CEIP Andr\u00e9s Segovia (amarillo).<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">La actuaci\u00f3n arrancar\u00e1 a las 12.30 horas con la presentaci\u00f3n del evento por parte del CEIP Eloy Saavedra, despu\u00e9s disfrutaremos de la actuaci\u00f3n de flautas del CEIP Virgen del Consuelo y el CEIP Andr\u00e9s Segovia. Despu\u00e9s, los alumnos de \u00e9ste \u00faltimo centro realizar\u00e1n una coreograf\u00eda. A continuaci\u00f3n habr\u00e1 una actuaci\u00f3n de voz\u00a0 de los IES Francisco Umbral, CEIP Virgen del Consuelo y CEIP Andr\u00e9s Segovia y el siguiente acto ser\u00e1 de percusi\u00f3n corporal en el que participar\u00e1n todos los centros y el p\u00fablico asistente. Por \u00faltimo actuar\u00e1 el coro \u2018Voces para la convivencia\u2019.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">Musiqueando es una iniciativa festiva de la Confederaci\u00f3n de Asociaciones de Educaci\u00f3n Musical (COAEM) que pretende celebrar y vivir la m\u00fasica como un derecho para todos mediante conciertos escolares en la calle. Docentes y alumnos de los centros educativos de Educaci\u00f3n Primaria, Secundaria y Bachillerato comparten as\u00ed una peque\u00f1a muestra del trabajo que se desarrolla en las aulas de m\u00fasica.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">Esta iniciativa est\u00e1 formada por 8500 participantes de 125 centros en m\u00e1s de 90 localizaciones. Toda la informaci\u00f3n relativa a esta convocatoria est\u00e1 disponible en <a href=\"http:\/\/musiqueando2016.weebly.com\/\">http:\/\/musiqueando2016.weebly.com\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 100 alumnos de nuestro municipio participan el 28 de abril en esta jornada de sensibilizaci\u00f3n musical Ciempozuelos se une a la convocatoria nacional de Musiqueando 2016 #nosimportalam\u00fasica, una jornada de sensibilizaci\u00f3n musical que traslada la m\u00fasica de las aulas a la calle de forma simult\u00e1nea en distintos puntos del pa\u00eds. La Plaza de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1221],"class_list":["post-11170","post","type-post","status-publish","format-standard","hentry","tag-1221"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"M\u00e1s de 100 alumnos de nuestro municipio participan el 28 de abril en esta jornada de sensibilizaci\u00f3n musical Ciempozuelos se une a la convocatoria nacional de Musiqueando 2016 #nosimportalam\u00fasica, una jornada de sensibilizaci\u00f3n musical que traslada la m\u00fasica de las aulas a la calle de forma simult\u00e1nea en distintos puntos del pa\u00eds. La Plaza de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Musiqueando 2016 en Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"M\u00e1s de 100 alumnos de nuestro municipio participan el 28 de abril en esta jornada de sensibilizaci\u00f3n musical Ciempozuelos se une a la convocatoria nacional de Musiqueando 2016 #nosimportalam\u00fasica, una jornada de sensibilizaci\u00f3n musical que traslada la m\u00fasica de las aulas a la calle de forma simult\u00e1nea en distintos puntos del pa\u00eds. La Plaza de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-04-26T08:58:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-04-26T08:58:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Musiqueando 2016 en Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"M\u00e1s de 100 alumnos de nuestro municipio participan el 28 de abril en esta jornada de sensibilizaci\u00f3n musical Ciempozuelos se une a la convocatoria nacional de Musiqueando 2016 #nosimportalam\u00fasica, una jornada de sensibilizaci\u00f3n musical que traslada la m\u00fasica de las aulas a la calle de forma simult\u00e1nea en distintos puntos del pa\u00eds. La Plaza de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/26\\\/musiqueando-2016-en-ciempozuelos\\\/#blogposting\",\"name\":\"Musiqueando 2016 en Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"Musiqueando 2016 en Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-04-26T08:58:40+02:00\",\"dateModified\":\"2016-04-26T08:58:40+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/26\\\/musiqueando-2016-en-ciempozuelos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/26\\\/musiqueando-2016-en-ciempozuelos\\\/#webpage\"},\"articleSection\":\"1105\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/26\\\/musiqueando-2016-en-ciempozuelos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1105\\\/#listItem\",\"name\":\"1105\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1105\\\/#listItem\",\"position\":2,\"name\":\"1105\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1105\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/26\\\/musiqueando-2016-en-ciempozuelos\\\/#listItem\",\"name\":\"Musiqueando 2016 en Ciempozuelos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/26\\\/musiqueando-2016-en-ciempozuelos\\\/#listItem\",\"position\":3,\"name\":\"Musiqueando 2016 en Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1105\\\/#listItem\",\"name\":\"1105\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/26\\\/musiqueando-2016-en-ciempozuelos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/26\\\/musiqueando-2016-en-ciempozuelos\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/26\\\/musiqueando-2016-en-ciempozuelos\\\/\",\"name\":\"Musiqueando 2016 en Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"M\\u00e1s de 100 alumnos de nuestro municipio participan el 28 de abril en esta jornada de sensibilizaci\\u00f3n musical Ciempozuelos se une a la convocatoria nacional de Musiqueando 2016 #nosimportalam\\u00fasica, una jornada de sensibilizaci\\u00f3n musical que traslada la m\\u00fasica de las aulas a la calle de forma simult\\u00e1nea en distintos puntos del pa\\u00eds. La Plaza de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/26\\\/musiqueando-2016-en-ciempozuelos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-04-26T08:58:40+02:00\",\"dateModified\":\"2016-04-26T08:58:40+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Musiqueando 2016 en Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"M\u00e1s de 100 alumnos de nuestro municipio participan el 28 de abril en esta jornada de sensibilizaci\u00f3n musical Ciempozuelos se une a la convocatoria nacional de Musiqueando 2016 #nosimportalam\u00fasica, una jornada de sensibilizaci\u00f3n musical que traslada la m\u00fasica de las aulas a la calle de forma simult\u00e1nea en distintos puntos del pa\u00eds. La Plaza de","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/#blogposting","name":"Musiqueando 2016 en Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"Musiqueando 2016 en Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-04-26T08:58:40+02:00","dateModified":"2016-04-26T08:58:40+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/#webpage"},"articleSection":"1105"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1105\/#listItem","name":"1105"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1105\/#listItem","position":2,"name":"1105","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1105\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/#listItem","name":"Musiqueando 2016 en Ciempozuelos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/#listItem","position":3,"name":"Musiqueando 2016 en Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1105\/#listItem","name":"1105"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/","name":"Musiqueando 2016 en Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"M\u00e1s de 100 alumnos de nuestro municipio participan el 28 de abril en esta jornada de sensibilizaci\u00f3n musical Ciempozuelos se une a la convocatoria nacional de Musiqueando 2016 #nosimportalam\u00fasica, una jornada de sensibilizaci\u00f3n musical que traslada la m\u00fasica de las aulas a la calle de forma simult\u00e1nea en distintos puntos del pa\u00eds. La Plaza de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-04-26T08:58:40+02:00","dateModified":"2016-04-26T08:58:40+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Musiqueando 2016 en Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"M\u00e1s de 100 alumnos de nuestro municipio participan el 28 de abril en esta jornada de sensibilizaci\u00f3n musical Ciempozuelos se une a la convocatoria nacional de Musiqueando 2016 #nosimportalam\u00fasica, una jornada de sensibilizaci\u00f3n musical que traslada la m\u00fasica de las aulas a la calle de forma simult\u00e1nea en distintos puntos del pa\u00eds. La Plaza de","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/","article:published_time":"2016-04-26T08:58:40+00:00","article:modified_time":"2016-04-26T08:58:40+00:00","twitter:card":"summary","twitter:title":"Musiqueando 2016 en Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"M\u00e1s de 100 alumnos de nuestro municipio participan el 28 de abril en esta jornada de sensibilizaci\u00f3n musical Ciempozuelos se une a la convocatoria nacional de Musiqueando 2016 #nosimportalam\u00fasica, una jornada de sensibilizaci\u00f3n musical que traslada la m\u00fasica de las aulas a la calle de forma simult\u00e1nea en distintos puntos del pa\u00eds. La Plaza de"},"aioseo_meta_data":{"post_id":"11170","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 16:00:40","updated":"2025-06-04 18:25:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1105\/\" title=\"1105\">1105<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMusiqueando 2016 en Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1105","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1105\/"},{"label":"Musiqueando 2016 en Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/26\/musiqueando-2016-en-ciempozuelos\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 22:14:48","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=11170"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11170\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=11170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=11170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=11170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}