{"id":11162,"date":"2016-04-22T08:03:25","date_gmt":"2016-04-22T08:03:25","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/"},"modified":"2016-04-22T08:03:25","modified_gmt":"2016-04-22T08:03:25","slug":"procedimiento-para-la-explotacion-del-bar-de-la-piscina-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/","title":{"rendered":"Procedimiento para la explotaci\u00f3n del bar de la piscina"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: left;\"><span style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">El Ayuntamiento de Ciempozuelos informa de la publicaci\u00f3n de un nuevo anuncio para la licitaci\u00f3n del contrato administrativo especial de explotaci\u00f3n del bar de la Ciudad Deportiva Municipal, a adjudicar por procedimiento abierto, \u00fanico criterio precio y tramitaci\u00f3n ordinaria.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: left;\"><span style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">En el\u00a0<a href=\"index.php\/tu-ayuntamiento\/perfil-del-contratante\/en-licitacion\/category\/139-explotacion-bar-ciudad-deportiva\">perfil del contratante <\/a>figura en anuncio de la licitaci\u00f3n publicado en el BOCM, el pliego de prescripciones t\u00e9cnicas y el pliego de cl\u00e1usulas administrativas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: left;\"><span style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">El equipo de gobierno contin\u00faa trabajando para llevar a cabo la explotaci\u00f3n del bar de la piscina de verano de Ciempozuelos con el objetivo de generar empleo y garantizar el servicio.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Ciempozuelos informa de la publicaci\u00f3n de un nuevo anuncio para la licitaci\u00f3n del contrato administrativo especial de explotaci\u00f3n del bar de la Ciudad Deportiva Municipal, a adjudicar por procedimiento abierto, \u00fanico criterio precio y tramitaci\u00f3n ordinaria. En el\u00a0perfil del contratante figura en anuncio de la licitaci\u00f3n publicado en el BOCM, el pliego [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1087],"class_list":["post-11162","post","type-post","status-publish","format-standard","hentry","tag-instalaciones"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Ayuntamiento de Ciempozuelos informa de la publicaci\u00f3n de un nuevo anuncio para la licitaci\u00f3n del contrato administrativo especial de explotaci\u00f3n del bar de la Ciudad Deportiva Municipal, a adjudicar por procedimiento abierto, \u00fanico criterio precio y tramitaci\u00f3n ordinaria. En el perfil del contratante figura en anuncio de la licitaci\u00f3n publicado en el BOCM, el pliego\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Procedimiento para la explotaci\u00f3n del bar de la piscina - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El Ayuntamiento de Ciempozuelos informa de la publicaci\u00f3n de un nuevo anuncio para la licitaci\u00f3n del contrato administrativo especial de explotaci\u00f3n del bar de la Ciudad Deportiva Municipal, a adjudicar por procedimiento abierto, \u00fanico criterio precio y tramitaci\u00f3n ordinaria. En el perfil del contratante figura en anuncio de la licitaci\u00f3n publicado en el BOCM, el pliego\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-04-22T08:03:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-04-22T08:03:25+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Procedimiento para la explotaci\u00f3n del bar de la piscina - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Ayuntamiento de Ciempozuelos informa de la publicaci\u00f3n de un nuevo anuncio para la licitaci\u00f3n del contrato administrativo especial de explotaci\u00f3n del bar de la Ciudad Deportiva Municipal, a adjudicar por procedimiento abierto, \u00fanico criterio precio y tramitaci\u00f3n ordinaria. En el perfil del contratante figura en anuncio de la licitaci\u00f3n publicado en el BOCM, el pliego\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/22\\\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\\\/#blogposting\",\"name\":\"Procedimiento para la explotaci\\u00f3n del bar de la piscina - Ayuntamiento de Ciempozuelos\",\"headline\":\"Procedimiento para la explotaci\\u00f3n del bar de la piscina\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-04-22T08:03:25+02:00\",\"dateModified\":\"2016-04-22T08:03:25+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/22\\\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/22\\\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\\\/#webpage\"},\"articleSection\":\"Instalaciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/22\\\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones\\\/#listItem\",\"name\":\"Instalaciones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones\\\/#listItem\",\"position\":2,\"name\":\"Instalaciones\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/22\\\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\\\/#listItem\",\"name\":\"Procedimiento para la explotaci\\u00f3n del bar de la piscina\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/22\\\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\\\/#listItem\",\"position\":3,\"name\":\"Procedimiento para la explotaci\\u00f3n del bar de la piscina\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/instalaciones\\\/#listItem\",\"name\":\"Instalaciones\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/22\\\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/22\\\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/22\\\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\\\/\",\"name\":\"Procedimiento para la explotaci\\u00f3n del bar de la piscina - Ayuntamiento de Ciempozuelos\",\"description\":\"El Ayuntamiento de Ciempozuelos informa de la publicaci\\u00f3n de un nuevo anuncio para la licitaci\\u00f3n del contrato administrativo especial de explotaci\\u00f3n del bar de la Ciudad Deportiva Municipal, a adjudicar por procedimiento abierto, \\u00fanico criterio precio y tramitaci\\u00f3n ordinaria. En el perfil del contratante figura en anuncio de la licitaci\\u00f3n publicado en el BOCM, el pliego\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/22\\\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-04-22T08:03:25+02:00\",\"dateModified\":\"2016-04-22T08:03:25+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Procedimiento para la explotaci\u00f3n del bar de la piscina - Ayuntamiento de Ciempozuelos","description":"El Ayuntamiento de Ciempozuelos informa de la publicaci\u00f3n de un nuevo anuncio para la licitaci\u00f3n del contrato administrativo especial de explotaci\u00f3n del bar de la Ciudad Deportiva Municipal, a adjudicar por procedimiento abierto, \u00fanico criterio precio y tramitaci\u00f3n ordinaria. En el perfil del contratante figura en anuncio de la licitaci\u00f3n publicado en el BOCM, el pliego","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/#blogposting","name":"Procedimiento para la explotaci\u00f3n del bar de la piscina - Ayuntamiento de Ciempozuelos","headline":"Procedimiento para la explotaci\u00f3n del bar de la piscina","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-04-22T08:03:25+02:00","dateModified":"2016-04-22T08:03:25+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/#webpage"},"articleSection":"Instalaciones"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones\/#listItem","name":"Instalaciones"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones\/#listItem","position":2,"name":"Instalaciones","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/#listItem","name":"Procedimiento para la explotaci\u00f3n del bar de la piscina"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/#listItem","position":3,"name":"Procedimiento para la explotaci\u00f3n del bar de la piscina","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones\/#listItem","name":"Instalaciones"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/","name":"Procedimiento para la explotaci\u00f3n del bar de la piscina - Ayuntamiento de Ciempozuelos","description":"El Ayuntamiento de Ciempozuelos informa de la publicaci\u00f3n de un nuevo anuncio para la licitaci\u00f3n del contrato administrativo especial de explotaci\u00f3n del bar de la Ciudad Deportiva Municipal, a adjudicar por procedimiento abierto, \u00fanico criterio precio y tramitaci\u00f3n ordinaria. En el perfil del contratante figura en anuncio de la licitaci\u00f3n publicado en el BOCM, el pliego","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-04-22T08:03:25+02:00","dateModified":"2016-04-22T08:03:25+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Procedimiento para la explotaci\u00f3n del bar de la piscina - Ayuntamiento de Ciempozuelos","og:description":"El Ayuntamiento de Ciempozuelos informa de la publicaci\u00f3n de un nuevo anuncio para la licitaci\u00f3n del contrato administrativo especial de explotaci\u00f3n del bar de la Ciudad Deportiva Municipal, a adjudicar por procedimiento abierto, \u00fanico criterio precio y tramitaci\u00f3n ordinaria. En el perfil del contratante figura en anuncio de la licitaci\u00f3n publicado en el BOCM, el pliego","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/","article:published_time":"2016-04-22T08:03:25+00:00","article:modified_time":"2016-04-22T08:03:25+00:00","twitter:card":"summary","twitter:title":"Procedimiento para la explotaci\u00f3n del bar de la piscina - Ayuntamiento de Ciempozuelos","twitter:description":"El Ayuntamiento de Ciempozuelos informa de la publicaci\u00f3n de un nuevo anuncio para la licitaci\u00f3n del contrato administrativo especial de explotaci\u00f3n del bar de la Ciudad Deportiva Municipal, a adjudicar por procedimiento abierto, \u00fanico criterio precio y tramitaci\u00f3n ordinaria. En el perfil del contratante figura en anuncio de la licitaci\u00f3n publicado en el BOCM, el pliego"},"aioseo_meta_data":{"post_id":"11162","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:59:58","updated":"2025-06-04 18:23:51","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones\/\" title=\"Instalaciones\">Instalaciones<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tProcedimiento para la explotaci\u00f3n del bar de la piscina\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Instalaciones","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/instalaciones\/"},{"label":"Procedimiento para la explotaci\u00f3n del bar de la piscina","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/22\/procedimiento-para-la-explotacion-del-bar-de-la-piscina-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:10:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=11162"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11162\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=11162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=11162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=11162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}