{"id":11158,"date":"2016-04-21T13:33:01","date_gmt":"2016-04-21T13:33:01","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/"},"modified":"2016-04-21T13:33:01","modified_gmt":"2016-04-21T13:33:01","slug":"programacion-por-amor-al-arte-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/","title":{"rendered":"Programaci\u00f3n Por Amor al Arte"},"content":{"rendered":"<p style=\"font-size: 12.16px; line-height: 15.808px;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: 15.6px; text-align: justify;\">Programaci\u00f3n de Por Amor al Arte, acci\u00f3n desarrollada por la Comisi\u00f3n de Cultura y Juventud y las Concejal\u00edas de Cultura, Juventud e Infancia:<\/span><\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\"><img decoding=\"async\" class=\" size-full wp-image-11154\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte2.jpg\" border=\"0\" width=\"100%\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: 15.6px; text-align: justify;\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte2-200x283.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte2-212x300.jpg 212w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte2-400x566.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte2-600x849.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte2.jpg 707w\" sizes=\"(max-width: 707px) 100vw, 707px\" \/><\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: 15.6px; text-align: justify;\"><img decoding=\"async\" class=\" size-full wp-image-11155\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte3.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte3-200x283.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte3-212x300.jpg 212w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte3-400x566.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte3-600x849.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte3.jpg 707w\" sizes=\"(max-width: 707px) 100vw, 707px\" \/><\/span><\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: 15.6px; text-align: justify;\"><img decoding=\"async\" class=\" size-full wp-image-11156\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte4.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte4-200x283.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte4-212x300.jpg 212w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte4-400x566.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte4-600x849.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte4.jpg 707w\" sizes=\"(max-width: 707px) 100vw, 707px\" \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programaci\u00f3n de Por Amor al Arte, acci\u00f3n desarrollada por la Comisi\u00f3n de Cultura y Juventud y las Concejal\u00edas de Cultura, Juventud e Infancia:<\/p>\n","protected":false},"author":1,"featured_media":11154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1070],"class_list":["post-11158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-actividades-culturales-del-mes"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Programaci\u00f3n de Por Amor al Arte, acci\u00f3n desarrollada por la Comisi\u00f3n de Cultura y Juventud y las Concejal\u00edas de Cultura, Juventud e Infancia:\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Programaci\u00f3n Por Amor al Arte - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Programaci\u00f3n de Por Amor al Arte, acci\u00f3n desarrollada por la Comisi\u00f3n de Cultura y Juventud y las Concejal\u00edas de Cultura, Juventud e Infancia:\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-04-21T13:33:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-04-21T13:33:01+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Programaci\u00f3n Por Amor al Arte - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Programaci\u00f3n de Por Amor al Arte, acci\u00f3n desarrollada por la Comisi\u00f3n de Cultura y Juventud y las Concejal\u00edas de Cultura, Juventud e Infancia:\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/#blogposting\",\"name\":\"Programaci\\u00f3n Por Amor al Arte - Ayuntamiento de Ciempozuelos\",\"headline\":\"Programaci\\u00f3n Por Amor al Arte\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/arte2.jpg\",\"width\":707,\"height\":1000},\"datePublished\":\"2016-04-21T13:33:01+02:00\",\"dateModified\":\"2016-04-21T13:33:01+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/#webpage\"},\"articleSection\":\"Actividades culturales del mes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/#listItem\",\"name\":\"Actividades culturales del mes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/#listItem\",\"position\":2,\"name\":\"Actividades culturales del mes\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/#listItem\",\"name\":\"Programaci\\u00f3n Por Amor al Arte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/#listItem\",\"position\":3,\"name\":\"Programaci\\u00f3n Por Amor al Arte\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/#listItem\",\"name\":\"Actividades culturales del mes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/\",\"name\":\"Programaci\\u00f3n Por Amor al Arte - Ayuntamiento de Ciempozuelos\",\"description\":\"Programaci\\u00f3n de Por Amor al Arte, acci\\u00f3n desarrollada por la Comisi\\u00f3n de Cultura y Juventud y las Concejal\\u00edas de Cultura, Juventud e Infancia:\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/arte2.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/#mainImage\",\"width\":707,\"height\":1000},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/21\\\/programacion-por-amor-al-arte-2\\\/#mainImage\"},\"datePublished\":\"2016-04-21T13:33:01+02:00\",\"dateModified\":\"2016-04-21T13:33:01+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Programaci\u00f3n Por Amor al Arte - Ayuntamiento de Ciempozuelos","description":"Programaci\u00f3n de Por Amor al Arte, acci\u00f3n desarrollada por la Comisi\u00f3n de Cultura y Juventud y las Concejal\u00edas de Cultura, Juventud e Infancia:","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/#blogposting","name":"Programaci\u00f3n Por Amor al Arte - Ayuntamiento de Ciempozuelos","headline":"Programaci\u00f3n Por Amor al Arte","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte2.jpg","width":707,"height":1000},"datePublished":"2016-04-21T13:33:01+02:00","dateModified":"2016-04-21T13:33:01+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/#webpage"},"articleSection":"Actividades culturales del mes"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/#listItem","name":"Actividades culturales del mes"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/#listItem","position":2,"name":"Actividades culturales del mes","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/#listItem","name":"Programaci\u00f3n Por Amor al Arte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/#listItem","position":3,"name":"Programaci\u00f3n Por Amor al Arte","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/#listItem","name":"Actividades culturales del mes"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/","name":"Programaci\u00f3n Por Amor al Arte - Ayuntamiento de Ciempozuelos","description":"Programaci\u00f3n de Por Amor al Arte, acci\u00f3n desarrollada por la Comisi\u00f3n de Cultura y Juventud y las Concejal\u00edas de Cultura, Juventud e Infancia:","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/04\/arte2.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/#mainImage","width":707,"height":1000},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/#mainImage"},"datePublished":"2016-04-21T13:33:01+02:00","dateModified":"2016-04-21T13:33:01+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Programaci\u00f3n Por Amor al Arte - Ayuntamiento de Ciempozuelos","og:description":"Programaci\u00f3n de Por Amor al Arte, acci\u00f3n desarrollada por la Comisi\u00f3n de Cultura y Juventud y las Concejal\u00edas de Cultura, Juventud e Infancia:","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/","article:published_time":"2016-04-21T13:33:01+00:00","article:modified_time":"2016-04-21T13:33:01+00:00","twitter:card":"summary","twitter:title":"Programaci\u00f3n Por Amor al Arte - Ayuntamiento de Ciempozuelos","twitter:description":"Programaci\u00f3n de Por Amor al Arte, acci\u00f3n desarrollada por la Comisi\u00f3n de Cultura y Juventud y las Concejal\u00edas de Cultura, Juventud e Infancia:"},"aioseo_meta_data":{"post_id":"11158","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:59:04","updated":"2025-06-04 18:23:51","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/\" title=\"Actividades culturales del mes\">Actividades culturales del mes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tProgramaci\u00f3n Por Amor al Arte\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Actividades culturales del mes","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/"},{"label":"Programaci\u00f3n Por Amor al Arte","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/21\/programacion-por-amor-al-arte-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:49:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=11158"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/11154"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=11158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=11158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=11158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}