{"id":11140,"date":"2016-04-18T12:33:22","date_gmt":"2016-04-18T12:33:22","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/"},"modified":"2016-04-18T12:33:22","modified_gmt":"2016-04-18T12:33:22","slug":"xvii-lectura-publica-de-el-quijote-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/","title":{"rendered":"XVII Lectura P\u00fablica de &#8216;El Quijote&#8217;"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><em>Cuarto centenario de la muerte de Miguel de Cervantes<\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><em> <\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La asociaci\u00f3n cultural La Torre, en colaboraci\u00f3n con el Ayuntamiento de Ciempozuelos, organiza la XVII lectura p\u00fablica de \u2018El ingenioso hidalgo Don Quijote de la Mancha\u2019 en Ciempozuelos. La cita es este domingo, 24 de abril, de 10.00 a 14.00 horas en el Sal\u00f3n de Plenos del Ayuntamiento de Ciempozuelos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Esta decimos\u00e9ptima edici\u00f3n de la lectura p\u00fablica del cl\u00e1sico de la literatura coincide con el 400 aniversario del fallecimiento del autor, Miguel de Cervantes y Saavedra, as\u00ed como de William Shakespeare y Garcilaso de la Vega, ocurridos el 23 de abril de 2016. Por este motivo, la Unesco acord\u00f3 proclamar el 23 de abril como el D\u00eda Mundial del Libro y de los Derechos de Autor.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Todas las personas que quieran participar en esta lectura p\u00fablica pueden retirar su lectura en la Biblioteca Municipal o enviando un correo a asociacion.la.torre@gmail.com. Tambi\u00e9n se podr\u00e1 participar sin turno previo aunque tendr\u00e1n preferencia los que ya cuenten con su lectura reservada. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuarto centenario de la muerte de Miguel de Cervantes La asociaci\u00f3n cultural La Torre, en colaboraci\u00f3n con el Ayuntamiento de Ciempozuelos, organiza la XVII lectura p\u00fablica de \u2018El ingenioso hidalgo Don Quijote de la Mancha\u2019 en Ciempozuelos. La cita es este domingo, 24 de abril, de 10.00 a 14.00 horas en el Sal\u00f3n de Plenos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1070],"class_list":["post-11140","post","type-post","status-publish","format-standard","hentry","tag-actividades-culturales-del-mes"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cuarto centenario de la muerte de Miguel de Cervantes La asociaci\u00f3n cultural La Torre, en colaboraci\u00f3n con el Ayuntamiento de Ciempozuelos, organiza la XVII lectura p\u00fablica de \u2018El ingenioso hidalgo Don Quijote de la Mancha\u2019 en Ciempozuelos. La cita es este domingo, 24 de abril, de 10.00 a 14.00 horas en el Sal\u00f3n de Plenos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"XVII Lectura P\u00fablica de \u2018El Quijote\u2019 - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Cuarto centenario de la muerte de Miguel de Cervantes La asociaci\u00f3n cultural La Torre, en colaboraci\u00f3n con el Ayuntamiento de Ciempozuelos, organiza la XVII lectura p\u00fablica de \u2018El ingenioso hidalgo Don Quijote de la Mancha\u2019 en Ciempozuelos. La cita es este domingo, 24 de abril, de 10.00 a 14.00 horas en el Sal\u00f3n de Plenos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-04-18T12:33:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-04-18T12:33:22+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"XVII Lectura P\u00fablica de \u2018El Quijote\u2019 - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cuarto centenario de la muerte de Miguel de Cervantes La asociaci\u00f3n cultural La Torre, en colaboraci\u00f3n con el Ayuntamiento de Ciempozuelos, organiza la XVII lectura p\u00fablica de \u2018El ingenioso hidalgo Don Quijote de la Mancha\u2019 en Ciempozuelos. La cita es este domingo, 24 de abril, de 10.00 a 14.00 horas en el Sal\u00f3n de Plenos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/18\\\/xvii-lectura-publica-de-el-quijote-2\\\/#blogposting\",\"name\":\"XVII Lectura P\\u00fablica de \\u2018El Quijote\\u2019 - Ayuntamiento de Ciempozuelos\",\"headline\":\"XVII Lectura P\\u00fablica de &#8216;El Quijote&#8217;\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-04-18T12:33:22+02:00\",\"dateModified\":\"2016-04-18T12:33:22+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/18\\\/xvii-lectura-publica-de-el-quijote-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/18\\\/xvii-lectura-publica-de-el-quijote-2\\\/#webpage\"},\"articleSection\":\"Actividades culturales del mes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/18\\\/xvii-lectura-publica-de-el-quijote-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/#listItem\",\"name\":\"Actividades culturales del mes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/#listItem\",\"position\":2,\"name\":\"Actividades culturales del mes\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/18\\\/xvii-lectura-publica-de-el-quijote-2\\\/#listItem\",\"name\":\"XVII Lectura P\\u00fablica de &#8216;El Quijote&#8217;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/18\\\/xvii-lectura-publica-de-el-quijote-2\\\/#listItem\",\"position\":3,\"name\":\"XVII Lectura P\\u00fablica de &#8216;El Quijote&#8217;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/#listItem\",\"name\":\"Actividades culturales del mes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/18\\\/xvii-lectura-publica-de-el-quijote-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/18\\\/xvii-lectura-publica-de-el-quijote-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/18\\\/xvii-lectura-publica-de-el-quijote-2\\\/\",\"name\":\"XVII Lectura P\\u00fablica de \\u2018El Quijote\\u2019 - Ayuntamiento de Ciempozuelos\",\"description\":\"Cuarto centenario de la muerte de Miguel de Cervantes La asociaci\\u00f3n cultural La Torre, en colaboraci\\u00f3n con el Ayuntamiento de Ciempozuelos, organiza la XVII lectura p\\u00fablica de \\u2018El ingenioso hidalgo Don Quijote de la Mancha\\u2019 en Ciempozuelos. La cita es este domingo, 24 de abril, de 10.00 a 14.00 horas en el Sal\\u00f3n de Plenos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/04\\\/18\\\/xvii-lectura-publica-de-el-quijote-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-04-18T12:33:22+02:00\",\"dateModified\":\"2016-04-18T12:33:22+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"XVII Lectura P\u00fablica de \u2018El Quijote\u2019 - Ayuntamiento de Ciempozuelos","description":"Cuarto centenario de la muerte de Miguel de Cervantes La asociaci\u00f3n cultural La Torre, en colaboraci\u00f3n con el Ayuntamiento de Ciempozuelos, organiza la XVII lectura p\u00fablica de \u2018El ingenioso hidalgo Don Quijote de la Mancha\u2019 en Ciempozuelos. La cita es este domingo, 24 de abril, de 10.00 a 14.00 horas en el Sal\u00f3n de Plenos","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/#blogposting","name":"XVII Lectura P\u00fablica de \u2018El Quijote\u2019 - Ayuntamiento de Ciempozuelos","headline":"XVII Lectura P\u00fablica de &#8216;El Quijote&#8217;","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-04-18T12:33:22+02:00","dateModified":"2016-04-18T12:33:22+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/#webpage"},"articleSection":"Actividades culturales del mes"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/#listItem","name":"Actividades culturales del mes"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/#listItem","position":2,"name":"Actividades culturales del mes","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/#listItem","name":"XVII Lectura P\u00fablica de &#8216;El Quijote&#8217;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/#listItem","position":3,"name":"XVII Lectura P\u00fablica de &#8216;El Quijote&#8217;","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/#listItem","name":"Actividades culturales del mes"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/","name":"XVII Lectura P\u00fablica de \u2018El Quijote\u2019 - Ayuntamiento de Ciempozuelos","description":"Cuarto centenario de la muerte de Miguel de Cervantes La asociaci\u00f3n cultural La Torre, en colaboraci\u00f3n con el Ayuntamiento de Ciempozuelos, organiza la XVII lectura p\u00fablica de \u2018El ingenioso hidalgo Don Quijote de la Mancha\u2019 en Ciempozuelos. La cita es este domingo, 24 de abril, de 10.00 a 14.00 horas en el Sal\u00f3n de Plenos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-04-18T12:33:22+02:00","dateModified":"2016-04-18T12:33:22+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"XVII Lectura P\u00fablica de \u2018El Quijote\u2019 - Ayuntamiento de Ciempozuelos","og:description":"Cuarto centenario de la muerte de Miguel de Cervantes La asociaci\u00f3n cultural La Torre, en colaboraci\u00f3n con el Ayuntamiento de Ciempozuelos, organiza la XVII lectura p\u00fablica de \u2018El ingenioso hidalgo Don Quijote de la Mancha\u2019 en Ciempozuelos. La cita es este domingo, 24 de abril, de 10.00 a 14.00 horas en el Sal\u00f3n de Plenos","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/","article:published_time":"2016-04-18T12:33:22+00:00","article:modified_time":"2016-04-18T12:33:22+00:00","twitter:card":"summary","twitter:title":"XVII Lectura P\u00fablica de \u2018El Quijote\u2019 - Ayuntamiento de Ciempozuelos","twitter:description":"Cuarto centenario de la muerte de Miguel de Cervantes La asociaci\u00f3n cultural La Torre, en colaboraci\u00f3n con el Ayuntamiento de Ciempozuelos, organiza la XVII lectura p\u00fablica de \u2018El ingenioso hidalgo Don Quijote de la Mancha\u2019 en Ciempozuelos. La cita es este domingo, 24 de abril, de 10.00 a 14.00 horas en el Sal\u00f3n de Plenos"},"aioseo_meta_data":{"post_id":"11140","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:58:20","updated":"2025-06-04 18:22:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/\" title=\"Actividades culturales del mes\">Actividades culturales del mes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tXVII Lectura P\u00fablica de \u2018El Quijote\u2019\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Actividades culturales del mes","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/"},{"label":"XVII Lectura P\u00fablica de &#8216;El Quijote&#8217;","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/04\/18\/xvii-lectura-publica-de-el-quijote-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:07:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=11140"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11140\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=11140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=11140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=11140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}