{"id":11066,"date":"2016-03-22T11:04:16","date_gmt":"2016-03-22T11:04:16","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/"},"modified":"2016-03-22T11:04:16","modified_gmt":"2016-03-22T11:04:16","slug":"bodegones-sin-complejos-en-la-biblioteca-municipal-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/","title":{"rendered":"&#8216;Bodegones sin complejos&#8217; en la Biblioteca Municipal"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">J<\/span><em style=\"font-size: 12.16px; line-height: 1.3em;\">os\u00e9 Manuel Hidalgo ofrece una nueva perspectiva de la naturaleza muerta<\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La Biblioteca Municipal de Ciempozuelos acoge la exposici\u00f3n pict\u00f3rica \u2018Bodegones sin complejos\u2019 del vecino Jos\u00e9 Manuel Hidalgo. La muestra, compuesta por 20 \u00f3leos, se puede visitar hasta el 26 de abril.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El autor busca \u201ccambiar el concepto clasicista del bodeg\u00f3n\u201d, innovar mediante el uso de los mismos elementos tradicionales que conforman la naturaleza muerta pero sac\u00e1ndolos al exterior, al espacio libre. Una colecci\u00f3n colorida con un gusto especial por las transparencias y reflejos que aporta el cristal, material preferido por el pintor.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Jos\u00e9 Manuel Hidalgo (Madrid 1953), vecino de Ciempozuelos desde 1997, es un artista multidisciplinar. Su pasi\u00f3n y dedicaci\u00f3n le ha llevado a crear colecciones de diferentes estilos art\u00edsticos y pict\u00f3ricos para expresar la creatividad de su arte. Entre sus varias facetas destaca como pintor autodidacta, poeta y pensador.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La muestra se puede visitar hasta el 26 de abril en la Biblioteca Municipal (c\/ Colegiata, 3) en horario de lunes a viernes de 9.00 a 21.00. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jos\u00e9 Manuel Hidalgo ofrece una nueva perspectiva de la naturaleza muerta La Biblioteca Municipal de Ciempozuelos acoge la exposici\u00f3n pict\u00f3rica \u2018Bodegones sin complejos\u2019 del vecino Jos\u00e9 Manuel Hidalgo. La muestra, compuesta por 20 \u00f3leos, se puede visitar hasta el 26 de abril. El autor busca \u201ccambiar el concepto clasicista del bodeg\u00f3n\u201d, innovar mediante el uso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1180],"class_list":["post-11066","post","type-post","status-publish","format-standard","hentry","tag-exposiciones"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Jos\u00e9 Manuel Hidalgo ofrece una nueva perspectiva de la naturaleza muerta La Biblioteca Municipal de Ciempozuelos acoge la exposici\u00f3n pict\u00f3rica \u2018Bodegones sin complejos\u2019 del vecino Jos\u00e9 Manuel Hidalgo. La muestra, compuesta por 20 \u00f3leos, se puede visitar hasta el 26 de abril. El autor busca \u201ccambiar el concepto clasicista del bodeg\u00f3n\u201d, innovar mediante el uso\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u2018Bodegones sin complejos\u2019 en la Biblioteca Municipal - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Jos\u00e9 Manuel Hidalgo ofrece una nueva perspectiva de la naturaleza muerta La Biblioteca Municipal de Ciempozuelos acoge la exposici\u00f3n pict\u00f3rica \u2018Bodegones sin complejos\u2019 del vecino Jos\u00e9 Manuel Hidalgo. La muestra, compuesta por 20 \u00f3leos, se puede visitar hasta el 26 de abril. El autor busca \u201ccambiar el concepto clasicista del bodeg\u00f3n\u201d, innovar mediante el uso\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-03-22T11:04:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-03-22T11:04:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u2018Bodegones sin complejos\u2019 en la Biblioteca Municipal - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Jos\u00e9 Manuel Hidalgo ofrece una nueva perspectiva de la naturaleza muerta La Biblioteca Municipal de Ciempozuelos acoge la exposici\u00f3n pict\u00f3rica \u2018Bodegones sin complejos\u2019 del vecino Jos\u00e9 Manuel Hidalgo. La muestra, compuesta por 20 \u00f3leos, se puede visitar hasta el 26 de abril. El autor busca \u201ccambiar el concepto clasicista del bodeg\u00f3n\u201d, innovar mediante el uso\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/22\\\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\\\/#blogposting\",\"name\":\"\\u2018Bodegones sin complejos\\u2019 en la Biblioteca Municipal - Ayuntamiento de Ciempozuelos\",\"headline\":\"&#8216;Bodegones sin complejos&#8217; en la Biblioteca Municipal\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-03-22T11:04:16+01:00\",\"dateModified\":\"2016-03-22T11:04:16+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/22\\\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/22\\\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\\\/#webpage\"},\"articleSection\":\"Exposiciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/22\\\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposiciones\\\/#listItem\",\"name\":\"Exposiciones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposiciones\\\/#listItem\",\"position\":2,\"name\":\"Exposiciones\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposiciones\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/22\\\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\\\/#listItem\",\"name\":\"&#8216;Bodegones sin complejos&#8217; en la Biblioteca Municipal\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/22\\\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\\\/#listItem\",\"position\":3,\"name\":\"&#8216;Bodegones sin complejos&#8217; en la Biblioteca Municipal\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposiciones\\\/#listItem\",\"name\":\"Exposiciones\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/22\\\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/22\\\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/22\\\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\\\/\",\"name\":\"\\u2018Bodegones sin complejos\\u2019 en la Biblioteca Municipal - Ayuntamiento de Ciempozuelos\",\"description\":\"Jos\\u00e9 Manuel Hidalgo ofrece una nueva perspectiva de la naturaleza muerta La Biblioteca Municipal de Ciempozuelos acoge la exposici\\u00f3n pict\\u00f3rica \\u2018Bodegones sin complejos\\u2019 del vecino Jos\\u00e9 Manuel Hidalgo. La muestra, compuesta por 20 \\u00f3leos, se puede visitar hasta el 26 de abril. El autor busca \\u201ccambiar el concepto clasicista del bodeg\\u00f3n\\u201d, innovar mediante el uso\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/22\\\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-03-22T11:04:16+01:00\",\"dateModified\":\"2016-03-22T11:04:16+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u2018Bodegones sin complejos\u2019 en la Biblioteca Municipal - Ayuntamiento de Ciempozuelos","description":"Jos\u00e9 Manuel Hidalgo ofrece una nueva perspectiva de la naturaleza muerta La Biblioteca Municipal de Ciempozuelos acoge la exposici\u00f3n pict\u00f3rica \u2018Bodegones sin complejos\u2019 del vecino Jos\u00e9 Manuel Hidalgo. La muestra, compuesta por 20 \u00f3leos, se puede visitar hasta el 26 de abril. El autor busca \u201ccambiar el concepto clasicista del bodeg\u00f3n\u201d, innovar mediante el uso","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/#blogposting","name":"\u2018Bodegones sin complejos\u2019 en la Biblioteca Municipal - Ayuntamiento de Ciempozuelos","headline":"&#8216;Bodegones sin complejos&#8217; en la Biblioteca Municipal","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-03-22T11:04:16+01:00","dateModified":"2016-03-22T11:04:16+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/#webpage"},"articleSection":"Exposiciones"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/#listItem","name":"Exposiciones"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/#listItem","position":2,"name":"Exposiciones","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/#listItem","name":"&#8216;Bodegones sin complejos&#8217; en la Biblioteca Municipal"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/#listItem","position":3,"name":"&#8216;Bodegones sin complejos&#8217; en la Biblioteca Municipal","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/#listItem","name":"Exposiciones"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/","name":"\u2018Bodegones sin complejos\u2019 en la Biblioteca Municipal - Ayuntamiento de Ciempozuelos","description":"Jos\u00e9 Manuel Hidalgo ofrece una nueva perspectiva de la naturaleza muerta La Biblioteca Municipal de Ciempozuelos acoge la exposici\u00f3n pict\u00f3rica \u2018Bodegones sin complejos\u2019 del vecino Jos\u00e9 Manuel Hidalgo. La muestra, compuesta por 20 \u00f3leos, se puede visitar hasta el 26 de abril. El autor busca \u201ccambiar el concepto clasicista del bodeg\u00f3n\u201d, innovar mediante el uso","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-03-22T11:04:16+01:00","dateModified":"2016-03-22T11:04:16+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"\u2018Bodegones sin complejos\u2019 en la Biblioteca Municipal - Ayuntamiento de Ciempozuelos","og:description":"Jos\u00e9 Manuel Hidalgo ofrece una nueva perspectiva de la naturaleza muerta La Biblioteca Municipal de Ciempozuelos acoge la exposici\u00f3n pict\u00f3rica \u2018Bodegones sin complejos\u2019 del vecino Jos\u00e9 Manuel Hidalgo. La muestra, compuesta por 20 \u00f3leos, se puede visitar hasta el 26 de abril. El autor busca \u201ccambiar el concepto clasicista del bodeg\u00f3n\u201d, innovar mediante el uso","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/","article:published_time":"2016-03-22T11:04:16+00:00","article:modified_time":"2016-03-22T11:04:16+00:00","twitter:card":"summary","twitter:title":"\u2018Bodegones sin complejos\u2019 en la Biblioteca Municipal - Ayuntamiento de Ciempozuelos","twitter:description":"Jos\u00e9 Manuel Hidalgo ofrece una nueva perspectiva de la naturaleza muerta La Biblioteca Municipal de Ciempozuelos acoge la exposici\u00f3n pict\u00f3rica \u2018Bodegones sin complejos\u2019 del vecino Jos\u00e9 Manuel Hidalgo. La muestra, compuesta por 20 \u00f3leos, se puede visitar hasta el 26 de abril. El autor busca \u201ccambiar el concepto clasicista del bodeg\u00f3n\u201d, innovar mediante el uso"},"aioseo_meta_data":{"post_id":"11066","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:49:06","updated":"2025-06-04 18:14:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/\" title=\"Exposiciones\">Exposiciones<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u2018Bodegones sin complejos\u2019 en la Biblioteca Municipal\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Exposiciones","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/"},{"label":"&#8216;Bodegones sin complejos&#8217; en la Biblioteca Municipal","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/22\/bodegones-sin-complejos-en-la-biblioteca-municipal-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 21:06:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=11066"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11066\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=11066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=11066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=11066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}