{"id":11050,"date":"2016-03-17T11:39:08","date_gmt":"2016-03-17T11:39:08","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/"},"modified":"2016-03-17T11:39:08","modified_gmt":"2016-03-17T11:39:08","slug":"la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/","title":{"rendered":"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\"><em style=\"font-size: 12.16px; line-height: 1.3em;\">El equipo de Gobierno rechaza la situaci\u00f3n por inhumana e irresponsable<\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\"><em style=\"font-size: 12.16px; line-height: 1.3em;\"><\/em><span style=\"font-size: 12.16px; line-height: 1.3em; text-align: justify;\">El Ayuntamiento de Ciempozuelos ha ordenado, mediante decreto de alcald\u00eda, que las banderas de la Uni\u00f3n Europea situadas en edificios y dependencias municipales ondeen a media asta en se\u00f1al de protesta por las pol\u00edticas de inanici\u00f3n y no acogimiento de los refugiados y en recuerdo de los miles de fallecidos intentando alcanzar la esperanza de una vida digna por los conflictos b\u00e9licos de Siria y otros pa\u00edses.<\/span><span style=\"text-align: justify; font-size: 12.16px; line-height: 1.3em;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify;text-justify:inter-ideograph\">A finales de agosto de 2015, la crisis humanitaria provocada por la inacci\u00f3n de los poderes pol\u00edticos en torno al grave problema humanitario con los refugiados que llegaban a los pa\u00edses europeos alcanz\u00f3 de lleno a todas las instituciones europeas, gobiernos nacionales y opini\u00f3n p\u00fablica.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify;text-justify:inter-ideograph\">Esta situaci\u00f3n gener\u00f3 iniciativas en multitud de \u00e1mbitos, que fueron desde los intentos por solucionar los conflictos de origen, la b\u00fasqueda de acuerdos respecto a los criterios de distribuci\u00f3n de refugiados entre los pa\u00edses de la Uni\u00f3n Europea o los intentos de avanzar en una legislaci\u00f3n de asilo europeo.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify;text-justify:inter-ideograph\">En Ciempozuelos se celebr\u00f3 una reuni\u00f3n el 9 de septiembre del 2015 para abordar la posible suma de nuestro municipio a la red de ciudades solidarias con las personas refugiadas. En esta reuni\u00f3n fueron invitados\u00a0 un miembro de CEAR (Comisi\u00f3n Espa\u00f1ola de Ayuda al Refugiado) y un miembro de la Asociaci\u00f3n de Parla con el S\u00e1hara y se lleg\u00f3 a la conclusi\u00f3n de que era necesario la suma\u00a0 a la red de ciudades solidarias. En el pleno de septiembre todos los partidos firmaron una\u00a0 declaraci\u00f3n institucional de apoyo a los refugiados a expensas de las iniciativas que desde el Estado se prometieron y que se iban a canalizar a trav\u00e9s de la Federaci\u00f3n Espa\u00f1ola de Municipios y Provincias.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify;text-justify:inter-ideograph\">Pero pr\u00e1cticamente ninguna de las medidas presentadas se ha puesto en marcha de manera completa, y casi seis meses despu\u00e9s la situaci\u00f3n, lejos de mejorar, no ha hecho sino empeorar.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify;text-justify:inter-ideograph\">En este marco, el 7 de marzo se ha celebrado una cumbre de Jefes de Estado y de Gobierno de la Uni\u00f3n Europea con Turqu\u00eda en la que se ha dado un giro radical a la posici\u00f3n de la UE en relaci\u00f3n con la crisis de refugiados, consistente en devolver a Turqu\u00eda a todos los que lleguen a las costas griegas, a cambio de incrementar las ayudas a este pa\u00eds y aumentar los reasentamientos en los Estados miembros, no exigir visado a sus ciudadanos y avanzar en el proceso de adhesi\u00f3n, aumentando la incertidumbre, el sufrimiento y las condiciones de vida de los exiliados a causa del conflicto armado de Siria y otros pa\u00edses.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify;text-justify:inter-ideograph\">El equipo de Gobierno del Ayuntamiento de Ciempozuelos, convencido de que esta precaria situaci\u00f3n se enfrenta a los principios de solidaridad y humanismo que Europa debe tener y que desde nuestra humilde condici\u00f3n local, la rechaza por inhumana e irresponsable.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify;text-justify:inter-ideograph\">La condici\u00f3n de pa\u00eds comunitario obliga a exigir a las autoridades europeas pol\u00edticas solidarias y valientes que sean capaces de albergar y proteger a los v\u00edctimas inocentes de una guerra que no han provocado y por ello, en se\u00f1al de protesta y solidaridad con los miles y miles de refugiados procedentes de pa\u00edses en conflicto armado, desprotegidos de la aplicaci\u00f3n del Derecho Internacional en materia de Refugiados y Asilo Pol\u00edtico Internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo de Gobierno rechaza la situaci\u00f3n por inhumana e irresponsable El Ayuntamiento de Ciempozuelos ha ordenado, mediante decreto de alcald\u00eda, que las banderas de la Uni\u00f3n Europea situadas en edificios y dependencias municipales ondeen a media asta en se\u00f1al de protesta por las pol\u00edticas de inanici\u00f3n y no acogimiento de los refugiados y en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1118],"class_list":["post-11050","post","type-post","status-publish","format-standard","hentry","tag-presidencia-maria-jesus-alonso-lazareno"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El equipo de Gobierno rechaza la situaci\u00f3n por inhumana e irresponsable El Ayuntamiento de Ciempozuelos ha ordenado, mediante decreto de alcald\u00eda, que las banderas de la Uni\u00f3n Europea situadas en edificios y dependencias municipales ondeen a media asta en se\u00f1al de protesta por las pol\u00edticas de inanici\u00f3n y no acogimiento de los refugiados y en\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El equipo de Gobierno rechaza la situaci\u00f3n por inhumana e irresponsable El Ayuntamiento de Ciempozuelos ha ordenado, mediante decreto de alcald\u00eda, que las banderas de la Uni\u00f3n Europea situadas en edificios y dependencias municipales ondeen a media asta en se\u00f1al de protesta por las pol\u00edticas de inanici\u00f3n y no acogimiento de los refugiados y en\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-03-17T11:39:08+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-03-17T11:39:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El equipo de Gobierno rechaza la situaci\u00f3n por inhumana e irresponsable El Ayuntamiento de Ciempozuelos ha ordenado, mediante decreto de alcald\u00eda, que las banderas de la Uni\u00f3n Europea situadas en edificios y dependencias municipales ondeen a media asta en se\u00f1al de protesta por las pol\u00edticas de inanici\u00f3n y no acogimiento de los refugiados y en\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/17\\\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\\\/#blogposting\",\"name\":\"La bandera de la UE ondea a media asta como protesta ante la pol\\u00edtica europea con los refugiados - Ayuntamiento de Ciempozuelos\",\"headline\":\"La bandera de la UE ondea a media asta como protesta ante la pol\\u00edtica europea con los refugiados\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-03-17T11:39:08+01:00\",\"dateModified\":\"2016-03-17T11:39:08+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/17\\\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/17\\\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\\\/#webpage\"},\"articleSection\":\"Presidencia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/17\\\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/presidencia-maria-jesus-alonso-lazareno\\\/#listItem\",\"name\":\"Presidencia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/presidencia-maria-jesus-alonso-lazareno\\\/#listItem\",\"position\":2,\"name\":\"Presidencia\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/presidencia-maria-jesus-alonso-lazareno\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/17\\\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\\\/#listItem\",\"name\":\"La bandera de la UE ondea a media asta como protesta ante la pol\\u00edtica europea con los refugiados\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/17\\\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\\\/#listItem\",\"position\":3,\"name\":\"La bandera de la UE ondea a media asta como protesta ante la pol\\u00edtica europea con los refugiados\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/presidencia-maria-jesus-alonso-lazareno\\\/#listItem\",\"name\":\"Presidencia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/17\\\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/17\\\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/17\\\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\\\/\",\"name\":\"La bandera de la UE ondea a media asta como protesta ante la pol\\u00edtica europea con los refugiados - Ayuntamiento de Ciempozuelos\",\"description\":\"El equipo de Gobierno rechaza la situaci\\u00f3n por inhumana e irresponsable El Ayuntamiento de Ciempozuelos ha ordenado, mediante decreto de alcald\\u00eda, que las banderas de la Uni\\u00f3n Europea situadas en edificios y dependencias municipales ondeen a media asta en se\\u00f1al de protesta por las pol\\u00edticas de inanici\\u00f3n y no acogimiento de los refugiados y en\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/17\\\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-03-17T11:39:08+01:00\",\"dateModified\":\"2016-03-17T11:39:08+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados - Ayuntamiento de Ciempozuelos","description":"El equipo de Gobierno rechaza la situaci\u00f3n por inhumana e irresponsable El Ayuntamiento de Ciempozuelos ha ordenado, mediante decreto de alcald\u00eda, que las banderas de la Uni\u00f3n Europea situadas en edificios y dependencias municipales ondeen a media asta en se\u00f1al de protesta por las pol\u00edticas de inanici\u00f3n y no acogimiento de los refugiados y en","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/#blogposting","name":"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados - Ayuntamiento de Ciempozuelos","headline":"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-03-17T11:39:08+01:00","dateModified":"2016-03-17T11:39:08+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/#webpage"},"articleSection":"Presidencia"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/#listItem","name":"Presidencia"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/#listItem","position":2,"name":"Presidencia","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/#listItem","name":"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/#listItem","position":3,"name":"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/#listItem","name":"Presidencia"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/","name":"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados - Ayuntamiento de Ciempozuelos","description":"El equipo de Gobierno rechaza la situaci\u00f3n por inhumana e irresponsable El Ayuntamiento de Ciempozuelos ha ordenado, mediante decreto de alcald\u00eda, que las banderas de la Uni\u00f3n Europea situadas en edificios y dependencias municipales ondeen a media asta en se\u00f1al de protesta por las pol\u00edticas de inanici\u00f3n y no acogimiento de los refugiados y en","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-03-17T11:39:08+01:00","dateModified":"2016-03-17T11:39:08+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados - Ayuntamiento de Ciempozuelos","og:description":"El equipo de Gobierno rechaza la situaci\u00f3n por inhumana e irresponsable El Ayuntamiento de Ciempozuelos ha ordenado, mediante decreto de alcald\u00eda, que las banderas de la Uni\u00f3n Europea situadas en edificios y dependencias municipales ondeen a media asta en se\u00f1al de protesta por las pol\u00edticas de inanici\u00f3n y no acogimiento de los refugiados y en","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/","article:published_time":"2016-03-17T11:39:08+00:00","article:modified_time":"2016-03-17T11:39:08+00:00","twitter:card":"summary","twitter:title":"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados - Ayuntamiento de Ciempozuelos","twitter:description":"El equipo de Gobierno rechaza la situaci\u00f3n por inhumana e irresponsable El Ayuntamiento de Ciempozuelos ha ordenado, mediante decreto de alcald\u00eda, que las banderas de la Uni\u00f3n Europea situadas en edificios y dependencias municipales ondeen a media asta en se\u00f1al de protesta por las pol\u00edticas de inanici\u00f3n y no acogimiento de los refugiados y en"},"aioseo_meta_data":{"post_id":"11050","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:47:56","updated":"2025-06-04 18:13:07","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/\" title=\"Presidencia\">Presidencia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Presidencia","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/"},{"label":"La bandera de la UE ondea a media asta como protesta ante la pol\u00edtica europea con los refugiados","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/17\/la-bandera-de-la-ue-ondea-a-media-asta-como-protesta-ante-la-politica-europea-con-los-refugiados-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:13:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=11050"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11050\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=11050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=11050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=11050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}