{"id":11007,"date":"2016-03-14T08:41:19","date_gmt":"2016-03-14T08:41:19","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/"},"modified":"2016-03-14T08:41:19","modified_gmt":"2016-03-14T08:41:19","slug":"campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/","title":{"rendered":"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><em>Hasta el 20 de marzo<\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">La Polic\u00eda Local de Ciempozuelos inicia hoy una campa\u00f1a de vigilancia y control de los dispositivos de seguridad: cintur\u00f3n y sistemas de retenci\u00f3n infantil (SRI) en nuestro municipio a iniciativa de la Direcci\u00f3n General de Tr\u00e1fico (DGT).<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Desde la Polic\u00eda Local recuerdan que es obligatorio llevar siempre el cintur\u00f3n de seguridad abrochado tanto en carretera como en ciudad. No llevarlo puesto, junto con la velocidad y la conducci\u00f3n bajo los efectos del alcohol, es uno de los principales factores de riesgo en la carretera. Su uso reduce a la mitad el riesgo de muerte en caso de accidente.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">\u00a0<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">En el caso de los sistemas de retenci\u00f3n infantil (SRI), su uso es obligatorio en ni\u00f1os con una altura inferior a 1,35m. (Alrededor de 12 a\u00f1os) y recomendable hasta los 1,50m, homologados a su talla y peso. Desde la campa\u00f1a recuerdan que nueve de cada diez lesiones infantiles graves o mortales se habr\u00edan evitado si se hubieran utilizado los sistemas de retenci\u00f3n infantil obligatorios.<\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hasta el 20 de marzo La Polic\u00eda Local de Ciempozuelos inicia hoy una campa\u00f1a de vigilancia y control de los dispositivos de seguridad: cintur\u00f3n y sistemas de retenci\u00f3n infantil (SRI) en nuestro municipio a iniciativa de la Direcci\u00f3n General de Tr\u00e1fico (DGT). Desde la Polic\u00eda Local recuerdan que es obligatorio llevar siempre el cintur\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1118],"class_list":["post-11007","post","type-post","status-publish","format-standard","hentry","tag-presidencia-maria-jesus-alonso-lazareno"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hasta el 20 de marzo La Polic\u00eda Local de Ciempozuelos inicia hoy una campa\u00f1a de vigilancia y control de los dispositivos de seguridad: cintur\u00f3n y sistemas de retenci\u00f3n infantil (SRI) en nuestro municipio a iniciativa de la Direcci\u00f3n General de Tr\u00e1fico (DGT). Desde la Polic\u00eda Local recuerdan que es obligatorio llevar siempre el cintur\u00f3n de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Hasta el 20 de marzo La Polic\u00eda Local de Ciempozuelos inicia hoy una campa\u00f1a de vigilancia y control de los dispositivos de seguridad: cintur\u00f3n y sistemas de retenci\u00f3n infantil (SRI) en nuestro municipio a iniciativa de la Direcci\u00f3n General de Tr\u00e1fico (DGT). Desde la Polic\u00eda Local recuerdan que es obligatorio llevar siempre el cintur\u00f3n de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-03-14T08:41:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-03-14T08:41:19+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hasta el 20 de marzo La Polic\u00eda Local de Ciempozuelos inicia hoy una campa\u00f1a de vigilancia y control de los dispositivos de seguridad: cintur\u00f3n y sistemas de retenci\u00f3n infantil (SRI) en nuestro municipio a iniciativa de la Direcci\u00f3n General de Tr\u00e1fico (DGT). Desde la Polic\u00eda Local recuerdan que es obligatorio llevar siempre el cintur\u00f3n de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/14\\\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\\\/#blogposting\",\"name\":\"Campa\\u00f1a de vigilancia y control de cintur\\u00f3n de seguridad y SRI - Ayuntamiento de Ciempozuelos\",\"headline\":\"Campa\\u00f1a de vigilancia y control de cintur\\u00f3n de seguridad y SRI\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-03-14T08:41:19+01:00\",\"dateModified\":\"2016-03-14T08:41:19+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/14\\\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/14\\\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\\\/#webpage\"},\"articleSection\":\"Presidencia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/14\\\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/presidencia-maria-jesus-alonso-lazareno\\\/#listItem\",\"name\":\"Presidencia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/presidencia-maria-jesus-alonso-lazareno\\\/#listItem\",\"position\":2,\"name\":\"Presidencia\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/presidencia-maria-jesus-alonso-lazareno\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/14\\\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\\\/#listItem\",\"name\":\"Campa\\u00f1a de vigilancia y control de cintur\\u00f3n de seguridad y SRI\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/14\\\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\\\/#listItem\",\"position\":3,\"name\":\"Campa\\u00f1a de vigilancia y control de cintur\\u00f3n de seguridad y SRI\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/presidencia-maria-jesus-alonso-lazareno\\\/#listItem\",\"name\":\"Presidencia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/14\\\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/14\\\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/14\\\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\\\/\",\"name\":\"Campa\\u00f1a de vigilancia y control de cintur\\u00f3n de seguridad y SRI - Ayuntamiento de Ciempozuelos\",\"description\":\"Hasta el 20 de marzo La Polic\\u00eda Local de Ciempozuelos inicia hoy una campa\\u00f1a de vigilancia y control de los dispositivos de seguridad: cintur\\u00f3n y sistemas de retenci\\u00f3n infantil (SRI) en nuestro municipio a iniciativa de la Direcci\\u00f3n General de Tr\\u00e1fico (DGT). Desde la Polic\\u00eda Local recuerdan que es obligatorio llevar siempre el cintur\\u00f3n de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/03\\\/14\\\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-03-14T08:41:19+01:00\",\"dateModified\":\"2016-03-14T08:41:19+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI - Ayuntamiento de Ciempozuelos","description":"Hasta el 20 de marzo La Polic\u00eda Local de Ciempozuelos inicia hoy una campa\u00f1a de vigilancia y control de los dispositivos de seguridad: cintur\u00f3n y sistemas de retenci\u00f3n infantil (SRI) en nuestro municipio a iniciativa de la Direcci\u00f3n General de Tr\u00e1fico (DGT). Desde la Polic\u00eda Local recuerdan que es obligatorio llevar siempre el cintur\u00f3n de","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/#blogposting","name":"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI - Ayuntamiento de Ciempozuelos","headline":"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-03-14T08:41:19+01:00","dateModified":"2016-03-14T08:41:19+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/#webpage"},"articleSection":"Presidencia"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/#listItem","name":"Presidencia"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/#listItem","position":2,"name":"Presidencia","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/#listItem","name":"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/#listItem","position":3,"name":"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/#listItem","name":"Presidencia"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/","name":"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI - Ayuntamiento de Ciempozuelos","description":"Hasta el 20 de marzo La Polic\u00eda Local de Ciempozuelos inicia hoy una campa\u00f1a de vigilancia y control de los dispositivos de seguridad: cintur\u00f3n y sistemas de retenci\u00f3n infantil (SRI) en nuestro municipio a iniciativa de la Direcci\u00f3n General de Tr\u00e1fico (DGT). Desde la Polic\u00eda Local recuerdan que es obligatorio llevar siempre el cintur\u00f3n de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-03-14T08:41:19+01:00","dateModified":"2016-03-14T08:41:19+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI - Ayuntamiento de Ciempozuelos","og:description":"Hasta el 20 de marzo La Polic\u00eda Local de Ciempozuelos inicia hoy una campa\u00f1a de vigilancia y control de los dispositivos de seguridad: cintur\u00f3n y sistemas de retenci\u00f3n infantil (SRI) en nuestro municipio a iniciativa de la Direcci\u00f3n General de Tr\u00e1fico (DGT). Desde la Polic\u00eda Local recuerdan que es obligatorio llevar siempre el cintur\u00f3n de","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/","article:published_time":"2016-03-14T08:41:19+00:00","article:modified_time":"2016-03-14T08:41:19+00:00","twitter:card":"summary","twitter:title":"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI - Ayuntamiento de Ciempozuelos","twitter:description":"Hasta el 20 de marzo La Polic\u00eda Local de Ciempozuelos inicia hoy una campa\u00f1a de vigilancia y control de los dispositivos de seguridad: cintur\u00f3n y sistemas de retenci\u00f3n infantil (SRI) en nuestro municipio a iniciativa de la Direcci\u00f3n General de Tr\u00e1fico (DGT). Desde la Polic\u00eda Local recuerdan que es obligatorio llevar siempre el cintur\u00f3n de"},"aioseo_meta_data":{"post_id":"11007","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:44:43","updated":"2025-06-04 18:10:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/\" title=\"Presidencia\">Presidencia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCampa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Presidencia","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/presidencia-maria-jesus-alonso-lazareno\/"},{"label":"Campa\u00f1a de vigilancia y control de cintur\u00f3n de seguridad y SRI","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/03\/14\/campana-de-vigilancia-y-control-de-cinturon-de-seguridad-y-sri-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 21:06:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=11007"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/11007\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=11007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=11007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=11007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}