{"id":10955,"date":"2016-02-23T09:36:54","date_gmt":"2016-02-23T09:36:54","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/"},"modified":"2016-02-23T09:36:54","modified_gmt":"2016-02-23T09:36:54","slug":"alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/","title":{"rendered":"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><em>El vecino de Ciempozuelos representar\u00e1 a Espa\u00f1a en el Campeonato del Mundo en Ucrania<\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><em> <\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Alberto Zafra, propietario del Centro Canino Ischadia de Ciempozuelos, ha conseguido el t\u00edtulo de campe\u00f3n de Espa\u00f1a de Rastro IPO- FH de la Real Federaci\u00f3n Canina de Espa\u00f1a con su perra pastor alem\u00e1n Lena de Haus Jill. El campeonato ha tenido lugar los d\u00edas 20 y 21 de febrero en el municipio de Ejea de los Caballeros (Zaragoza). Por este t\u00edtulo nacional, Alberto Zafra representar\u00e1 a Espa\u00f1a en el Campeonato del Mundo de Rastro IPO- FH que se celebrar\u00e1 del 7 al 10 de abril en Mukachevo (Ucrania).<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El IPO- FH es una disciplina deportiva en la que el perro debe completar dos pistas en dos v\u00edas diferentes que son trazadas por una persona ajena al animal. El trazador va realizando una serie de rectas, curvas y \u00e1ngulos, previamente indicados por el juez, hasta realizar un total de 1800 pasos en cada pista. Al mismo tiempo se van colocando 7 objetos de cualquier material que previamente se han impregnado de su olor. Tres horas despu\u00e9s del trazado, el perro deber\u00e1 seguirlo de forma intensa, a una distancia de 10 metros de su gu\u00eda- adiestrador, sin salirse m\u00e1s de un cuerpo del trazado y marcando los objetos encontrados tumb\u00e1ndose delante de ellos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Una pr\u00e1ctica de gran complejidad que implica una elevada capacidad de concentraci\u00f3n, estado f\u00edsico y equilibrio psicol\u00f3gico as\u00ed como un conocimiento y una comunicaci\u00f3n \u00f3ptimas entre el can y su adiestrador.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Desde el Ayuntamiento de Ciempozuelos queremos felicitar a Alberto Zafra <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">por el t\u00edtulo conseguido y desearle los mayores \u00e9xitos en la prueba internacional de abril.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><em style=\"font-size: 12.16px; line-height: 15.808px;\"><img decoding=\"async\" class=\" size-full wp-image-10953\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/zafra2.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/zafra2-200x133.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/zafra2-300x199.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/zafra2-400x265.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/zafra2-600x398.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/zafra2-768x509.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/zafra2-800x530.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/zafra2.jpg 1000w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El vecino de Ciempozuelos representar\u00e1 a Espa\u00f1a en el Campeonato del Mundo en Ucrania Alberto Zafra, propietario del Centro Canino Ischadia de Ciempozuelos, ha conseguido el t\u00edtulo de campe\u00f3n de Espa\u00f1a de Rastro IPO- FH de la Real Federaci\u00f3n Canina de Espa\u00f1a con su perra pastor alem\u00e1n Lena de Haus Jill. El campeonato ha tenido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1102],"class_list":["post-10955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-actividades-deportivas-curso-maratones-y-torneos"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El vecino de Ciempozuelos representar\u00e1 a Espa\u00f1a en el Campeonato del Mundo en Ucrania Alberto Zafra, propietario del Centro Canino Ischadia de Ciempozuelos, ha conseguido el t\u00edtulo de campe\u00f3n de Espa\u00f1a de Rastro IPO- FH de la Real Federaci\u00f3n Canina de Espa\u00f1a con su perra pastor alem\u00e1n Lena de Haus Jill. El campeonato ha tenido\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El vecino de Ciempozuelos representar\u00e1 a Espa\u00f1a en el Campeonato del Mundo en Ucrania Alberto Zafra, propietario del Centro Canino Ischadia de Ciempozuelos, ha conseguido el t\u00edtulo de campe\u00f3n de Espa\u00f1a de Rastro IPO- FH de la Real Federaci\u00f3n Canina de Espa\u00f1a con su perra pastor alem\u00e1n Lena de Haus Jill. El campeonato ha tenido\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-23T09:36:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-23T09:36:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El vecino de Ciempozuelos representar\u00e1 a Espa\u00f1a en el Campeonato del Mundo en Ucrania Alberto Zafra, propietario del Centro Canino Ischadia de Ciempozuelos, ha conseguido el t\u00edtulo de campe\u00f3n de Espa\u00f1a de Rastro IPO- FH de la Real Federaci\u00f3n Canina de Espa\u00f1a con su perra pastor alem\u00e1n Lena de Haus Jill. El campeonato ha tenido\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/#blogposting\",\"name\":\"Alberto Zafra, campe\\u00f3n de Espa\\u00f1a de Rastro IPO-FH - Ayuntamiento de Ciempozuelos\",\"headline\":\"Alberto Zafra, campe\\u00f3n de Espa\\u00f1a de Rastro IPO-FH\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/zafra2.jpg\",\"width\":1000,\"height\":663},\"datePublished\":\"2016-02-23T09:36:54+01:00\",\"dateModified\":\"2016-02-23T09:36:54+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/#webpage\"},\"articleSection\":\"Actividades deportivas \\\/Curso\\\/Maratones y Torneos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-deportivas-curso-maratones-y-torneos\\\/#listItem\",\"name\":\"Actividades deportivas \\\/Curso\\\/Maratones y Torneos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-deportivas-curso-maratones-y-torneos\\\/#listItem\",\"position\":2,\"name\":\"Actividades deportivas \\\/Curso\\\/Maratones y Torneos\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-deportivas-curso-maratones-y-torneos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/#listItem\",\"name\":\"Alberto Zafra, campe\\u00f3n de Espa\\u00f1a de Rastro IPO-FH\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/#listItem\",\"position\":3,\"name\":\"Alberto Zafra, campe\\u00f3n de Espa\\u00f1a de Rastro IPO-FH\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-deportivas-curso-maratones-y-torneos\\\/#listItem\",\"name\":\"Actividades deportivas \\\/Curso\\\/Maratones y Torneos\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/\",\"name\":\"Alberto Zafra, campe\\u00f3n de Espa\\u00f1a de Rastro IPO-FH - Ayuntamiento de Ciempozuelos\",\"description\":\"El vecino de Ciempozuelos representar\\u00e1 a Espa\\u00f1a en el Campeonato del Mundo en Ucrania Alberto Zafra, propietario del Centro Canino Ischadia de Ciempozuelos, ha conseguido el t\\u00edtulo de campe\\u00f3n de Espa\\u00f1a de Rastro IPO- FH de la Real Federaci\\u00f3n Canina de Espa\\u00f1a con su perra pastor alem\\u00e1n Lena de Haus Jill. El campeonato ha tenido\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/zafra2.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/#mainImage\",\"width\":1000,\"height\":663},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/23\\\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\\\/#mainImage\"},\"datePublished\":\"2016-02-23T09:36:54+01:00\",\"dateModified\":\"2016-02-23T09:36:54+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH - Ayuntamiento de Ciempozuelos","description":"El vecino de Ciempozuelos representar\u00e1 a Espa\u00f1a en el Campeonato del Mundo en Ucrania Alberto Zafra, propietario del Centro Canino Ischadia de Ciempozuelos, ha conseguido el t\u00edtulo de campe\u00f3n de Espa\u00f1a de Rastro IPO- FH de la Real Federaci\u00f3n Canina de Espa\u00f1a con su perra pastor alem\u00e1n Lena de Haus Jill. El campeonato ha tenido","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/#blogposting","name":"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH - Ayuntamiento de Ciempozuelos","headline":"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/zafra2.jpg","width":1000,"height":663},"datePublished":"2016-02-23T09:36:54+01:00","dateModified":"2016-02-23T09:36:54+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/#webpage"},"articleSection":"Actividades deportivas \/Curso\/Maratones y Torneos"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/#listItem","name":"Actividades deportivas \/Curso\/Maratones y Torneos"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/#listItem","position":2,"name":"Actividades deportivas \/Curso\/Maratones y Torneos","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/#listItem","name":"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/#listItem","position":3,"name":"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/#listItem","name":"Actividades deportivas \/Curso\/Maratones y Torneos"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/","name":"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH - Ayuntamiento de Ciempozuelos","description":"El vecino de Ciempozuelos representar\u00e1 a Espa\u00f1a en el Campeonato del Mundo en Ucrania Alberto Zafra, propietario del Centro Canino Ischadia de Ciempozuelos, ha conseguido el t\u00edtulo de campe\u00f3n de Espa\u00f1a de Rastro IPO- FH de la Real Federaci\u00f3n Canina de Espa\u00f1a con su perra pastor alem\u00e1n Lena de Haus Jill. El campeonato ha tenido","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/zafra2.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/#mainImage","width":1000,"height":663},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/#mainImage"},"datePublished":"2016-02-23T09:36:54+01:00","dateModified":"2016-02-23T09:36:54+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH - Ayuntamiento de Ciempozuelos","og:description":"El vecino de Ciempozuelos representar\u00e1 a Espa\u00f1a en el Campeonato del Mundo en Ucrania Alberto Zafra, propietario del Centro Canino Ischadia de Ciempozuelos, ha conseguido el t\u00edtulo de campe\u00f3n de Espa\u00f1a de Rastro IPO- FH de la Real Federaci\u00f3n Canina de Espa\u00f1a con su perra pastor alem\u00e1n Lena de Haus Jill. El campeonato ha tenido","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/","article:published_time":"2016-02-23T09:36:54+00:00","article:modified_time":"2016-02-23T09:36:54+00:00","twitter:card":"summary","twitter:title":"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH - Ayuntamiento de Ciempozuelos","twitter:description":"El vecino de Ciempozuelos representar\u00e1 a Espa\u00f1a en el Campeonato del Mundo en Ucrania Alberto Zafra, propietario del Centro Canino Ischadia de Ciempozuelos, ha conseguido el t\u00edtulo de campe\u00f3n de Espa\u00f1a de Rastro IPO- FH de la Real Federaci\u00f3n Canina de Espa\u00f1a con su perra pastor alem\u00e1n Lena de Haus Jill. El campeonato ha tenido"},"aioseo_meta_data":{"post_id":"10955","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:37:17","updated":"2025-06-04 18:02:47","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/\" title=\"Actividades deportivas \/Curso\/Maratones y Torneos\">Actividades deportivas \/Curso\/Maratones y Torneos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAlberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Actividades deportivas \/Curso\/Maratones y Torneos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/"},{"label":"Alberto Zafra, campe\u00f3n de Espa\u00f1a de Rastro IPO-FH","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/23\/alberto-zafra-campeon-de-espana-de-rastro-ipo-fh-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:56:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10955"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10953"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}