{"id":10945,"date":"2016-02-19T11:11:11","date_gmt":"2016-02-19T11:11:11","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/"},"modified":"2016-02-19T11:11:11","modified_gmt":"2016-02-19T11:11:11","slug":"ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/","title":{"rendered":"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\"><span style=\"line-height: normal; text-align: justify; font-size: 12.16px;\">La Consejer\u00eda de Pol\u00edticas Sociales y Familia de la Comunidad de Madrid ha aprobado recientemente la concesi\u00f3n de ayudas para el pago de facturas de suministro el\u00e9ctrico y\/o gas (Iberdrola, Gas Natural Fenosa y Endesa), que ser\u00e1n gestionadas por la Mancomunidad Intermunicipal de Servicios Sociales \u201cLas Vegas.\u201d<\/span><\/p>\n<p class=\"Standard\" style=\"font-size: 12.16px; margin-bottom: 0.0001pt; text-align: justify; line-height: normal;\">\u00a0<\/p>\n<p class=\"Standard\" style=\"font-size: 12.16px; margin-bottom: 0.0001pt; text-align: justify; line-height: normal;\"><span style=\"font-size: 12.16px;\">Para ser beneficiario de estas ayudas, los solicitantes deben cumplir los siguientes requisitos:<\/span><\/p>\n<p class=\"Standard\" style=\"font-size: 12.16px; margin-bottom: 0.0001pt; text-align: justify; line-height: normal;\">\u00a0<\/p>\n<p class=\"Standard\" style=\"font-size: 12.16px; margin: 0cm 0cm 0.0001pt 36pt; text-align: justify; text-indent: -18pt; line-height: normal;\">1)\u00a0\u00a0\u00a0\u00a0\u00a0Estar empadronado en la vivienda para la que se solicita la ayuda.<\/p>\n<p class=\"Standard\" style=\"font-size: 12.16px; margin: 0cm 0cm 0.0001pt 36pt; text-align: justify; text-indent: -18pt; line-height: normal;\">2)\u00a0\u00a0\u00a0\u00a0\u00a0Tener al menos una factura impagada y haber recibido la carta de la compa\u00f1\u00eda suministradora.<\/p>\n<p class=\"Standard\" style=\"font-size: 12.16px; margin: 0cm 0cm 0.0001pt 36pt; text-align: justify; text-indent: -18pt; line-height: normal;\">3)\u00a0\u00a0\u00a0\u00a0\u00a0Ser titular del contrato de suministros o figurar como pagador en las correspondientes facturas.<\/p>\n<p class=\"Standard\" style=\"font-size: 12.16px; margin: 0cm 0cm 0.0001pt 36pt; text-align: justify; text-indent: -18pt; line-height: normal;\">4)\u00a0\u00a0\u00a0\u00a0\u00a0Tener una potencia el\u00e9ctrica contratada de menos de 4,6 KW.<\/p>\n<p class=\"Standard\" style=\"font-size: 12.16px; margin: 0cm 0cm 0.0001pt 36pt; text-align: justify; text-indent: -18pt; line-height: normal;\">5)\u00a0\u00a0\u00a0\u00a0\u00a0Tener ingresos insuficientes.<\/p>\n<p class=\"Standard\" style=\"font-size: 12.16px; margin-bottom: 0.0001pt; text-align: justify; line-height: normal;\"><span style=\"font-size: 12.16px;\">Para solicitar la ayuda, debes dirigirte al Centro de Servicio Sociales (c\/ San Sebasti\u00e1n, 30. Primera Planta) con la nota de impago de la empresa suministradora. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Consejer\u00eda de Pol\u00edticas Sociales y Familia de la Comunidad de Madrid ha aprobado recientemente la concesi\u00f3n de ayudas para el pago de facturas de suministro el\u00e9ctrico y\/o gas (Iberdrola, Gas Natural Fenosa y Endesa), que ser\u00e1n gestionadas por la Mancomunidad Intermunicipal de Servicios Sociales \u201cLas Vegas.\u201d \u00a0 Para ser beneficiario de estas ayudas, los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1104],"class_list":["post-10945","post","type-post","status-publish","format-standard","hentry","tag-servicios-sociales-jorge-alonso-diaz"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Consejer\u00eda de Pol\u00edticas Sociales y Familia de la Comunidad de Madrid ha aprobado recientemente la concesi\u00f3n de ayudas para el pago de facturas de suministro el\u00e9ctrico y\/o gas (Iberdrola, Gas Natural Fenosa y Endesa), que ser\u00e1n gestionadas por la Mancomunidad Intermunicipal de Servicios Sociales \u201cLas Vegas.\u201d Para ser beneficiario de estas ayudas, los\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La Consejer\u00eda de Pol\u00edticas Sociales y Familia de la Comunidad de Madrid ha aprobado recientemente la concesi\u00f3n de ayudas para el pago de facturas de suministro el\u00e9ctrico y\/o gas (Iberdrola, Gas Natural Fenosa y Endesa), que ser\u00e1n gestionadas por la Mancomunidad Intermunicipal de Servicios Sociales \u201cLas Vegas.\u201d Para ser beneficiario de estas ayudas, los\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-19T11:11:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-19T11:11:11+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Consejer\u00eda de Pol\u00edticas Sociales y Familia de la Comunidad de Madrid ha aprobado recientemente la concesi\u00f3n de ayudas para el pago de facturas de suministro el\u00e9ctrico y\/o gas (Iberdrola, Gas Natural Fenosa y Endesa), que ser\u00e1n gestionadas por la Mancomunidad Intermunicipal de Servicios Sociales \u201cLas Vegas.\u201d Para ser beneficiario de estas ayudas, los\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/19\\\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\\\/#blogposting\",\"name\":\"Ayudas individuales de la Consejer\\u00eda de Pol\\u00edticas Sociales y Familia para el pago de las facturas de suministro el\\u00e9ctrico y\\\/o gas - Ayuntamiento de Ciempozuelos\",\"headline\":\"Ayudas individuales de la Consejer\\u00eda de Pol\\u00edticas Sociales y Familia para el pago de las facturas de suministro el\\u00e9ctrico y\\\/o gas\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-02-19T11:11:11+01:00\",\"dateModified\":\"2016-02-19T11:11:11+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/19\\\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/19\\\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\\\/#webpage\"},\"articleSection\":\"Servicios Sociales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/19\\\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales-jorge-alonso-diaz\\\/#listItem\",\"name\":\"Servicios Sociales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales-jorge-alonso-diaz\\\/#listItem\",\"position\":2,\"name\":\"Servicios Sociales\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales-jorge-alonso-diaz\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/19\\\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\\\/#listItem\",\"name\":\"Ayudas individuales de la Consejer\\u00eda de Pol\\u00edticas Sociales y Familia para el pago de las facturas de suministro el\\u00e9ctrico y\\\/o gas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/19\\\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\\\/#listItem\",\"position\":3,\"name\":\"Ayudas individuales de la Consejer\\u00eda de Pol\\u00edticas Sociales y Familia para el pago de las facturas de suministro el\\u00e9ctrico y\\\/o gas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales-jorge-alonso-diaz\\\/#listItem\",\"name\":\"Servicios Sociales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/19\\\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/19\\\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/19\\\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\\\/\",\"name\":\"Ayudas individuales de la Consejer\\u00eda de Pol\\u00edticas Sociales y Familia para el pago de las facturas de suministro el\\u00e9ctrico y\\\/o gas - Ayuntamiento de Ciempozuelos\",\"description\":\"La Consejer\\u00eda de Pol\\u00edticas Sociales y Familia de la Comunidad de Madrid ha aprobado recientemente la concesi\\u00f3n de ayudas para el pago de facturas de suministro el\\u00e9ctrico y\\\/o gas (Iberdrola, Gas Natural Fenosa y Endesa), que ser\\u00e1n gestionadas por la Mancomunidad Intermunicipal de Servicios Sociales \\u201cLas Vegas.\\u201d Para ser beneficiario de estas ayudas, los\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/19\\\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-02-19T11:11:11+01:00\",\"dateModified\":\"2016-02-19T11:11:11+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas - Ayuntamiento de Ciempozuelos","description":"La Consejer\u00eda de Pol\u00edticas Sociales y Familia de la Comunidad de Madrid ha aprobado recientemente la concesi\u00f3n de ayudas para el pago de facturas de suministro el\u00e9ctrico y\/o gas (Iberdrola, Gas Natural Fenosa y Endesa), que ser\u00e1n gestionadas por la Mancomunidad Intermunicipal de Servicios Sociales \u201cLas Vegas.\u201d Para ser beneficiario de estas ayudas, los","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/#blogposting","name":"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas - Ayuntamiento de Ciempozuelos","headline":"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-02-19T11:11:11+01:00","dateModified":"2016-02-19T11:11:11+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/#webpage"},"articleSection":"Servicios Sociales"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales-jorge-alonso-diaz\/#listItem","name":"Servicios Sociales"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales-jorge-alonso-diaz\/#listItem","position":2,"name":"Servicios Sociales","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales-jorge-alonso-diaz\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/#listItem","name":"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/#listItem","position":3,"name":"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales-jorge-alonso-diaz\/#listItem","name":"Servicios Sociales"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/","name":"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas - Ayuntamiento de Ciempozuelos","description":"La Consejer\u00eda de Pol\u00edticas Sociales y Familia de la Comunidad de Madrid ha aprobado recientemente la concesi\u00f3n de ayudas para el pago de facturas de suministro el\u00e9ctrico y\/o gas (Iberdrola, Gas Natural Fenosa y Endesa), que ser\u00e1n gestionadas por la Mancomunidad Intermunicipal de Servicios Sociales \u201cLas Vegas.\u201d Para ser beneficiario de estas ayudas, los","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-02-19T11:11:11+01:00","dateModified":"2016-02-19T11:11:11+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas - Ayuntamiento de Ciempozuelos","og:description":"La Consejer\u00eda de Pol\u00edticas Sociales y Familia de la Comunidad de Madrid ha aprobado recientemente la concesi\u00f3n de ayudas para el pago de facturas de suministro el\u00e9ctrico y\/o gas (Iberdrola, Gas Natural Fenosa y Endesa), que ser\u00e1n gestionadas por la Mancomunidad Intermunicipal de Servicios Sociales \u201cLas Vegas.\u201d Para ser beneficiario de estas ayudas, los","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/","article:published_time":"2016-02-19T11:11:11+00:00","article:modified_time":"2016-02-19T11:11:11+00:00","twitter:card":"summary","twitter:title":"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas - Ayuntamiento de Ciempozuelos","twitter:description":"La Consejer\u00eda de Pol\u00edticas Sociales y Familia de la Comunidad de Madrid ha aprobado recientemente la concesi\u00f3n de ayudas para el pago de facturas de suministro el\u00e9ctrico y\/o gas (Iberdrola, Gas Natural Fenosa y Endesa), que ser\u00e1n gestionadas por la Mancomunidad Intermunicipal de Servicios Sociales \u201cLas Vegas.\u201d Para ser beneficiario de estas ayudas, los"},"aioseo_meta_data":{"post_id":"10945","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:35:59","updated":"2025-06-04 18:02:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales-jorge-alonso-diaz\/\" title=\"Servicios Sociales\">Servicios Sociales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAyudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Servicios Sociales","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales-jorge-alonso-diaz\/"},{"label":"Ayudas individuales de la Consejer\u00eda de Pol\u00edticas Sociales y Familia para el pago de las facturas de suministro el\u00e9ctrico y\/o gas","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/19\/ayudas-individuales-de-la-consejeria-de-politicas-sociales-y-familia-para-el-pago-de-las-facturas-de-suministro-electrico-y-o-gas-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:46:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10945"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10945\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}