{"id":10929,"date":"2016-02-15T13:35:06","date_gmt":"2016-02-15T13:35:06","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/"},"modified":"2016-02-15T13:35:06","modified_gmt":"2016-02-15T13:35:06","slug":"el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/","title":{"rendered":"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><em style=\"font-size: 12.16px; line-height: 1.3em;\">El evento literario se ha celebrado este fin de semana con r\u00e9cord de asistencia<\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El encuentro de novela rom\u00e1ntica adulta \u2018Encuentro RA\u2019, organizado por la asociaci\u00f3n sin \u00e1nimo de lucro Yoleora, ha colaborado con el Banco de Alimentos de Ciempozuelos a trav\u00e9s de la donaci\u00f3n de alimentos no perecederos y objetos de higiene personal gracias a la aportaci\u00f3n voluntaria de los asistentes al evento literario.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">Gracias a la solidaridad de los participantes se han recogido m\u00e1s de 500 kilos entre alimentos, art\u00edculos de higiene personal y objetos para beb\u00e9s. Desde el Ayuntamiento de Ciempozuelos <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">se quiere trasmitir el m\u00e1s sincero agradecimiento tanto a la organizaci\u00f3n como a los asistentes que han hecho posible esta recogida.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El Encuentro RA, celebrado este fin de semana en el auditorio Marcelino Camacho (Madrid), ha congregado a m\u00e1s de medio millar de personas entre escritores, editores, distribuidores, impresores, lectores,\u2026 El evento ha cumplido este a\u00f1o su s\u00e9ptima edici\u00f3n y se ha convertido en referente de la literatura rom\u00e1ntica adulta en Espa\u00f1a y Sudam\u00e9rica. En esta edici\u00f3n se han presentado distintas novelas y realizado mesas redonda, con la asistencia destacada de Christina Courtenay, escritora brit\u00e1nica, y de la escritoria Pilar Eyre.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><img decoding=\"async\" class=\" size-full wp-image-10926\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1-66x66.jpg 66w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1-150x150.jpg 150w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1-200x200.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1-300x300.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1-400x400.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1-600x600.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1-768x768.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1-800x800.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1.jpg 960w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/span><\/p>\n<p>\u00a0<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><img decoding=\"async\" class=\" size-full wp-image-10927\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra-200x267.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra-225x300.jpg 225w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra-400x533.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra-600x800.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra.jpg 720w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><img decoding=\"async\" class=\" size-full wp-image-10928\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentrora2.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentrora2-66x66.jpg 66w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentrora2-150x150.jpg 150w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentrora2-200x200.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentrora2-300x300.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentrora2-400x400.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentrora2-600x600.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentrora2-768x768.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentrora2-800x800.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentrora2.jpg 960w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento literario se ha celebrado este fin de semana con r\u00e9cord de asistencia El encuentro de novela rom\u00e1ntica adulta \u2018Encuentro RA\u2019, organizado por la asociaci\u00f3n sin \u00e1nimo de lucro Yoleora, ha colaborado con el Banco de Alimentos de Ciempozuelos a trav\u00e9s de la donaci\u00f3n de alimentos no perecederos y objetos de higiene personal gracias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1213],"class_list":["post-10929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-servicios-sociales"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El evento literario se ha celebrado este fin de semana con r\u00e9cord de asistencia El encuentro de novela rom\u00e1ntica adulta \u2018Encuentro RA\u2019, organizado por la asociaci\u00f3n sin \u00e1nimo de lucro Yoleora, ha colaborado con el Banco de Alimentos de Ciempozuelos a trav\u00e9s de la donaci\u00f3n de alimentos no perecederos y objetos de higiene personal gracias\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El evento literario se ha celebrado este fin de semana con r\u00e9cord de asistencia El encuentro de novela rom\u00e1ntica adulta \u2018Encuentro RA\u2019, organizado por la asociaci\u00f3n sin \u00e1nimo de lucro Yoleora, ha colaborado con el Banco de Alimentos de Ciempozuelos a trav\u00e9s de la donaci\u00f3n de alimentos no perecederos y objetos de higiene personal gracias\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-15T13:35:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-15T13:35:06+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El evento literario se ha celebrado este fin de semana con r\u00e9cord de asistencia El encuentro de novela rom\u00e1ntica adulta \u2018Encuentro RA\u2019, organizado por la asociaci\u00f3n sin \u00e1nimo de lucro Yoleora, ha colaborado con el Banco de Alimentos de Ciempozuelos a trav\u00e9s de la donaci\u00f3n de alimentos no perecederos y objetos de higiene personal gracias\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/#blogposting\",\"name\":\"El Encuentro RA dona m\\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"El Encuentro RA dona m\\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/encuentro-ra1.jpg\",\"width\":960,\"height\":960},\"datePublished\":\"2016-02-15T13:35:06+01:00\",\"dateModified\":\"2016-02-15T13:35:06+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/#webpage\"},\"articleSection\":\"Servicios Sociales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales\\\/#listItem\",\"name\":\"Servicios Sociales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales\\\/#listItem\",\"position\":2,\"name\":\"Servicios Sociales\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/#listItem\",\"name\":\"El Encuentro RA dona m\\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/#listItem\",\"position\":3,\"name\":\"El Encuentro RA dona m\\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales\\\/#listItem\",\"name\":\"Servicios Sociales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/\",\"name\":\"El Encuentro RA dona m\\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"El evento literario se ha celebrado este fin de semana con r\\u00e9cord de asistencia El encuentro de novela rom\\u00e1ntica adulta \\u2018Encuentro RA\\u2019, organizado por la asociaci\\u00f3n sin \\u00e1nimo de lucro Yoleora, ha colaborado con el Banco de Alimentos de Ciempozuelos a trav\\u00e9s de la donaci\\u00f3n de alimentos no perecederos y objetos de higiene personal gracias\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/encuentro-ra1.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/#mainImage\",\"width\":960,\"height\":960},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\\\/#mainImage\"},\"datePublished\":\"2016-02-15T13:35:06+01:00\",\"dateModified\":\"2016-02-15T13:35:06+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"El evento literario se ha celebrado este fin de semana con r\u00e9cord de asistencia El encuentro de novela rom\u00e1ntica adulta \u2018Encuentro RA\u2019, organizado por la asociaci\u00f3n sin \u00e1nimo de lucro Yoleora, ha colaborado con el Banco de Alimentos de Ciempozuelos a trav\u00e9s de la donaci\u00f3n de alimentos no perecederos y objetos de higiene personal gracias","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/#blogposting","name":"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1.jpg","width":960,"height":960},"datePublished":"2016-02-15T13:35:06+01:00","dateModified":"2016-02-15T13:35:06+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/#webpage"},"articleSection":"Servicios Sociales"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/#listItem","name":"Servicios Sociales"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/#listItem","position":2,"name":"Servicios Sociales","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/#listItem","name":"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/#listItem","position":3,"name":"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/#listItem","name":"Servicios Sociales"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/","name":"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"El evento literario se ha celebrado este fin de semana con r\u00e9cord de asistencia El encuentro de novela rom\u00e1ntica adulta \u2018Encuentro RA\u2019, organizado por la asociaci\u00f3n sin \u00e1nimo de lucro Yoleora, ha colaborado con el Banco de Alimentos de Ciempozuelos a trav\u00e9s de la donaci\u00f3n de alimentos no perecederos y objetos de higiene personal gracias","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/encuentro-ra1.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/#mainImage","width":960,"height":960},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/#mainImage"},"datePublished":"2016-02-15T13:35:06+01:00","dateModified":"2016-02-15T13:35:06+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"El evento literario se ha celebrado este fin de semana con r\u00e9cord de asistencia El encuentro de novela rom\u00e1ntica adulta \u2018Encuentro RA\u2019, organizado por la asociaci\u00f3n sin \u00e1nimo de lucro Yoleora, ha colaborado con el Banco de Alimentos de Ciempozuelos a trav\u00e9s de la donaci\u00f3n de alimentos no perecederos y objetos de higiene personal gracias","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/","article:published_time":"2016-02-15T13:35:06+00:00","article:modified_time":"2016-02-15T13:35:06+00:00","twitter:card":"summary","twitter:title":"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"El evento literario se ha celebrado este fin de semana con r\u00e9cord de asistencia El encuentro de novela rom\u00e1ntica adulta \u2018Encuentro RA\u2019, organizado por la asociaci\u00f3n sin \u00e1nimo de lucro Yoleora, ha colaborado con el Banco de Alimentos de Ciempozuelos a trav\u00e9s de la donaci\u00f3n de alimentos no perecederos y objetos de higiene personal gracias"},"aioseo_meta_data":{"post_id":"10929","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:35:04","updated":"2025-06-04 18:00:11","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/\" title=\"Servicios Sociales\">Servicios Sociales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Servicios Sociales","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/"},{"label":"El Encuentro RA dona m\u00e1s de 500 kilos al Banco de Alimentos de Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/el-encuentro-ra-dona-mas-de-500-kilos-al-banco-de-alimentos-de-ciempozuelos\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:11:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10929"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10926"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}