{"id":10918,"date":"2016-02-15T11:30:39","date_gmt":"2016-02-15T11:30:39","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/"},"modified":"2016-02-15T11:30:39","modified_gmt":"2016-02-15T11:30:39","slug":"ciempozuelos-amanece-en-estado-permanente-de-poesia-4","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/","title":{"rendered":"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><em>El taller colectivo concluy\u00f3 con la pegada de carteles con mensajes po\u00e9ticos<\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><em> <\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La ma\u00f1ana del domingo 14 de febrero distintos puntos de Ciempozuelos aparecieron decorados con carteles con frases po\u00e9ticas. Esta pegada de carteles es el resultado del trabajo realizado en taller colectivo de acci\u00f3n po\u00e9tica que ha tenido lugar el pasado viernes y s\u00e1bado, dentro de las actividades municipales programadas para el mes de febrero.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">En el taller se hizo una selecci\u00f3n de los textos en un trabajo conjunto entre organizadores y participantes. Tras finalizar el s\u00e1bado la segunda sesi\u00f3n del taller se llev\u00f3 a cabo la pegada de carteles.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Desde el Ayuntamiento de Ciempozuelos se quiere agradecer la colaboraci\u00f3n del Centro Joven, la Asociaci\u00f3n La Torre, los escritores locales, los trabajadores de la Concejal\u00edas de Cultura y Juventud, el personal de la Biblioteca Municipal as\u00ed como a los vecinos y vecinas que participaron en la acci\u00f3n.<\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">Asimismo, se anima a los participantes y a los que est\u00e9n interesados a formar parte en las futuras acciones po\u00e9ticas que tendr\u00e1n lugar en Ciempozuelos.<\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><em style=\"font-size: 12.16px; line-height: 15.808px;\"><img decoding=\"async\" class=\" size-full wp-image-10914\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller-200x112.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller-300x168.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller-400x225.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller-600x337.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller-768x431.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller-800x449.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller-1024x575.jpg 1024w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller-1200x674.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller-1536x862.jpg 1536w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller.jpg 1600w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El taller colectivo concluy\u00f3 con la pegada de carteles con mensajes po\u00e9ticos La ma\u00f1ana del domingo 14 de febrero distintos puntos de Ciempozuelos aparecieron decorados con carteles con frases po\u00e9ticas. Esta pegada de carteles es el resultado del trabajo realizado en taller colectivo de acci\u00f3n po\u00e9tica que ha tenido lugar el pasado viernes y s\u00e1bado, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1217],"class_list":["post-10918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-1217"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El taller colectivo concluy\u00f3 con la pegada de carteles con mensajes po\u00e9ticos La ma\u00f1ana del domingo 14 de febrero distintos puntos de Ciempozuelos aparecieron decorados con carteles con frases po\u00e9ticas. Esta pegada de carteles es el resultado del trabajo realizado en taller colectivo de acci\u00f3n po\u00e9tica que ha tenido lugar el pasado viernes y s\u00e1bado,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019 - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El taller colectivo concluy\u00f3 con la pegada de carteles con mensajes po\u00e9ticos La ma\u00f1ana del domingo 14 de febrero distintos puntos de Ciempozuelos aparecieron decorados con carteles con frases po\u00e9ticas. Esta pegada de carteles es el resultado del trabajo realizado en taller colectivo de acci\u00f3n po\u00e9tica que ha tenido lugar el pasado viernes y s\u00e1bado,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-15T11:30:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-15T11:30:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019 - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El taller colectivo concluy\u00f3 con la pegada de carteles con mensajes po\u00e9ticos La ma\u00f1ana del domingo 14 de febrero distintos puntos de Ciempozuelos aparecieron decorados con carteles con frases po\u00e9ticas. Esta pegada de carteles es el resultado del trabajo realizado en taller colectivo de acci\u00f3n po\u00e9tica que ha tenido lugar el pasado viernes y s\u00e1bado,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/#blogposting\",\"name\":\"Ciempozuelos amanece en \\u2018estado permanente de poes\\u00eda\\u2019 - Ayuntamiento de Ciempozuelos\",\"headline\":\"Ciempozuelos amanece en \\u2018estado permanente de poes\\u00eda\\u2019\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/accion-poetica-taller.jpg\",\"width\":1600,\"height\":898},\"datePublished\":\"2016-02-15T11:30:39+01:00\",\"dateModified\":\"2016-02-15T11:30:39+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/#webpage\"},\"articleSection\":\"1139\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"position\":2,\"name\":\"1139\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/#listItem\",\"name\":\"Ciempozuelos amanece en \\u2018estado permanente de poes\\u00eda\\u2019\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/#listItem\",\"position\":3,\"name\":\"Ciempozuelos amanece en \\u2018estado permanente de poes\\u00eda\\u2019\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/\",\"name\":\"Ciempozuelos amanece en \\u2018estado permanente de poes\\u00eda\\u2019 - Ayuntamiento de Ciempozuelos\",\"description\":\"El taller colectivo concluy\\u00f3 con la pegada de carteles con mensajes po\\u00e9ticos La ma\\u00f1ana del domingo 14 de febrero distintos puntos de Ciempozuelos aparecieron decorados con carteles con frases po\\u00e9ticas. Esta pegada de carteles es el resultado del trabajo realizado en taller colectivo de acci\\u00f3n po\\u00e9tica que ha tenido lugar el pasado viernes y s\\u00e1bado,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/accion-poetica-taller.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/#mainImage\",\"width\":1600,\"height\":898},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/15\\\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\\\/#mainImage\"},\"datePublished\":\"2016-02-15T11:30:39+01:00\",\"dateModified\":\"2016-02-15T11:30:39+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019 - Ayuntamiento de Ciempozuelos","description":"El taller colectivo concluy\u00f3 con la pegada de carteles con mensajes po\u00e9ticos La ma\u00f1ana del domingo 14 de febrero distintos puntos de Ciempozuelos aparecieron decorados con carteles con frases po\u00e9ticas. Esta pegada de carteles es el resultado del trabajo realizado en taller colectivo de acci\u00f3n po\u00e9tica que ha tenido lugar el pasado viernes y s\u00e1bado,","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/#blogposting","name":"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019 - Ayuntamiento de Ciempozuelos","headline":"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller.jpg","width":1600,"height":898},"datePublished":"2016-02-15T11:30:39+01:00","dateModified":"2016-02-15T11:30:39+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/#webpage"},"articleSection":"1139"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","position":2,"name":"1139","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/#listItem","name":"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/#listItem","position":3,"name":"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/","name":"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019 - Ayuntamiento de Ciempozuelos","description":"El taller colectivo concluy\u00f3 con la pegada de carteles con mensajes po\u00e9ticos La ma\u00f1ana del domingo 14 de febrero distintos puntos de Ciempozuelos aparecieron decorados con carteles con frases po\u00e9ticas. Esta pegada de carteles es el resultado del trabajo realizado en taller colectivo de acci\u00f3n po\u00e9tica que ha tenido lugar el pasado viernes y s\u00e1bado,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/accion-poetica-taller.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/#mainImage","width":1600,"height":898},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/#mainImage"},"datePublished":"2016-02-15T11:30:39+01:00","dateModified":"2016-02-15T11:30:39+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019 - Ayuntamiento de Ciempozuelos","og:description":"El taller colectivo concluy\u00f3 con la pegada de carteles con mensajes po\u00e9ticos La ma\u00f1ana del domingo 14 de febrero distintos puntos de Ciempozuelos aparecieron decorados con carteles con frases po\u00e9ticas. Esta pegada de carteles es el resultado del trabajo realizado en taller colectivo de acci\u00f3n po\u00e9tica que ha tenido lugar el pasado viernes y s\u00e1bado,","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/","article:published_time":"2016-02-15T11:30:39+00:00","article:modified_time":"2016-02-15T11:30:39+00:00","twitter:card":"summary","twitter:title":"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019 - Ayuntamiento de Ciempozuelos","twitter:description":"El taller colectivo concluy\u00f3 con la pegada de carteles con mensajes po\u00e9ticos La ma\u00f1ana del domingo 14 de febrero distintos puntos de Ciempozuelos aparecieron decorados con carteles con frases po\u00e9ticas. Esta pegada de carteles es el resultado del trabajo realizado en taller colectivo de acci\u00f3n po\u00e9tica que ha tenido lugar el pasado viernes y s\u00e1bado,"},"aioseo_meta_data":{"post_id":"10918","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:34:27","updated":"2025-06-04 17:58:53","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/\" title=\"1139\">1139<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCiempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1139","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/"},{"label":"Ciempozuelos amanece en \u2018estado permanente de poes\u00eda\u2019","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/15\/ciempozuelos-amanece-en-estado-permanente-de-poesia-4\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:45:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10918"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10914"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}