{"id":10901,"date":"2016-02-10T10:34:07","date_gmt":"2016-02-10T10:34:07","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/"},"modified":"2016-02-10T10:34:07","modified_gmt":"2016-02-10T10:34:07","slug":"el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/","title":{"rendered":"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><em>La primera actuaci\u00f3n consistir\u00e1 en el desarrollo y equipamiento de una ruta ornitol\u00f3gica en La Vega de Ciempozuelos<\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><em> <\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El Ayuntamiento de Ciempozuelos, a trav\u00e9s de la Concejal\u00eda de Agricultura, ha firmado un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal para la defensa del medio ambiente.<\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">La firma tuvo lugar ayer, martes 9 de febrero, en la Casa Consistorial de Ciempozuelos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El objetivo del convenio es establecer de forma conjunta planes y proyectos de actuaci\u00f3n para la realizaci\u00f3n de actividades que fomenten la sensibilizaci\u00f3n, el conocimiento y la conservaci\u00f3n de la biodiversidad y, en particular, el desarrollo de \u2018AgroSOStenible\u2019, para la conservaci\u00f3n de especies asociadas al medio agrario en Ciempozuelos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La primera actuaci\u00f3n a desarrollar tras la firma de este convenio ser\u00e1 el desarrollo de una ruta ornitol\u00f3gica por la Vega de Ciempozuelos con el equipamiento did\u00e1ctico necesario para su uso y disfrute.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Seg\u00fan el acuerdo, Brinzal aportar\u00e1 los medios materiales y humanos necesarios para el desarrollo de planes y proyectos. <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">El compromiso del Ayuntamiento de Ciempozuelos en este convenio, con vigencia hasta el 31 de diciembre de 2016, es el de facilitar las intervenciones que se lleven a cabo en pro de la conservaci\u00f3n de las especies faun\u00edsticas asociadas al medio rural en Ciempozuelos. Tambi\u00e9n se compromete a la difusi\u00f3n de las actividades y a la distribuci\u00f3n del material divulgativo que le facilite Brinzal.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Uno de los objetivos del Ayuntamiento de Ciempozuelos es la promoci\u00f3n de la educaci\u00f3n ambiental como instrumento para la sensibilizaci\u00f3n, conocimiento y desarrollo de actitudes de responsabilidad hacia el medio ambiente. Por su parte, Brinzal persigue promover, alentar y asegurar la conservaci\u00f3n de la fauna, flora, aguas, suelos y dem\u00e1s recursos naturales. En especial, actuar en pro del estudio y la conservaci\u00f3n de las rapaces nocturnas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La primera actuaci\u00f3n consistir\u00e1 en el desarrollo y equipamiento de una ruta ornitol\u00f3gica en La Vega de Ciempozuelos El Ayuntamiento de Ciempozuelos, a trav\u00e9s de la Concejal\u00eda de Agricultura, ha firmado un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal para la defensa del medio ambiente. La firma tuvo lugar ayer, martes 9 de febrero, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1233],"class_list":["post-10901","post","type-post","status-publish","format-standard","hentry","tag-medio-ambiente"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La primera actuaci\u00f3n consistir\u00e1 en el desarrollo y equipamiento de una ruta ornitol\u00f3gica en La Vega de Ciempozuelos El Ayuntamiento de Ciempozuelos, a trav\u00e9s de la Concejal\u00eda de Agricultura, ha firmado un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal para la defensa del medio ambiente. La firma tuvo lugar ayer, martes 9 de febrero,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La primera actuaci\u00f3n consistir\u00e1 en el desarrollo y equipamiento de una ruta ornitol\u00f3gica en La Vega de Ciempozuelos El Ayuntamiento de Ciempozuelos, a trav\u00e9s de la Concejal\u00eda de Agricultura, ha firmado un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal para la defensa del medio ambiente. La firma tuvo lugar ayer, martes 9 de febrero,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-10T10:34:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-10T10:34:07+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La primera actuaci\u00f3n consistir\u00e1 en el desarrollo y equipamiento de una ruta ornitol\u00f3gica en La Vega de Ciempozuelos El Ayuntamiento de Ciempozuelos, a trav\u00e9s de la Concejal\u00eda de Agricultura, ha firmado un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal para la defensa del medio ambiente. La firma tuvo lugar ayer, martes 9 de febrero,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/10\\\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\\\/#blogposting\",\"name\":\"El Ayuntamiento firma un convenio de colaboraci\\u00f3n con la Asociaci\\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible - Ayuntamiento de Ciempozuelos\",\"headline\":\"El Ayuntamiento firma un convenio de colaboraci\\u00f3n con la Asociaci\\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-02-10T10:34:07+01:00\",\"dateModified\":\"2016-02-10T10:34:07+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/10\\\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/10\\\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\\\/#webpage\"},\"articleSection\":\"Medio Ambiente\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/10\\\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/medio-ambiente\\\/#listItem\",\"name\":\"Medio Ambiente\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/medio-ambiente\\\/#listItem\",\"position\":2,\"name\":\"Medio Ambiente\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/medio-ambiente\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/10\\\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\\\/#listItem\",\"name\":\"El Ayuntamiento firma un convenio de colaboraci\\u00f3n con la Asociaci\\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/10\\\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\\\/#listItem\",\"position\":3,\"name\":\"El Ayuntamiento firma un convenio de colaboraci\\u00f3n con la Asociaci\\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/medio-ambiente\\\/#listItem\",\"name\":\"Medio Ambiente\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/10\\\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/10\\\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/10\\\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\\\/\",\"name\":\"El Ayuntamiento firma un convenio de colaboraci\\u00f3n con la Asociaci\\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible - Ayuntamiento de Ciempozuelos\",\"description\":\"La primera actuaci\\u00f3n consistir\\u00e1 en el desarrollo y equipamiento de una ruta ornitol\\u00f3gica en La Vega de Ciempozuelos El Ayuntamiento de Ciempozuelos, a trav\\u00e9s de la Concejal\\u00eda de Agricultura, ha firmado un convenio de colaboraci\\u00f3n con la Asociaci\\u00f3n Grupo Brinzal para la defensa del medio ambiente. La firma tuvo lugar ayer, martes 9 de febrero,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/10\\\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-02-10T10:34:07+01:00\",\"dateModified\":\"2016-02-10T10:34:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible - Ayuntamiento de Ciempozuelos","description":"La primera actuaci\u00f3n consistir\u00e1 en el desarrollo y equipamiento de una ruta ornitol\u00f3gica en La Vega de Ciempozuelos El Ayuntamiento de Ciempozuelos, a trav\u00e9s de la Concejal\u00eda de Agricultura, ha firmado un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal para la defensa del medio ambiente. La firma tuvo lugar ayer, martes 9 de febrero,","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/#blogposting","name":"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible - Ayuntamiento de Ciempozuelos","headline":"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-02-10T10:34:07+01:00","dateModified":"2016-02-10T10:34:07+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/#webpage"},"articleSection":"Medio Ambiente"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/medio-ambiente\/#listItem","name":"Medio Ambiente"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/medio-ambiente\/#listItem","position":2,"name":"Medio Ambiente","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/medio-ambiente\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/#listItem","name":"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/#listItem","position":3,"name":"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/medio-ambiente\/#listItem","name":"Medio Ambiente"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/","name":"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible - Ayuntamiento de Ciempozuelos","description":"La primera actuaci\u00f3n consistir\u00e1 en el desarrollo y equipamiento de una ruta ornitol\u00f3gica en La Vega de Ciempozuelos El Ayuntamiento de Ciempozuelos, a trav\u00e9s de la Concejal\u00eda de Agricultura, ha firmado un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal para la defensa del medio ambiente. La firma tuvo lugar ayer, martes 9 de febrero,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-02-10T10:34:07+01:00","dateModified":"2016-02-10T10:34:07+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible - Ayuntamiento de Ciempozuelos","og:description":"La primera actuaci\u00f3n consistir\u00e1 en el desarrollo y equipamiento de una ruta ornitol\u00f3gica en La Vega de Ciempozuelos El Ayuntamiento de Ciempozuelos, a trav\u00e9s de la Concejal\u00eda de Agricultura, ha firmado un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal para la defensa del medio ambiente. La firma tuvo lugar ayer, martes 9 de febrero,","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/","article:published_time":"2016-02-10T10:34:07+00:00","article:modified_time":"2016-02-10T10:34:07+00:00","twitter:card":"summary","twitter:title":"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible - Ayuntamiento de Ciempozuelos","twitter:description":"La primera actuaci\u00f3n consistir\u00e1 en el desarrollo y equipamiento de una ruta ornitol\u00f3gica en La Vega de Ciempozuelos El Ayuntamiento de Ciempozuelos, a trav\u00e9s de la Concejal\u00eda de Agricultura, ha firmado un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal para la defensa del medio ambiente. La firma tuvo lugar ayer, martes 9 de febrero,"},"aioseo_meta_data":{"post_id":"10901","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:32:57","updated":"2025-06-04 17:58:12","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/medio-ambiente\/\" title=\"Medio Ambiente\">Medio Ambiente<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Medio Ambiente","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/medio-ambiente\/"},{"label":"El Ayuntamiento firma un convenio de colaboraci\u00f3n con la Asociaci\u00f3n Grupo Brinzal en el marco del proyecto agroSOStenible","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/10\/el-ayuntamiento-firma-un-convenio-de-colaboracion-con-la-asociacion-grupo-brinzal-en-el-marco-del-proyecto-agrosostenible\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 21:06:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10901"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10901\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}