{"id":10897,"date":"2016-02-09T12:45:45","date_gmt":"2016-02-09T12:45:45","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/"},"modified":"2016-02-09T12:45:45","modified_gmt":"2016-02-09T12:45:45","slug":"la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/","title":{"rendered":"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><em>La aportaci\u00f3n de Ciempozuelos se reduce en m\u00e1s de 730.000 euros <\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La Mancomunidad Intermunicipal Ciempozuelos- Titulcia para la Recogida de Residuos S\u00f3lidos Urbanos se reuni\u00f3 ayer, lunes 8 de febrero, en sesi\u00f3n de Junta Extraordinaria para determinar la aportaci\u00f3n de los dos ayuntamientos as\u00ed como dar cuenta del acuerdo plenario para el estudio y debate de la posible eliminaci\u00f3n de la tasa de basuras.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">A finales de 2015, se present\u00f3 el borrador de presupuesto para el 2016 y al no ser aprobado, autom\u00e1ticamente se ve prorrogado el presupuesto de 2013 con la reducci\u00f3n de <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">la aportaci\u00f3n del Ayuntamiento de Ciempozuelos que ser\u00e1 de 1.275.333,18 euros (antes 2.014.777,01 euros) mientras que la del Ayuntamiento de Titulcia ser\u00e1 de 141.703,69 euros (antes 25.730,15 euros). Esta reducci\u00f3n est\u00e1 motivada por dos causas: un error en las aportaciones de cada ayuntamiento y la sobrefacturaci\u00f3n detectada en el servicio.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">En 2004 se establecieron los porcentajes de participaci\u00f3n en los ingresos y los gastos de la Mancomunidad de los ayuntamientos, con un 90% para Ciempozuelos y un 10% para Titulcia. Seg\u00fan los informes t\u00e9cnicos de intervenci\u00f3n, existe un error material en el presupuesto del ejercicio de 2013 ya que las aportaciones municipales no cumplen estos porcentajes.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Por otro lado, el informe de intervenci\u00f3n con fecha de enero de 2016 pone de manifiesto la existencia de sobrefacturaci\u00f3n en el servicio de recogida de residuos s\u00f3lidos, recogida selectiva y limpieza viaria. Por este motivo, para ajustar la situaci\u00f3n presupuestaria a la realidad del coste y al no haber sido aprobado el borrador para el presupuesto del 2016, se estima necesaria la reducci\u00f3n de las partidas de 2013. Con esta medida se logra tambi\u00e9n ajustar el presupuesto del Ayuntamiento de Ciempozuelos con el objetivo de garantizar los servicios b\u00e1sicos a los vecinos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Respecto al debate y estudio ante la posible eliminaci\u00f3n de la tasa de basuras, la presidenta de la Mancomunidad comunic\u00f3 que no se puede eliminar la tasa para el ejercicio 2016 porque los informes t\u00e9cnicos de intervenci\u00f3n de la Mancomunidad no lo permit\u00edan, adem\u00e1s la tasa est\u00e1 devengada a fecha 1 de enero de 2016. A esta circunstancia se suma la necesidad de equilibrio entre los gastos e ingresos que impiden su eliminaci\u00f3n en el ejercicio de 2016 con el compromiso de su eliminaci\u00f3n de cara al 2017 al verse reducida la aportaci\u00f3n de los ayuntamientos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La pr\u00f3rroga de los presupuestos de 2013 con la reducci\u00f3n de gastos expuesta fue aprobada con los votos a favor de Ahora Ciempozuelos, PSOE Ciempozuelos, PIC y PSOE Titulcia. CPCI, PP de Ciempozuelos y PP de Titulcia votaron en contra.<\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La aportaci\u00f3n de Ciempozuelos se reduce en m\u00e1s de 730.000 euros La Mancomunidad Intermunicipal Ciempozuelos- Titulcia para la Recogida de Residuos S\u00f3lidos Urbanos se reuni\u00f3 ayer, lunes 8 de febrero, en sesi\u00f3n de Junta Extraordinaria para determinar la aportaci\u00f3n de los dos ayuntamientos as\u00ed como dar cuenta del acuerdo plenario para el estudio y debate [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1210],"class_list":["post-10897","post","type-post","status-publish","format-standard","hentry","tag-servicios-generales"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La aportaci\u00f3n de Ciempozuelos se reduce en m\u00e1s de 730.000 euros La Mancomunidad Intermunicipal Ciempozuelos- Titulcia para la Recogida de Residuos S\u00f3lidos Urbanos se reuni\u00f3 ayer, lunes 8 de febrero, en sesi\u00f3n de Junta Extraordinaria para determinar la aportaci\u00f3n de los dos ayuntamientos as\u00ed como dar cuenta del acuerdo plenario para el estudio y debate\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La aportaci\u00f3n de Ciempozuelos se reduce en m\u00e1s de 730.000 euros La Mancomunidad Intermunicipal Ciempozuelos- Titulcia para la Recogida de Residuos S\u00f3lidos Urbanos se reuni\u00f3 ayer, lunes 8 de febrero, en sesi\u00f3n de Junta Extraordinaria para determinar la aportaci\u00f3n de los dos ayuntamientos as\u00ed como dar cuenta del acuerdo plenario para el estudio y debate\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-09T12:45:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-09T12:45:45+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La aportaci\u00f3n de Ciempozuelos se reduce en m\u00e1s de 730.000 euros La Mancomunidad Intermunicipal Ciempozuelos- Titulcia para la Recogida de Residuos S\u00f3lidos Urbanos se reuni\u00f3 ayer, lunes 8 de febrero, en sesi\u00f3n de Junta Extraordinaria para determinar la aportaci\u00f3n de los dos ayuntamientos as\u00ed como dar cuenta del acuerdo plenario para el estudio y debate\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/09\\\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\\\/#blogposting\",\"name\":\"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\\u00f3n de los gastos - Ayuntamiento de Ciempozuelos\",\"headline\":\"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\\u00f3n de los gastos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-02-09T12:45:45+01:00\",\"dateModified\":\"2016-02-09T12:45:45+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/09\\\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/09\\\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\\\/#webpage\"},\"articleSection\":\"Servicios Generales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/09\\\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-generales\\\/#listItem\",\"name\":\"Servicios Generales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-generales\\\/#listItem\",\"position\":2,\"name\":\"Servicios Generales\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-generales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/09\\\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\\\/#listItem\",\"name\":\"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\\u00f3n de los gastos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/09\\\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\\\/#listItem\",\"position\":3,\"name\":\"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\\u00f3n de los gastos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-generales\\\/#listItem\",\"name\":\"Servicios Generales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/09\\\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/09\\\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/09\\\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\\\/\",\"name\":\"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\\u00f3n de los gastos - Ayuntamiento de Ciempozuelos\",\"description\":\"La aportaci\\u00f3n de Ciempozuelos se reduce en m\\u00e1s de 730.000 euros La Mancomunidad Intermunicipal Ciempozuelos- Titulcia para la Recogida de Residuos S\\u00f3lidos Urbanos se reuni\\u00f3 ayer, lunes 8 de febrero, en sesi\\u00f3n de Junta Extraordinaria para determinar la aportaci\\u00f3n de los dos ayuntamientos as\\u00ed como dar cuenta del acuerdo plenario para el estudio y debate\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/09\\\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-02-09T12:45:45+01:00\",\"dateModified\":\"2016-02-09T12:45:45+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos - Ayuntamiento de Ciempozuelos","description":"La aportaci\u00f3n de Ciempozuelos se reduce en m\u00e1s de 730.000 euros La Mancomunidad Intermunicipal Ciempozuelos- Titulcia para la Recogida de Residuos S\u00f3lidos Urbanos se reuni\u00f3 ayer, lunes 8 de febrero, en sesi\u00f3n de Junta Extraordinaria para determinar la aportaci\u00f3n de los dos ayuntamientos as\u00ed como dar cuenta del acuerdo plenario para el estudio y debate","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/#blogposting","name":"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos - Ayuntamiento de Ciempozuelos","headline":"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-02-09T12:45:45+01:00","dateModified":"2016-02-09T12:45:45+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/#webpage"},"articleSection":"Servicios Generales"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-generales\/#listItem","name":"Servicios Generales"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-generales\/#listItem","position":2,"name":"Servicios Generales","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-generales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/#listItem","name":"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/#listItem","position":3,"name":"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-generales\/#listItem","name":"Servicios Generales"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/","name":"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos - Ayuntamiento de Ciempozuelos","description":"La aportaci\u00f3n de Ciempozuelos se reduce en m\u00e1s de 730.000 euros La Mancomunidad Intermunicipal Ciempozuelos- Titulcia para la Recogida de Residuos S\u00f3lidos Urbanos se reuni\u00f3 ayer, lunes 8 de febrero, en sesi\u00f3n de Junta Extraordinaria para determinar la aportaci\u00f3n de los dos ayuntamientos as\u00ed como dar cuenta del acuerdo plenario para el estudio y debate","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-02-09T12:45:45+01:00","dateModified":"2016-02-09T12:45:45+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos - Ayuntamiento de Ciempozuelos","og:description":"La aportaci\u00f3n de Ciempozuelos se reduce en m\u00e1s de 730.000 euros La Mancomunidad Intermunicipal Ciempozuelos- Titulcia para la Recogida de Residuos S\u00f3lidos Urbanos se reuni\u00f3 ayer, lunes 8 de febrero, en sesi\u00f3n de Junta Extraordinaria para determinar la aportaci\u00f3n de los dos ayuntamientos as\u00ed como dar cuenta del acuerdo plenario para el estudio y debate","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/","article:published_time":"2016-02-09T12:45:45+00:00","article:modified_time":"2016-02-09T12:45:45+00:00","twitter:card":"summary","twitter:title":"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos - Ayuntamiento de Ciempozuelos","twitter:description":"La aportaci\u00f3n de Ciempozuelos se reduce en m\u00e1s de 730.000 euros La Mancomunidad Intermunicipal Ciempozuelos- Titulcia para la Recogida de Residuos S\u00f3lidos Urbanos se reuni\u00f3 ayer, lunes 8 de febrero, en sesi\u00f3n de Junta Extraordinaria para determinar la aportaci\u00f3n de los dos ayuntamientos as\u00ed como dar cuenta del acuerdo plenario para el estudio y debate"},"aioseo_meta_data":{"post_id":"10897","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:32:22","updated":"2025-06-04 17:58:12","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-generales\/\" title=\"Servicios Generales\">Servicios Generales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Servicios Generales","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-generales\/"},{"label":"La Mancomunidad Ciempozuelos- Titulcia prorroga el presupuesto con una reducci\u00f3n de los gastos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/09\/la-mancomunidad-ciempozuelos-titulcia-prorroga-el-presupuesto-con-una-reduccion-de-los-gastos\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:10:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10897"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10897\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}