{"id":10896,"date":"2016-02-08T13:23:42","date_gmt":"2016-02-08T13:23:42","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/"},"modified":"2016-02-08T13:23:42","modified_gmt":"2016-02-08T13:23:42","slug":"musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/","title":{"rendered":"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><em style=\"font-size: 12.16px; line-height: 1.3em;\">Este mi\u00e9rcoles 10 a las 16.30 horas celebramos el entierro de la sardina<\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La plaza de la Constituci\u00f3n de Ciempozuelos fue el escenario el pasado viernes de la fiesta de Carnaval organizada por las Mesas de Festejos, Cultura y Juventud. La tem\u00e1tica escogida para el inicio de Carnaval fue el cine de la d\u00e9cada de los ochenta por lo que pudimos disfrutar de indumentarias de Grease, Star Wars, Flashdance, Batman, Buscando a Susan desesperadamente o Los Picapiedra, entre otros. Vocingleando, disfrazados de payasos, fueron los encargados de dirigir y presentar la fiesta.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Los ganadores de la categor\u00eda infantil fueron Rub\u00e9n Mart\u00ednez, Sheila Mart\u00ednez, M\u00edriam Cervig\u00f3n y Paula Fern\u00e1ndez disfrazados de Los Picapiedra y la princesa. El primer premio de los adultos recay\u00f3 en Las Michael Jackson. <\/span><span style=\"font-size: 12.16px; line-height: 15.808px;\">Los ganadores de ambas categor\u00edas recibieron sendos vales de 100\u20ac cada uno para material de papeler\u00eda en las Papeler\u00edas Charada y Berrocal, respectivamente.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">El s\u00e1bado, el Carnaval se traslad\u00f3 al Hogar del Jubilado con un baile de disfraces y el domingo pudimos disfrutar de la obra teatral \u2018La fiesta loca de Carnaval\u2019 en la Sala Multifuncional. Adem\u00e1s, el viernes y el s\u00e1bado se celebr\u00f3 el Mercado de Artesan\u00eda en la plaza Ventura Rodr\u00edguez.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><strong style=\"font-size: 12.16px; line-height: 1.3em;\">Entierro de la Sardina<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><strong> <\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El broche final al Carnaval llega este mi\u00e9rcoles, 10 de febrero, a las 16.30 horas con el entierro de la sardina. El pasacalles arrancar\u00e1 en la Plaza de la Constituci\u00f3n y llegar\u00e1 hasta el Pabell\u00f3n de Deportes. Habr\u00e1 limonada, sardinas, m\u00fasica y malabares. Esta fiesta cuenta con la colaboraci\u00f3n del Centro Joven y del Hogar del Jubilado de Ciempozuelos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">Desde el Ayuntamiento de Ciempozuelos se quiere agradecer el trabajo y la participaci\u00f3n de los miembros de las mesas de trabajo, el Centro Joven, la Compa\u00f1\u00eda Bloop, Vocingleando como maestros de ceremonias, los trabajadores del Ayuntamiento y las personas que hicieron posible la celebraci\u00f3n as\u00ed como animar a participar a todos en las actividades programadas.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><img decoding=\"async\" class=\" size-full wp-image-10893\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalnios.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalnios-200x157.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalnios-300x235.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalnios-400x313.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalnios-600x470.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalnios.jpg 695w\" sizes=\"(max-width: 695px) 100vw, 695px\" \/><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">\u00a0<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><img decoding=\"async\" class=\" size-full wp-image-10894\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalganadores_adultos.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalganadores_adultos-200x150.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalganadores_adultos-300x225.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalganadores_adultos-400x300.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalganadores_adultos-600x450.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalganadores_adultos-768x576.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalganadores_adultos-800x600.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalganadores_adultos-1024x769.jpg 1024w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalganadores_adultos-1200x901.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalganadores_adultos.jpg 1207w\" sizes=\"(max-width: 1207px) 100vw, 1207px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles 10 a las 16.30 horas celebramos el entierro de la sardina La plaza de la Constituci\u00f3n de Ciempozuelos fue el escenario el pasado viernes de la fiesta de Carnaval organizada por las Mesas de Festejos, Cultura y Juventud. La tem\u00e1tica escogida para el inicio de Carnaval fue el cine de la d\u00e9cada de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1077],"class_list":["post-10896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-carnavales"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Este mi\u00e9rcoles 10 a las 16.30 horas celebramos el entierro de la sardina La plaza de la Constituci\u00f3n de Ciempozuelos fue el escenario el pasado viernes de la fiesta de Carnaval organizada por las Mesas de Festejos, Cultura y Juventud. La tem\u00e1tica escogida para el inicio de Carnaval fue el cine de la d\u00e9cada de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Este mi\u00e9rcoles 10 a las 16.30 horas celebramos el entierro de la sardina La plaza de la Constituci\u00f3n de Ciempozuelos fue el escenario el pasado viernes de la fiesta de Carnaval organizada por las Mesas de Festejos, Cultura y Juventud. La tem\u00e1tica escogida para el inicio de Carnaval fue el cine de la d\u00e9cada de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-02-08T13:23:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-08T13:23:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Este mi\u00e9rcoles 10 a las 16.30 horas celebramos el entierro de la sardina La plaza de la Constituci\u00f3n de Ciempozuelos fue el escenario el pasado viernes de la fiesta de Carnaval organizada por las Mesas de Festejos, Cultura y Juventud. La tem\u00e1tica escogida para el inicio de Carnaval fue el cine de la d\u00e9cada de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/#blogposting\",\"name\":\"M\\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"M\\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/carnavalnios.jpg\",\"width\":695,\"height\":544},\"datePublished\":\"2016-02-08T13:23:42+01:00\",\"dateModified\":\"2016-02-08T13:23:42+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/#webpage\"},\"articleSection\":\"Carnavales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/carnavales\\\/#listItem\",\"name\":\"Carnavales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/carnavales\\\/#listItem\",\"position\":2,\"name\":\"Carnavales\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/carnavales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/#listItem\",\"name\":\"M\\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/#listItem\",\"position\":3,\"name\":\"M\\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/carnavales\\\/#listItem\",\"name\":\"Carnavales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/\",\"name\":\"M\\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"Este mi\\u00e9rcoles 10 a las 16.30 horas celebramos el entierro de la sardina La plaza de la Constituci\\u00f3n de Ciempozuelos fue el escenario el pasado viernes de la fiesta de Carnaval organizada por las Mesas de Festejos, Cultura y Juventud. La tem\\u00e1tica escogida para el inicio de Carnaval fue el cine de la d\\u00e9cada de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/carnavalnios.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/#mainImage\",\"width\":695,\"height\":544},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/02\\\/08\\\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\\\/#mainImage\"},\"datePublished\":\"2016-02-08T13:23:42+01:00\",\"dateModified\":\"2016-02-08T13:23:42+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"Este mi\u00e9rcoles 10 a las 16.30 horas celebramos el entierro de la sardina La plaza de la Constituci\u00f3n de Ciempozuelos fue el escenario el pasado viernes de la fiesta de Carnaval organizada por las Mesas de Festejos, Cultura y Juventud. La tem\u00e1tica escogida para el inicio de Carnaval fue el cine de la d\u00e9cada de","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/#blogposting","name":"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalnios.jpg","width":695,"height":544},"datePublished":"2016-02-08T13:23:42+01:00","dateModified":"2016-02-08T13:23:42+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/#webpage"},"articleSection":"Carnavales"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/carnavales\/#listItem","name":"Carnavales"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/carnavales\/#listItem","position":2,"name":"Carnavales","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/carnavales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/#listItem","name":"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/#listItem","position":3,"name":"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/carnavales\/#listItem","name":"Carnavales"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/","name":"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"Este mi\u00e9rcoles 10 a las 16.30 horas celebramos el entierro de la sardina La plaza de la Constituci\u00f3n de Ciempozuelos fue el escenario el pasado viernes de la fiesta de Carnaval organizada por las Mesas de Festejos, Cultura y Juventud. La tem\u00e1tica escogida para el inicio de Carnaval fue el cine de la d\u00e9cada de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2016\/02\/carnavalnios.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/#mainImage","width":695,"height":544},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/#mainImage"},"datePublished":"2016-02-08T13:23:42+01:00","dateModified":"2016-02-08T13:23:42+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"Este mi\u00e9rcoles 10 a las 16.30 horas celebramos el entierro de la sardina La plaza de la Constituci\u00f3n de Ciempozuelos fue el escenario el pasado viernes de la fiesta de Carnaval organizada por las Mesas de Festejos, Cultura y Juventud. La tem\u00e1tica escogida para el inicio de Carnaval fue el cine de la d\u00e9cada de","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/","article:published_time":"2016-02-08T13:23:42+00:00","article:modified_time":"2016-02-08T13:23:42+00:00","twitter:card":"summary","twitter:title":"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"Este mi\u00e9rcoles 10 a las 16.30 horas celebramos el entierro de la sardina La plaza de la Constituci\u00f3n de Ciempozuelos fue el escenario el pasado viernes de la fiesta de Carnaval organizada por las Mesas de Festejos, Cultura y Juventud. La tem\u00e1tica escogida para el inicio de Carnaval fue el cine de la d\u00e9cada de"},"aioseo_meta_data":{"post_id":"10896","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:32:22","updated":"2025-06-04 17:58:12","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/carnavales\/\" title=\"Carnavales\">Carnavales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tM\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Carnavales","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/carnavales\/"},{"label":"M\u00fasica, cine y color en el Carnaval ochentero de Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/02\/08\/musica-cine-y-color-en-el-carnaval-ochentero-de-ciempozuelos-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:56:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10896"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10893"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}