{"id":10841,"date":"2016-01-26T09:30:59","date_gmt":"2016-01-26T09:30:59","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/"},"modified":"2016-01-26T09:30:59","modified_gmt":"2016-01-26T09:30:59","slug":"el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/","title":{"rendered":"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; margin-bottom: 0.0001pt; text-align: justify; line-height: normal;\">Durante el mes de octubre, la alcaldesa de Ciempozuelos y la concejala delegada de obras se reunieron con los responsables de ADIF para poner en su conocimiento la necesidad urgente de desdoblamiento de v\u00edas de la l\u00ednea C3 de cercan\u00edas y, m\u00e1s all\u00e1 de eso, la exigencia de adecuar la estaci\u00f3n de Ciempozuelos para eliminar las barreras arquitect\u00f3nicas instalando un ascensor que permita acceso a la v\u00eda en ambas direcciones. La alcaldesa insisti\u00f3 en que hay vecinas y vecinos que, para poder ir a Madrid, se ven obligados a dirigirse primero a Aranjuez y all\u00ed esperar la salida de un nuevo convoy con direcci\u00f3n a Atocha y Sol.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; margin-bottom: 0.0001pt; text-align: justify; line-height: normal;\"><span style=\"font-size: 12.16px;\">Esta semana se ha recibido en el Ayuntamiento la contestaci\u00f3n de ADIF, en la que se\u00f1alan que no se va a proceder a la instalaci\u00f3n del ascensor requerido.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; margin-bottom: 0.0001pt; text-align: justify; line-height: normal;\">Por ese motivo la alcald\u00eda ha remitido a ADIF un escrito protestando por esa decisi\u00f3n, que supone una grave discriminaci\u00f3n para los vecinos de Ciempozuelos.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; margin-bottom: 0.0001pt; text-align: justify; line-height: normal;\">Desde la Concejal\u00eda de Obras se han iniciado contactos con los Ayuntamientos de Pinto, Valdemoro y Aranjuez para coordinar acciones encaminadas a exigir el desdoblamiento de la v\u00eda y la instalaci\u00f3n de los ascensores que permitan eliminar las barreras arquitect\u00f3nicas.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; margin-bottom: 0.0001pt; text-align: justify; line-height: normal;\"><span style=\"font-size: 12.16px;\">Desde el Ayuntamiento se hace un llamamiento a las vecinas y vecinos usuarios del tren de cercan\u00edas para que expresen a ADIF mediante las quejas oportunas su rechazo de la actual situaci\u00f3n y la exigencia de que se atienda la reivindicaci\u00f3n de las vecinas y vecinos. La eliminaci\u00f3n de las barreras arquitect\u00f3nicas es una exigencia de sentido com\u00fan que va en beneficio de la dignidad de las personas. Por ese motivo, el Ayuntamiento de Ciempozuelos no descarta impulsar acciones ciudadanas frente a las pretensiones manifestadas por ADIF.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el mes de octubre, la alcaldesa de Ciempozuelos y la concejala delegada de obras se reunieron con los responsables de ADIF para poner en su conocimiento la necesidad urgente de desdoblamiento de v\u00edas de la l\u00ednea C3 de cercan\u00edas y, m\u00e1s all\u00e1 de eso, la exigencia de adecuar la estaci\u00f3n de Ciempozuelos para eliminar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1133],"class_list":["post-10841","post","type-post","status-publish","format-standard","hentry","tag-movilidad"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Durante el mes de octubre, la alcaldesa de Ciempozuelos y la concejala delegada de obras se reunieron con los responsables de ADIF para poner en su conocimiento la necesidad urgente de desdoblamiento de v\u00edas de la l\u00ednea C3 de cercan\u00edas y, m\u00e1s all\u00e1 de eso, la exigencia de adecuar la estaci\u00f3n de Ciempozuelos para eliminar\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Durante el mes de octubre, la alcaldesa de Ciempozuelos y la concejala delegada de obras se reunieron con los responsables de ADIF para poner en su conocimiento la necesidad urgente de desdoblamiento de v\u00edas de la l\u00ednea C3 de cercan\u00edas y, m\u00e1s all\u00e1 de eso, la exigencia de adecuar la estaci\u00f3n de Ciempozuelos para eliminar\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-01-26T09:30:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-26T09:30:59+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Durante el mes de octubre, la alcaldesa de Ciempozuelos y la concejala delegada de obras se reunieron con los responsables de ADIF para poner en su conocimiento la necesidad urgente de desdoblamiento de v\u00edas de la l\u00ednea C3 de cercan\u00edas y, m\u00e1s all\u00e1 de eso, la exigencia de adecuar la estaci\u00f3n de Ciempozuelos para eliminar\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/26\\\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\\\/#blogposting\",\"name\":\"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\\u00f3nicas en la estaci\\u00f3n de cercan\\u00edas de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\\u00f3nicas en la estaci\\u00f3n de cercan\\u00edas de Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2016-01-26T09:30:59+01:00\",\"dateModified\":\"2016-01-26T09:30:59+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/26\\\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/26\\\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\\\/#webpage\"},\"articleSection\":\"Movilidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/26\\\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/movilidad\\\/#listItem\",\"name\":\"Movilidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/movilidad\\\/#listItem\",\"position\":2,\"name\":\"Movilidad\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/movilidad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/26\\\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\\\/#listItem\",\"name\":\"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\\u00f3nicas en la estaci\\u00f3n de cercan\\u00edas de Ciempozuelos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/26\\\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\\\/#listItem\",\"position\":3,\"name\":\"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\\u00f3nicas en la estaci\\u00f3n de cercan\\u00edas de Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/movilidad\\\/#listItem\",\"name\":\"Movilidad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/26\\\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/26\\\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/26\\\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\\\/\",\"name\":\"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\\u00f3nicas en la estaci\\u00f3n de cercan\\u00edas de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"Durante el mes de octubre, la alcaldesa de Ciempozuelos y la concejala delegada de obras se reunieron con los responsables de ADIF para poner en su conocimiento la necesidad urgente de desdoblamiento de v\\u00edas de la l\\u00ednea C3 de cercan\\u00edas y, m\\u00e1s all\\u00e1 de eso, la exigencia de adecuar la estaci\\u00f3n de Ciempozuelos para eliminar\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2016\\\/01\\\/26\\\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2016-01-26T09:30:59+01:00\",\"dateModified\":\"2016-01-26T09:30:59+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"Durante el mes de octubre, la alcaldesa de Ciempozuelos y la concejala delegada de obras se reunieron con los responsables de ADIF para poner en su conocimiento la necesidad urgente de desdoblamiento de v\u00edas de la l\u00ednea C3 de cercan\u00edas y, m\u00e1s all\u00e1 de eso, la exigencia de adecuar la estaci\u00f3n de Ciempozuelos para eliminar","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/#blogposting","name":"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2016-01-26T09:30:59+01:00","dateModified":"2016-01-26T09:30:59+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/#webpage"},"articleSection":"Movilidad"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/movilidad\/#listItem","name":"Movilidad"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/movilidad\/#listItem","position":2,"name":"Movilidad","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/movilidad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/#listItem","name":"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/#listItem","position":3,"name":"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/movilidad\/#listItem","name":"Movilidad"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/","name":"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"Durante el mes de octubre, la alcaldesa de Ciempozuelos y la concejala delegada de obras se reunieron con los responsables de ADIF para poner en su conocimiento la necesidad urgente de desdoblamiento de v\u00edas de la l\u00ednea C3 de cercan\u00edas y, m\u00e1s all\u00e1 de eso, la exigencia de adecuar la estaci\u00f3n de Ciempozuelos para eliminar","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2016-01-26T09:30:59+01:00","dateModified":"2016-01-26T09:30:59+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"Durante el mes de octubre, la alcaldesa de Ciempozuelos y la concejala delegada de obras se reunieron con los responsables de ADIF para poner en su conocimiento la necesidad urgente de desdoblamiento de v\u00edas de la l\u00ednea C3 de cercan\u00edas y, m\u00e1s all\u00e1 de eso, la exigencia de adecuar la estaci\u00f3n de Ciempozuelos para eliminar","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/","article:published_time":"2016-01-26T09:30:59+00:00","article:modified_time":"2016-01-26T09:30:59+00:00","twitter:card":"summary","twitter:title":"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"Durante el mes de octubre, la alcaldesa de Ciempozuelos y la concejala delegada de obras se reunieron con los responsables de ADIF para poner en su conocimiento la necesidad urgente de desdoblamiento de v\u00edas de la l\u00ednea C3 de cercan\u00edas y, m\u00e1s all\u00e1 de eso, la exigencia de adecuar la estaci\u00f3n de Ciempozuelos para eliminar"},"aioseo_meta_data":{"post_id":"10841","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:28:17","updated":"2025-06-04 17:53:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/movilidad\/\" title=\"Movilidad\">Movilidad<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Movilidad","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/movilidad\/"},{"label":"El Ayuntamiento protesta ante ADIF por su negativa a eliminar las barreras arquitect\u00f3nicas en la estaci\u00f3n de cercan\u00edas de Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2016\/01\/26\/el-ayuntamiento-protesta-ante-adif-por-su-negativa-a-eliminar-las-barreras-arquitectonicas-en-la-estacion-de-cercanias-de-ciempozuelos-4\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:20:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10841"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10841\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}