{"id":10716,"date":"2015-12-18T10:09:32","date_gmt":"2015-12-18T10:09:32","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/"},"modified":"2015-12-18T10:09:32","modified_gmt":"2015-12-18T10:09:32","slug":"xvi-certamen-de-teatro-villa-de-ciempozuelos-2016","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/","title":{"rendered":"XVI Certamen de Teatro &#8220;Villa de Ciempozuelos 2016&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>El plazo de inscripci\u00f3n estar\u00e1 abierto desde el 21 de diciembre al 21 de enero de 2016.<\/em><\/p>\n<p style=\"text-align: justify;\">El Ayuntamiento de Ciempozuelos organiza el XVI Certamen de Teatro \u2018Villa de Ciempozuelos 2016\u2019, con el fin de acercar la cultura a todos los vecinos del municipio de una forma l\u00fadica y participativa.<\/p>\n<p style=\"text-align: justify;\">Podr\u00e1n inscribirse todas aquellas compa\u00f1\u00edas o grupos de adultos de car\u00e1cter profesional o amateur. Las compa\u00f1\u00edas seleccionadas para participar en el Certamen recibir\u00e1n una subvenci\u00f3n de 300 euros. Adem\u00e1s habr\u00e1 un premio de 1000 euros para el ganador, un segundo premio de 600 euros, un tercero de 300 euros y los mejores actores en categor\u00eda femenina y masculina recibir\u00e1n 200 euros cada uno. A su vez habr\u00e1 una menci\u00f3n a la mejor escenograf\u00eda.<\/p>\n<p style=\"text-align: justify;\">El plazo de inscripci\u00f3n estar\u00e1 abierto a partir del d\u00eda 21 de diciembre hasta el 21 de enero de 2016. Se deber\u00e1 rellenar la solicitud y aportar la siguiente documentaci\u00f3n:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Documentos que acrediten la personalidad del solicitante y, en su caso, la representaci\u00f3n de quien firme la solicitud.<\/li>\n<li>Declaraci\u00f3n responsable de que en el solicitante no concurre ninguna de las circunstancias que impidan obtener la condici\u00f3n de beneficiario de subvenciones p\u00fablicas.<\/li>\n<li>V\u00eddeo en DVD o enlace a p\u00e1gina web.<\/li>\n<li>Fotograf\u00edas de la obra.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Las propuestas deber\u00e1n enviarse al Ayuntamiento de Ciempozuelos mediante correo ordinario o presentarlas en el Registro en horario de lunes a viernes, de 9.00 a 14.00 horas y, martes y jueves, de 17.00 a 19.00. Se conocer\u00e1n los grupos elegidos en el plazo de un mes a partir de la fecha final del plazo de presentaci\u00f3n de solicitudes.<\/p>\n<p style=\"text-align: justify;\">Las representaciones ser\u00e1n los s\u00e1bados de los meses de marzo (d\u00edas 5 y 12 a las 19.00 horas), abril (d\u00edas 2, 9 y 23 a las 20.00 horas), mayo (d\u00edas 7, 21 y 28 a las 21.30 horas) y junio (d\u00edas 4 y 11 a las 21.30 horas). Los primeros dos meses se realizar\u00e1 en la Sala Multifuncional y los dos \u00faltimos en la Plaza de la Constituci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La entrega de premios y la clausura del certamen ser\u00e1 en el mes de julio de 2016.<\/p>\n<p style=\"text-align: justify;\">Toda la informaci\u00f3n y formularios de inscripci\u00f3n est\u00e1n a disposici\u00f3n en los documentos adjuntos a esta nota.<\/p>\n<p>Descargar archivo: {jd_file file==533}<\/p>\n<p>Descargar archivo: {jd_file file==534}<\/p>\n<p>Descargar archivo: {jd_file file==535}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El plazo de inscripci\u00f3n estar\u00e1 abierto desde el 21 de diciembre al 21 de enero de 2016. El Ayuntamiento de Ciempozuelos organiza el XVI Certamen de Teatro \u2018Villa de Ciempozuelos 2016\u2019, con el fin de acercar la cultura a todos los vecinos del municipio de una forma l\u00fadica y participativa. Podr\u00e1n inscribirse todas aquellas compa\u00f1\u00edas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1217],"class_list":["post-10716","post","type-post","status-publish","format-standard","hentry","tag-1217"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El plazo de inscripci\u00f3n estar\u00e1 abierto desde el 21 de diciembre al 21 de enero de 2016. El Ayuntamiento de Ciempozuelos organiza el XVI Certamen de Teatro \u2018Villa de Ciempozuelos 2016\u2019, con el fin de acercar la cultura a todos los vecinos del municipio de una forma l\u00fadica y participativa. Podr\u00e1n inscribirse todas aquellas compa\u00f1\u00edas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"XVI Certamen de Teatro \u201cVilla de Ciempozuelos 2016\u201d - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El plazo de inscripci\u00f3n estar\u00e1 abierto desde el 21 de diciembre al 21 de enero de 2016. El Ayuntamiento de Ciempozuelos organiza el XVI Certamen de Teatro \u2018Villa de Ciempozuelos 2016\u2019, con el fin de acercar la cultura a todos los vecinos del municipio de una forma l\u00fadica y participativa. Podr\u00e1n inscribirse todas aquellas compa\u00f1\u00edas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-12-18T10:09:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-12-18T10:09:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"XVI Certamen de Teatro \u201cVilla de Ciempozuelos 2016\u201d - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El plazo de inscripci\u00f3n estar\u00e1 abierto desde el 21 de diciembre al 21 de enero de 2016. El Ayuntamiento de Ciempozuelos organiza el XVI Certamen de Teatro \u2018Villa de Ciempozuelos 2016\u2019, con el fin de acercar la cultura a todos los vecinos del municipio de una forma l\u00fadica y participativa. Podr\u00e1n inscribirse todas aquellas compa\u00f1\u00edas\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/18\\\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\\\/#blogposting\",\"name\":\"XVI Certamen de Teatro \\u201cVilla de Ciempozuelos 2016\\u201d - Ayuntamiento de Ciempozuelos\",\"headline\":\"XVI Certamen de Teatro &#8220;Villa de Ciempozuelos 2016&#8221;\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-12-18T10:09:32+01:00\",\"dateModified\":\"2015-12-18T10:09:32+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/18\\\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/18\\\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\\\/#webpage\"},\"articleSection\":\"1139\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/18\\\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"position\":2,\"name\":\"1139\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/18\\\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\\\/#listItem\",\"name\":\"XVI Certamen de Teatro &#8220;Villa de Ciempozuelos 2016&#8221;\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/18\\\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\\\/#listItem\",\"position\":3,\"name\":\"XVI Certamen de Teatro &#8220;Villa de Ciempozuelos 2016&#8221;\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/18\\\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/18\\\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/18\\\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\\\/\",\"name\":\"XVI Certamen de Teatro \\u201cVilla de Ciempozuelos 2016\\u201d - Ayuntamiento de Ciempozuelos\",\"description\":\"El plazo de inscripci\\u00f3n estar\\u00e1 abierto desde el 21 de diciembre al 21 de enero de 2016. El Ayuntamiento de Ciempozuelos organiza el XVI Certamen de Teatro \\u2018Villa de Ciempozuelos 2016\\u2019, con el fin de acercar la cultura a todos los vecinos del municipio de una forma l\\u00fadica y participativa. Podr\\u00e1n inscribirse todas aquellas compa\\u00f1\\u00edas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/18\\\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-12-18T10:09:32+01:00\",\"dateModified\":\"2015-12-18T10:09:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"XVI Certamen de Teatro \u201cVilla de Ciempozuelos 2016\u201d - Ayuntamiento de Ciempozuelos","description":"El plazo de inscripci\u00f3n estar\u00e1 abierto desde el 21 de diciembre al 21 de enero de 2016. El Ayuntamiento de Ciempozuelos organiza el XVI Certamen de Teatro \u2018Villa de Ciempozuelos 2016\u2019, con el fin de acercar la cultura a todos los vecinos del municipio de una forma l\u00fadica y participativa. Podr\u00e1n inscribirse todas aquellas compa\u00f1\u00edas","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/#blogposting","name":"XVI Certamen de Teatro \u201cVilla de Ciempozuelos 2016\u201d - Ayuntamiento de Ciempozuelos","headline":"XVI Certamen de Teatro &#8220;Villa de Ciempozuelos 2016&#8221;","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-12-18T10:09:32+01:00","dateModified":"2015-12-18T10:09:32+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/#webpage"},"articleSection":"1139"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","position":2,"name":"1139","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/#listItem","name":"XVI Certamen de Teatro &#8220;Villa de Ciempozuelos 2016&#8221;"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/#listItem","position":3,"name":"XVI Certamen de Teatro &#8220;Villa de Ciempozuelos 2016&#8221;","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/","name":"XVI Certamen de Teatro \u201cVilla de Ciempozuelos 2016\u201d - Ayuntamiento de Ciempozuelos","description":"El plazo de inscripci\u00f3n estar\u00e1 abierto desde el 21 de diciembre al 21 de enero de 2016. El Ayuntamiento de Ciempozuelos organiza el XVI Certamen de Teatro \u2018Villa de Ciempozuelos 2016\u2019, con el fin de acercar la cultura a todos los vecinos del municipio de una forma l\u00fadica y participativa. Podr\u00e1n inscribirse todas aquellas compa\u00f1\u00edas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-12-18T10:09:32+01:00","dateModified":"2015-12-18T10:09:32+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"XVI Certamen de Teatro \u201cVilla de Ciempozuelos 2016\u201d - Ayuntamiento de Ciempozuelos","og:description":"El plazo de inscripci\u00f3n estar\u00e1 abierto desde el 21 de diciembre al 21 de enero de 2016. El Ayuntamiento de Ciempozuelos organiza el XVI Certamen de Teatro \u2018Villa de Ciempozuelos 2016\u2019, con el fin de acercar la cultura a todos los vecinos del municipio de una forma l\u00fadica y participativa. Podr\u00e1n inscribirse todas aquellas compa\u00f1\u00edas","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/","article:published_time":"2015-12-18T10:09:32+00:00","article:modified_time":"2015-12-18T10:09:32+00:00","twitter:card":"summary","twitter:title":"XVI Certamen de Teatro \u201cVilla de Ciempozuelos 2016\u201d - Ayuntamiento de Ciempozuelos","twitter:description":"El plazo de inscripci\u00f3n estar\u00e1 abierto desde el 21 de diciembre al 21 de enero de 2016. El Ayuntamiento de Ciempozuelos organiza el XVI Certamen de Teatro \u2018Villa de Ciempozuelos 2016\u2019, con el fin de acercar la cultura a todos los vecinos del municipio de una forma l\u00fadica y participativa. Podr\u00e1n inscribirse todas aquellas compa\u00f1\u00edas"},"aioseo_meta_data":{"post_id":"10716","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:16:32","updated":"2025-06-04 17:43:12","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/\" title=\"1139\">1139<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tXVI Certamen de Teatro \u201cVilla de Ciempozuelos 2016\u201d\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1139","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/"},{"label":"XVI Certamen de Teatro &#8220;Villa de Ciempozuelos 2016&#8221;","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/18\/xvi-certamen-de-teatro-villa-de-ciempozuelos-2016\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:02:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10716"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10716\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}