{"id":10683,"date":"2015-12-01T13:52:45","date_gmt":"2015-12-01T13:52:45","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/"},"modified":"2015-12-01T13:52:45","modified_gmt":"2015-12-01T13:52:45","slug":"apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/","title":{"rendered":"Apertura de la bolsa de empleo para auxiliares administrativos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 15.808px;\"><em>Las solicitudes se pueden presentar del 2 al 21 de diciembre, ambos incluidos.<\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Tras las subsanaciones pertinentes, el Ayuntamiento de Ciempozuelos, en atenci\u00f3n a las necesidades existentes en la Corporaci\u00f3n, aprueba las bases y la convocatoria para la constituci\u00f3n de una bolsa de empleo con el fin de cubrir las plazas de auxiliares administrativos vacantes en la plantilla de personal. Las solicitudes se pueden presentar del 2 de diciembre al 21 de diciembre, ambos incluidos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Las funciones ser\u00e1n las propias de un auxiliar administrativo y el horario laboral ser\u00e1 de 37,5 horas semanales, de lunes a viernes, en horario de ma\u00f1ana y\/o tarde. La retribuci\u00f3n bruta mensual acordada para estas plazas corresponder\u00e1 a un grupo C2, del personal funcionario, con un nivel 13 de complemento de destino.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\">Los requisitos para optar a estas plazas son los siguientes:<\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\">Ser espa\u00f1ol o ciudadano de un Estado miembro de la Uni\u00f3n Europea.<\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\"><span lang=\"ES-TRAD\">Tener cumplidos 16 a\u00f1os de edad y no exceder, en su caso, de la edad m\u00e1xima de jubilaci\u00f3n forzosa.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\"><span lang=\"ES-TRAD\">Poseer la capacidad funcional para el desempe\u00f1o de las tareas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\"><span lang=\"ES-TRAD\">No haber sido separado mediante expediente disciplinario del servicio del Estado, de la Administraci\u00f3n Local, Auton\u00f3mica o Institucional ni hallarse inhabilitado para el ejercicio de funciones p\u00fablicas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\"><span lang=\"ES-TRAD\">Estar en posesi\u00f3n de la Titulaci\u00f3n de Graduado ESO o equivalente seg\u00fan los distintos planes de estudios.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><strong>Documentaci\u00f3n a presentar:<\/strong><\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\">Fotocopia del documento nacional de identidad, pasaporte en vigor o documento equivalente<\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\">Los m\u00e9ritos valorables se alegar\u00e1n en la instancia, dentro del plazo establecido para presentar la solicitud. Deber\u00e1n estar debidamente compulsados y justificados con la documentaci\u00f3n adecuada<\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\">Fotocopia de la titulaci\u00f3n exigida o justificante de haberla solicitado con entrada en el registro del \u00f3rgano competente, sin perjuicio de que sea necesaria la presentaci\u00f3n posterior del original<\/p>\n<p class=\"MsoNormal\" style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12px; line-height: normal; text-align: justify;\">El horario de compulsa de documentos es de lunes a viernes de 9:00 a 14:00 horas<span style=\"font-size: 12.16px; line-height: 1.3em;\">. Los criterios de selecci\u00f3n figuran en la resoluci\u00f3n publicada en el BOCM, destacando la realizaci\u00f3n de un examen con una puntuaci\u00f3n que marcar\u00e1 el orden de la bolsa.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\">Las bases, la subsanaci\u00f3n, la instancia, <\/span><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12.16px; line-height: 1.3em;\">las tasas de <\/span><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12.16px; line-height: 1.3em;\">examen<\/span><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: 12.16px; line-height: 1.3em;\"> y las tasas de examen para desempleados est\u00e1n disponibles como archivos adjuntos y descargables al final de esta nota<\/span><\/p>\n<p>Descargar archivo: {jd_file file==514}<\/p>\n<p>Descargar archivo: {jd_file file==515}<\/p>\n<p>Descargar archivo: {jd_file file==516}<\/p>\n<p>Descargar archivo: {jd_file file==517}<\/p>\n<p>Descargar archivo: {jd_file file==518}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las solicitudes se pueden presentar del 2 al 21 de diciembre, ambos incluidos. Tras las subsanaciones pertinentes, el Ayuntamiento de Ciempozuelos, en atenci\u00f3n a las necesidades existentes en la Corporaci\u00f3n, aprueba las bases y la convocatoria para la constituci\u00f3n de una bolsa de empleo con el fin de cubrir las plazas de auxiliares administrativos vacantes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1147],"class_list":["post-10683","post","type-post","status-publish","format-standard","hentry","tag-empleo-ruben-iglesias-garcia"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las solicitudes se pueden presentar del 2 al 21 de diciembre, ambos incluidos. Tras las subsanaciones pertinentes, el Ayuntamiento de Ciempozuelos, en atenci\u00f3n a las necesidades existentes en la Corporaci\u00f3n, aprueba las bases y la convocatoria para la constituci\u00f3n de una bolsa de empleo con el fin de cubrir las plazas de auxiliares administrativos vacantes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Apertura de la bolsa de empleo para auxiliares administrativos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Las solicitudes se pueden presentar del 2 al 21 de diciembre, ambos incluidos. Tras las subsanaciones pertinentes, el Ayuntamiento de Ciempozuelos, en atenci\u00f3n a las necesidades existentes en la Corporaci\u00f3n, aprueba las bases y la convocatoria para la constituci\u00f3n de una bolsa de empleo con el fin de cubrir las plazas de auxiliares administrativos vacantes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-12-01T13:52:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-12-01T13:52:45+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Apertura de la bolsa de empleo para auxiliares administrativos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las solicitudes se pueden presentar del 2 al 21 de diciembre, ambos incluidos. Tras las subsanaciones pertinentes, el Ayuntamiento de Ciempozuelos, en atenci\u00f3n a las necesidades existentes en la Corporaci\u00f3n, aprueba las bases y la convocatoria para la constituci\u00f3n de una bolsa de empleo con el fin de cubrir las plazas de auxiliares administrativos vacantes\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/01\\\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\\\/#blogposting\",\"name\":\"Apertura de la bolsa de empleo para auxiliares administrativos - Ayuntamiento de Ciempozuelos\",\"headline\":\"Apertura de la bolsa de empleo para auxiliares administrativos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-12-01T13:52:45+01:00\",\"dateModified\":\"2015-12-01T13:52:45+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/01\\\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/01\\\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\\\/#webpage\"},\"articleSection\":\"Empleo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/01\\\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/empleo-ruben-iglesias-garcia\\\/#listItem\",\"name\":\"Empleo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/empleo-ruben-iglesias-garcia\\\/#listItem\",\"position\":2,\"name\":\"Empleo\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/empleo-ruben-iglesias-garcia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/01\\\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\\\/#listItem\",\"name\":\"Apertura de la bolsa de empleo para auxiliares administrativos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/01\\\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\\\/#listItem\",\"position\":3,\"name\":\"Apertura de la bolsa de empleo para auxiliares administrativos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/empleo-ruben-iglesias-garcia\\\/#listItem\",\"name\":\"Empleo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/01\\\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/01\\\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/01\\\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\\\/\",\"name\":\"Apertura de la bolsa de empleo para auxiliares administrativos - Ayuntamiento de Ciempozuelos\",\"description\":\"Las solicitudes se pueden presentar del 2 al 21 de diciembre, ambos incluidos. Tras las subsanaciones pertinentes, el Ayuntamiento de Ciempozuelos, en atenci\\u00f3n a las necesidades existentes en la Corporaci\\u00f3n, aprueba las bases y la convocatoria para la constituci\\u00f3n de una bolsa de empleo con el fin de cubrir las plazas de auxiliares administrativos vacantes\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/12\\\/01\\\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-12-01T13:52:45+01:00\",\"dateModified\":\"2015-12-01T13:52:45+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Apertura de la bolsa de empleo para auxiliares administrativos - Ayuntamiento de Ciempozuelos","description":"Las solicitudes se pueden presentar del 2 al 21 de diciembre, ambos incluidos. Tras las subsanaciones pertinentes, el Ayuntamiento de Ciempozuelos, en atenci\u00f3n a las necesidades existentes en la Corporaci\u00f3n, aprueba las bases y la convocatoria para la constituci\u00f3n de una bolsa de empleo con el fin de cubrir las plazas de auxiliares administrativos vacantes","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/#blogposting","name":"Apertura de la bolsa de empleo para auxiliares administrativos - Ayuntamiento de Ciempozuelos","headline":"Apertura de la bolsa de empleo para auxiliares administrativos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-12-01T13:52:45+01:00","dateModified":"2015-12-01T13:52:45+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/#webpage"},"articleSection":"Empleo"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia\/#listItem","name":"Empleo"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia\/#listItem","position":2,"name":"Empleo","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/#listItem","name":"Apertura de la bolsa de empleo para auxiliares administrativos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/#listItem","position":3,"name":"Apertura de la bolsa de empleo para auxiliares administrativos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia\/#listItem","name":"Empleo"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/","name":"Apertura de la bolsa de empleo para auxiliares administrativos - Ayuntamiento de Ciempozuelos","description":"Las solicitudes se pueden presentar del 2 al 21 de diciembre, ambos incluidos. Tras las subsanaciones pertinentes, el Ayuntamiento de Ciempozuelos, en atenci\u00f3n a las necesidades existentes en la Corporaci\u00f3n, aprueba las bases y la convocatoria para la constituci\u00f3n de una bolsa de empleo con el fin de cubrir las plazas de auxiliares administrativos vacantes","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-12-01T13:52:45+01:00","dateModified":"2015-12-01T13:52:45+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Apertura de la bolsa de empleo para auxiliares administrativos - Ayuntamiento de Ciempozuelos","og:description":"Las solicitudes se pueden presentar del 2 al 21 de diciembre, ambos incluidos. Tras las subsanaciones pertinentes, el Ayuntamiento de Ciempozuelos, en atenci\u00f3n a las necesidades existentes en la Corporaci\u00f3n, aprueba las bases y la convocatoria para la constituci\u00f3n de una bolsa de empleo con el fin de cubrir las plazas de auxiliares administrativos vacantes","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/","article:published_time":"2015-12-01T13:52:45+00:00","article:modified_time":"2015-12-01T13:52:45+00:00","twitter:card":"summary","twitter:title":"Apertura de la bolsa de empleo para auxiliares administrativos - Ayuntamiento de Ciempozuelos","twitter:description":"Las solicitudes se pueden presentar del 2 al 21 de diciembre, ambos incluidos. Tras las subsanaciones pertinentes, el Ayuntamiento de Ciempozuelos, en atenci\u00f3n a las necesidades existentes en la Corporaci\u00f3n, aprueba las bases y la convocatoria para la constituci\u00f3n de una bolsa de empleo con el fin de cubrir las plazas de auxiliares administrativos vacantes"},"aioseo_meta_data":{"post_id":"10683","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:10:55","updated":"2025-06-04 17:37:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia\/\" title=\"Empleo\">Empleo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tApertura de la bolsa de empleo para auxiliares administrativos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Empleo","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/empleo-ruben-iglesias-garcia\/"},{"label":"Apertura de la bolsa de empleo para auxiliares administrativos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/12\/01\/apertura-de-la-bolsa-de-empleo-para-auxiliares-administrativos-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:01:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10683"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10683\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}