{"id":10655,"date":"2015-11-25T11:40:40","date_gmt":"2015-11-25T11:40:40","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/"},"modified":"2015-11-25T11:40:40","modified_gmt":"2015-11-25T11:40:40","slug":"la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/","title":{"rendered":"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><em>Se podr\u00e1 visitar hasta el d\u00eda 17 de diciembre <\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El Ayuntamiento de Ciempozuelos, en colaboraci\u00f3n con la Comunidad de Madrid, presenta la exposici\u00f3n Red Itiner \u2018Mujeres modelo. Mujeres de moda\u2019 (1850-1940) que se puede visitar a partir de hoy, mi\u00e9rcoles 25 de noviembre, y hasta el d\u00eda 17 de diciembre en la Casa de la Cultura de Ciempozuelos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La muestra est\u00e1 formada por 26 fotograf\u00edas de artistas consagrados que retratan a diferentes mujeres que representan el papel de la modelo. Familiares, amigas, actrices, bailarinas, que act\u00faan como modelos amateur para que el espectador aprecie los cambios que se han desarrolado en el rol de la mujer, en el vestuario y, sobre todo, en la actitud desde finales del siglo XIX y durante las primeras d\u00e9cadas del siglo XX en Europa y Am\u00e9rica.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">A trav\u00e9s de ellas el espectador puede observar el doble papel de la mujer modelo -sujeto y objeto- a trav\u00e9s de im\u00e1genes en donde la moda se convierte en uno de los veh\u00edculos m\u00e1s eficaces para revelar rupturas culturales, pol\u00edticas y sociales a lo largo de 80 a\u00f1os de historia.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La exposici\u00f3n nos presenta im\u00e1genes de Lady Clementina Hawarden, Lewis Carroll, Margaret Cameron, Kitagawa Utamaro, Antonio Calvache, Dora Kallmus, Eugene R. Richee y Horst, entre otros.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Como detalles curiosos de la exposici\u00f3n, la primera fotograf\u00eda es un daguerrotipo, invento patentado por Louis Daguerre, considerado como el primer procedimiento fotogr\u00e1fico. Tambi\u00e9n, entre las seis primeras fotograf\u00edas figuran im\u00e1genes tomadas por Lewis Carroll, una de ellas corresponde a la ni\u00f1a que inspir\u00f3 al autor para escribir \u2018Alicia en el Pa\u00eds de las Maravillas\u2019.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">El horario para visitar la exposici\u00f3n es de lunes a viernes de 10.30 a 13.30 horas y de 17.30 a 20.00 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se podr\u00e1 visitar hasta el d\u00eda 17 de diciembre El Ayuntamiento de Ciempozuelos, en colaboraci\u00f3n con la Comunidad de Madrid, presenta la exposici\u00f3n Red Itiner \u2018Mujeres modelo. Mujeres de moda\u2019 (1850-1940) que se puede visitar a partir de hoy, mi\u00e9rcoles 25 de noviembre, y hasta el d\u00eda 17 de diciembre en la Casa de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1217],"class_list":["post-10655","post","type-post","status-publish","format-standard","hentry","tag-1217"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Se podr\u00e1 visitar hasta el d\u00eda 17 de diciembre El Ayuntamiento de Ciempozuelos, en colaboraci\u00f3n con la Comunidad de Madrid, presenta la exposici\u00f3n Red Itiner \u2018Mujeres modelo. Mujeres de moda\u2019 (1850-1940) que se puede visitar a partir de hoy, mi\u00e9rcoles 25 de noviembre, y hasta el d\u00eda 17 de diciembre en la Casa de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019 - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Se podr\u00e1 visitar hasta el d\u00eda 17 de diciembre El Ayuntamiento de Ciempozuelos, en colaboraci\u00f3n con la Comunidad de Madrid, presenta la exposici\u00f3n Red Itiner \u2018Mujeres modelo. Mujeres de moda\u2019 (1850-1940) que se puede visitar a partir de hoy, mi\u00e9rcoles 25 de noviembre, y hasta el d\u00eda 17 de diciembre en la Casa de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-11-25T11:40:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-11-25T11:40:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019 - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Se podr\u00e1 visitar hasta el d\u00eda 17 de diciembre El Ayuntamiento de Ciempozuelos, en colaboraci\u00f3n con la Comunidad de Madrid, presenta la exposici\u00f3n Red Itiner \u2018Mujeres modelo. Mujeres de moda\u2019 (1850-1940) que se puede visitar a partir de hoy, mi\u00e9rcoles 25 de noviembre, y hasta el d\u00eda 17 de diciembre en la Casa de la\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/25\\\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\\\/#blogposting\",\"name\":\"La Casa de la Cultura acoge la exposici\\u00f3n \\u2018Mujeres modelo. Mujeres de moda\\u2019 - Ayuntamiento de Ciempozuelos\",\"headline\":\"La Casa de la Cultura acoge la exposici\\u00f3n \\u2018Mujeres modelo. Mujeres de moda\\u2019\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-11-25T11:40:40+01:00\",\"dateModified\":\"2015-11-25T11:40:40+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/25\\\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/25\\\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\\\/#webpage\"},\"articleSection\":\"1139\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/25\\\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"position\":2,\"name\":\"1139\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/25\\\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\\\/#listItem\",\"name\":\"La Casa de la Cultura acoge la exposici\\u00f3n \\u2018Mujeres modelo. Mujeres de moda\\u2019\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/25\\\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\\\/#listItem\",\"position\":3,\"name\":\"La Casa de la Cultura acoge la exposici\\u00f3n \\u2018Mujeres modelo. Mujeres de moda\\u2019\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/25\\\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/25\\\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/25\\\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\\\/\",\"name\":\"La Casa de la Cultura acoge la exposici\\u00f3n \\u2018Mujeres modelo. Mujeres de moda\\u2019 - Ayuntamiento de Ciempozuelos\",\"description\":\"Se podr\\u00e1 visitar hasta el d\\u00eda 17 de diciembre El Ayuntamiento de Ciempozuelos, en colaboraci\\u00f3n con la Comunidad de Madrid, presenta la exposici\\u00f3n Red Itiner \\u2018Mujeres modelo. Mujeres de moda\\u2019 (1850-1940) que se puede visitar a partir de hoy, mi\\u00e9rcoles 25 de noviembre, y hasta el d\\u00eda 17 de diciembre en la Casa de la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/25\\\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-11-25T11:40:40+01:00\",\"dateModified\":\"2015-11-25T11:40:40+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019 - Ayuntamiento de Ciempozuelos","description":"Se podr\u00e1 visitar hasta el d\u00eda 17 de diciembre El Ayuntamiento de Ciempozuelos, en colaboraci\u00f3n con la Comunidad de Madrid, presenta la exposici\u00f3n Red Itiner \u2018Mujeres modelo. Mujeres de moda\u2019 (1850-1940) que se puede visitar a partir de hoy, mi\u00e9rcoles 25 de noviembre, y hasta el d\u00eda 17 de diciembre en la Casa de la","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/#blogposting","name":"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019 - Ayuntamiento de Ciempozuelos","headline":"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-11-25T11:40:40+01:00","dateModified":"2015-11-25T11:40:40+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/#webpage"},"articleSection":"1139"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","position":2,"name":"1139","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/#listItem","name":"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/#listItem","position":3,"name":"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/","name":"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019 - Ayuntamiento de Ciempozuelos","description":"Se podr\u00e1 visitar hasta el d\u00eda 17 de diciembre El Ayuntamiento de Ciempozuelos, en colaboraci\u00f3n con la Comunidad de Madrid, presenta la exposici\u00f3n Red Itiner \u2018Mujeres modelo. Mujeres de moda\u2019 (1850-1940) que se puede visitar a partir de hoy, mi\u00e9rcoles 25 de noviembre, y hasta el d\u00eda 17 de diciembre en la Casa de la","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-11-25T11:40:40+01:00","dateModified":"2015-11-25T11:40:40+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019 - Ayuntamiento de Ciempozuelos","og:description":"Se podr\u00e1 visitar hasta el d\u00eda 17 de diciembre El Ayuntamiento de Ciempozuelos, en colaboraci\u00f3n con la Comunidad de Madrid, presenta la exposici\u00f3n Red Itiner \u2018Mujeres modelo. Mujeres de moda\u2019 (1850-1940) que se puede visitar a partir de hoy, mi\u00e9rcoles 25 de noviembre, y hasta el d\u00eda 17 de diciembre en la Casa de la","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/","article:published_time":"2015-11-25T11:40:40+00:00","article:modified_time":"2015-11-25T11:40:40+00:00","twitter:card":"summary","twitter:title":"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019 - Ayuntamiento de Ciempozuelos","twitter:description":"Se podr\u00e1 visitar hasta el d\u00eda 17 de diciembre El Ayuntamiento de Ciempozuelos, en colaboraci\u00f3n con la Comunidad de Madrid, presenta la exposici\u00f3n Red Itiner \u2018Mujeres modelo. Mujeres de moda\u2019 (1850-1940) que se puede visitar a partir de hoy, mi\u00e9rcoles 25 de noviembre, y hasta el d\u00eda 17 de diciembre en la Casa de la"},"aioseo_meta_data":{"post_id":"10655","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:06:56","updated":"2025-06-04 17:33:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/\" title=\"1139\">1139<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1139","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/"},{"label":"La Casa de la Cultura acoge la exposici\u00f3n \u2018Mujeres modelo. Mujeres de moda\u2019","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/25\/la-casa-de-la-cultura-acoge-la-exposicion-mujeres-modelo-mujeres-de-moda\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:50:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10655"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10655\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}