{"id":10621,"date":"2015-11-16T10:25:07","date_gmt":"2015-11-16T10:25:07","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/"},"modified":"2015-11-16T10:25:07","modified_gmt":"2015-11-16T10:25:07","slug":"voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/","title":{"rendered":"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><em>Los ganadores viajar\u00e1n al campamento de refugiados saharauis en Tindouf<\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La Asociaci\u00f3n \u2018Gdeim Izik\u2019 Ciempozuelos con el pueblo Saharaui ha dado a conocer el trabajo ganador del concurso de proyectos de cooperaci\u00f3n e intercambio cultural con el pueblo saharaui, organizado con la colaboracion de la Concejal\u00eda de Juventud del Ayuntamiento de Ciempozuelos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El proyecto ganador es \u2018Diferentes voces, diferentes etnias, mismo coraz\u00f3n\u2019, presentado por la asociaci\u00f3n juvenil de Ciempozuelos \u2018Voces para la convivencia\u2019. El jurado quiso resaltar un\u00e1nimemente el gran trabajo desarrollado, la vocaci\u00f3n integradora del mismo y la gran importancia que da al aspecto cultural de esta actividad de cooperaci\u00f3n.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Se realizar\u00e1n diversas actividades l\u00fadicas y culturales para autofinanciar el proyecto, que culminar\u00e1 con el viaje al campamento de refugiados saharauis en Tindouf, donde los ganadores participar\u00e1n en proyectos de cooperaci\u00f3n, disfrutar\u00e1n de un intercambio cultural con j\u00f3venes de la zona y vivir\u00e1n una experiencia \u00fanica y enriquecedora.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Por parte de la Asociaci\u00f3n \u2018Gdeim Izik\u2019 y del Ayuntamiento de Ciempozuelos se quiere agradecer el inter\u00e9s y participaci\u00f3n de los j\u00f3venes en este proyecto.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ganadores viajar\u00e1n al campamento de refugiados saharauis en Tindouf La Asociaci\u00f3n \u2018Gdeim Izik\u2019 Ciempozuelos con el pueblo Saharaui ha dado a conocer el trabajo ganador del concurso de proyectos de cooperaci\u00f3n e intercambio cultural con el pueblo saharaui, organizado con la colaboracion de la Concejal\u00eda de Juventud del Ayuntamiento de Ciempozuelos. El proyecto ganador [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1227],"class_list":["post-10621","post","type-post","status-publish","format-standard","hentry","tag-infancia-y-juventud"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los ganadores viajar\u00e1n al campamento de refugiados saharauis en Tindouf La Asociaci\u00f3n \u2018Gdeim Izik\u2019 Ciempozuelos con el pueblo Saharaui ha dado a conocer el trabajo ganador del concurso de proyectos de cooperaci\u00f3n e intercambio cultural con el pueblo saharaui, organizado con la colaboracion de la Concejal\u00eda de Juventud del Ayuntamiento de Ciempozuelos. El proyecto ganador\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Los ganadores viajar\u00e1n al campamento de refugiados saharauis en Tindouf La Asociaci\u00f3n \u2018Gdeim Izik\u2019 Ciempozuelos con el pueblo Saharaui ha dado a conocer el trabajo ganador del concurso de proyectos de cooperaci\u00f3n e intercambio cultural con el pueblo saharaui, organizado con la colaboracion de la Concejal\u00eda de Juventud del Ayuntamiento de Ciempozuelos. El proyecto ganador\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-11-16T10:25:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-11-16T10:25:07+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los ganadores viajar\u00e1n al campamento de refugiados saharauis en Tindouf La Asociaci\u00f3n \u2018Gdeim Izik\u2019 Ciempozuelos con el pueblo Saharaui ha dado a conocer el trabajo ganador del concurso de proyectos de cooperaci\u00f3n e intercambio cultural con el pueblo saharaui, organizado con la colaboracion de la Concejal\u00eda de Juventud del Ayuntamiento de Ciempozuelos. El proyecto ganador\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/16\\\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\\\/#blogposting\",\"name\":\"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\\u00f3n e intercambio con el pueblo saharaui - Ayuntamiento de Ciempozuelos\",\"headline\":\"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\\u00f3n e intercambio con el pueblo saharaui\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-11-16T10:25:07+01:00\",\"dateModified\":\"2015-11-16T10:25:07+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/16\\\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/16\\\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\\\/#webpage\"},\"articleSection\":\"Infancia y Juventud\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/16\\\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/infancia-y-juventud\\\/#listItem\",\"name\":\"Infancia y Juventud\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/infancia-y-juventud\\\/#listItem\",\"position\":2,\"name\":\"Infancia y Juventud\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/infancia-y-juventud\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/16\\\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\\\/#listItem\",\"name\":\"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\\u00f3n e intercambio con el pueblo saharaui\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/16\\\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\\\/#listItem\",\"position\":3,\"name\":\"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\\u00f3n e intercambio con el pueblo saharaui\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/infancia-y-juventud\\\/#listItem\",\"name\":\"Infancia y Juventud\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/16\\\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/16\\\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/16\\\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\\\/\",\"name\":\"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\\u00f3n e intercambio con el pueblo saharaui - Ayuntamiento de Ciempozuelos\",\"description\":\"Los ganadores viajar\\u00e1n al campamento de refugiados saharauis en Tindouf La Asociaci\\u00f3n \\u2018Gdeim Izik\\u2019 Ciempozuelos con el pueblo Saharaui ha dado a conocer el trabajo ganador del concurso de proyectos de cooperaci\\u00f3n e intercambio cultural con el pueblo saharaui, organizado con la colaboracion de la Concejal\\u00eda de Juventud del Ayuntamiento de Ciempozuelos. El proyecto ganador\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/16\\\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-11-16T10:25:07+01:00\",\"dateModified\":\"2015-11-16T10:25:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui - Ayuntamiento de Ciempozuelos","description":"Los ganadores viajar\u00e1n al campamento de refugiados saharauis en Tindouf La Asociaci\u00f3n \u2018Gdeim Izik\u2019 Ciempozuelos con el pueblo Saharaui ha dado a conocer el trabajo ganador del concurso de proyectos de cooperaci\u00f3n e intercambio cultural con el pueblo saharaui, organizado con la colaboracion de la Concejal\u00eda de Juventud del Ayuntamiento de Ciempozuelos. El proyecto ganador","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/#blogposting","name":"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui - Ayuntamiento de Ciempozuelos","headline":"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-11-16T10:25:07+01:00","dateModified":"2015-11-16T10:25:07+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/#webpage"},"articleSection":"Infancia y Juventud"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/infancia-y-juventud\/#listItem","name":"Infancia y Juventud"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/infancia-y-juventud\/#listItem","position":2,"name":"Infancia y Juventud","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/infancia-y-juventud\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/#listItem","name":"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/#listItem","position":3,"name":"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/infancia-y-juventud\/#listItem","name":"Infancia y Juventud"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/","name":"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui - Ayuntamiento de Ciempozuelos","description":"Los ganadores viajar\u00e1n al campamento de refugiados saharauis en Tindouf La Asociaci\u00f3n \u2018Gdeim Izik\u2019 Ciempozuelos con el pueblo Saharaui ha dado a conocer el trabajo ganador del concurso de proyectos de cooperaci\u00f3n e intercambio cultural con el pueblo saharaui, organizado con la colaboracion de la Concejal\u00eda de Juventud del Ayuntamiento de Ciempozuelos. El proyecto ganador","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-11-16T10:25:07+01:00","dateModified":"2015-11-16T10:25:07+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui - Ayuntamiento de Ciempozuelos","og:description":"Los ganadores viajar\u00e1n al campamento de refugiados saharauis en Tindouf La Asociaci\u00f3n \u2018Gdeim Izik\u2019 Ciempozuelos con el pueblo Saharaui ha dado a conocer el trabajo ganador del concurso de proyectos de cooperaci\u00f3n e intercambio cultural con el pueblo saharaui, organizado con la colaboracion de la Concejal\u00eda de Juventud del Ayuntamiento de Ciempozuelos. El proyecto ganador","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/","article:published_time":"2015-11-16T10:25:07+00:00","article:modified_time":"2015-11-16T10:25:07+00:00","twitter:card":"summary","twitter:title":"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui - Ayuntamiento de Ciempozuelos","twitter:description":"Los ganadores viajar\u00e1n al campamento de refugiados saharauis en Tindouf La Asociaci\u00f3n \u2018Gdeim Izik\u2019 Ciempozuelos con el pueblo Saharaui ha dado a conocer el trabajo ganador del concurso de proyectos de cooperaci\u00f3n e intercambio cultural con el pueblo saharaui, organizado con la colaboracion de la Concejal\u00eda de Juventud del Ayuntamiento de Ciempozuelos. El proyecto ganador"},"aioseo_meta_data":{"post_id":"10621","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 15:02:55","updated":"2025-06-04 17:29:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/infancia-y-juventud\/\" title=\"Infancia y Juventud\">Infancia y Juventud<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVoces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Infancia y Juventud","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/infancia-y-juventud\/"},{"label":"Voces para la Convivencia, ganadores del concurso de proyectos de cooperaci\u00f3n e intercambio con el pueblo saharaui","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/16\/voces-para-la-convivencia-ganadores-del-concurso-de-proyectos-de-cooperacion-e-intercambio-con-el-pueblo-saharaui-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:56:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10621"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10621\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}