{"id":10544,"date":"2015-10-30T13:10:07","date_gmt":"2015-10-30T13:10:07","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/"},"modified":"2015-10-30T13:10:07","modified_gmt":"2015-10-30T13:10:07","slug":"la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/","title":{"rendered":"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><em>Adem\u00e1s, se acord\u00f3 un convenio de colaboraci\u00f3n en materia de atenci\u00f3n primaria, autonom\u00eda personal y atenci\u00f3n a personas dependientes <\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La Mancomunidad Intermunicipal de Servicios Sociales \u2018Las Vegas\u2019 convoc\u00f3 el pasado martes 27 de octubre una sesi\u00f3n plenaria de car\u00e1cter extraordinario que tuvo lugar en el Sal\u00f3n de Plenos del Ayuntamiento de Morata de Taju\u00f1a. En el orden del d\u00eda figuraba la aprobaci\u00f3n de la propuesta para un convenio de colaboraci\u00f3n de lucha contra la pobreza infantil para 2015.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El objetivo de este convenio es regular la cooperaci\u00f3n entre la Mancomunidad y la Comunidad de Madrid para regular la cooperaci\u00f3n en la puesta en marcha de proyectos tendentes a la lucha contra la pobreza infantil en el marco de las actuaciones contra la exclusi\u00f3n social.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">Con este convenio, ambas entidades expresan su acuerdo para reforzar las actuaciones conjuntas de planificaci\u00f3n del sistema p\u00fablico para mejorar la calidad en la atenci\u00f3n a los ciudadanos.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">El coste del proyecto ser\u00e1 de 27.410,58 euros y est\u00e1 financiado de forma \u00edntegra por la Comunidad de Madrid.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">Otro punto destacado del orden del d\u00eda fue la aprobaci\u00f3n de la pr\u00f3rroga del convenio de atenci\u00f3n social primaria, promoci\u00f3n de la autonom\u00eda personal y atenci\u00f3n a las personas en situaci\u00f3n de dependencia para el a\u00f1o 2016. Este convenio fue suscrito en diciembre de 2014 y prorrogado para el a\u00f1o 2015. Con este acuerdo se ampl\u00eda su vigencia para el periodo comprendido entre el uno de enero y el 31 de diciembre de 2016.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s, se acord\u00f3 un convenio de colaboraci\u00f3n en materia de atenci\u00f3n primaria, autonom\u00eda personal y atenci\u00f3n a personas dependientes La Mancomunidad Intermunicipal de Servicios Sociales \u2018Las Vegas\u2019 convoc\u00f3 el pasado martes 27 de octubre una sesi\u00f3n plenaria de car\u00e1cter extraordinario que tuvo lugar en el Sal\u00f3n de Plenos del Ayuntamiento de Morata de Taju\u00f1a. En [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1213],"class_list":["post-10544","post","type-post","status-publish","format-standard","hentry","tag-servicios-sociales"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Adem\u00e1s, se acord\u00f3 un convenio de colaboraci\u00f3n en materia de atenci\u00f3n primaria, autonom\u00eda personal y atenci\u00f3n a personas dependientes La Mancomunidad Intermunicipal de Servicios Sociales \u2018Las Vegas\u2019 convoc\u00f3 el pasado martes 27 de octubre una sesi\u00f3n plenaria de car\u00e1cter extraordinario que tuvo lugar en el Sal\u00f3n de Plenos del Ayuntamiento de Morata de Taju\u00f1a. En\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Adem\u00e1s, se acord\u00f3 un convenio de colaboraci\u00f3n en materia de atenci\u00f3n primaria, autonom\u00eda personal y atenci\u00f3n a personas dependientes La Mancomunidad Intermunicipal de Servicios Sociales \u2018Las Vegas\u2019 convoc\u00f3 el pasado martes 27 de octubre una sesi\u00f3n plenaria de car\u00e1cter extraordinario que tuvo lugar en el Sal\u00f3n de Plenos del Ayuntamiento de Morata de Taju\u00f1a. En\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-10-30T13:10:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-10-30T13:10:07+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Adem\u00e1s, se acord\u00f3 un convenio de colaboraci\u00f3n en materia de atenci\u00f3n primaria, autonom\u00eda personal y atenci\u00f3n a personas dependientes La Mancomunidad Intermunicipal de Servicios Sociales \u2018Las Vegas\u2019 convoc\u00f3 el pasado martes 27 de octubre una sesi\u00f3n plenaria de car\u00e1cter extraordinario que tuvo lugar en el Sal\u00f3n de Plenos del Ayuntamiento de Morata de Taju\u00f1a. En\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\\\/#blogposting\",\"name\":\"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil - Ayuntamiento de Ciempozuelos\",\"headline\":\"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-10-30T13:10:07+01:00\",\"dateModified\":\"2015-10-30T13:10:07+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\\\/#webpage\"},\"articleSection\":\"Servicios Sociales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales\\\/#listItem\",\"name\":\"Servicios Sociales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales\\\/#listItem\",\"position\":2,\"name\":\"Servicios Sociales\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\\\/#listItem\",\"name\":\"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\\\/#listItem\",\"position\":3,\"name\":\"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/servicios-sociales\\\/#listItem\",\"name\":\"Servicios Sociales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\\\/\",\"name\":\"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil - Ayuntamiento de Ciempozuelos\",\"description\":\"Adem\\u00e1s, se acord\\u00f3 un convenio de colaboraci\\u00f3n en materia de atenci\\u00f3n primaria, autonom\\u00eda personal y atenci\\u00f3n a personas dependientes La Mancomunidad Intermunicipal de Servicios Sociales \\u2018Las Vegas\\u2019 convoc\\u00f3 el pasado martes 27 de octubre una sesi\\u00f3n plenaria de car\\u00e1cter extraordinario que tuvo lugar en el Sal\\u00f3n de Plenos del Ayuntamiento de Morata de Taju\\u00f1a. En\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-10-30T13:10:07+01:00\",\"dateModified\":\"2015-10-30T13:10:07+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil - Ayuntamiento de Ciempozuelos","description":"Adem\u00e1s, se acord\u00f3 un convenio de colaboraci\u00f3n en materia de atenci\u00f3n primaria, autonom\u00eda personal y atenci\u00f3n a personas dependientes La Mancomunidad Intermunicipal de Servicios Sociales \u2018Las Vegas\u2019 convoc\u00f3 el pasado martes 27 de octubre una sesi\u00f3n plenaria de car\u00e1cter extraordinario que tuvo lugar en el Sal\u00f3n de Plenos del Ayuntamiento de Morata de Taju\u00f1a. En","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/#blogposting","name":"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil - Ayuntamiento de Ciempozuelos","headline":"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-10-30T13:10:07+01:00","dateModified":"2015-10-30T13:10:07+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/#webpage"},"articleSection":"Servicios Sociales"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/#listItem","name":"Servicios Sociales"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/#listItem","position":2,"name":"Servicios Sociales","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/#listItem","name":"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/#listItem","position":3,"name":"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/#listItem","name":"Servicios Sociales"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/","name":"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil - Ayuntamiento de Ciempozuelos","description":"Adem\u00e1s, se acord\u00f3 un convenio de colaboraci\u00f3n en materia de atenci\u00f3n primaria, autonom\u00eda personal y atenci\u00f3n a personas dependientes La Mancomunidad Intermunicipal de Servicios Sociales \u2018Las Vegas\u2019 convoc\u00f3 el pasado martes 27 de octubre una sesi\u00f3n plenaria de car\u00e1cter extraordinario que tuvo lugar en el Sal\u00f3n de Plenos del Ayuntamiento de Morata de Taju\u00f1a. En","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-10-30T13:10:07+01:00","dateModified":"2015-10-30T13:10:07+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil - Ayuntamiento de Ciempozuelos","og:description":"Adem\u00e1s, se acord\u00f3 un convenio de colaboraci\u00f3n en materia de atenci\u00f3n primaria, autonom\u00eda personal y atenci\u00f3n a personas dependientes La Mancomunidad Intermunicipal de Servicios Sociales \u2018Las Vegas\u2019 convoc\u00f3 el pasado martes 27 de octubre una sesi\u00f3n plenaria de car\u00e1cter extraordinario que tuvo lugar en el Sal\u00f3n de Plenos del Ayuntamiento de Morata de Taju\u00f1a. En","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/","article:published_time":"2015-10-30T13:10:07+00:00","article:modified_time":"2015-10-30T13:10:07+00:00","twitter:card":"summary","twitter:title":"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil - Ayuntamiento de Ciempozuelos","twitter:description":"Adem\u00e1s, se acord\u00f3 un convenio de colaboraci\u00f3n en materia de atenci\u00f3n primaria, autonom\u00eda personal y atenci\u00f3n a personas dependientes La Mancomunidad Intermunicipal de Servicios Sociales \u2018Las Vegas\u2019 convoc\u00f3 el pasado martes 27 de octubre una sesi\u00f3n plenaria de car\u00e1cter extraordinario que tuvo lugar en el Sal\u00f3n de Plenos del Ayuntamiento de Morata de Taju\u00f1a. En"},"aioseo_meta_data":{"post_id":"10544","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:56:55","updated":"2025-06-04 17:23:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/\" title=\"Servicios Sociales\">Servicios Sociales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Servicios Sociales","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/servicios-sociales\/"},{"label":"La Mancomunidad de Servicios Sociales aprueba un plan contra la pobreza infantil","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-mancomunidad-de-servicios-sociales-aprueba-un-plan-contra-la-pobreza-infantil\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:57:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10544"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10544\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}