{"id":10542,"date":"2015-10-30T11:19:26","date_gmt":"2015-10-30T11:19:26","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/"},"modified":"2015-10-30T11:19:26","modified_gmt":"2015-10-30T11:19:26","slug":"la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/","title":{"rendered":"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><em>El pleno comenz\u00f3 con un minuto de silencio en memoria de los dos fallecidos recientemente en Ciempozuelos<\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El Ayuntamiento de Ciempozuelos celebr\u00f3 ayer a las 20.00 horas la sesi\u00f3n plenaria de car\u00e1cter ordinaria del mes de octubre en la que se aprobaron todos los puntos que figuraban en el Orden del D\u00eda, a excepci\u00f3n del primer punto que fue retirado y la desestimaci\u00f3n de la moci\u00f3n presentada por el Partido Popular.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El pleno se abri\u00f3 con un minuto de silencio en memoria del miembro de la PAH de Ciempozuelos y del trabajador fallecido en accidente laboral. El primer punto, la aprobaci\u00f3n del acta de la sesi\u00f3n extraordinaria del 13\/08, fue retirado por unanimidad al contener defectos de redacci\u00f3n. El segundo punto referente a la aprobaci\u00f3n del acta con correcciones de la sesi\u00f3n ordinaria con fecha 30\/09 fue aprobado con 15 votos a favor y 4 abstenciones.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Con 14 votos afirmativos y 4 negativos se aprob\u00f3 el dictamen emitido por la C.I. Municipio Sostenible con fecha 19\/10 referente a la devoluci\u00f3n de avales del PGOU de Ciempozuelos. A su vez tambi\u00e9n se aprob\u00f3 por 13 votos afirmativos, 4 negativos y 2 abstenciones el cuarto punto referente al dictamen emitido por la C.I. de Hacienda el d\u00eda 19\/10 en relaci\u00f3n a las nuevas altas de actuaci\u00f3n del Plan Prisma 2008-2011. Tras la inclusi\u00f3n de una enmienda por parte del PSOE del punto 5, relativo a la modificaci\u00f3n del IBI, y la desestimaci\u00f3n de la enmienda de CPC y PIC, fue aprobado por 11 votos a favor y 8 en contra.<\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">Se aprob\u00f3 por unanimidad la concesi\u00f3n de subvenciones como premios en el II Concurso de C\u00f3mic Ilustrado \u2018Villa de Ciempozuelos\u2019 y el II Concurso de marcap\u00e1ginas Navide\u00f1os \u2018Villa de Ciempozuelos\u2019. Tambi\u00e9n fue un\u00e1nime la aprobaci\u00f3n de los anexos de los convenios suscritos con los centros educativos para ayudas de libros y material escolar.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El grupo popular present\u00f3 una moci\u00f3n que solicitaba informaci\u00f3n respecto a la estrategia jur\u00eddica seguida por parte del Ayuntamiento en relaci\u00f3n con el ere de la Escuela de M\u00fasica y Danza. La moci\u00f3n fue desestimada con 4 votos afirmativos, 13 negativos y 2 abstenciones. La moci\u00f3n presentada por todos los grupos en relaci\u00f3n al plan Prisma y su renovaci\u00f3n para los a\u00f1os 2015-2019 fue aprobada por unanimidad.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Por \u00faltimo, los grupos municipales plantearon varios ruegos y se contestaron verbalmente distintas preguntas y otras se emplazaron a una respuesta por escrito por parte del equipo de gobierno.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pleno comenz\u00f3 con un minuto de silencio en memoria de los dos fallecidos recientemente en Ciempozuelos El Ayuntamiento de Ciempozuelos celebr\u00f3 ayer a las 20.00 horas la sesi\u00f3n plenaria de car\u00e1cter ordinaria del mes de octubre en la que se aprobaron todos los puntos que figuraban en el Orden del D\u00eda, a excepci\u00f3n del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1235],"class_list":["post-10542","post","type-post","status-publish","format-standard","hentry","tag-1235"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El pleno comenz\u00f3 con un minuto de silencio en memoria de los dos fallecidos recientemente en Ciempozuelos El Ayuntamiento de Ciempozuelos celebr\u00f3 ayer a las 20.00 horas la sesi\u00f3n plenaria de car\u00e1cter ordinaria del mes de octubre en la que se aprobaron todos los puntos que figuraban en el Orden del D\u00eda, a excepci\u00f3n del\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El pleno comenz\u00f3 con un minuto de silencio en memoria de los dos fallecidos recientemente en Ciempozuelos El Ayuntamiento de Ciempozuelos celebr\u00f3 ayer a las 20.00 horas la sesi\u00f3n plenaria de car\u00e1cter ordinaria del mes de octubre en la que se aprobaron todos los puntos que figuraban en el Orden del D\u00eda, a excepci\u00f3n del\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-10-30T11:19:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-10-30T11:19:26+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El pleno comenz\u00f3 con un minuto de silencio en memoria de los dos fallecidos recientemente en Ciempozuelos El Ayuntamiento de Ciempozuelos celebr\u00f3 ayer a las 20.00 horas la sesi\u00f3n plenaria de car\u00e1cter ordinaria del mes de octubre en la que se aprobaron todos los puntos que figuraban en el Orden del D\u00eda, a excepci\u00f3n del\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\\\/#blogposting\",\"name\":\"La corporaci\\u00f3n municipal celebra el pleno ordinario de octubre - Ayuntamiento de Ciempozuelos\",\"headline\":\"La corporaci\\u00f3n municipal celebra el pleno ordinario de octubre\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-10-30T11:19:26+01:00\",\"dateModified\":\"2015-10-30T11:19:26+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\\\/#webpage\"},\"articleSection\":\"1118\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1118\\\/#listItem\",\"name\":\"1118\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1118\\\/#listItem\",\"position\":2,\"name\":\"1118\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1118\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\\\/#listItem\",\"name\":\"La corporaci\\u00f3n municipal celebra el pleno ordinario de octubre\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\\\/#listItem\",\"position\":3,\"name\":\"La corporaci\\u00f3n municipal celebra el pleno ordinario de octubre\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1118\\\/#listItem\",\"name\":\"1118\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\\\/\",\"name\":\"La corporaci\\u00f3n municipal celebra el pleno ordinario de octubre - Ayuntamiento de Ciempozuelos\",\"description\":\"El pleno comenz\\u00f3 con un minuto de silencio en memoria de los dos fallecidos recientemente en Ciempozuelos El Ayuntamiento de Ciempozuelos celebr\\u00f3 ayer a las 20.00 horas la sesi\\u00f3n plenaria de car\\u00e1cter ordinaria del mes de octubre en la que se aprobaron todos los puntos que figuraban en el Orden del D\\u00eda, a excepci\\u00f3n del\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/30\\\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-10-30T11:19:26+01:00\",\"dateModified\":\"2015-10-30T11:19:26+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre - Ayuntamiento de Ciempozuelos","description":"El pleno comenz\u00f3 con un minuto de silencio en memoria de los dos fallecidos recientemente en Ciempozuelos El Ayuntamiento de Ciempozuelos celebr\u00f3 ayer a las 20.00 horas la sesi\u00f3n plenaria de car\u00e1cter ordinaria del mes de octubre en la que se aprobaron todos los puntos que figuraban en el Orden del D\u00eda, a excepci\u00f3n del","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/#blogposting","name":"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre - Ayuntamiento de Ciempozuelos","headline":"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-10-30T11:19:26+01:00","dateModified":"2015-10-30T11:19:26+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/#webpage"},"articleSection":"1118"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/#listItem","name":"1118"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/#listItem","position":2,"name":"1118","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/#listItem","name":"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/#listItem","position":3,"name":"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/#listItem","name":"1118"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/","name":"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre - Ayuntamiento de Ciempozuelos","description":"El pleno comenz\u00f3 con un minuto de silencio en memoria de los dos fallecidos recientemente en Ciempozuelos El Ayuntamiento de Ciempozuelos celebr\u00f3 ayer a las 20.00 horas la sesi\u00f3n plenaria de car\u00e1cter ordinaria del mes de octubre en la que se aprobaron todos los puntos que figuraban en el Orden del D\u00eda, a excepci\u00f3n del","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-10-30T11:19:26+01:00","dateModified":"2015-10-30T11:19:26+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre - Ayuntamiento de Ciempozuelos","og:description":"El pleno comenz\u00f3 con un minuto de silencio en memoria de los dos fallecidos recientemente en Ciempozuelos El Ayuntamiento de Ciempozuelos celebr\u00f3 ayer a las 20.00 horas la sesi\u00f3n plenaria de car\u00e1cter ordinaria del mes de octubre en la que se aprobaron todos los puntos que figuraban en el Orden del D\u00eda, a excepci\u00f3n del","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/","article:published_time":"2015-10-30T11:19:26+00:00","article:modified_time":"2015-10-30T11:19:26+00:00","twitter:card":"summary","twitter:title":"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre - Ayuntamiento de Ciempozuelos","twitter:description":"El pleno comenz\u00f3 con un minuto de silencio en memoria de los dos fallecidos recientemente en Ciempozuelos El Ayuntamiento de Ciempozuelos celebr\u00f3 ayer a las 20.00 horas la sesi\u00f3n plenaria de car\u00e1cter ordinaria del mes de octubre en la que se aprobaron todos los puntos que figuraban en el Orden del D\u00eda, a excepci\u00f3n del"},"aioseo_meta_data":{"post_id":"10542","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:56:55","updated":"2025-06-04 17:23:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/\" title=\"1118\">1118<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa corporaci\u00f3n municipal celebra el pleno ordinario de octubre\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1118","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/"},{"label":"La corporaci\u00f3n municipal celebra el pleno ordinario de octubre","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/30\/la-corporacion-municipal-celebra-el-pleno-ordinario-de-octubre\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:51:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10542"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10542\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}