{"id":10541,"date":"2015-10-29T12:09:12","date_gmt":"2015-10-29T12:09:12","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/"},"modified":"2015-10-29T12:09:12","modified_gmt":"2015-10-29T12:09:12","slug":"arranca-el-noviembre-cultural-4","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/","title":{"rendered":"Arranca el Noviembre cultural"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><em>La Semana de la Ciencia y el Mercado de Trueque destacan en la programaci\u00f3n de este mes<\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Bajo el t\u00edtulo \u2018Noviembre cultural\u2019, el Ayuntamiento de Ciempozuelos presenta la programaci\u00f3n para el mes de noviembre para acercar la cultura de forma gratuita a todos los vecinos de nuestro municipio a trav\u00e9s de actividades de distintos campos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Del 2 al 13 de noviembre se celebrar\u00e1 la Semana de la Ciencia. Enmarcada en esta iniciativa, la asociaci\u00f3n Amigos de la Historia de Ciempozuelos y sus Salinas y la asociaci\u00f3n La Torre, con el patrocinio del Consistorio, organizan la exposici\u00f3n \u2018La vega, el secano, los cerros: Historia de la ciencia en paisajes cercanos\u2019 que podr\u00e1 visitarse en la Casa de la Cultura (c\/Mayor) de lunes a viernes de 10.00 a 14.00 y de 17.00 a 20.00 horas. Otra de las actividades programadas dentro de esta semana es la charla \u2018Las Salinas Espartinas: la vulnerabilidad de un espacio protegido\u2019 que impartir\u00e1 Daniel Carvajal el s\u00e1bado 7 de noviembre a las 12.00 horas tambi\u00e9n la Casa de la Cultura.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El viernes 6 a las 19.00 horas en la Biblioteca Municipal, la autora local Merche Diolch presentar\u00e1 su libro \u2018Encrucijada\u2019 y el cine llegar\u00e1 para toda la familia en forma de cortometrajes el domingo 8 con el Ciclo de Cortos infantiles de CortoEspa\u00f1a que tendr\u00e1 lugar en la Sala Multifuncional a las 18.00 horas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El s\u00e1bado 14 y el domingo 15 la plaza Ventura Rodr\u00edguez de 11.00 a 21.00 horas ser\u00e1 el escenario del Mercado de Trueque, segunda mano, artesan\u00eda local y solidaridad. Aquellos que est\u00e9n interesados deber\u00e1n enviar un email a <\/span><a href=\"mailto:comercios@ayto-ciempozuelos.org\" style=\"font-size: 12.16px; line-height: 1.3em;\">mercados@ayto-ciempozuelos.org<\/a><span style=\"font-size: 12.16px; line-height: 15.808px;\">. Para los puestos de <\/span><span style=\"font-size: 12.16px; line-height: 15.808px;\">Artesan\u00eda o Solidaridad<\/span><span style=\"font-size: 12.16px; line-height: 15.808px;\"> en el email deber\u00e1 incluirse informaci\u00f3n <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">con el tama\u00f1o de la mesa que quieran colocar, el objeto de la asociaci\u00f3n\/cooperaci\u00f3n, el tipo de puesto y la fecha en la que quieren estar presentes en el mercado. En el caso de los puestos de trueque y segunda mano no ser\u00e1 necesario ya que el Ayuntamiento pone a disposici\u00f3n de los interesados las mesas correspondientes.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Las exposiciones continuar\u00e1n en Ciempozuelos con la muestra fotogr\u00e1fica de David Afonte que se podr\u00e1 visitar del lunes 16 al viernes 27 en la sala de exposiciones de la Biblioteca Municipal en horario de<\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">lunes a viernes de 10.00 a 14.00 y de 17.00 a 20.00 horas. <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">Del 25 al 17 de noviembre ser\u00e1 el turno para exposici\u00f3n Red Itiner \u2018Mujeres modelo. Mujeres de moda\u2019 (1850-1940) situada en la Casa de la Cultura en horario de lunes a viernes de 10.30 a 13.30 horas y de 17.30 a 20.00 horas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">Con motivo de la festividad de Santa Cecilia, patrona de la m\u00fasica, el s\u00e1bado 21 podremos disfrutar de un concierto de la Banda de M\u00fasica de Ciempozuelos en la Sala Multifuncional a las 19.00 horas. Al d\u00eda siguiente, el domingo, est\u00e1 programado un concierto did\u00e1ctico de Ars Combinatoria a las 18.00 horas tambi\u00e9n en la Sala Multifuncional.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">El \u00faltimo fin de semana de noviembre arrancar\u00e1 con flamenco de la mano de Casa Guar\u00edn. En la tertulia flamenca, presentada por Javier Brice\u00f1o, actuar\u00e1n Paco M\u00e1rquez, el Peque, Juan de Badajoz, Casi Vioque, Mame Rinc\u00f3n, Andr\u00e9s S\u00e1nchez, Mar\u00eda Revuelta, Montse, Irene Reyes. La cita tendr\u00e1 lugar en la Sala Multifuncional a las 21.00 horas.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">El cine cierra la programaci\u00f3n cultural el domingo 29 a las 18.00 horas en la Sala Multifuncional con el ciclo de Cortos infantiles de CortoEspa\u00f1a. En esta jornada se proyectar\u00e1 el corto del taller de los Veranos Culturales \u2018C\u00f3mo hacer un corto\u2019, organizado por la asociaci\u00f3n Cinephiles.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">El mes de noviembre tambi\u00e9n acoger\u00e1 la segunda edici\u00f3n del Concurso de c\u00f3mic ilustrado \u2018Villa de Ciempozuelos\u2019.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><em style=\"font-size: 12.16px; line-height: 15.808px;\"><img decoding=\"async\" class=\" size-full wp-image-10537\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-scaled.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-200x283.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-212x300.jpg 212w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-400x566.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-600x849.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-724x1024.jpg 724w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-768x1086.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-800x1132.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-1086x1536.jpg 1086w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-1200x1697.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-1448x2048.jpg 1448w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-scaled.jpg 1810w\" sizes=\"(max-width: 1810px) 100vw, 1810px\" \/><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Semana de la Ciencia y el Mercado de Trueque destacan en la programaci\u00f3n de este mes Bajo el t\u00edtulo \u2018Noviembre cultural\u2019, el Ayuntamiento de Ciempozuelos presenta la programaci\u00f3n para el mes de noviembre para acercar la cultura de forma gratuita a todos los vecinos de nuestro municipio a trav\u00e9s de actividades de distintos campos. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1070],"class_list":["post-10541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-actividades-culturales-del-mes"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Semana de la Ciencia y el Mercado de Trueque destacan en la programaci\u00f3n de este mes Bajo el t\u00edtulo \u2018Noviembre cultural\u2019, el Ayuntamiento de Ciempozuelos presenta la programaci\u00f3n para el mes de noviembre para acercar la cultura de forma gratuita a todos los vecinos de nuestro municipio a trav\u00e9s de actividades de distintos campos.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Arranca el Noviembre cultural - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La Semana de la Ciencia y el Mercado de Trueque destacan en la programaci\u00f3n de este mes Bajo el t\u00edtulo \u2018Noviembre cultural\u2019, el Ayuntamiento de Ciempozuelos presenta la programaci\u00f3n para el mes de noviembre para acercar la cultura de forma gratuita a todos los vecinos de nuestro municipio a trav\u00e9s de actividades de distintos campos.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-10-29T12:09:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-10-29T12:09:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Arranca el Noviembre cultural - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Semana de la Ciencia y el Mercado de Trueque destacan en la programaci\u00f3n de este mes Bajo el t\u00edtulo \u2018Noviembre cultural\u2019, el Ayuntamiento de Ciempozuelos presenta la programaci\u00f3n para el mes de noviembre para acercar la cultura de forma gratuita a todos los vecinos de nuestro municipio a trav\u00e9s de actividades de distintos campos.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/#blogposting\",\"name\":\"Arranca el Noviembre cultural - Ayuntamiento de Ciempozuelos\",\"headline\":\"Arranca el Noviembre cultural\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/noviembre-cultura2-copia-scaled.jpg\",\"width\":1810,\"height\":2560},\"datePublished\":\"2015-10-29T12:09:12+01:00\",\"dateModified\":\"2015-10-29T12:09:12+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/#webpage\"},\"articleSection\":\"Actividades culturales del mes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/#listItem\",\"name\":\"Actividades culturales del mes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/#listItem\",\"position\":2,\"name\":\"Actividades culturales del mes\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/#listItem\",\"name\":\"Arranca el Noviembre cultural\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/#listItem\",\"position\":3,\"name\":\"Arranca el Noviembre cultural\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-culturales-del-mes\\\/#listItem\",\"name\":\"Actividades culturales del mes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/\",\"name\":\"Arranca el Noviembre cultural - Ayuntamiento de Ciempozuelos\",\"description\":\"La Semana de la Ciencia y el Mercado de Trueque destacan en la programaci\\u00f3n de este mes Bajo el t\\u00edtulo \\u2018Noviembre cultural\\u2019, el Ayuntamiento de Ciempozuelos presenta la programaci\\u00f3n para el mes de noviembre para acercar la cultura de forma gratuita a todos los vecinos de nuestro municipio a trav\\u00e9s de actividades de distintos campos.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/noviembre-cultura2-copia-scaled.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/#mainImage\",\"width\":1810,\"height\":2560},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/29\\\/arranca-el-noviembre-cultural-4\\\/#mainImage\"},\"datePublished\":\"2015-10-29T12:09:12+01:00\",\"dateModified\":\"2015-10-29T12:09:12+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Arranca el Noviembre cultural - Ayuntamiento de Ciempozuelos","description":"La Semana de la Ciencia y el Mercado de Trueque destacan en la programaci\u00f3n de este mes Bajo el t\u00edtulo \u2018Noviembre cultural\u2019, el Ayuntamiento de Ciempozuelos presenta la programaci\u00f3n para el mes de noviembre para acercar la cultura de forma gratuita a todos los vecinos de nuestro municipio a trav\u00e9s de actividades de distintos campos.","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/#blogposting","name":"Arranca el Noviembre cultural - Ayuntamiento de Ciempozuelos","headline":"Arranca el Noviembre cultural","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-scaled.jpg","width":1810,"height":2560},"datePublished":"2015-10-29T12:09:12+01:00","dateModified":"2015-10-29T12:09:12+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/#webpage"},"articleSection":"Actividades culturales del mes"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/#listItem","name":"Actividades culturales del mes"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/#listItem","position":2,"name":"Actividades culturales del mes","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/#listItem","name":"Arranca el Noviembre cultural"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/#listItem","position":3,"name":"Arranca el Noviembre cultural","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/#listItem","name":"Actividades culturales del mes"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/","name":"Arranca el Noviembre cultural - Ayuntamiento de Ciempozuelos","description":"La Semana de la Ciencia y el Mercado de Trueque destacan en la programaci\u00f3n de este mes Bajo el t\u00edtulo \u2018Noviembre cultural\u2019, el Ayuntamiento de Ciempozuelos presenta la programaci\u00f3n para el mes de noviembre para acercar la cultura de forma gratuita a todos los vecinos de nuestro municipio a trav\u00e9s de actividades de distintos campos.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/noviembre-cultura2-copia-scaled.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/#mainImage","width":1810,"height":2560},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/#mainImage"},"datePublished":"2015-10-29T12:09:12+01:00","dateModified":"2015-10-29T12:09:12+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Arranca el Noviembre cultural - Ayuntamiento de Ciempozuelos","og:description":"La Semana de la Ciencia y el Mercado de Trueque destacan en la programaci\u00f3n de este mes Bajo el t\u00edtulo \u2018Noviembre cultural\u2019, el Ayuntamiento de Ciempozuelos presenta la programaci\u00f3n para el mes de noviembre para acercar la cultura de forma gratuita a todos los vecinos de nuestro municipio a trav\u00e9s de actividades de distintos campos.","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/","article:published_time":"2015-10-29T12:09:12+00:00","article:modified_time":"2015-10-29T12:09:12+00:00","twitter:card":"summary","twitter:title":"Arranca el Noviembre cultural - Ayuntamiento de Ciempozuelos","twitter:description":"La Semana de la Ciencia y el Mercado de Trueque destacan en la programaci\u00f3n de este mes Bajo el t\u00edtulo \u2018Noviembre cultural\u2019, el Ayuntamiento de Ciempozuelos presenta la programaci\u00f3n para el mes de noviembre para acercar la cultura de forma gratuita a todos los vecinos de nuestro municipio a trav\u00e9s de actividades de distintos campos."},"aioseo_meta_data":{"post_id":"10541","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:56:55","updated":"2025-06-04 17:23:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/\" title=\"Actividades culturales del mes\">Actividades culturales del mes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArranca el Noviembre cultural\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Actividades culturales del mes","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-culturales-del-mes\/"},{"label":"Arranca el Noviembre cultural","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/29\/arranca-el-noviembre-cultural-4\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:57:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10541"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10537"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}