{"id":10523,"date":"2015-11-08T07:17:16","date_gmt":"2015-11-08T07:17:16","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/"},"modified":"2015-11-08T07:17:16","modified_gmt":"2015-11-08T07:17:16","slug":"actividades-8-de-noviembre-3","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/","title":{"rendered":"Actividades 8 de noviembre"},"content":{"rendered":"<p style=\"font-size: 12.16px; line-height: 15.808px;\">Ciclo de cortos infantiles &#8216;CortoEspa\u00f1a&#8217;<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">Lugar: Sala Multifuncional<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">Hora: 18.00<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">P\u00fablico familiar<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">\u00a0<\/p>\n<hr \/>\n<p>\u00a0<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">Exposici\u00f3n de la Semana de la Ciencia &#8216;La vega, el secano, los cerros: Historia de la Ciencia en paisajes cercanos&#8217;<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">Lugar: Casa de la Cultura<\/p>\n<p style=\"font-size: 12.16px; line-height: 15.808px;\">Hora: 10.00 a 14.00 horas- 17.00 a 20.00 horas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciclo de cortos infantiles &#8216;CortoEspa\u00f1a&#8217; Lugar: Sala Multifuncional Hora: 18.00 P\u00fablico familiar \u00a0 \u00a0 Exposici\u00f3n de la Semana de la Ciencia &#8216;La vega, el secano, los cerros: Historia de la Ciencia en paisajes cercanos&#8217; Lugar: Casa de la Cultura Hora: 10.00 a 14.00 horas- 17.00 a 20.00 horas<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1072],"class_list":["post-10523","post","type-post","status-publish","format-standard","hentry","tag-agenda"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ciclo de cortos infantiles &#039;CortoEspa\u00f1a&#039; Lugar: Sala Multifuncional Hora: 18.00 P\u00fablico familiar Exposici\u00f3n de la Semana de la Ciencia &#039;La vega, el secano, los cerros: Historia de la Ciencia en paisajes cercanos&#039; Lugar: Casa de la Cultura Hora: 10.00 a 14.00 horas- 17.00 a 20.00 horas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Actividades 8 de noviembre - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"Ciclo de cortos infantiles &#039;CortoEspa\u00f1a&#039; Lugar: Sala Multifuncional Hora: 18.00 P\u00fablico familiar Exposici\u00f3n de la Semana de la Ciencia &#039;La vega, el secano, los cerros: Historia de la Ciencia en paisajes cercanos&#039; Lugar: Casa de la Cultura Hora: 10.00 a 14.00 horas- 17.00 a 20.00 horas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-11-08T07:17:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-11-08T07:17:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Actividades 8 de noviembre - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ciclo de cortos infantiles &#039;CortoEspa\u00f1a&#039; Lugar: Sala Multifuncional Hora: 18.00 P\u00fablico familiar Exposici\u00f3n de la Semana de la Ciencia &#039;La vega, el secano, los cerros: Historia de la Ciencia en paisajes cercanos&#039; Lugar: Casa de la Cultura Hora: 10.00 a 14.00 horas- 17.00 a 20.00 horas\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/08\\\/actividades-8-de-noviembre-3\\\/#blogposting\",\"name\":\"Actividades 8 de noviembre - Ayuntamiento de Ciempozuelos\",\"headline\":\"Actividades 8 de noviembre\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-11-08T07:17:16+01:00\",\"dateModified\":\"2015-11-08T07:17:16+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/08\\\/actividades-8-de-noviembre-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/08\\\/actividades-8-de-noviembre-3\\\/#webpage\"},\"articleSection\":\"Agenda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/08\\\/actividades-8-de-noviembre-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/08\\\/actividades-8-de-noviembre-3\\\/#listItem\",\"name\":\"Actividades 8 de noviembre\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/08\\\/actividades-8-de-noviembre-3\\\/#listItem\",\"position\":3,\"name\":\"Actividades 8 de noviembre\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/08\\\/actividades-8-de-noviembre-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/08\\\/actividades-8-de-noviembre-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/08\\\/actividades-8-de-noviembre-3\\\/\",\"name\":\"Actividades 8 de noviembre - Ayuntamiento de Ciempozuelos\",\"description\":\"Ciclo de cortos infantiles 'CortoEspa\\u00f1a' Lugar: Sala Multifuncional Hora: 18.00 P\\u00fablico familiar Exposici\\u00f3n de la Semana de la Ciencia 'La vega, el secano, los cerros: Historia de la Ciencia en paisajes cercanos' Lugar: Casa de la Cultura Hora: 10.00 a 14.00 horas- 17.00 a 20.00 horas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/11\\\/08\\\/actividades-8-de-noviembre-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-11-08T07:17:16+01:00\",\"dateModified\":\"2015-11-08T07:17:16+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Actividades 8 de noviembre - Ayuntamiento de Ciempozuelos","description":"Ciclo de cortos infantiles 'CortoEspa\u00f1a' Lugar: Sala Multifuncional Hora: 18.00 P\u00fablico familiar Exposici\u00f3n de la Semana de la Ciencia 'La vega, el secano, los cerros: Historia de la Ciencia en paisajes cercanos' Lugar: Casa de la Cultura Hora: 10.00 a 14.00 horas- 17.00 a 20.00 horas","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/#blogposting","name":"Actividades 8 de noviembre - Ayuntamiento de Ciempozuelos","headline":"Actividades 8 de noviembre","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-11-08T07:17:16+01:00","dateModified":"2015-11-08T07:17:16+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/#webpage"},"articleSection":"Agenda"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/#listItem","name":"Actividades 8 de noviembre"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/#listItem","position":3,"name":"Actividades 8 de noviembre","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/","name":"Actividades 8 de noviembre - Ayuntamiento de Ciempozuelos","description":"Ciclo de cortos infantiles 'CortoEspa\u00f1a' Lugar: Sala Multifuncional Hora: 18.00 P\u00fablico familiar Exposici\u00f3n de la Semana de la Ciencia 'La vega, el secano, los cerros: Historia de la Ciencia en paisajes cercanos' Lugar: Casa de la Cultura Hora: 10.00 a 14.00 horas- 17.00 a 20.00 horas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-11-08T07:17:16+01:00","dateModified":"2015-11-08T07:17:16+01:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Actividades 8 de noviembre - Ayuntamiento de Ciempozuelos","og:description":"Ciclo de cortos infantiles 'CortoEspa\u00f1a' Lugar: Sala Multifuncional Hora: 18.00 P\u00fablico familiar Exposici\u00f3n de la Semana de la Ciencia 'La vega, el secano, los cerros: Historia de la Ciencia en paisajes cercanos' Lugar: Casa de la Cultura Hora: 10.00 a 14.00 horas- 17.00 a 20.00 horas","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/","article:published_time":"2015-11-08T07:17:16+00:00","article:modified_time":"2015-11-08T07:17:16+00:00","twitter:card":"summary","twitter:title":"Actividades 8 de noviembre - Ayuntamiento de Ciempozuelos","twitter:description":"Ciclo de cortos infantiles 'CortoEspa\u00f1a' Lugar: Sala Multifuncional Hora: 18.00 P\u00fablico familiar Exposici\u00f3n de la Semana de la Ciencia 'La vega, el secano, los cerros: Historia de la Ciencia en paisajes cercanos' Lugar: Casa de la Cultura Hora: 10.00 a 14.00 horas- 17.00 a 20.00 horas"},"aioseo_meta_data":{"post_id":"10523","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:59:56","updated":"2025-06-04 17:26:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tActividades 8 de noviembre\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Agenda","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/agenda\/"},{"label":"Actividades 8 de noviembre","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/11\/08\/actividades-8-de-noviembre-3\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:50:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10523"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10523\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}