{"id":10486,"date":"2015-10-20T08:47:02","date_gmt":"2015-10-20T08:47:02","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/"},"modified":"2015-10-20T08:47:02","modified_gmt":"2015-10-20T08:47:02","slug":"desvio-de-itinerario-y-suspension-de-parada-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/","title":{"rendered":"Desv\u00edo de itinerario y suspensi\u00f3n de parada"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\">El Ayuntamiento de Ciempozuelos informa que con motivo de las obras que se van a ejecutar en la calzada del 21 al 23 de octubre en la Plaza de San Jos\u00e9, el autob\u00fas de San Mart\u00edn de la Vega- Ciempozuelos- Aranjuez tendr\u00e1 un cambio en su itinerario.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\">A partir de las 8.00 horas de ma\u00f1ana, mi\u00e9rcoles 21, hasta su reapertura al tr\u00e1fico (prevista para el viernes 23 sobre las 14.00 horas), el itinerario tendr\u00e1 un desv\u00edo en el cruce de la calle de las Cuestas, girando a la izquierda para acceder a la Avda. de la Circunvalanci\u00f3n donde continuar\u00e1 hasta el final de la calle para acceder a la c\/ Cruz Verde. All\u00ed, girar\u00e1 a la derecha para llegar a la calle Prado Redondo. En este punto se restablecer\u00e1 el recorrido habitual.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px;\">Por lo tanto, las paradas de la Plaza San Jos\u00e9 y c\/San Jos\u00e9 quedar\u00e1n suspendidas hasta el restablecimiento del itinerario habitual.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><img decoding=\"async\" class=\" size-full wp-image-10484\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/cambio_itinerariobus.jpg\" border=\"0\" width=\"100%\" style=\"font-size: 12.16px; line-height: 15.808px;\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/cambio_itinerariobus-200x117.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/cambio_itinerariobus-300x176.jpg 300w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/cambio_itinerariobus-400x234.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/cambio_itinerariobus-600x352.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/cambio_itinerariobus.jpg 679w\" sizes=\"(max-width: 679px) 100vw, 679px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Ciempozuelos informa que con motivo de las obras que se van a ejecutar en la calzada del 21 al 23 de octubre en la Plaza de San Jos\u00e9, el autob\u00fas de San Mart\u00edn de la Vega- Ciempozuelos- Aranjuez tendr\u00e1 un cambio en su itinerario. A partir de las 8.00 horas de ma\u00f1ana, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1421],"class_list":["post-10486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-transportes-sin-categoria"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Ayuntamiento de Ciempozuelos informa que con motivo de las obras que se van a ejecutar en la calzada del 21 al 23 de octubre en la Plaza de San Jos\u00e9, el autob\u00fas de San Mart\u00edn de la Vega- Ciempozuelos- Aranjuez tendr\u00e1 un cambio en su itinerario. A partir de las 8.00 horas de ma\u00f1ana,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Desv\u00edo de itinerario y suspensi\u00f3n de parada - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El Ayuntamiento de Ciempozuelos informa que con motivo de las obras que se van a ejecutar en la calzada del 21 al 23 de octubre en la Plaza de San Jos\u00e9, el autob\u00fas de San Mart\u00edn de la Vega- Ciempozuelos- Aranjuez tendr\u00e1 un cambio en su itinerario. A partir de las 8.00 horas de ma\u00f1ana,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-10-20T08:47:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-10-20T08:47:02+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Desv\u00edo de itinerario y suspensi\u00f3n de parada - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Ayuntamiento de Ciempozuelos informa que con motivo de las obras que se van a ejecutar en la calzada del 21 al 23 de octubre en la Plaza de San Jos\u00e9, el autob\u00fas de San Mart\u00edn de la Vega- Ciempozuelos- Aranjuez tendr\u00e1 un cambio en su itinerario. A partir de las 8.00 horas de ma\u00f1ana,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/#blogposting\",\"name\":\"Desv\\u00edo de itinerario y suspensi\\u00f3n de parada - Ayuntamiento de Ciempozuelos\",\"headline\":\"Desv\\u00edo de itinerario y suspensi\\u00f3n de parada\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/cambio_itinerariobus.jpg\",\"width\":679,\"height\":398},\"datePublished\":\"2015-10-20T08:47:02+02:00\",\"dateModified\":\"2015-10-20T08:47:02+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/#webpage\"},\"articleSection\":\"Transportes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/transportes-sin-categoria\\\/#listItem\",\"name\":\"Transportes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/transportes-sin-categoria\\\/#listItem\",\"position\":2,\"name\":\"Transportes\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/transportes-sin-categoria\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/#listItem\",\"name\":\"Desv\\u00edo de itinerario y suspensi\\u00f3n de parada\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/#listItem\",\"position\":3,\"name\":\"Desv\\u00edo de itinerario y suspensi\\u00f3n de parada\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/transportes-sin-categoria\\\/#listItem\",\"name\":\"Transportes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/\",\"name\":\"Desv\\u00edo de itinerario y suspensi\\u00f3n de parada - Ayuntamiento de Ciempozuelos\",\"description\":\"El Ayuntamiento de Ciempozuelos informa que con motivo de las obras que se van a ejecutar en la calzada del 21 al 23 de octubre en la Plaza de San Jos\\u00e9, el autob\\u00fas de San Mart\\u00edn de la Vega- Ciempozuelos- Aranjuez tendr\\u00e1 un cambio en su itinerario. A partir de las 8.00 horas de ma\\u00f1ana,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/cambio_itinerariobus.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/#mainImage\",\"width\":679,\"height\":398},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/20\\\/desvio-de-itinerario-y-suspension-de-parada-2\\\/#mainImage\"},\"datePublished\":\"2015-10-20T08:47:02+02:00\",\"dateModified\":\"2015-10-20T08:47:02+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Desv\u00edo de itinerario y suspensi\u00f3n de parada - Ayuntamiento de Ciempozuelos","description":"El Ayuntamiento de Ciempozuelos informa que con motivo de las obras que se van a ejecutar en la calzada del 21 al 23 de octubre en la Plaza de San Jos\u00e9, el autob\u00fas de San Mart\u00edn de la Vega- Ciempozuelos- Aranjuez tendr\u00e1 un cambio en su itinerario. A partir de las 8.00 horas de ma\u00f1ana,","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/#blogposting","name":"Desv\u00edo de itinerario y suspensi\u00f3n de parada - Ayuntamiento de Ciempozuelos","headline":"Desv\u00edo de itinerario y suspensi\u00f3n de parada","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/cambio_itinerariobus.jpg","width":679,"height":398},"datePublished":"2015-10-20T08:47:02+02:00","dateModified":"2015-10-20T08:47:02+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/#webpage"},"articleSection":"Transportes"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/transportes-sin-categoria\/#listItem","name":"Transportes"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/transportes-sin-categoria\/#listItem","position":2,"name":"Transportes","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/transportes-sin-categoria\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/#listItem","name":"Desv\u00edo de itinerario y suspensi\u00f3n de parada"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/#listItem","position":3,"name":"Desv\u00edo de itinerario y suspensi\u00f3n de parada","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/transportes-sin-categoria\/#listItem","name":"Transportes"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/","name":"Desv\u00edo de itinerario y suspensi\u00f3n de parada - Ayuntamiento de Ciempozuelos","description":"El Ayuntamiento de Ciempozuelos informa que con motivo de las obras que se van a ejecutar en la calzada del 21 al 23 de octubre en la Plaza de San Jos\u00e9, el autob\u00fas de San Mart\u00edn de la Vega- Ciempozuelos- Aranjuez tendr\u00e1 un cambio en su itinerario. A partir de las 8.00 horas de ma\u00f1ana,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/10\/cambio_itinerariobus.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/#mainImage","width":679,"height":398},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/#mainImage"},"datePublished":"2015-10-20T08:47:02+02:00","dateModified":"2015-10-20T08:47:02+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Desv\u00edo de itinerario y suspensi\u00f3n de parada - Ayuntamiento de Ciempozuelos","og:description":"El Ayuntamiento de Ciempozuelos informa que con motivo de las obras que se van a ejecutar en la calzada del 21 al 23 de octubre en la Plaza de San Jos\u00e9, el autob\u00fas de San Mart\u00edn de la Vega- Ciempozuelos- Aranjuez tendr\u00e1 un cambio en su itinerario. A partir de las 8.00 horas de ma\u00f1ana,","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/","article:published_time":"2015-10-20T08:47:02+00:00","article:modified_time":"2015-10-20T08:47:02+00:00","twitter:card":"summary","twitter:title":"Desv\u00edo de itinerario y suspensi\u00f3n de parada - Ayuntamiento de Ciempozuelos","twitter:description":"El Ayuntamiento de Ciempozuelos informa que con motivo de las obras que se van a ejecutar en la calzada del 21 al 23 de octubre en la Plaza de San Jos\u00e9, el autob\u00fas de San Mart\u00edn de la Vega- Ciempozuelos- Aranjuez tendr\u00e1 un cambio en su itinerario. A partir de las 8.00 horas de ma\u00f1ana,"},"aioseo_meta_data":{"post_id":"10486","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:51:55","updated":"2025-06-04 17:18:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/transportes-sin-categoria\/\" title=\"Transportes\">Transportes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDesv\u00edo de itinerario y suspensi\u00f3n de parada\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Transportes","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/transportes-sin-categoria\/"},{"label":"Desv\u00edo de itinerario y suspensi\u00f3n de parada","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/20\/desvio-de-itinerario-y-suspension-de-parada-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:56:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10486"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10486\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10484"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}