{"id":10445,"date":"2015-10-05T13:47:32","date_gmt":"2015-10-05T13:47:32","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/"},"modified":"2015-10-05T13:47:32","modified_gmt":"2015-10-05T13:47:32","slug":"gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/","title":{"rendered":"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><em>La prueba cont\u00f3 con la participaci\u00f3n de m\u00e1s de 300 corredores<\/em><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">La XXX Carrera Popular, organizada por el Ayuntamiento de Ciempozuelos, se celebr\u00f3 ayer domingo 4 de octubre con una gran participaci\u00f3n de deportistas y asistentes, a pesar de la amenaza de lluvia en los primeros momentos. Un total de 304 corredores (166 en las categor\u00edas de adultos y 138 en infantiles) recorrieron las distancias seg\u00fan sus respectivas categor\u00edas. Para los adultos, en esta edici\u00f3n se inauguraba un recorrido mixto de 10 kil\u00f3metros que tuvo buena aceptaci\u00f3n por parte de los participantes.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\"><strong>Clasificaci\u00f3n por categor\u00eda<span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">El ganador de la categor\u00eda Senior masculina fue Javier Ferrero Bonilla, con un tiempo de 35:50.10, seguido por Daniel Ru\u00edz Front\u00f3n y Miguel \u00c1ngel Valdepe\u00f1as Rodr\u00edguez. La clasificaci\u00f3n de Senior femenino fue: Mercedes Herrera Vicente (45:04.92), Lara Fern\u00e1ndez Moreno y Sandra Garrido Alcaide.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">En la categor\u00eda de Veteranos A el primer puesto lo ocup\u00f3 Jos\u00e9 Antonio Mart\u00ednez Cobos (36:17.70), seguido por Ramiro L\u00f3pez Villarrubia y en tercer lugar, Luis Palomo Casado.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">El grupo femenino lo lider\u00f3 Sof\u00eda Inmaculada Fern\u00e1ndez Rodr\u00edguez (43:32.00), seguida por Olga S\u00e1nchez-Rey Quir\u00f3s y Alicia Pascual Paredes. En los Veteranos B masculino, el p\u00f3dium fue para Jos\u00e9 Fernando Luis Santiao (40:31.70), Joaqu\u00edn de Paco Parrado y Jos\u00e9 Antonio Granados L\u00f3pez. En cuanto a la clasificaci\u00f3n femenina Gabriela Valiente Ors (59:32.20) se hizo con el primer puesto, seguida por Mar\u00eda del Sagrario S\u00e1nchez Fern\u00e1ndez y Rosario Pueyo P\u00e9rez.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">La categor\u00eda de Cadetes femeninas fue liderada por Andrea Avil\u00e9s Castellanos (7\u201944\u201d), seguida por Claudia P\u00e9rez Prieto y Susana L\u00f3pez Pueyo. En cuanto a la clasificaci\u00f3n de los chicos, el resultado fue: Noel Jim\u00e9nez Garc\u00eda (7\u201921\u201d), Alejandro D\u00edaz Gonz\u00e1lez y Ivan Todrov Ivanov. En la prueba Infantil femenino, el primer puesto fue para Alexandra Wruszak (5\u201905\u201d), la segunda fue Irene de la Vara Fern\u00e1ndez y la tercera Raquel Bernard Calvo. En Infantil masculino, el p\u00f3dium fue para Samuel Montero Vera (4\u201914\u201d), Jorge Fern\u00e1ndez San Jos\u00e9 y David Torres Sorensen. En la categor\u00eda de Alev\u00edn femenino (nacidas entre el a\u00f1os 2003 y 2004) el primer puesto fue para Sara Morales S\u00e1nchez (2\u201910\u201d), el segundo lugar lo ocup\u00f3 Esther Rodr\u00edguez Peinado y el tercero Miriam Porral Benito. En la categor\u00eda masculina el primer lugar fue para Neizar L\u00f3pez Villaverde (2\u201915\u201d), seguido por David Hern\u00e1ndez Cede\u00f1o y Asier Guerra Zudaire.<\/p>\n<p class=\"MsoNormal\" style=\"font-size: 12.16px; line-height: 15.808px; text-align: justify;\">Por causas de log\u00edstica, no se ha podido hacer entrega de los trofeos a los primeros clasificados de las categor\u00edas Alev\u00edn, Infantil y Cadete. Este viernes, los campeones podr\u00e1n recogerlos en el \u00c1rea de Deportes (pabell\u00f3n).<\/p>\n<p>Descargar archivo: {jd_file file==466}<\/p>\n<p>Descargar archivo: {jd_file file==468}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La prueba cont\u00f3 con la participaci\u00f3n de m\u00e1s de 300 corredores La XXX Carrera Popular, organizada por el Ayuntamiento de Ciempozuelos, se celebr\u00f3 ayer domingo 4 de octubre con una gran participaci\u00f3n de deportistas y asistentes, a pesar de la amenaza de lluvia en los primeros momentos. Un total de 304 corredores (166 en las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1102],"class_list":["post-10445","post","type-post","status-publish","format-standard","hentry","tag-actividades-deportivas-curso-maratones-y-torneos"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La prueba cont\u00f3 con la participaci\u00f3n de m\u00e1s de 300 corredores La XXX Carrera Popular, organizada por el Ayuntamiento de Ciempozuelos, se celebr\u00f3 ayer domingo 4 de octubre con una gran participaci\u00f3n de deportistas y asistentes, a pesar de la amenaza de lluvia en los primeros momentos. Un total de 304 corredores (166 en las\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La prueba cont\u00f3 con la participaci\u00f3n de m\u00e1s de 300 corredores La XXX Carrera Popular, organizada por el Ayuntamiento de Ciempozuelos, se celebr\u00f3 ayer domingo 4 de octubre con una gran participaci\u00f3n de deportistas y asistentes, a pesar de la amenaza de lluvia en los primeros momentos. Un total de 304 corredores (166 en las\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-10-05T13:47:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-10-05T13:47:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La prueba cont\u00f3 con la participaci\u00f3n de m\u00e1s de 300 corredores La XXX Carrera Popular, organizada por el Ayuntamiento de Ciempozuelos, se celebr\u00f3 ayer domingo 4 de octubre con una gran participaci\u00f3n de deportistas y asistentes, a pesar de la amenaza de lluvia en los primeros momentos. Un total de 304 corredores (166 en las\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/05\\\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\\\/#blogposting\",\"name\":\"Gran ambiente y participaci\\u00f3n en la XXX Carrera Popular de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"Gran ambiente y participaci\\u00f3n en la XXX Carrera Popular de Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-10-05T13:47:32+02:00\",\"dateModified\":\"2015-10-05T13:47:32+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/05\\\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/05\\\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\\\/#webpage\"},\"articleSection\":\"Actividades deportivas \\\/Curso\\\/Maratones y Torneos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/05\\\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-deportivas-curso-maratones-y-torneos\\\/#listItem\",\"name\":\"Actividades deportivas \\\/Curso\\\/Maratones y Torneos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-deportivas-curso-maratones-y-torneos\\\/#listItem\",\"position\":2,\"name\":\"Actividades deportivas \\\/Curso\\\/Maratones y Torneos\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-deportivas-curso-maratones-y-torneos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/05\\\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\\\/#listItem\",\"name\":\"Gran ambiente y participaci\\u00f3n en la XXX Carrera Popular de Ciempozuelos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/05\\\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\\\/#listItem\",\"position\":3,\"name\":\"Gran ambiente y participaci\\u00f3n en la XXX Carrera Popular de Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/actividades-deportivas-curso-maratones-y-torneos\\\/#listItem\",\"name\":\"Actividades deportivas \\\/Curso\\\/Maratones y Torneos\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/05\\\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/05\\\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/05\\\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\\\/\",\"name\":\"Gran ambiente y participaci\\u00f3n en la XXX Carrera Popular de Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"La prueba cont\\u00f3 con la participaci\\u00f3n de m\\u00e1s de 300 corredores La XXX Carrera Popular, organizada por el Ayuntamiento de Ciempozuelos, se celebr\\u00f3 ayer domingo 4 de octubre con una gran participaci\\u00f3n de deportistas y asistentes, a pesar de la amenaza de lluvia en los primeros momentos. Un total de 304 corredores (166 en las\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/05\\\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-10-05T13:47:32+02:00\",\"dateModified\":\"2015-10-05T13:47:32+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"La prueba cont\u00f3 con la participaci\u00f3n de m\u00e1s de 300 corredores La XXX Carrera Popular, organizada por el Ayuntamiento de Ciempozuelos, se celebr\u00f3 ayer domingo 4 de octubre con una gran participaci\u00f3n de deportistas y asistentes, a pesar de la amenaza de lluvia en los primeros momentos. Un total de 304 corredores (166 en las","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/#blogposting","name":"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-10-05T13:47:32+02:00","dateModified":"2015-10-05T13:47:32+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/#webpage"},"articleSection":"Actividades deportivas \/Curso\/Maratones y Torneos"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/#listItem","name":"Actividades deportivas \/Curso\/Maratones y Torneos"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/#listItem","position":2,"name":"Actividades deportivas \/Curso\/Maratones y Torneos","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/#listItem","name":"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/#listItem","position":3,"name":"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/#listItem","name":"Actividades deportivas \/Curso\/Maratones y Torneos"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/","name":"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"La prueba cont\u00f3 con la participaci\u00f3n de m\u00e1s de 300 corredores La XXX Carrera Popular, organizada por el Ayuntamiento de Ciempozuelos, se celebr\u00f3 ayer domingo 4 de octubre con una gran participaci\u00f3n de deportistas y asistentes, a pesar de la amenaza de lluvia en los primeros momentos. Un total de 304 corredores (166 en las","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-10-05T13:47:32+02:00","dateModified":"2015-10-05T13:47:32+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"La prueba cont\u00f3 con la participaci\u00f3n de m\u00e1s de 300 corredores La XXX Carrera Popular, organizada por el Ayuntamiento de Ciempozuelos, se celebr\u00f3 ayer domingo 4 de octubre con una gran participaci\u00f3n de deportistas y asistentes, a pesar de la amenaza de lluvia en los primeros momentos. Un total de 304 corredores (166 en las","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/","article:published_time":"2015-10-05T13:47:32+00:00","article:modified_time":"2015-10-05T13:47:32+00:00","twitter:card":"summary","twitter:title":"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"La prueba cont\u00f3 con la participaci\u00f3n de m\u00e1s de 300 corredores La XXX Carrera Popular, organizada por el Ayuntamiento de Ciempozuelos, se celebr\u00f3 ayer domingo 4 de octubre con una gran participaci\u00f3n de deportistas y asistentes, a pesar de la amenaza de lluvia en los primeros momentos. Un total de 304 corredores (166 en las"},"aioseo_meta_data":{"post_id":"10445","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:47:53","updated":"2025-06-04 17:13:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/\" title=\"Actividades deportivas \/Curso\/Maratones y Torneos\">Actividades deportivas \/Curso\/Maratones y Torneos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Actividades deportivas \/Curso\/Maratones y Torneos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/actividades-deportivas-curso-maratones-y-torneos\/"},{"label":"Gran ambiente y participaci\u00f3n en la XXX Carrera Popular de Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/05\/gran-ambiente-y-participacion-en-la-xxx-carrera-popular-de-ciempozuelos-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 21:04:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10445"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10445\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}