{"id":10434,"date":"2015-10-02T12:14:14","date_gmt":"2015-10-02T12:14:14","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/"},"modified":"2015-10-02T12:14:14","modified_gmt":"2015-10-02T12:14:14","slug":"arranca-el-octubre-celta-en-ciempozuelos","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/","title":{"rendered":"Arranca el octubre celta en Ciempozuelos"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: left;\"><em>La programaci\u00f3n de este fin de semana cuenta con pasacalles, talleres y m\u00fasica tradicional celta <\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: left;\"><span style=\"text-align: justify; font-size: 12.16px; line-height: 1.3em;\">El Ayuntamiento de Ciempozuelos inicia este pr\u00f3ximo fin de semana la programaci\u00f3n cultural del mes de octubre, \u2018Samhain 2015\u2019, centrado en la tradici\u00f3n celta. El objetivo es acercar esta cultura de una forma atractiva y participativa a p\u00fablicos de distintas edades y gustos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">\u2018Samhain 2015\u2019 comienza el s\u00e1bado 3 de octubre a las 12.00 horas con un pasacalles que ir\u00e1 desde la Plaza de las Palmeras hasta el templete del parque San Juan de Dios. A las 12.30 horas, tambi\u00e9n en el templete del parque, los m\u00e1s peque\u00f1os podr\u00e1n disfrutar de un taller de maquillaje.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">Por la tarde, en la Sala Multifuncional a las 19.00 horas est\u00e1 programado un taller de armas y sistema de combate y a las 20.00 horas podremos disfrutar de m\u00fasica celta en directo y humor\/baile tradicional celta.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El domingo 4 de octubre, a las 11.00 horas, contin\u00faan las actividades en la Sala Multifuncional con un taller de fabricaci\u00f3n de velas para ni\u00f1os. Un cuentacuentos mitol\u00f3gico amenizar\u00e1 a mayores y peque\u00f1os a las 12.00 horas y la jornada se cerrar\u00e1 a las 13.00 horas con un baile participativo con m\u00fasica tradicional celta.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">Todas las actividades ir\u00e1n de la mano del Grupo Taranis, especialista en la recreaci\u00f3n de diversos periodos hist\u00f3ricos desde la Edad de Hierro hasta la Edad Media europea. Cuentan con un amplio equipo de arque\u00f3logos, historiadores y grupos culturales que dotan a todas las actividades de la mayor calidad y realismo posibles.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La programaci\u00f3n de este fin de semana cuenta con pasacalles, talleres y m\u00fasica tradicional celta El Ayuntamiento de Ciempozuelos inicia este pr\u00f3ximo fin de semana la programaci\u00f3n cultural del mes de octubre, \u2018Samhain 2015\u2019, centrado en la tradici\u00f3n celta. El objetivo es acercar esta cultura de una forma atractiva y participativa a p\u00fablicos de distintas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1217],"class_list":["post-10434","post","type-post","status-publish","format-standard","hentry","tag-1217"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La programaci\u00f3n de este fin de semana cuenta con pasacalles, talleres y m\u00fasica tradicional celta El Ayuntamiento de Ciempozuelos inicia este pr\u00f3ximo fin de semana la programaci\u00f3n cultural del mes de octubre, \u2018Samhain 2015\u2019, centrado en la tradici\u00f3n celta. El objetivo es acercar esta cultura de una forma atractiva y participativa a p\u00fablicos de distintas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Arranca el octubre celta en Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La programaci\u00f3n de este fin de semana cuenta con pasacalles, talleres y m\u00fasica tradicional celta El Ayuntamiento de Ciempozuelos inicia este pr\u00f3ximo fin de semana la programaci\u00f3n cultural del mes de octubre, \u2018Samhain 2015\u2019, centrado en la tradici\u00f3n celta. El objetivo es acercar esta cultura de una forma atractiva y participativa a p\u00fablicos de distintas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-10-02T12:14:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-10-02T12:14:14+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Arranca el octubre celta en Ciempozuelos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La programaci\u00f3n de este fin de semana cuenta con pasacalles, talleres y m\u00fasica tradicional celta El Ayuntamiento de Ciempozuelos inicia este pr\u00f3ximo fin de semana la programaci\u00f3n cultural del mes de octubre, \u2018Samhain 2015\u2019, centrado en la tradici\u00f3n celta. El objetivo es acercar esta cultura de una forma atractiva y participativa a p\u00fablicos de distintas\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/02\\\/arranca-el-octubre-celta-en-ciempozuelos\\\/#blogposting\",\"name\":\"Arranca el octubre celta en Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"headline\":\"Arranca el octubre celta en Ciempozuelos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-10-02T12:14:14+02:00\",\"dateModified\":\"2015-10-02T12:14:14+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/02\\\/arranca-el-octubre-celta-en-ciempozuelos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/02\\\/arranca-el-octubre-celta-en-ciempozuelos\\\/#webpage\"},\"articleSection\":\"1139\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/02\\\/arranca-el-octubre-celta-en-ciempozuelos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"position\":2,\"name\":\"1139\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/02\\\/arranca-el-octubre-celta-en-ciempozuelos\\\/#listItem\",\"name\":\"Arranca el octubre celta en Ciempozuelos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/02\\\/arranca-el-octubre-celta-en-ciempozuelos\\\/#listItem\",\"position\":3,\"name\":\"Arranca el octubre celta en Ciempozuelos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1139\\\/#listItem\",\"name\":\"1139\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/02\\\/arranca-el-octubre-celta-en-ciempozuelos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/02\\\/arranca-el-octubre-celta-en-ciempozuelos\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/02\\\/arranca-el-octubre-celta-en-ciempozuelos\\\/\",\"name\":\"Arranca el octubre celta en Ciempozuelos - Ayuntamiento de Ciempozuelos\",\"description\":\"La programaci\\u00f3n de este fin de semana cuenta con pasacalles, talleres y m\\u00fasica tradicional celta El Ayuntamiento de Ciempozuelos inicia este pr\\u00f3ximo fin de semana la programaci\\u00f3n cultural del mes de octubre, \\u2018Samhain 2015\\u2019, centrado en la tradici\\u00f3n celta. El objetivo es acercar esta cultura de una forma atractiva y participativa a p\\u00fablicos de distintas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/10\\\/02\\\/arranca-el-octubre-celta-en-ciempozuelos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-10-02T12:14:14+02:00\",\"dateModified\":\"2015-10-02T12:14:14+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Arranca el octubre celta en Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"La programaci\u00f3n de este fin de semana cuenta con pasacalles, talleres y m\u00fasica tradicional celta El Ayuntamiento de Ciempozuelos inicia este pr\u00f3ximo fin de semana la programaci\u00f3n cultural del mes de octubre, \u2018Samhain 2015\u2019, centrado en la tradici\u00f3n celta. El objetivo es acercar esta cultura de una forma atractiva y participativa a p\u00fablicos de distintas","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/#blogposting","name":"Arranca el octubre celta en Ciempozuelos - Ayuntamiento de Ciempozuelos","headline":"Arranca el octubre celta en Ciempozuelos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-10-02T12:14:14+02:00","dateModified":"2015-10-02T12:14:14+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/#webpage"},"articleSection":"1139"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","position":2,"name":"1139","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/#listItem","name":"Arranca el octubre celta en Ciempozuelos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/#listItem","position":3,"name":"Arranca el octubre celta en Ciempozuelos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/#listItem","name":"1139"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/","name":"Arranca el octubre celta en Ciempozuelos - Ayuntamiento de Ciempozuelos","description":"La programaci\u00f3n de este fin de semana cuenta con pasacalles, talleres y m\u00fasica tradicional celta El Ayuntamiento de Ciempozuelos inicia este pr\u00f3ximo fin de semana la programaci\u00f3n cultural del mes de octubre, \u2018Samhain 2015\u2019, centrado en la tradici\u00f3n celta. El objetivo es acercar esta cultura de una forma atractiva y participativa a p\u00fablicos de distintas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-10-02T12:14:14+02:00","dateModified":"2015-10-02T12:14:14+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Arranca el octubre celta en Ciempozuelos - Ayuntamiento de Ciempozuelos","og:description":"La programaci\u00f3n de este fin de semana cuenta con pasacalles, talleres y m\u00fasica tradicional celta El Ayuntamiento de Ciempozuelos inicia este pr\u00f3ximo fin de semana la programaci\u00f3n cultural del mes de octubre, \u2018Samhain 2015\u2019, centrado en la tradici\u00f3n celta. El objetivo es acercar esta cultura de una forma atractiva y participativa a p\u00fablicos de distintas","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/","article:published_time":"2015-10-02T12:14:14+00:00","article:modified_time":"2015-10-02T12:14:14+00:00","twitter:card":"summary","twitter:title":"Arranca el octubre celta en Ciempozuelos - Ayuntamiento de Ciempozuelos","twitter:description":"La programaci\u00f3n de este fin de semana cuenta con pasacalles, talleres y m\u00fasica tradicional celta El Ayuntamiento de Ciempozuelos inicia este pr\u00f3ximo fin de semana la programaci\u00f3n cultural del mes de octubre, \u2018Samhain 2015\u2019, centrado en la tradici\u00f3n celta. El objetivo es acercar esta cultura de una forma atractiva y participativa a p\u00fablicos de distintas"},"aioseo_meta_data":{"post_id":"10434","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:46:51","updated":"2025-06-04 17:12:01","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/\" title=\"1139\">1139<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArranca el octubre celta en Ciempozuelos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1139","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1139\/"},{"label":"Arranca el octubre celta en Ciempozuelos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/10\/02\/arranca-el-octubre-celta-en-ciempozuelos\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:54:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10434"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10434\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}