{"id":10314,"date":"2015-09-04T09:26:34","date_gmt":"2015-09-04T09:26:34","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/"},"modified":"2015-09-04T09:26:34","modified_gmt":"2015-09-04T09:26:34","slug":"el-pintor-realista-antonio-vazquez-expone-en-turin-2","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/","title":{"rendered":"El pintor realista Antonio V\u00e1zquez expone en Turin"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: left;\"><em>La muestra est\u00e1 enmarcada en la Exposici\u00f3n Universal de Milan 2015<\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: left;\"><span style=\"text-align: justify; font-size: 12.16px; line-height: 1.3em;\">Antonio V\u00e1zquez, vecino de Ciempozuelos, es uno de los pintores escogidos en la exposici\u00f3n internacional de realismo e hiperrealismo \u2018Non solo vero\u2019 que se exhibe en el Palacio Enaudi de Chivasso (Turin). La muestra, enmarcada dentro de la Exposici\u00f3n Universal de Milan 2015, se puede visitar en la ciudad italiana hasta el 30 de septiembre.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El artista participa con los \u00f3leos sobre tabla \u2018Membrillo sobre arc\u00f3n\u2019 <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.16px; line-height: 1.3em;\">(70&#215;85 cm) y \u2018Cubiertos,\u2019 una vista cenital de 120&#215;120 cm. La exposici\u00f3n que est\u00e1 formada por una selecci\u00f3n de 15 artistas italianos y 15 espa\u00f1oles.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La inauguraci\u00f3n, a la que asistieron m\u00e1s de 200 personas, cont\u00f3 tambi\u00e9n con la presencia de autoridades como el alcalde de Turin, la directora de Cultura, el Obispo de Turin, comisarios de la exposici\u00f3n, entre otros.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">La obra de Antonio V\u00e1zquez, considerada como realista, cuenta con multitud de premios y est\u00e1 presente en colecciones p\u00fablicas y privadas tanto dentro como fuera de Espa\u00f1a. A esta trayectoria art\u00edstica se suma la faceta pedag\u00f3gica que ha desarrollado de forma paralela en diversas instituciones p\u00fablicas y privadas. En la actualidad, dirige dos escuelas en Ciempozuelos de dibujo y pintura para ni\u00f1os y adultos en las que trasmite sus conocimientos art\u00edsticos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\">El Ayuntamiento de Ciempozuelos quiere mostrar su m\u00e1s sincera enhorabuena por su participaci\u00f3n en esta destacada exposici\u00f3n as\u00ed como el reconocimiento a una premiada trayectoria art\u00edstica y pedag\u00f3gica.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><em style=\"font-size: 12.16px; line-height: 15.808px;\"><img decoding=\"async\" class=\" size-full wp-image-10311\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/09\/n2-membrillos-sobe-arconesl-70-x85cm-copia.gif\" border=\"0\" width=\"100%\" \/><\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.16px; line-height: 1.3em;\"><img decoding=\"async\" class=\" size-full wp-image-10312\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/09\/n1-cubiertosvista-cenital-120x120cm.gif\" border=\"0\" width=\"100%\" \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La muestra est\u00e1 enmarcada en la Exposici\u00f3n Universal de Milan 2015 Antonio V\u00e1zquez, vecino de Ciempozuelos, es uno de los pintores escogidos en la exposici\u00f3n internacional de realismo e hiperrealismo \u2018Non solo vero\u2019 que se exhibe en el Palacio Enaudi de Chivasso (Turin). La muestra, enmarcada dentro de la Exposici\u00f3n Universal de Milan 2015, se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1180],"class_list":["post-10314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-exposiciones"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La muestra est\u00e1 enmarcada en la Exposici\u00f3n Universal de Milan 2015 Antonio V\u00e1zquez, vecino de Ciempozuelos, es uno de los pintores escogidos en la exposici\u00f3n internacional de realismo e hiperrealismo \u2018Non solo vero\u2019 que se exhibe en el Palacio Enaudi de Chivasso (Turin). La muestra, enmarcada dentro de la Exposici\u00f3n Universal de Milan 2015, se\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El pintor realista Antonio V\u00e1zquez expone en Turin - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"La muestra est\u00e1 enmarcada en la Exposici\u00f3n Universal de Milan 2015 Antonio V\u00e1zquez, vecino de Ciempozuelos, es uno de los pintores escogidos en la exposici\u00f3n internacional de realismo e hiperrealismo \u2018Non solo vero\u2019 que se exhibe en el Palacio Enaudi de Chivasso (Turin). La muestra, enmarcada dentro de la Exposici\u00f3n Universal de Milan 2015, se\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-09-04T09:26:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-09-04T09:26:34+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El pintor realista Antonio V\u00e1zquez expone en Turin - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La muestra est\u00e1 enmarcada en la Exposici\u00f3n Universal de Milan 2015 Antonio V\u00e1zquez, vecino de Ciempozuelos, es uno de los pintores escogidos en la exposici\u00f3n internacional de realismo e hiperrealismo \u2018Non solo vero\u2019 que se exhibe en el Palacio Enaudi de Chivasso (Turin). La muestra, enmarcada dentro de la Exposici\u00f3n Universal de Milan 2015, se\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/#blogposting\",\"name\":\"El pintor realista Antonio V\\u00e1zquez expone en Turin - Ayuntamiento de Ciempozuelos\",\"headline\":\"El pintor realista Antonio V\\u00e1zquez expone en Turin\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/n2-membrillos-sobe-arconesl-70-x85cm-copia.gif\",\"width\":1575,\"height\":1289},\"datePublished\":\"2015-09-04T09:26:34+02:00\",\"dateModified\":\"2015-09-04T09:26:34+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/#webpage\"},\"articleSection\":\"Exposiciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposiciones\\\/#listItem\",\"name\":\"Exposiciones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposiciones\\\/#listItem\",\"position\":2,\"name\":\"Exposiciones\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposiciones\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/#listItem\",\"name\":\"El pintor realista Antonio V\\u00e1zquez expone en Turin\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/#listItem\",\"position\":3,\"name\":\"El pintor realista Antonio V\\u00e1zquez expone en Turin\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/exposiciones\\\/#listItem\",\"name\":\"Exposiciones\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/\",\"name\":\"El pintor realista Antonio V\\u00e1zquez expone en Turin - Ayuntamiento de Ciempozuelos\",\"description\":\"La muestra est\\u00e1 enmarcada en la Exposici\\u00f3n Universal de Milan 2015 Antonio V\\u00e1zquez, vecino de Ciempozuelos, es uno de los pintores escogidos en la exposici\\u00f3n internacional de realismo e hiperrealismo \\u2018Non solo vero\\u2019 que se exhibe en el Palacio Enaudi de Chivasso (Turin). La muestra, enmarcada dentro de la Exposici\\u00f3n Universal de Milan 2015, se\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/n2-membrillos-sobe-arconesl-70-x85cm-copia.gif\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/#mainImage\",\"width\":1575,\"height\":1289},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/09\\\/04\\\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\\\/#mainImage\"},\"datePublished\":\"2015-09-04T09:26:34+02:00\",\"dateModified\":\"2015-09-04T09:26:34+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El pintor realista Antonio V\u00e1zquez expone en Turin - Ayuntamiento de Ciempozuelos","description":"La muestra est\u00e1 enmarcada en la Exposici\u00f3n Universal de Milan 2015 Antonio V\u00e1zquez, vecino de Ciempozuelos, es uno de los pintores escogidos en la exposici\u00f3n internacional de realismo e hiperrealismo \u2018Non solo vero\u2019 que se exhibe en el Palacio Enaudi de Chivasso (Turin). La muestra, enmarcada dentro de la Exposici\u00f3n Universal de Milan 2015, se","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/#blogposting","name":"El pintor realista Antonio V\u00e1zquez expone en Turin - Ayuntamiento de Ciempozuelos","headline":"El pintor realista Antonio V\u00e1zquez expone en Turin","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/09\/n2-membrillos-sobe-arconesl-70-x85cm-copia.gif","width":1575,"height":1289},"datePublished":"2015-09-04T09:26:34+02:00","dateModified":"2015-09-04T09:26:34+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/#webpage"},"articleSection":"Exposiciones"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/#listItem","name":"Exposiciones"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/#listItem","position":2,"name":"Exposiciones","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/#listItem","name":"El pintor realista Antonio V\u00e1zquez expone en Turin"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/#listItem","position":3,"name":"El pintor realista Antonio V\u00e1zquez expone en Turin","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/#listItem","name":"Exposiciones"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/","name":"El pintor realista Antonio V\u00e1zquez expone en Turin - Ayuntamiento de Ciempozuelos","description":"La muestra est\u00e1 enmarcada en la Exposici\u00f3n Universal de Milan 2015 Antonio V\u00e1zquez, vecino de Ciempozuelos, es uno de los pintores escogidos en la exposici\u00f3n internacional de realismo e hiperrealismo \u2018Non solo vero\u2019 que se exhibe en el Palacio Enaudi de Chivasso (Turin). La muestra, enmarcada dentro de la Exposici\u00f3n Universal de Milan 2015, se","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/09\/n2-membrillos-sobe-arconesl-70-x85cm-copia.gif","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/#mainImage","width":1575,"height":1289},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/#mainImage"},"datePublished":"2015-09-04T09:26:34+02:00","dateModified":"2015-09-04T09:26:34+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"El pintor realista Antonio V\u00e1zquez expone en Turin - Ayuntamiento de Ciempozuelos","og:description":"La muestra est\u00e1 enmarcada en la Exposici\u00f3n Universal de Milan 2015 Antonio V\u00e1zquez, vecino de Ciempozuelos, es uno de los pintores escogidos en la exposici\u00f3n internacional de realismo e hiperrealismo \u2018Non solo vero\u2019 que se exhibe en el Palacio Enaudi de Chivasso (Turin). La muestra, enmarcada dentro de la Exposici\u00f3n Universal de Milan 2015, se","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/","article:published_time":"2015-09-04T09:26:34+00:00","article:modified_time":"2015-09-04T09:26:34+00:00","twitter:card":"summary","twitter:title":"El pintor realista Antonio V\u00e1zquez expone en Turin - Ayuntamiento de Ciempozuelos","twitter:description":"La muestra est\u00e1 enmarcada en la Exposici\u00f3n Universal de Milan 2015 Antonio V\u00e1zquez, vecino de Ciempozuelos, es uno de los pintores escogidos en la exposici\u00f3n internacional de realismo e hiperrealismo \u2018Non solo vero\u2019 que se exhibe en el Palacio Enaudi de Chivasso (Turin). La muestra, enmarcada dentro de la Exposici\u00f3n Universal de Milan 2015, se"},"aioseo_meta_data":{"post_id":"10314","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:35:05","updated":"2025-06-04 17:01:49","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/\" title=\"Exposiciones\">Exposiciones<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl pintor realista Antonio V\u00e1zquez expone en Turin\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"Exposiciones","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/exposiciones\/"},{"label":"El pintor realista Antonio V\u00e1zquez expone en Turin","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/09\/04\/el-pintor-realista-antonio-vazquez-expone-en-turin-2\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:54:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10314"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10311"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}