{"id":10257,"date":"2015-08-14T12:43:00","date_gmt":"2015-08-14T12:43:00","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/"},"modified":"2015-08-14T12:43:00","modified_gmt":"2015-08-14T12:43:00","slug":"aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/","title":{"rendered":"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos"},"content":{"rendered":"<p>El Ayuntamiento de Ciempozuelos celebr\u00f3 el pasado jueves, 13 de agosto a las 20.00 horas en la Sala Multifuncional, una sesi\u00f3n plenaria de car\u00e1cter extraordinario pedida por los grupos de la oposici\u00f3n donde se llev\u00f3 a votaci\u00f3n el siguiente Orden del D\u00eda:<\/p>\n<p>&#8211; Celebraci\u00f3n de encierros en las fiestas patronales 2015 y concurso de recortes con una reducci\u00f3n de m\u00e1s del 50% respecto al gasto total realizado en 2014 para festejos taurinos as\u00ed como la organizaci\u00f3n de estos festejos por parte del Ayuntamiento.<\/p>\n<p>&#8211; Que estos festejos taurinos sean realizados de una forma directa por parte del Ayuntamiento.<\/p>\n<p>&#8211; Convocatoria de la Comisi\u00f3n de Medio Ambiente para la elaboraci\u00f3n de una normativa de obligado cumplimiento por gestores que garantice la ausencia total de maltrato a los animales en estos eventos.<\/p>\n<p>Los puntos fueron aprobados con los votos a favor de PSOE, PP, Ciudadanos por Ciempozuelos y PIC y los votos en contra de Ahora Ciempozuelos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Ciempozuelos celebr\u00f3 el pasado jueves, 13 de agosto a las 20.00 horas en la Sala Multifuncional, una sesi\u00f3n plenaria de car\u00e1cter extraordinario pedida por los grupos de la oposici\u00f3n donde se llev\u00f3 a votaci\u00f3n el siguiente Orden del D\u00eda: &#8211; Celebraci\u00f3n de encierros en las fiestas patronales 2015 y concurso de recortes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1235],"class_list":["post-10257","post","type-post","status-publish","format-standard","hentry","tag-1235"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Ayuntamiento de Ciempozuelos celebr\u00f3 el pasado jueves, 13 de agosto a las 20.00 horas en la Sala Multifuncional, una sesi\u00f3n plenaria de car\u00e1cter extraordinario pedida por los grupos de la oposici\u00f3n donde se llev\u00f3 a votaci\u00f3n el siguiente Orden del D\u00eda: - Celebraci\u00f3n de encierros en las fiestas patronales 2015 y concurso de recortes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El Ayuntamiento de Ciempozuelos celebr\u00f3 el pasado jueves, 13 de agosto a las 20.00 horas en la Sala Multifuncional, una sesi\u00f3n plenaria de car\u00e1cter extraordinario pedida por los grupos de la oposici\u00f3n donde se llev\u00f3 a votaci\u00f3n el siguiente Orden del D\u00eda: - Celebraci\u00f3n de encierros en las fiestas patronales 2015 y concurso de recortes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-08-14T12:43:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-08-14T12:43:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Ayuntamiento de Ciempozuelos celebr\u00f3 el pasado jueves, 13 de agosto a las 20.00 horas en la Sala Multifuncional, una sesi\u00f3n plenaria de car\u00e1cter extraordinario pedida por los grupos de la oposici\u00f3n donde se llev\u00f3 a votaci\u00f3n el siguiente Orden del D\u00eda: - Celebraci\u00f3n de encierros en las fiestas patronales 2015 y concurso de recortes\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/14\\\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\\\/#blogposting\",\"name\":\"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\\u00f3n para la subvenci\\u00f3n por parte del Ayto de los festejos taurinos - Ayuntamiento de Ciempozuelos\",\"headline\":\"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\\u00f3n para la subvenci\\u00f3n por parte del Ayto de los festejos taurinos\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"datePublished\":\"2015-08-14T12:43:00+02:00\",\"dateModified\":\"2015-08-14T12:43:00+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/14\\\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/14\\\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\\\/#webpage\"},\"articleSection\":\"1118\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/14\\\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1118\\\/#listItem\",\"name\":\"1118\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1118\\\/#listItem\",\"position\":2,\"name\":\"1118\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1118\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/14\\\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\\\/#listItem\",\"name\":\"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\\u00f3n para la subvenci\\u00f3n por parte del Ayto de los festejos taurinos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/14\\\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\\\/#listItem\",\"position\":3,\"name\":\"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\\u00f3n para la subvenci\\u00f3n por parte del Ayto de los festejos taurinos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1118\\\/#listItem\",\"name\":\"1118\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/14\\\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/14\\\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/14\\\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\\\/\",\"name\":\"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\\u00f3n para la subvenci\\u00f3n por parte del Ayto de los festejos taurinos - Ayuntamiento de Ciempozuelos\",\"description\":\"El Ayuntamiento de Ciempozuelos celebr\\u00f3 el pasado jueves, 13 de agosto a las 20.00 horas en la Sala Multifuncional, una sesi\\u00f3n plenaria de car\\u00e1cter extraordinario pedida por los grupos de la oposici\\u00f3n donde se llev\\u00f3 a votaci\\u00f3n el siguiente Orden del D\\u00eda: - Celebraci\\u00f3n de encierros en las fiestas patronales 2015 y concurso de recortes\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/14\\\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"datePublished\":\"2015-08-14T12:43:00+02:00\",\"dateModified\":\"2015-08-14T12:43:00+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos - Ayuntamiento de Ciempozuelos","description":"El Ayuntamiento de Ciempozuelos celebr\u00f3 el pasado jueves, 13 de agosto a las 20.00 horas en la Sala Multifuncional, una sesi\u00f3n plenaria de car\u00e1cter extraordinario pedida por los grupos de la oposici\u00f3n donde se llev\u00f3 a votaci\u00f3n el siguiente Orden del D\u00eda: - Celebraci\u00f3n de encierros en las fiestas patronales 2015 y concurso de recortes","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/#blogposting","name":"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos - Ayuntamiento de Ciempozuelos","headline":"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"datePublished":"2015-08-14T12:43:00+02:00","dateModified":"2015-08-14T12:43:00+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/#webpage"},"articleSection":"1118"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/#listItem","name":"1118"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/#listItem","position":2,"name":"1118","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/#listItem","name":"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/#listItem","position":3,"name":"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/#listItem","name":"1118"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/","name":"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos - Ayuntamiento de Ciempozuelos","description":"El Ayuntamiento de Ciempozuelos celebr\u00f3 el pasado jueves, 13 de agosto a las 20.00 horas en la Sala Multifuncional, una sesi\u00f3n plenaria de car\u00e1cter extraordinario pedida por los grupos de la oposici\u00f3n donde se llev\u00f3 a votaci\u00f3n el siguiente Orden del D\u00eda: - Celebraci\u00f3n de encierros en las fiestas patronales 2015 y concurso de recortes","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"datePublished":"2015-08-14T12:43:00+02:00","dateModified":"2015-08-14T12:43:00+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos - Ayuntamiento de Ciempozuelos","og:description":"El Ayuntamiento de Ciempozuelos celebr\u00f3 el pasado jueves, 13 de agosto a las 20.00 horas en la Sala Multifuncional, una sesi\u00f3n plenaria de car\u00e1cter extraordinario pedida por los grupos de la oposici\u00f3n donde se llev\u00f3 a votaci\u00f3n el siguiente Orden del D\u00eda: - Celebraci\u00f3n de encierros en las fiestas patronales 2015 y concurso de recortes","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/","article:published_time":"2015-08-14T12:43:00+00:00","article:modified_time":"2015-08-14T12:43:00+00:00","twitter:card":"summary","twitter:title":"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos - Ayuntamiento de Ciempozuelos","twitter:description":"El Ayuntamiento de Ciempozuelos celebr\u00f3 el pasado jueves, 13 de agosto a las 20.00 horas en la Sala Multifuncional, una sesi\u00f3n plenaria de car\u00e1cter extraordinario pedida por los grupos de la oposici\u00f3n donde se llev\u00f3 a votaci\u00f3n el siguiente Orden del D\u00eda: - Celebraci\u00f3n de encierros en las fiestas patronales 2015 y concurso de recortes"},"aioseo_meta_data":{"post_id":"10257","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:30:06","updated":"2025-06-04 16:56:00","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/\" title=\"1118\">1118<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1118","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1118\/"},{"label":"Aprobadas en pleno extraordinario las propuestas planteadas por la oposici\u00f3n para la subvenci\u00f3n por parte del Ayto de los festejos taurinos","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/14\/aprobadas-en-pleno-extraordinario-las-propuestas-planteadas-por-la-oposicion-para-la-subvencion-por-parte-del-ayto-de-los-festejos-taurinos\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:14:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10257"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10257\/revisions"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}