{"id":10249,"date":"2015-08-11T11:38:57","date_gmt":"2015-08-11T11:38:57","guid":{"rendered":"http:\/\/pre.ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/"},"modified":"2015-08-11T11:38:57","modified_gmt":"2015-08-11T11:38:57","slug":"campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015","status":"publish","type":"post","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/","title":{"rendered":"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\"><em>El campeonato arranca el d\u00eda 24 de agosto a las 20.00 horas en la plaza Ventura Rodr\u00edguez<\/em><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><em> <\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Con motivo de las fiestas patronales Virgen del Consuelo 2015, la asociaci\u00f3n de vecinos \u2018Las Salinas\u2019 organiza un a\u00f1o m\u00e1s el Campeonato de Mus que dar\u00e1 comienzo el 24 de agosto a las 20.00 horas en la plaza Ventura Rodr\u00edguez. <\/span><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Esta actividad cuenta con la colaboraci\u00f3n del Ayuntamiento de Ciempozuelos.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Los interesados podr\u00e1n inscribirse en el bar \u2018Okapi\u2019 y en la asociaci\u00f3n hasta el mismo d\u00eda del campeonato a las 19.00 horas. El precio de la inscripci\u00f3n es de 20 euros por pareja y las parejas son limitadas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">Se jugar\u00e1n dos partidas por d\u00eda y los premios ser\u00e1n para las dos primeras parejas del grupo A<\/span><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\"> <\/span><span style=\"font-size: 12.1599998474121px; line-height: 1.3em;\">y B, la primera pareja del grupo C, la mejor pareja mixta o femenina, a la pareja veterana y a la pareja joven.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-justify: inter-ideograph;\"><em style=\"font-size: 12.1599998474121px; line-height: 15.8079996109009px;\"><img decoding=\"async\" class=\" size-full wp-image-10248\" src=\"http:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-scaled.jpg\" border=\"0\" width=\"100%\" srcset=\"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-200x283.jpg 200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-212x300.jpg 212w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-400x566.jpg 400w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-600x849.jpg 600w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-724x1024.jpg 724w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-768x1086.jpg 768w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-800x1131.jpg 800w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-1086x1536.jpg 1086w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-1200x1697.jpg 1200w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-1448x2048.jpg 1448w, https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-scaled.jpg 1810w\" sizes=\"(max-width: 1810px) 100vw, 1810px\" \/><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El campeonato arranca el d\u00eda 24 de agosto a las 20.00 horas en la plaza Ventura Rodr\u00edguez Con motivo de las fiestas patronales Virgen del Consuelo 2015, la asociaci\u00f3n de vecinos \u2018Las Salinas\u2019 organiza un a\u00f1o m\u00e1s el Campeonato de Mus que dar\u00e1 comienzo el 24 de agosto a las 20.00 horas en la plaza [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[],"tags":[1232],"class_list":["post-10249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-1232"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El campeonato arranca el d\u00eda 24 de agosto a las 20.00 horas en la plaza Ventura Rodr\u00edguez Con motivo de las fiestas patronales Virgen del Consuelo 2015, la asociaci\u00f3n de vecinos \u2018Las Salinas\u2019 organiza un a\u00f1o m\u00e1s el Campeonato de Mus que dar\u00e1 comienzo el 24 de agosto a las 20.00 horas en la plaza\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"informatica1\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015 - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta property=\"og:description\" content=\"El campeonato arranca el d\u00eda 24 de agosto a las 20.00 horas en la plaza Ventura Rodr\u00edguez Con motivo de las fiestas patronales Virgen del Consuelo 2015, la asociaci\u00f3n de vecinos \u2018Las Salinas\u2019 organiza un a\u00f1o m\u00e1s el Campeonato de Mus que dar\u00e1 comienzo el 24 de agosto a las 20.00 horas en la plaza\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-08-11T11:38:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-08-11T11:38:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015 - Ayuntamiento de Ciempozuelos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El campeonato arranca el d\u00eda 24 de agosto a las 20.00 horas en la plaza Ventura Rodr\u00edguez Con motivo de las fiestas patronales Virgen del Consuelo 2015, la asociaci\u00f3n de vecinos \u2018Las Salinas\u2019 organiza un a\u00f1o m\u00e1s el Campeonato de Mus que dar\u00e1 comienzo el 24 de agosto a las 20.00 horas en la plaza\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/#blogposting\",\"name\":\"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015 - Ayuntamiento de Ciempozuelos\",\"headline\":\"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015\",\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/final_cartel_con_publi-scaled.jpg\",\"width\":1810,\"height\":2560},\"datePublished\":\"2015-08-11T11:38:57+02:00\",\"dateModified\":\"2015-08-11T11:38:57+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/#webpage\"},\"articleSection\":\"1218\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1218\\\/#listItem\",\"name\":\"1218\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1218\\\/#listItem\",\"position\":2,\"name\":\"1218\",\"item\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1218\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/#listItem\",\"name\":\"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/#listItem\",\"position\":3,\"name\":\"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/tag\\\/1218\\\/#listItem\",\"name\":\"1218\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/\",\"name\":\"informatica1\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"informatica1\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/#webpage\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/\",\"name\":\"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015 - Ayuntamiento de Ciempozuelos\",\"description\":\"El campeonato arranca el d\\u00eda 24 de agosto a las 20.00 horas en la plaza Ventura Rodr\\u00edguez Con motivo de las fiestas patronales Virgen del Consuelo 2015, la asociaci\\u00f3n de vecinos \\u2018Las Salinas\\u2019 organiza un a\\u00f1o m\\u00e1s el Campeonato de Mus que dar\\u00e1 comienzo el 24 de agosto a las 20.00 horas en la plaza\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/author\\\/informatica1\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/final_cartel_con_publi-scaled.jpg\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/#mainImage\",\"width\":1810,\"height\":2560},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/index.php\\\/2015\\\/08\\\/11\\\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\\\/#mainImage\"},\"datePublished\":\"2015-08-11T11:38:57+02:00\",\"dateModified\":\"2015-08-11T11:38:57+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#website\",\"url\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/\",\"name\":\"Ayuntamiento de Ciempozuelos\",\"description\":\"Web oficial del Ayuntamiento de Ciempozuelos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/ayto-ciempozuelos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015 - Ayuntamiento de Ciempozuelos","description":"El campeonato arranca el d\u00eda 24 de agosto a las 20.00 horas en la plaza Ventura Rodr\u00edguez Con motivo de las fiestas patronales Virgen del Consuelo 2015, la asociaci\u00f3n de vecinos \u2018Las Salinas\u2019 organiza un a\u00f1o m\u00e1s el Campeonato de Mus que dar\u00e1 comienzo el 24 de agosto a las 20.00 horas en la plaza","canonical_url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/#blogposting","name":"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015 - Ayuntamiento de Ciempozuelos","headline":"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015","author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-scaled.jpg","width":1810,"height":2560},"datePublished":"2015-08-11T11:38:57+02:00","dateModified":"2015-08-11T11:38:57+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/#webpage"},"isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/#webpage"},"articleSection":"1218"},{"@type":"BreadcrumbList","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","position":1,"name":"Home","item":"https:\/\/ayto-ciempozuelos.org","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1218\/#listItem","name":"1218"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1218\/#listItem","position":2,"name":"1218","item":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1218\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/#listItem","name":"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/#listItem","position":3,"name":"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015","previousItem":{"@type":"ListItem","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1218\/#listItem","name":"1218"}}]},{"@type":"Organization","@id":"https:\/\/ayto-ciempozuelos.org\/#organization","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","url":"https:\/\/ayto-ciempozuelos.org\/"},{"@type":"Person","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/","name":"informatica1","image":{"@type":"ImageObject","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4c1ae48c149a4ec864ada8687863033edb89876d96b1562cbe40fb86c33ec21e?s=96&d=mm&r=g","width":96,"height":96,"caption":"informatica1"}},{"@type":"WebPage","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/#webpage","url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/","name":"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015 - Ayuntamiento de Ciempozuelos","description":"El campeonato arranca el d\u00eda 24 de agosto a las 20.00 horas en la plaza Ventura Rodr\u00edguez Con motivo de las fiestas patronales Virgen del Consuelo 2015, la asociaci\u00f3n de vecinos \u2018Las Salinas\u2019 organiza un a\u00f1o m\u00e1s el Campeonato de Mus que dar\u00e1 comienzo el 24 de agosto a las 20.00 horas en la plaza","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/ayto-ciempozuelos.org\/#website"},"breadcrumb":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/#breadcrumblist"},"author":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"creator":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/author\/informatica1\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/ayto-ciempozuelos.org\/wp-content\/uploads\/2015\/08\/final_cartel_con_publi-scaled.jpg","@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/#mainImage","width":1810,"height":2560},"primaryImageOfPage":{"@id":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/#mainImage"},"datePublished":"2015-08-11T11:38:57+02:00","dateModified":"2015-08-11T11:38:57+02:00"},{"@type":"WebSite","@id":"https:\/\/ayto-ciempozuelos.org\/#website","url":"https:\/\/ayto-ciempozuelos.org\/","name":"Ayuntamiento de Ciempozuelos","description":"Web oficial del Ayuntamiento de Ciempozuelos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/ayto-ciempozuelos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ayuntamiento de Ciempozuelos - Web oficial del Ayuntamiento de Ciempozuelos","og:type":"article","og:title":"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015 - Ayuntamiento de Ciempozuelos","og:description":"El campeonato arranca el d\u00eda 24 de agosto a las 20.00 horas en la plaza Ventura Rodr\u00edguez Con motivo de las fiestas patronales Virgen del Consuelo 2015, la asociaci\u00f3n de vecinos \u2018Las Salinas\u2019 organiza un a\u00f1o m\u00e1s el Campeonato de Mus que dar\u00e1 comienzo el 24 de agosto a las 20.00 horas en la plaza","og:url":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/","article:published_time":"2015-08-11T11:38:57+00:00","article:modified_time":"2015-08-11T11:38:57+00:00","twitter:card":"summary","twitter:title":"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015 - Ayuntamiento de Ciempozuelos","twitter:description":"El campeonato arranca el d\u00eda 24 de agosto a las 20.00 horas en la plaza Ventura Rodr\u00edguez Con motivo de las fiestas patronales Virgen del Consuelo 2015, la asociaci\u00f3n de vecinos \u2018Las Salinas\u2019 organiza un a\u00f1o m\u00e1s el Campeonato de Mus que dar\u00e1 comienzo el 24 de agosto a las 20.00 horas en la plaza"},"aioseo_meta_data":{"post_id":"10249","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":0,"ai":null,"created":"2022-06-30 14:28:59","updated":"2025-06-04 16:56:00","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1218\/\" title=\"1218\">1218<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCampeonato de Mus Fiestas Patronales Virgen del Consuelo 2015\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ayto-ciempozuelos.org"},{"label":"1218","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/tag\/1218\/"},{"label":"Campeonato de Mus Fiestas Patronales Virgen del Consuelo 2015","link":"https:\/\/ayto-ciempozuelos.org\/index.php\/2015\/08\/11\/campeonato-de-mus-fiestas-patronales-virgen-del-consuelo-2015\/"}],"modified_by":null,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:08:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/comments?post=10249"}],"version-history":[{"count":0,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/posts\/10249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media\/10248"}],"wp:attachment":[{"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/media?parent=10249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/categories?post=10249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto-ciempozuelos.org\/index.php\/wp-json\/wp\/v2\/tags?post=10249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}